{"id":138,"date":"2025-04-29T10:57:37","date_gmt":"2025-04-29T08:57:37","guid":{"rendered":"https:\/\/comunicacity.net\/acercampania\/2024\/05\/24\/avviso-orari-di-ricevimento\/"},"modified":"2025-07-14T10:59:41","modified_gmt":"2025-07-14T08:59:41","slug":"avviso-orari-di-ricevimento","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/acercampania\/2025\/04\/29\/avviso-orari-di-ricevimento\/","title":{"rendered":"Presentato a Eboli il progetto per la nuova vita del Rione Borgo: case moderne, pi\u00f9 verde e spazi per la comunit\u00e0"},"content":{"rendered":"<p><em>A Eboli presentato il progetto di ricostruzione di 56 alloggi popolari, efficienti e sostenibili, con ampie aree verdi e spazi comuni per migliorare la qualit\u00e0 di vita.<\/p>\n<p><\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Eboli | Luned\u00ec 28 aprile<\/p>\n<p>Si \u00e8 tenuta oggi a Eboli la cerimonia di presentazione del progetto di ricostruzione degli alloggi popolari del Rione Borgo, un intervento strategico finanziato con il Fondo Complementare al PNRR, nell\u2019ambito del programma \u201cSicuro, verde e sociale\u201d, destinato alla riqualificazione dell\u2019edilizia residenziale pubblica.<\/p>\n<p>Alla conferenza stampa sono intervenuti l\u2019Assessore all\u2019Urbanistica della Regione Campania Bruno Discepolo, il Sindaco di Eboli Mario Conte e il Presidente di ACER Campania David Lebro.<\/p>\n<p>Durante l\u2019evento, che ha visto anche la posa simbolica della prima pietra del nuovo insediamento, \u00e8 stato illustrato il progetto che prevede la realizzazione di tre edifici moderni nel quartiere Rione Pescara, destinati ad accogliere 56 famiglie.<\/p>\n<p>Le nuove abitazioni, progettate secondo criteri di efficienza e sostenibilit\u00e0, comprenderanno 32 appartamenti, con spazi pensati per offrire comfort, risparmio energetico e una migliore qualit\u00e0 della vita.<\/p>\n<p>Il nuovo insediamento sorger\u00e0 su un\u2019area tre volte pi\u00f9 ampia rispetto a quella attuale, con una significativa riduzione dell\u2019impatto edilizio: solo il 40% del suolo sar\u00e0 costruito, mentre il resto sar\u00e0 destinato a verde pubblico, aree pedonali e spazi sportivi, restituendo cos\u00ec alla comunit\u00e0 un quartiere pi\u00f9 vivibile e inclusivo.<\/p>\n<p>\u00abCon questo progetto vogliamo essere concretamente vicini ai cittadini, non solo offrendo loro abitazioni moderne, sicure e accoglienti, ma anche ascoltando le loro esigenze e costruendo risposte concrete \u2013 ha dichiarato il Presidente di ACER Campania, David Lebro \u2013.<\/p>\n<p>Un\u2019iniziativa che punta a migliorare la qualit\u00e0 della vita delle famiglie e a rafforzare il senso di comunit\u00e0, grazie alla collaborazione tra Regione Campania, Comune di Eboli e ACER Campania.\u00bb<\/p>\n<p><strong>Per informazioni:<\/strong><\/p>\n<ul>\n<li>Ufficio Stampa e Comunicazione ACER Campania<\/li>\n<li><a href=\"mailto:rossella.guarracino@acercampania.it\">rossella.guarracino@acercampania.it<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><b>Immagini e Video&nbsp;<\/b><\/p>\n<p><img src='http:\/\/acercampania.sviluppopa.it\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-04-28-at-14.39.39.jpeg' alt='image'><\/p>\n<p><img src='http:\/\/acercampania.sviluppopa.it\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-04-28-at-14.39.40-1024x576-1.jpeg' alt='image'><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Eboli presentato il progetto di ricostruzione di 56 alloggi popolari, efficienti e sostenibili, con ampie aree verdi e spazi comuni per migliorare la qualit\u00e0 di vita. &nbsp; Descrizione&nbsp; Eboli [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":185,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentato a Eboli il progetto per la nuova vita del Rione Borgo: case moderne, pi\u00f9 verde e spazi per la comunit\u00e0 - Acer Campania<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/acercampania\/2024\/05\/24\/avviso-orari-di-ricevimento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentato a Eboli il progetto per la nuova vita del Rione Borgo: case moderne, pi\u00f9 verde e spazi per la comunit\u00e0 - Acer Campania\" \/>\n<meta property=\"og:description\" content=\"A Eboli presentato il progetto di ricostruzione di 56 alloggi popolari, efficienti e sostenibili, con ampie aree verdi e spazi comuni per migliorare la qualit\u00e0 di vita. &nbsp; Descrizione&nbsp; Eboli [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/acercampania\/2024\/05\/24\/avviso-orari-di-ricevimento\/\" \/>\n<meta property=\"og:site_name\" content=\"Acer Campania\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-29T08:57:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-14T08:59:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/acercampania\/wp-content\/uploads\/sites\/235\/2025\/05\/immagine_evidenza_iacp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2024\\\/05\\\/24\\\/avviso-orari-di-ricevimento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2024\\\/05\\\/24\\\/avviso-orari-di-ricevimento\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Presentato a Eboli il progetto per la nuova vita del Rione Borgo: case moderne, pi\u00f9 verde e spazi per la comunit\u00e0\",\"datePublished\":\"2025-04-29T08:57:37+00:00\",\"dateModified\":\"2025-07-14T08:59:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2024\\\/05\\\/24\\\/avviso-orari-di-ricevimento\\\/\"},\"wordCount\":323,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2024\\\/05\\\/24\\\/avviso-orari-di-ricevimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/wp-content\\\/uploads\\\/sites\\\/235\\\/2025\\\/07\\\/WhatsApp-Image-2025-04-28-at-14.39.39.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2024\\\/05\\\/24\\\/avviso-orari-di-ricevimento\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2024\\\/05\\\/24\\\/avviso-orari-di-ricevimento\\\/\",\"name\":\"Presentato a Eboli il progetto per la nuova vita del Rione Borgo: case moderne, pi\u00f9 verde e spazi per la comunit\u00e0 - Acer Campania\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2024\\\/05\\\/24\\\/avviso-orari-di-ricevimento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2024\\\/05\\\/24\\\/avviso-orari-di-ricevimento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/wp-content\\\/uploads\\\/sites\\\/235\\\/2025\\\/07\\\/WhatsApp-Image-2025-04-28-at-14.39.39.jpeg\",\"datePublished\":\"2025-04-29T08:57:37+00:00\",\"dateModified\":\"2025-07-14T08:59:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2024\\\/05\\\/24\\\/avviso-orari-di-ricevimento\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2024\\\/05\\\/24\\\/avviso-orari-di-ricevimento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2024\\\/05\\\/24\\\/avviso-orari-di-ricevimento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/wp-content\\\/uploads\\\/sites\\\/235\\\/2025\\\/07\\\/WhatsApp-Image-2025-04-28-at-14.39.39.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/wp-content\\\/uploads\\\/sites\\\/235\\\/2025\\\/07\\\/WhatsApp-Image-2025-04-28-at-14.39.39.jpeg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2024\\\/05\\\/24\\\/avviso-orari-di-ricevimento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso orari di ricevimento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentato a Eboli il progetto per la nuova vita del Rione Borgo: case moderne, pi\u00f9 verde e spazi per la comunit\u00e0 - Acer Campania","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/acercampania\/2024\/05\/24\/avviso-orari-di-ricevimento\/","og_locale":"it_IT","og_type":"article","og_title":"Presentato a Eboli il progetto per la nuova vita del Rione Borgo: case moderne, pi\u00f9 verde e spazi per la comunit\u00e0 - Acer Campania","og_description":"A Eboli presentato il progetto di ricostruzione di 56 alloggi popolari, efficienti e sostenibili, con ampie aree verdi e spazi comuni per migliorare la qualit\u00e0 di vita. &nbsp; Descrizione&nbsp; Eboli [&hellip;]","og_url":"https:\/\/comunicacity.net\/acercampania\/2024\/05\/24\/avviso-orari-di-ricevimento\/","og_site_name":"Acer Campania","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-04-29T08:57:37+00:00","article_modified_time":"2025-07-14T08:59:41+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/comunicacity.net\/acercampania\/wp-content\/uploads\/sites\/235\/2025\/05\/immagine_evidenza_iacp.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/acercampania\/2024\/05\/24\/avviso-orari-di-ricevimento\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/acercampania\/2024\/05\/24\/avviso-orari-di-ricevimento\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/acercampania\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Presentato a Eboli il progetto per la nuova vita del Rione Borgo: case moderne, pi\u00f9 verde e spazi per la comunit\u00e0","datePublished":"2025-04-29T08:57:37+00:00","dateModified":"2025-07-14T08:59:41+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/acercampania\/2024\/05\/24\/avviso-orari-di-ricevimento\/"},"wordCount":323,"publisher":{"@id":"https:\/\/comunicacity.net\/acercampania\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/acercampania\/2024\/05\/24\/avviso-orari-di-ricevimento\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/acercampania\/wp-content\/uploads\/sites\/235\/2025\/07\/WhatsApp-Image-2025-04-28-at-14.39.39.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/acercampania\/2024\/05\/24\/avviso-orari-di-ricevimento\/","url":"https:\/\/comunicacity.net\/acercampania\/2024\/05\/24\/avviso-orari-di-ricevimento\/","name":"Presentato a Eboli il progetto per la nuova vita del Rione Borgo: case moderne, pi\u00f9 verde e spazi per la comunit\u00e0 - Acer Campania","isPartOf":{"@id":"https:\/\/comunicacity.net\/acercampania\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/acercampania\/2024\/05\/24\/avviso-orari-di-ricevimento\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/acercampania\/2024\/05\/24\/avviso-orari-di-ricevimento\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/acercampania\/wp-content\/uploads\/sites\/235\/2025\/07\/WhatsApp-Image-2025-04-28-at-14.39.39.jpeg","datePublished":"2025-04-29T08:57:37+00:00","dateModified":"2025-07-14T08:59:41+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/acercampania\/2024\/05\/24\/avviso-orari-di-ricevimento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/acercampania\/2024\/05\/24\/avviso-orari-di-ricevimento\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/acercampania\/2024\/05\/24\/avviso-orari-di-ricevimento\/#primaryimage","url":"https:\/\/comunicacity.net\/acercampania\/wp-content\/uploads\/sites\/235\/2025\/07\/WhatsApp-Image-2025-04-28-at-14.39.39.jpeg","contentUrl":"https:\/\/comunicacity.net\/acercampania\/wp-content\/uploads\/sites\/235\/2025\/07\/WhatsApp-Image-2025-04-28-at-14.39.39.jpeg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/acercampania\/2024\/05\/24\/avviso-orari-di-ricevimento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/acercampania\/"},{"@type":"ListItem","position":2,"name":"Avviso orari di ricevimento"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/acercampania\/#website","url":"https:\/\/comunicacity.net\/acercampania\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/acercampania\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/acercampania\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/acercampania\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/acercampania\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/acercampania\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/acercampania\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/acercampania\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00003080"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/posts\/138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/comments?post=138"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/posts\/138\/revisions"}],"predecessor-version":[{"id":184,"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/posts\/138\/revisions\/184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/media\/185"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/media?parent=138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/categories?post=138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/tags?post=138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}