{"id":226,"date":"2025-09-19T12:27:55","date_gmt":"2025-09-19T10:27:55","guid":{"rendered":"https:\/\/comunicacity.net\/acercampania\/?p=226"},"modified":"2025-09-23T10:27:24","modified_gmt":"2025-09-23T08:27:24","slug":"acer-campania-attivo-il-pagamento-tramite-pagopa","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/acercampania\/2025\/09\/19\/acer-campania-attivo-il-pagamento-tramite-pagopa\/","title":{"rendered":"ACER Campania: attivo il pagamento tramite pagoPA"},"content":{"rendered":"<p><em>Un nuovo strumento a disposizione degli utenti: si aggiunge pagoPA ai metodi di pagamento di ACER Campania.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">ACER Campania: attivo il pagamento tramite pagoPA <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Un nuovo strumento a disposizione degli utenti: si aggiunge pagoPA ai metodi di pagamento di ACER Campania.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">ACER Campania amplia i canali a disposizione degli utenti per effettuare i propri versamenti. Da oggi \u00e8 infatti possibile utilizzare pagoPA, il sistema nazionale di pagamenti elettronici verso la Pubblica Amministrazione. <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Grazie a questa novit\u00e0, tutti gli utenti potranno mettersi in regola in maniera semplice, sicura e trasparente, scegliendo tra home banking, sportelli bancari e postali, tabaccai, app dedicate e portali online abilitati.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Oltre alle modalit\u00e0 gi\u00e0 disponibili \u2014 POS presso le sedi, bonifico bancario, conto corrente postale e assegno circolare \u2014 da oggi i versamenti possono essere effettuati anche tramite pagoPA. <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Il sistema consente di pagare online da PC o tablet, attraverso app per smartphone come IO, Satispay, PostePay e app bancarie, oppure presso punti fisici convenzionati come tabaccherie, sportelli bancari e ATM.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Questa nuova opzione nasce per offrire strumenti pi\u00f9 semplici e flessibili, in linea con le esigenze dei cittadini.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Per maggiori informazioni \u00e8 possibile consultare il sito www.pagopa.gov.it<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Per assistenza, gli utenti possono rivolgersi agli uffici ACER Campania tramite il Numero Verde 800 994 840.<\/span><\/span><\/p>\n<p><span dir=\"auto\" style=\"vertical-align: inherit\"><span dir=\"auto\" style=\"vertical-align: inherit\">Con l&#8217;attivazione di pagoPA, ACER Campania conferma il proprio impegno nel migliorare l&#8217;accessibilit\u00e0 e la qualit\u00e0 dei servizi, rafforzando al tempo stesso il rapporto di fiducia e vicinanza con la propria utenza.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un nuovo strumento a disposizione degli utenti: si aggiunge pagoPA ai metodi di pagamento di ACER Campania.&nbsp; Descrizione&nbsp; ACER Campania: attivo il pagamento tramite pagoPA Un nuovo strumento a disposizione [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":238,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ACER Campania: attivo il pagamento tramite pagoPA - Acer Campania<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/acercampania\/2025\/09\/19\/acer-campania-attivo-il-pagamento-tramite-pagopa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ACER Campania: attivo il pagamento tramite pagoPA - Acer Campania\" \/>\n<meta property=\"og:description\" content=\"Un nuovo strumento a disposizione degli utenti: si aggiunge pagoPA ai metodi di pagamento di ACER Campania.&nbsp; Descrizione&nbsp; ACER Campania: attivo il pagamento tramite pagoPA Un nuovo strumento a disposizione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/acercampania\/2025\/09\/19\/acer-campania-attivo-il-pagamento-tramite-pagopa\/\" \/>\n<meta property=\"og:site_name\" content=\"Acer Campania\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-19T10:27:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-23T08:27:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/acercampania\/wp-content\/uploads\/sites\/235\/2025\/09\/immaginePagoPA-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"396\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2025\\\/09\\\/19\\\/acer-campania-attivo-il-pagamento-tramite-pagopa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2025\\\/09\\\/19\\\/acer-campania-attivo-il-pagamento-tramite-pagopa\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"ACER Campania: attivo il pagamento tramite pagoPA\",\"datePublished\":\"2025-09-19T10:27:55+00:00\",\"dateModified\":\"2025-09-23T08:27:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2025\\\/09\\\/19\\\/acer-campania-attivo-il-pagamento-tramite-pagopa\\\/\"},\"wordCount\":247,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2025\\\/09\\\/19\\\/acer-campania-attivo-il-pagamento-tramite-pagopa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/wp-content\\\/uploads\\\/sites\\\/235\\\/2025\\\/09\\\/immaginePagoPA-1-1.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2025\\\/09\\\/19\\\/acer-campania-attivo-il-pagamento-tramite-pagopa\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2025\\\/09\\\/19\\\/acer-campania-attivo-il-pagamento-tramite-pagopa\\\/\",\"name\":\"ACER Campania: attivo il pagamento tramite pagoPA - Acer Campania\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2025\\\/09\\\/19\\\/acer-campania-attivo-il-pagamento-tramite-pagopa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2025\\\/09\\\/19\\\/acer-campania-attivo-il-pagamento-tramite-pagopa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/wp-content\\\/uploads\\\/sites\\\/235\\\/2025\\\/09\\\/immaginePagoPA-1-1.jpeg\",\"datePublished\":\"2025-09-19T10:27:55+00:00\",\"dateModified\":\"2025-09-23T08:27:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2025\\\/09\\\/19\\\/acer-campania-attivo-il-pagamento-tramite-pagopa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2025\\\/09\\\/19\\\/acer-campania-attivo-il-pagamento-tramite-pagopa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2025\\\/09\\\/19\\\/acer-campania-attivo-il-pagamento-tramite-pagopa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/wp-content\\\/uploads\\\/sites\\\/235\\\/2025\\\/09\\\/immaginePagoPA-1-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/wp-content\\\/uploads\\\/sites\\\/235\\\/2025\\\/09\\\/immaginePagoPA-1-1.jpeg\",\"width\":640,\"height\":396},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/2025\\\/09\\\/19\\\/acer-campania-attivo-il-pagamento-tramite-pagopa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ACER Campania: attivo il pagamento tramite pagoPA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acercampania\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ACER Campania: attivo il pagamento tramite pagoPA - Acer Campania","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/acercampania\/2025\/09\/19\/acer-campania-attivo-il-pagamento-tramite-pagopa\/","og_locale":"it_IT","og_type":"article","og_title":"ACER Campania: attivo il pagamento tramite pagoPA - Acer Campania","og_description":"Un nuovo strumento a disposizione degli utenti: si aggiunge pagoPA ai metodi di pagamento di ACER Campania.&nbsp; Descrizione&nbsp; ACER Campania: attivo il pagamento tramite pagoPA Un nuovo strumento a disposizione [&hellip;]","og_url":"https:\/\/comunicacity.net\/acercampania\/2025\/09\/19\/acer-campania-attivo-il-pagamento-tramite-pagopa\/","og_site_name":"Acer Campania","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-09-19T10:27:55+00:00","article_modified_time":"2025-09-23T08:27:24+00:00","og_image":[{"width":640,"height":396,"url":"https:\/\/comunicacity.net\/acercampania\/wp-content\/uploads\/sites\/235\/2025\/09\/immaginePagoPA-1.jpeg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/acercampania\/2025\/09\/19\/acer-campania-attivo-il-pagamento-tramite-pagopa\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/acercampania\/2025\/09\/19\/acer-campania-attivo-il-pagamento-tramite-pagopa\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/acercampania\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"ACER Campania: attivo il pagamento tramite pagoPA","datePublished":"2025-09-19T10:27:55+00:00","dateModified":"2025-09-23T08:27:24+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/acercampania\/2025\/09\/19\/acer-campania-attivo-il-pagamento-tramite-pagopa\/"},"wordCount":247,"publisher":{"@id":"https:\/\/comunicacity.net\/acercampania\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/acercampania\/2025\/09\/19\/acer-campania-attivo-il-pagamento-tramite-pagopa\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/acercampania\/wp-content\/uploads\/sites\/235\/2025\/09\/immaginePagoPA-1-1.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/acercampania\/2025\/09\/19\/acer-campania-attivo-il-pagamento-tramite-pagopa\/","url":"https:\/\/comunicacity.net\/acercampania\/2025\/09\/19\/acer-campania-attivo-il-pagamento-tramite-pagopa\/","name":"ACER Campania: attivo il pagamento tramite pagoPA - Acer Campania","isPartOf":{"@id":"https:\/\/comunicacity.net\/acercampania\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/acercampania\/2025\/09\/19\/acer-campania-attivo-il-pagamento-tramite-pagopa\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/acercampania\/2025\/09\/19\/acer-campania-attivo-il-pagamento-tramite-pagopa\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/acercampania\/wp-content\/uploads\/sites\/235\/2025\/09\/immaginePagoPA-1-1.jpeg","datePublished":"2025-09-19T10:27:55+00:00","dateModified":"2025-09-23T08:27:24+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/acercampania\/2025\/09\/19\/acer-campania-attivo-il-pagamento-tramite-pagopa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/acercampania\/2025\/09\/19\/acer-campania-attivo-il-pagamento-tramite-pagopa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/acercampania\/2025\/09\/19\/acer-campania-attivo-il-pagamento-tramite-pagopa\/#primaryimage","url":"https:\/\/comunicacity.net\/acercampania\/wp-content\/uploads\/sites\/235\/2025\/09\/immaginePagoPA-1-1.jpeg","contentUrl":"https:\/\/comunicacity.net\/acercampania\/wp-content\/uploads\/sites\/235\/2025\/09\/immaginePagoPA-1-1.jpeg","width":640,"height":396},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/acercampania\/2025\/09\/19\/acer-campania-attivo-il-pagamento-tramite-pagopa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/acercampania\/"},{"@type":"ListItem","position":2,"name":"ACER Campania: attivo il pagamento tramite pagoPA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/acercampania\/#website","url":"https:\/\/comunicacity.net\/acercampania\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/acercampania\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/acercampania\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/acercampania\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/acercampania\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/acercampania\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/acercampania\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/acercampania\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00003564"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/posts\/226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/comments?post=226"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/posts\/226\/revisions"}],"predecessor-version":[{"id":236,"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/posts\/226\/revisions\/236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/media\/238"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/media?parent=226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/categories?post=226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/acercampania\/wp-json\/wp\/v2\/tags?post=226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}