{"id":1205,"date":"2019-01-05T16:29:31","date_gmt":"2019-01-05T15:29:31","guid":{"rendered":"https:\/\/comunicacity.net\/acerra\/?p=1205"},"modified":"2019-01-05T16:29:31","modified_gmt":"2019-01-05T15:29:31","slug":"divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/acerra\/2019\/01\/05\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\/","title":{"rendered":"Divieto di circolazione e di sosta sulle strade interessate dal Trofeo della Befana"},"content":{"rendered":"<p>In occasione della gara podistica \u201c<em>Trofeo della Befana \u2013 30esima edizione<\/em>\u201d, in programma per domani, <strong>domenica 6 gennaio 2019, con inizio alle ore 8,30, partenza ed arrivo in Piazzale Calipari,<\/strong> si informa che su alcune strade cittadine \u00e8 <strong>sospesa la circolazione e la sosta dei veicoli per la durata strettamente necessaria al transito dei concorrenti.<\/strong><\/p>\n<p>Le strade interessate dal passaggio degli sportivi, su cui \u00e8 vietata la circolazione e la sosta dei veicoli sono: <strong>Via Paisiello, Via Pio la Torre, Via Paganini, Corso Vittorio Emanuele II, Via Annunziata, Via Roma, Via del Penino, Piazza San Pietro, Corso Italia, Via dei Mille, Via Zara, Via Calzolaio, Via Soriano (dall\u2019incrocio con Corso Garibaldi all\u2019incrocio con Via Santa Caterina da Siena), Via Santa Caterina da Siena, Via Vittorio Veneto, Via Mulino Vecchio, Via Don Puglisi, Via Boris Giuliano, Via Ammaturo, Via Muro di Piombo, Via Vivaldi, Via Madonnella<\/strong>.<\/p>\n<p><strong>I trasgressori saranno sanzionati a norma del Codice della Strada e i veicoli in sosta vietata saranno rimossi a mezzo carro-gru.<\/strong><\/p>\n<p>Si ribadisce che<strong> per la durata strettamente necessaria al transito dei concorrenti \u00e8 vietata la circolazione e la sosta delle auto<\/strong> pertanto si invita la cittadinanza a <em>limitare l\u2019uso delle automobili, lasciandole a casa ove possibile e vivendo a piedi la citt\u00e0 e la manifestazione.<\/em><\/p>\n<p>Tutti gli utenti della strada, infine, sono invitati a rispettare le segnalazioni, a non attraversare le strade impegnate dai concorrenti, ad adottare tutte le cautele necessarie ed a rivolgersi al personale della Polizia Municipale presente sul posto.<\/p>\n<p>Consulta l\u2019Ordinanza completa<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_1206\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2019\/01\/4_121109256-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2019\/01\/4_121109256-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>4_121109256 (1)<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In occasione della gara podistica \u201cTrofeo della Befana \u2013 30esima edizione\u201d, in programma per domani, domenica 6 gennaio 2019, con inizio alle ore 8,30, partenza ed arrivo in Piazzale Calipari, [&hellip;]<\/p>\n","protected":false},"author":140,"featured_media":391,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-1205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Divieto di circolazione e di sosta sulle strade interessate dal Trofeo della Befana - Acerra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/acerra\/2019\/01\/05\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Divieto di circolazione e di sosta sulle strade interessate dal Trofeo della Befana - Acerra\" \/>\n<meta property=\"og:description\" content=\"In occasione della gara podistica \u201cTrofeo della Befana \u2013 30esima edizione\u201d, in programma per domani, domenica 6 gennaio 2019, con inizio alle ore 8,30, partenza ed arrivo in Piazzale Calipari, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/acerra\/2019\/01\/05\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\/\" \/>\n<meta property=\"og:site_name\" content=\"Acerra\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-05T15:29:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/02\/viabilita-modificata.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"664\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marioamelia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"marioamelia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/01\\\/05\\\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/01\\\/05\\\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\\\/\"},\"author\":{\"name\":\"marioamelia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#\\\/schema\\\/person\\\/ffc746891ee9789194f211d721d68534\"},\"headline\":\"Divieto di circolazione e di sosta sulle strade interessate dal Trofeo della Befana\",\"datePublished\":\"2019-01-05T15:29:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/01\\\/05\\\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\\\/\"},\"wordCount\":261,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/01\\\/05\\\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2017\\\/02\\\/viabilita-modificata.jpeg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/01\\\/05\\\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/01\\\/05\\\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\\\/\",\"name\":\"Divieto di circolazione e di sosta sulle strade interessate dal Trofeo della Befana - Acerra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/01\\\/05\\\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/01\\\/05\\\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2017\\\/02\\\/viabilita-modificata.jpeg\",\"datePublished\":\"2019-01-05T15:29:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#\\\/schema\\\/person\\\/ffc746891ee9789194f211d721d68534\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/01\\\/05\\\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/01\\\/05\\\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/01\\\/05\\\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2017\\\/02\\\/viabilita-modificata.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2017\\\/02\\\/viabilita-modificata.jpeg\",\"width\":664,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/01\\\/05\\\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Divieto di circolazione e di sosta sulle strade interessate dal Trofeo della Befana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/\",\"name\":\"Acerra\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#\\\/schema\\\/person\\\/ffc746891ee9789194f211d721d68534\",\"name\":\"marioamelia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g\",\"caption\":\"marioamelia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/author\\\/marioamelia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Divieto di circolazione e di sosta sulle strade interessate dal Trofeo della Befana - Acerra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/acerra\/2019\/01\/05\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\/","og_locale":"it_IT","og_type":"article","og_title":"Divieto di circolazione e di sosta sulle strade interessate dal Trofeo della Befana - Acerra","og_description":"In occasione della gara podistica \u201cTrofeo della Befana \u2013 30esima edizione\u201d, in programma per domani, domenica 6 gennaio 2019, con inizio alle ore 8,30, partenza ed arrivo in Piazzale Calipari, [&hellip;]","og_url":"https:\/\/comunicacity.net\/acerra\/2019\/01\/05\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\/","og_site_name":"Acerra","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-01-05T15:29:31+00:00","og_image":[{"width":664,"height":800,"url":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/02\/viabilita-modificata.jpeg","type":"image\/jpeg"}],"author":"marioamelia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"marioamelia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/acerra\/2019\/01\/05\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/acerra\/2019\/01\/05\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\/"},"author":{"name":"marioamelia","@id":"https:\/\/comunicacity.net\/acerra\/#\/schema\/person\/ffc746891ee9789194f211d721d68534"},"headline":"Divieto di circolazione e di sosta sulle strade interessate dal Trofeo della Befana","datePublished":"2019-01-05T15:29:31+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/acerra\/2019\/01\/05\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\/"},"wordCount":261,"image":{"@id":"https:\/\/comunicacity.net\/acerra\/2019\/01\/05\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/02\/viabilita-modificata.jpeg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/acerra\/2019\/01\/05\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\/","url":"https:\/\/comunicacity.net\/acerra\/2019\/01\/05\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\/","name":"Divieto di circolazione e di sosta sulle strade interessate dal Trofeo della Befana - Acerra","isPartOf":{"@id":"https:\/\/comunicacity.net\/acerra\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/acerra\/2019\/01\/05\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/acerra\/2019\/01\/05\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/02\/viabilita-modificata.jpeg","datePublished":"2019-01-05T15:29:31+00:00","author":{"@id":"https:\/\/comunicacity.net\/acerra\/#\/schema\/person\/ffc746891ee9789194f211d721d68534"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/acerra\/2019\/01\/05\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/acerra\/2019\/01\/05\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/acerra\/2019\/01\/05\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\/#primaryimage","url":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/02\/viabilita-modificata.jpeg","contentUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/02\/viabilita-modificata.jpeg","width":664,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/acerra\/2019\/01\/05\/divieto-di-circolazione-e-di-sosta-sulle-strade-interessate-dal-trofeo-della-befana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/acerra\/"},{"@type":"ListItem","position":2,"name":"Divieto di circolazione e di sosta sulle strade interessate dal Trofeo della Befana"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/acerra\/#website","url":"https:\/\/comunicacity.net\/acerra\/","name":"Acerra","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/acerra\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/acerra\/#\/schema\/person\/ffc746891ee9789194f211d721d68534","name":"marioamelia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g","caption":"marioamelia"},"url":"https:\/\/comunicacity.net\/acerra\/author\/marioamelia\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts\/1205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/users\/140"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/comments?post=1205"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts\/1205\/revisions"}],"predecessor-version":[{"id":1207,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts\/1205\/revisions\/1207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/media\/391"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/media?parent=1205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/categories?post=1205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/tags?post=1205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}