{"id":1284,"date":"2019-04-23T18:44:57","date_gmt":"2019-04-23T16:44:57","guid":{"rendered":"https:\/\/comunicacity.net\/acerra\/?p=1284"},"modified":"2019-04-23T18:44:57","modified_gmt":"2019-04-23T16:44:57","slug":"festa-nazionale-della-liberazione-25-aprile-2019","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/acerra\/2019\/04\/23\/festa-nazionale-della-liberazione-25-aprile-2019\/","title":{"rendered":"Festa Nazionale della Liberazione &#8211; 25 aprile 2019"},"content":{"rendered":"<p>In occasione della celebrazione della <strong>Festa nazionale della Liberazione<\/strong>, in programma per gioved\u00ec <strong>25 aprile 2019<\/strong>, si terr\u00e0 il tradizionale corteo commemorativo, con partenza <strong>dalle ore 10,00 da Piazza Castello<\/strong> ed il seguente itinerario: <em>Via Trieste e Trento, Via Mons. Casoria, Piazza Duomo, Via Mons. Verolino, Corso Garibaldi, Via C. Petrella, Via F. Castaldi, Piazzale Russo Spena, Via F. Castaldi, Via C. Petrella, Corso Garibaldi, Via C. Petrella, Via Mons. Casoria, Via del Pennino, Corso Resistenza, Via A. Moro, Piazza Soriano, Via L. Da Vinci, P.le Renella, Piazza Castello<\/em>.<\/p>\n<p>La cittadinanza \u00e8 invitata a partecipare.<\/p>\n<p>Consulta il manifesto<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1285\" src=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2019\/04\/manifesto25aprile-210x300.jpg\" alt=\"\" width=\"210\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2019\/04\/manifesto25aprile-210x300.jpg 210w, https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2019\/04\/manifesto25aprile-768x1097.jpg 768w, https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2019\/04\/manifesto25aprile-717x1024.jpg 717w, https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2019\/04\/manifesto25aprile-680x972.jpg 680w, https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2019\/04\/manifesto25aprile.jpg 1240w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/p>\n<p>&nbsp;<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_1286\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2019\/04\/manifesto25aprile.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2019\/04\/manifesto25aprile.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>manifesto25aprile<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In occasione della celebrazione della Festa nazionale della Liberazione, in programma per gioved\u00ec 25 aprile 2019, si terr\u00e0 il tradizionale corteo commemorativo, con partenza dalle ore 10,00 da Piazza Castello [&hellip;]<\/p>\n","protected":false},"author":140,"featured_media":1285,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festa Nazionale della Liberazione - 25 aprile 2019 - Acerra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/acerra\/2019\/04\/23\/festa-nazionale-della-liberazione-25-aprile-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festa Nazionale della Liberazione - 25 aprile 2019 - Acerra\" \/>\n<meta property=\"og:description\" content=\"In occasione della celebrazione della Festa nazionale della Liberazione, in programma per gioved\u00ec 25 aprile 2019, si terr\u00e0 il tradizionale corteo commemorativo, con partenza dalle ore 10,00 da Piazza Castello [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/acerra\/2019\/04\/23\/festa-nazionale-della-liberazione-25-aprile-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Acerra\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-23T16:44:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2019\/04\/manifesto25aprile.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"1772\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marioamelia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"marioamelia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/04\\\/23\\\/festa-nazionale-della-liberazione-25-aprile-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/04\\\/23\\\/festa-nazionale-della-liberazione-25-aprile-2019\\\/\"},\"author\":{\"name\":\"marioamelia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#\\\/schema\\\/person\\\/ffc746891ee9789194f211d721d68534\"},\"headline\":\"Festa Nazionale della Liberazione &#8211; 25 aprile 2019\",\"datePublished\":\"2019-04-23T16:44:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/04\\\/23\\\/festa-nazionale-della-liberazione-25-aprile-2019\\\/\"},\"wordCount\":102,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/04\\\/23\\\/festa-nazionale-della-liberazione-25-aprile-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2019\\\/04\\\/manifesto25aprile.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/04\\\/23\\\/festa-nazionale-della-liberazione-25-aprile-2019\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/04\\\/23\\\/festa-nazionale-della-liberazione-25-aprile-2019\\\/\",\"name\":\"Festa Nazionale della Liberazione - 25 aprile 2019 - Acerra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/04\\\/23\\\/festa-nazionale-della-liberazione-25-aprile-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/04\\\/23\\\/festa-nazionale-della-liberazione-25-aprile-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2019\\\/04\\\/manifesto25aprile.jpg\",\"datePublished\":\"2019-04-23T16:44:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#\\\/schema\\\/person\\\/ffc746891ee9789194f211d721d68534\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/04\\\/23\\\/festa-nazionale-della-liberazione-25-aprile-2019\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/04\\\/23\\\/festa-nazionale-della-liberazione-25-aprile-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/04\\\/23\\\/festa-nazionale-della-liberazione-25-aprile-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2019\\\/04\\\/manifesto25aprile.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2019\\\/04\\\/manifesto25aprile.jpg\",\"width\":1240,\"height\":1772},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2019\\\/04\\\/23\\\/festa-nazionale-della-liberazione-25-aprile-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festa Nazionale della Liberazione &#8211; 25 aprile 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/\",\"name\":\"Acerra\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#\\\/schema\\\/person\\\/ffc746891ee9789194f211d721d68534\",\"name\":\"marioamelia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g\",\"caption\":\"marioamelia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/author\\\/marioamelia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festa Nazionale della Liberazione - 25 aprile 2019 - Acerra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/acerra\/2019\/04\/23\/festa-nazionale-della-liberazione-25-aprile-2019\/","og_locale":"it_IT","og_type":"article","og_title":"Festa Nazionale della Liberazione - 25 aprile 2019 - Acerra","og_description":"In occasione della celebrazione della Festa nazionale della Liberazione, in programma per gioved\u00ec 25 aprile 2019, si terr\u00e0 il tradizionale corteo commemorativo, con partenza dalle ore 10,00 da Piazza Castello [&hellip;]","og_url":"https:\/\/comunicacity.net\/acerra\/2019\/04\/23\/festa-nazionale-della-liberazione-25-aprile-2019\/","og_site_name":"Acerra","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-04-23T16:44:57+00:00","og_image":[{"width":1240,"height":1772,"url":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2019\/04\/manifesto25aprile.jpg","type":"image\/jpeg"}],"author":"marioamelia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"marioamelia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/acerra\/2019\/04\/23\/festa-nazionale-della-liberazione-25-aprile-2019\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/acerra\/2019\/04\/23\/festa-nazionale-della-liberazione-25-aprile-2019\/"},"author":{"name":"marioamelia","@id":"https:\/\/comunicacity.net\/acerra\/#\/schema\/person\/ffc746891ee9789194f211d721d68534"},"headline":"Festa Nazionale della Liberazione &#8211; 25 aprile 2019","datePublished":"2019-04-23T16:44:57+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/acerra\/2019\/04\/23\/festa-nazionale-della-liberazione-25-aprile-2019\/"},"wordCount":102,"image":{"@id":"https:\/\/comunicacity.net\/acerra\/2019\/04\/23\/festa-nazionale-della-liberazione-25-aprile-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2019\/04\/manifesto25aprile.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/acerra\/2019\/04\/23\/festa-nazionale-della-liberazione-25-aprile-2019\/","url":"https:\/\/comunicacity.net\/acerra\/2019\/04\/23\/festa-nazionale-della-liberazione-25-aprile-2019\/","name":"Festa Nazionale della Liberazione - 25 aprile 2019 - Acerra","isPartOf":{"@id":"https:\/\/comunicacity.net\/acerra\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/acerra\/2019\/04\/23\/festa-nazionale-della-liberazione-25-aprile-2019\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/acerra\/2019\/04\/23\/festa-nazionale-della-liberazione-25-aprile-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2019\/04\/manifesto25aprile.jpg","datePublished":"2019-04-23T16:44:57+00:00","author":{"@id":"https:\/\/comunicacity.net\/acerra\/#\/schema\/person\/ffc746891ee9789194f211d721d68534"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/acerra\/2019\/04\/23\/festa-nazionale-della-liberazione-25-aprile-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/acerra\/2019\/04\/23\/festa-nazionale-della-liberazione-25-aprile-2019\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/acerra\/2019\/04\/23\/festa-nazionale-della-liberazione-25-aprile-2019\/#primaryimage","url":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2019\/04\/manifesto25aprile.jpg","contentUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2019\/04\/manifesto25aprile.jpg","width":1240,"height":1772},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/acerra\/2019\/04\/23\/festa-nazionale-della-liberazione-25-aprile-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/acerra\/"},{"@type":"ListItem","position":2,"name":"Festa Nazionale della Liberazione &#8211; 25 aprile 2019"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/acerra\/#website","url":"https:\/\/comunicacity.net\/acerra\/","name":"Acerra","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/acerra\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/acerra\/#\/schema\/person\/ffc746891ee9789194f211d721d68534","name":"marioamelia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g","caption":"marioamelia"},"url":"https:\/\/comunicacity.net\/acerra\/author\/marioamelia\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts\/1284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/users\/140"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/comments?post=1284"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts\/1284\/revisions"}],"predecessor-version":[{"id":1287,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts\/1284\/revisions\/1287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/media\/1285"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/media?parent=1284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/categories?post=1284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/tags?post=1284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}