{"id":2126,"date":"2022-06-03T09:54:44","date_gmt":"2022-06-03T07:54:44","guid":{"rendered":"https:\/\/comunicacity.net\/acerra\/?p=2126"},"modified":"2022-06-03T09:54:44","modified_gmt":"2022-06-03T07:54:44","slug":"anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/acerra\/2022\/06\/03\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\/","title":{"rendered":"Anteprima dell&#8217;allestimento del Museo di Archeologia e Storia di Acerra e Suessula"},"content":{"rendered":"<p>Anteprima dell&#8217;allestimento del Museo di Archeologia e Storia di Acerra e Suessula, inaugurazione prima sala.<\/p>\n<p>Venerd\u00ec 3 giugno, ore 17,30, Castello dei Conti Acerra<\/p>\n<p><a href=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2022\/06\/invito_cittadinanza-1.pdf\">invito_cittadinanza<\/a> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2129\" src=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2022\/06\/invito_cittadinanza-717x1024.jpg\" alt=\"\" width=\"640\" height=\"914\" srcset=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2022\/06\/invito_cittadinanza-717x1024.jpg 717w, https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2022\/06\/invito_cittadinanza-210x300.jpg 210w, https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2022\/06\/invito_cittadinanza-768x1097.jpg 768w, https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2022\/06\/invito_cittadinanza-1075x1536.jpg 1075w, https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2022\/06\/invito_cittadinanza-1434x2048.jpg 1434w, https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2022\/06\/invito_cittadinanza-scaled.jpg 1792w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>&nbsp;<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_2128\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2022\/06\/invito_cittadinanza-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2022\/06\/invito_cittadinanza-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>invito_cittadinanza<\/a><\/li>\n<li><a id=\"wpba_attachment_list_2127\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2022\/06\/invito_cittadinanza.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2022\/06\/invito_cittadinanza.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>invito_cittadinanza<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Anteprima dell&#8217;allestimento del Museo di Archeologia e Storia di Acerra e Suessula, inaugurazione prima sala. Venerd\u00ec 3 giugno, ore 17,30, Castello dei Conti Acerra invito_cittadinanza &nbsp; \ud83d\udcce Allegatiinvito_cittadinanza invito_cittadinanza<\/p>\n","protected":false},"author":140,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2126","post","type-post","status-publish","format-standard","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anteprima dell&#039;allestimento del Museo di Archeologia e Storia di Acerra e Suessula - Acerra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/acerra\/2022\/06\/03\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anteprima dell&#039;allestimento del Museo di Archeologia e Storia di Acerra e Suessula - Acerra\" \/>\n<meta property=\"og:description\" content=\"Anteprima dell&#8217;allestimento del Museo di Archeologia e Storia di Acerra e Suessula, inaugurazione prima sala. Venerd\u00ec 3 giugno, ore 17,30, Castello dei Conti Acerra invito_cittadinanza &nbsp; \ud83d\udcce Allegatiinvito_cittadinanza invito_cittadinanza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/acerra\/2022\/06\/03\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\/\" \/>\n<meta property=\"og:site_name\" content=\"Acerra\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-03T07:54:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2022\/06\/invito_cittadinanza-717x1024.jpg\" \/>\n<meta name=\"author\" content=\"marioamelia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"marioamelia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2022\\\/06\\\/03\\\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2022\\\/06\\\/03\\\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\\\/\"},\"author\":{\"name\":\"marioamelia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#\\\/schema\\\/person\\\/ffc746891ee9789194f211d721d68534\"},\"headline\":\"Anteprima dell&#8217;allestimento del Museo di Archeologia e Storia di Acerra e Suessula\",\"datePublished\":\"2022-06-03T07:54:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2022\\\/06\\\/03\\\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\\\/\"},\"wordCount\":37,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2022\\\/06\\\/03\\\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2022\\\/06\\\/invito_cittadinanza-717x1024.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2022\\\/06\\\/03\\\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2022\\\/06\\\/03\\\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\\\/\",\"name\":\"Anteprima dell'allestimento del Museo di Archeologia e Storia di Acerra e Suessula - Acerra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2022\\\/06\\\/03\\\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2022\\\/06\\\/03\\\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2022\\\/06\\\/invito_cittadinanza-717x1024.jpg\",\"datePublished\":\"2022-06-03T07:54:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#\\\/schema\\\/person\\\/ffc746891ee9789194f211d721d68534\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2022\\\/06\\\/03\\\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2022\\\/06\\\/03\\\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2022\\\/06\\\/03\\\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2022\\\/06\\\/invito_cittadinanza-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2022\\\/06\\\/invito_cittadinanza-scaled.jpg\",\"width\":1792,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2022\\\/06\\\/03\\\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anteprima dell&#8217;allestimento del Museo di Archeologia e Storia di Acerra e Suessula\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/\",\"name\":\"Acerra\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#\\\/schema\\\/person\\\/ffc746891ee9789194f211d721d68534\",\"name\":\"marioamelia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g\",\"caption\":\"marioamelia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/author\\\/marioamelia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anteprima dell'allestimento del Museo di Archeologia e Storia di Acerra e Suessula - Acerra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/acerra\/2022\/06\/03\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\/","og_locale":"it_IT","og_type":"article","og_title":"Anteprima dell'allestimento del Museo di Archeologia e Storia di Acerra e Suessula - Acerra","og_description":"Anteprima dell&#8217;allestimento del Museo di Archeologia e Storia di Acerra e Suessula, inaugurazione prima sala. Venerd\u00ec 3 giugno, ore 17,30, Castello dei Conti Acerra invito_cittadinanza &nbsp; \ud83d\udcce Allegatiinvito_cittadinanza invito_cittadinanza","og_url":"https:\/\/comunicacity.net\/acerra\/2022\/06\/03\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\/","og_site_name":"Acerra","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-06-03T07:54:44+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2022\/06\/invito_cittadinanza-717x1024.jpg","type":"","width":"","height":""}],"author":"marioamelia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"marioamelia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/acerra\/2022\/06\/03\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/acerra\/2022\/06\/03\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\/"},"author":{"name":"marioamelia","@id":"https:\/\/comunicacity.net\/acerra\/#\/schema\/person\/ffc746891ee9789194f211d721d68534"},"headline":"Anteprima dell&#8217;allestimento del Museo di Archeologia e Storia di Acerra e Suessula","datePublished":"2022-06-03T07:54:44+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/acerra\/2022\/06\/03\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\/"},"wordCount":37,"image":{"@id":"https:\/\/comunicacity.net\/acerra\/2022\/06\/03\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2022\/06\/invito_cittadinanza-717x1024.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/acerra\/2022\/06\/03\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\/","url":"https:\/\/comunicacity.net\/acerra\/2022\/06\/03\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\/","name":"Anteprima dell'allestimento del Museo di Archeologia e Storia di Acerra e Suessula - Acerra","isPartOf":{"@id":"https:\/\/comunicacity.net\/acerra\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/acerra\/2022\/06\/03\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/acerra\/2022\/06\/03\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2022\/06\/invito_cittadinanza-717x1024.jpg","datePublished":"2022-06-03T07:54:44+00:00","author":{"@id":"https:\/\/comunicacity.net\/acerra\/#\/schema\/person\/ffc746891ee9789194f211d721d68534"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/acerra\/2022\/06\/03\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/acerra\/2022\/06\/03\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/acerra\/2022\/06\/03\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\/#primaryimage","url":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2022\/06\/invito_cittadinanza-scaled.jpg","contentUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2022\/06\/invito_cittadinanza-scaled.jpg","width":1792,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/acerra\/2022\/06\/03\/anteprima-dellallestimento-del-museo-di-archeologia-e-storia-di-acerra-e-suessula\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/acerra\/"},{"@type":"ListItem","position":2,"name":"Anteprima dell&#8217;allestimento del Museo di Archeologia e Storia di Acerra e Suessula"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/acerra\/#website","url":"https:\/\/comunicacity.net\/acerra\/","name":"Acerra","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/acerra\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/acerra\/#\/schema\/person\/ffc746891ee9789194f211d721d68534","name":"marioamelia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g","caption":"marioamelia"},"url":"https:\/\/comunicacity.net\/acerra\/author\/marioamelia\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts\/2126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/users\/140"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/comments?post=2126"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts\/2126\/revisions"}],"predecessor-version":[{"id":2130,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts\/2126\/revisions\/2130"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/media?parent=2126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/categories?post=2126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/tags?post=2126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}