{"id":514,"date":"2017-05-07T14:18:11","date_gmt":"2017-05-07T12:18:11","guid":{"rendered":"https:\/\/comunicacity.net\/acerra\/?p=514"},"modified":"2017-05-07T14:21:08","modified_gmt":"2017-05-07T12:21:08","slug":"la-prevenzione-migliora-la-vita","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/acerra\/2017\/05\/07\/la-prevenzione-migliora-la-vita\/","title":{"rendered":"La prevenzione migliora la vita"},"content":{"rendered":"<p>Domani, luned\u00ec 8 maggio 2017, dalle ore 10 alle ore 13, presso il Parco Urbano di Citt\u00e0 Sicura, via Gerge Sand, ad Acerra, si terr\u00e0 una campagna di prevenzione del tumore al seno in favore delle donne che risiedono ad Acerra, con esame diagnostico ecografico gratuito. L&#8217;accettazione per le visite sar\u00e0 effettuata dalle ore 9,30 alle ore 11, fino all&#8217;esaurimento delle visite massime disponibili. Per maggiori informazioni consultare il manifesto o rivolgersi all&#8217;associazione Safila.<\/p>\n<p>La campagna sar\u00e0 ripetuta anche luned\u00ec 22 maggio 2017.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-516\" src=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/05\/EVENTO-COMUNE-safila-prevencione-2017-2-210x300.jpg\" alt=\"\" width=\"210\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/05\/EVENTO-COMUNE-safila-prevencione-2017-2-210x300.jpg 210w, https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/05\/EVENTO-COMUNE-safila-prevencione-2017-2.jpg 560w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/p>\n<p>&nbsp;<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_515\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/05\/EVENTO-COMUNE-safila-prevencione-2017-2.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/05\/EVENTO-COMUNE-safila-prevencione-2017-2.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>EVENTO COMUNE safila prevencione 2017 (2)<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Domani, luned\u00ec 8 maggio 2017, dalle ore 10 alle ore 13, presso il Parco Urbano di Citt\u00e0 Sicura, via Gerge Sand, ad Acerra, si terr\u00e0 una campagna di prevenzione del [&hellip;]<\/p>\n","protected":false},"author":140,"featured_media":517,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La prevenzione migliora la vita - Acerra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/acerra\/2017\/05\/07\/la-prevenzione-migliora-la-vita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La prevenzione migliora la vita - Acerra\" \/>\n<meta property=\"og:description\" content=\"Domani, luned\u00ec 8 maggio 2017, dalle ore 10 alle ore 13, presso il Parco Urbano di Citt\u00e0 Sicura, via Gerge Sand, ad Acerra, si terr\u00e0 una campagna di prevenzione del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/acerra\/2017\/05\/07\/la-prevenzione-migliora-la-vita\/\" \/>\n<meta property=\"og:site_name\" content=\"Acerra\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-07T12:18:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-07T12:21:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/05\/Tumore-al-seno-riparte-la-campagna-criptata-su-Facebook-352x372.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"352\" \/>\n\t<meta property=\"og:image:height\" content=\"372\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marioamelia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"marioamelia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2017\\\/05\\\/07\\\/la-prevenzione-migliora-la-vita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2017\\\/05\\\/07\\\/la-prevenzione-migliora-la-vita\\\/\"},\"author\":{\"name\":\"marioamelia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#\\\/schema\\\/person\\\/ffc746891ee9789194f211d721d68534\"},\"headline\":\"La prevenzione migliora la vita\",\"datePublished\":\"2017-05-07T12:18:11+00:00\",\"dateModified\":\"2017-05-07T12:21:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2017\\\/05\\\/07\\\/la-prevenzione-migliora-la-vita\\\/\"},\"wordCount\":81,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2017\\\/05\\\/07\\\/la-prevenzione-migliora-la-vita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2017\\\/05\\\/Tumore-al-seno-riparte-la-campagna-criptata-su-Facebook-352x372.jpg\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2017\\\/05\\\/07\\\/la-prevenzione-migliora-la-vita\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2017\\\/05\\\/07\\\/la-prevenzione-migliora-la-vita\\\/\",\"name\":\"La prevenzione migliora la vita - Acerra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2017\\\/05\\\/07\\\/la-prevenzione-migliora-la-vita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2017\\\/05\\\/07\\\/la-prevenzione-migliora-la-vita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2017\\\/05\\\/Tumore-al-seno-riparte-la-campagna-criptata-su-Facebook-352x372.jpg\",\"datePublished\":\"2017-05-07T12:18:11+00:00\",\"dateModified\":\"2017-05-07T12:21:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#\\\/schema\\\/person\\\/ffc746891ee9789194f211d721d68534\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2017\\\/05\\\/07\\\/la-prevenzione-migliora-la-vita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2017\\\/05\\\/07\\\/la-prevenzione-migliora-la-vita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2017\\\/05\\\/07\\\/la-prevenzione-migliora-la-vita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2017\\\/05\\\/Tumore-al-seno-riparte-la-campagna-criptata-su-Facebook-352x372.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2017\\\/05\\\/Tumore-al-seno-riparte-la-campagna-criptata-su-Facebook-352x372.jpg\",\"width\":352,\"height\":372},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2017\\\/05\\\/07\\\/la-prevenzione-migliora-la-vita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La prevenzione migliora la vita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/\",\"name\":\"Acerra\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#\\\/schema\\\/person\\\/ffc746891ee9789194f211d721d68534\",\"name\":\"marioamelia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g\",\"caption\":\"marioamelia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/author\\\/marioamelia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La prevenzione migliora la vita - Acerra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/acerra\/2017\/05\/07\/la-prevenzione-migliora-la-vita\/","og_locale":"it_IT","og_type":"article","og_title":"La prevenzione migliora la vita - Acerra","og_description":"Domani, luned\u00ec 8 maggio 2017, dalle ore 10 alle ore 13, presso il Parco Urbano di Citt\u00e0 Sicura, via Gerge Sand, ad Acerra, si terr\u00e0 una campagna di prevenzione del [&hellip;]","og_url":"https:\/\/comunicacity.net\/acerra\/2017\/05\/07\/la-prevenzione-migliora-la-vita\/","og_site_name":"Acerra","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-05-07T12:18:11+00:00","article_modified_time":"2017-05-07T12:21:08+00:00","og_image":[{"width":352,"height":372,"url":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/05\/Tumore-al-seno-riparte-la-campagna-criptata-su-Facebook-352x372.jpg","type":"image\/jpeg"}],"author":"marioamelia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"marioamelia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/acerra\/2017\/05\/07\/la-prevenzione-migliora-la-vita\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/acerra\/2017\/05\/07\/la-prevenzione-migliora-la-vita\/"},"author":{"name":"marioamelia","@id":"https:\/\/comunicacity.net\/acerra\/#\/schema\/person\/ffc746891ee9789194f211d721d68534"},"headline":"La prevenzione migliora la vita","datePublished":"2017-05-07T12:18:11+00:00","dateModified":"2017-05-07T12:21:08+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/acerra\/2017\/05\/07\/la-prevenzione-migliora-la-vita\/"},"wordCount":81,"image":{"@id":"https:\/\/comunicacity.net\/acerra\/2017\/05\/07\/la-prevenzione-migliora-la-vita\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/05\/Tumore-al-seno-riparte-la-campagna-criptata-su-Facebook-352x372.jpg","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/acerra\/2017\/05\/07\/la-prevenzione-migliora-la-vita\/","url":"https:\/\/comunicacity.net\/acerra\/2017\/05\/07\/la-prevenzione-migliora-la-vita\/","name":"La prevenzione migliora la vita - Acerra","isPartOf":{"@id":"https:\/\/comunicacity.net\/acerra\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/acerra\/2017\/05\/07\/la-prevenzione-migliora-la-vita\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/acerra\/2017\/05\/07\/la-prevenzione-migliora-la-vita\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/05\/Tumore-al-seno-riparte-la-campagna-criptata-su-Facebook-352x372.jpg","datePublished":"2017-05-07T12:18:11+00:00","dateModified":"2017-05-07T12:21:08+00:00","author":{"@id":"https:\/\/comunicacity.net\/acerra\/#\/schema\/person\/ffc746891ee9789194f211d721d68534"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/acerra\/2017\/05\/07\/la-prevenzione-migliora-la-vita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/acerra\/2017\/05\/07\/la-prevenzione-migliora-la-vita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/acerra\/2017\/05\/07\/la-prevenzione-migliora-la-vita\/#primaryimage","url":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/05\/Tumore-al-seno-riparte-la-campagna-criptata-su-Facebook-352x372.jpg","contentUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/05\/Tumore-al-seno-riparte-la-campagna-criptata-su-Facebook-352x372.jpg","width":352,"height":372},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/acerra\/2017\/05\/07\/la-prevenzione-migliora-la-vita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/acerra\/"},{"@type":"ListItem","position":2,"name":"La prevenzione migliora la vita"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/acerra\/#website","url":"https:\/\/comunicacity.net\/acerra\/","name":"Acerra","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/acerra\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/acerra\/#\/schema\/person\/ffc746891ee9789194f211d721d68534","name":"marioamelia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g","caption":"marioamelia"},"url":"https:\/\/comunicacity.net\/acerra\/author\/marioamelia\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts\/514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/users\/140"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/comments?post=514"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts\/514\/revisions"}],"predecessor-version":[{"id":519,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts\/514\/revisions\/519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/media\/517"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/media?parent=514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/categories?post=514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/tags?post=514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}