{"id":685,"date":"2018-01-13T17:09:50","date_gmt":"2018-01-13T16:09:50","guid":{"rendered":"https:\/\/comunicacity.net\/acerra\/?p=685"},"modified":"2018-01-13T17:09:50","modified_gmt":"2018-01-13T16:09:50","slug":"divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/acerra\/2018\/01\/13\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\/","title":{"rendered":"Divieto di vendita per asporto di bevande contenute in bottiglie, lattine  e\/o bicchieri di vetro per il 14 gennaio 2018 in Via Leonardo da Vinci e Piazza Castello"},"content":{"rendered":"<p>Si informa che con\u00a0Ordinanza Sindacale n.1 del 13\/01\/2018,\u00a0per motivi di tutela dell&#8217;ordine, della sicurezza pubblica e di decoro della citt\u00e0,<strong>\u00a0<\/strong><strong>nella giornata del 14 gennaio 2018, dalle ore 11,00 alle ore 13,00 in Via Leonardo da Vinci e Piazza Castello e dalle ore 18,30 alle 22,00 in Piazza Castello<\/strong>, \u00e8 fatto divieto<strong> di vendita per asporto di bevande contenute in bottiglie, lattine di alluminio e bicchieri ai vetro o comunque in contenitori realizzati con il medesimo materiale<\/strong>, anche dove dispensate da distributori automatici, da parte degli esercenti delle seguenti attivit\u00e0:\u00a01) attivit\u00e0 di somministrazione di alimenti e bevande, autorizzate anche in forma temporanea e\/o ambulante;\u00a02) circoli privati;\u00a03) attivit\u00e0 artigianali autorizzati alla vendita di bevande;\u00a04) attivit\u00e0 di commercio di prodotti alimentari;\u00a0 5) operatori del commercio su area pubblica;\u00a06) ed in genere da tutte le forme speciali di commercio che consentono la vendita di bevande in vetro.<\/p>\n<p>E\u2019 consentita la somministrazione e\/o il consumo delle bevande in bicchieri di vetro solo all\u2019interno del locale con esclusione delle aree di pertinenza esterne.\u00a0Resta ferma, per le attivit\u00e0 autorizzate, la facolt\u00e0 di vendere per asporto le bevande in contenitori di plastica o carta dove le bevande devono essere versate direttamente da chi effettua la somministrazione o la vendita.<\/p>\n<p><strong>Consulta l&#8217;Ordinanza completa<\/strong><\/p>\n<p>&nbsp;<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_686\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2018\/01\/ordinanza1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2018\/01\/ordinanza1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ordinanza pag.1<\/a><\/li>\n<li><a id=\"wpba_attachment_list_687\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2018\/01\/ordinanza-2.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2018\/01\/ordinanza-2.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ordinanza pag.2<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si informa che con\u00a0Ordinanza Sindacale n.1 del 13\/01\/2018,\u00a0per motivi di tutela dell&#8217;ordine, della sicurezza pubblica e di decoro della citt\u00e0,\u00a0nella giornata del 14 gennaio 2018, dalle ore 11,00 alle ore [&hellip;]<\/p>\n","protected":false},"author":140,"featured_media":668,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pubblica-sicurezza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Divieto di vendita per asporto di bevande contenute in bottiglie, lattine e\/o bicchieri di vetro per il 14 gennaio 2018 in Via Leonardo da Vinci e Piazza Castello - Acerra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/acerra\/2018\/01\/13\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Divieto di vendita per asporto di bevande contenute in bottiglie, lattine e\/o bicchieri di vetro per il 14 gennaio 2018 in Via Leonardo da Vinci e Piazza Castello - Acerra\" \/>\n<meta property=\"og:description\" content=\"Si informa che con\u00a0Ordinanza Sindacale n.1 del 13\/01\/2018,\u00a0per motivi di tutela dell&#8217;ordine, della sicurezza pubblica e di decoro della citt\u00e0,\u00a0nella giornata del 14 gennaio 2018, dalle ore 11,00 alle ore [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/acerra\/2018\/01\/13\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\/\" \/>\n<meta property=\"og:site_name\" content=\"Acerra\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-13T16:09:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/12\/Image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"503\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marioamelia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"marioamelia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2018\\\/01\\\/13\\\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2018\\\/01\\\/13\\\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\\\/\"},\"author\":{\"name\":\"marioamelia\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#\\\/schema\\\/person\\\/ffc746891ee9789194f211d721d68534\"},\"headline\":\"Divieto di vendita per asporto di bevande contenute in bottiglie, lattine e\\\/o bicchieri di vetro per il 14 gennaio 2018 in Via Leonardo da Vinci e Piazza Castello\",\"datePublished\":\"2018-01-13T16:09:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2018\\\/01\\\/13\\\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\\\/\"},\"wordCount\":230,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2018\\\/01\\\/13\\\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2017\\\/12\\\/Image.jpg\",\"articleSection\":[\"Pubblica Sicurezza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2018\\\/01\\\/13\\\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2018\\\/01\\\/13\\\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\\\/\",\"name\":\"Divieto di vendita per asporto di bevande contenute in bottiglie, lattine e\\\/o bicchieri di vetro per il 14 gennaio 2018 in Via Leonardo da Vinci e Piazza Castello - Acerra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2018\\\/01\\\/13\\\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2018\\\/01\\\/13\\\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2017\\\/12\\\/Image.jpg\",\"datePublished\":\"2018-01-13T16:09:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#\\\/schema\\\/person\\\/ffc746891ee9789194f211d721d68534\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2018\\\/01\\\/13\\\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2018\\\/01\\\/13\\\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2018\\\/01\\\/13\\\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2017\\\/12\\\/Image.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2017\\\/12\\\/Image.jpg\",\"width\":700,\"height\":503},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/2018\\\/01\\\/13\\\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Divieto di vendita per asporto di bevande contenute in bottiglie, lattine e\\\/o bicchieri di vetro per il 14 gennaio 2018 in Via Leonardo da Vinci e Piazza Castello\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/\",\"name\":\"Acerra\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#\\\/schema\\\/person\\\/ffc746891ee9789194f211d721d68534\",\"name\":\"marioamelia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g\",\"caption\":\"marioamelia\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/author\\\/marioamelia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Divieto di vendita per asporto di bevande contenute in bottiglie, lattine e\/o bicchieri di vetro per il 14 gennaio 2018 in Via Leonardo da Vinci e Piazza Castello - Acerra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/acerra\/2018\/01\/13\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\/","og_locale":"it_IT","og_type":"article","og_title":"Divieto di vendita per asporto di bevande contenute in bottiglie, lattine e\/o bicchieri di vetro per il 14 gennaio 2018 in Via Leonardo da Vinci e Piazza Castello - Acerra","og_description":"Si informa che con\u00a0Ordinanza Sindacale n.1 del 13\/01\/2018,\u00a0per motivi di tutela dell&#8217;ordine, della sicurezza pubblica e di decoro della citt\u00e0,\u00a0nella giornata del 14 gennaio 2018, dalle ore 11,00 alle ore [&hellip;]","og_url":"https:\/\/comunicacity.net\/acerra\/2018\/01\/13\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\/","og_site_name":"Acerra","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-01-13T16:09:50+00:00","og_image":[{"width":700,"height":503,"url":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/12\/Image.jpg","type":"image\/jpeg"}],"author":"marioamelia","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"marioamelia","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/acerra\/2018\/01\/13\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/acerra\/2018\/01\/13\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\/"},"author":{"name":"marioamelia","@id":"https:\/\/comunicacity.net\/acerra\/#\/schema\/person\/ffc746891ee9789194f211d721d68534"},"headline":"Divieto di vendita per asporto di bevande contenute in bottiglie, lattine e\/o bicchieri di vetro per il 14 gennaio 2018 in Via Leonardo da Vinci e Piazza Castello","datePublished":"2018-01-13T16:09:50+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/acerra\/2018\/01\/13\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\/"},"wordCount":230,"image":{"@id":"https:\/\/comunicacity.net\/acerra\/2018\/01\/13\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/12\/Image.jpg","articleSection":["Pubblica Sicurezza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/acerra\/2018\/01\/13\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\/","url":"https:\/\/comunicacity.net\/acerra\/2018\/01\/13\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\/","name":"Divieto di vendita per asporto di bevande contenute in bottiglie, lattine e\/o bicchieri di vetro per il 14 gennaio 2018 in Via Leonardo da Vinci e Piazza Castello - Acerra","isPartOf":{"@id":"https:\/\/comunicacity.net\/acerra\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/acerra\/2018\/01\/13\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/acerra\/2018\/01\/13\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/12\/Image.jpg","datePublished":"2018-01-13T16:09:50+00:00","author":{"@id":"https:\/\/comunicacity.net\/acerra\/#\/schema\/person\/ffc746891ee9789194f211d721d68534"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/acerra\/2018\/01\/13\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/acerra\/2018\/01\/13\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/acerra\/2018\/01\/13\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\/#primaryimage","url":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/12\/Image.jpg","contentUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2017\/12\/Image.jpg","width":700,"height":503},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/acerra\/2018\/01\/13\/divieto-di-vendita-per-asporto-di-bevande-contenute-in-bottiglie-lattine-eo-bicchieri-di-vetro-per-il-14-gennaio-2018-in-via-leonardo-da-vinci-e-piazza-castello\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/acerra\/"},{"@type":"ListItem","position":2,"name":"Divieto di vendita per asporto di bevande contenute in bottiglie, lattine e\/o bicchieri di vetro per il 14 gennaio 2018 in Via Leonardo da Vinci e Piazza Castello"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/acerra\/#website","url":"https:\/\/comunicacity.net\/acerra\/","name":"Acerra","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/acerra\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/acerra\/#\/schema\/person\/ffc746891ee9789194f211d721d68534","name":"marioamelia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/35bee2fe63fa029fca0da3ea6464848a00c6141e558e45ef4874af2c601832a3?s=96&d=mm&r=g","caption":"marioamelia"},"url":"https:\/\/comunicacity.net\/acerra\/author\/marioamelia\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts\/685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/users\/140"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/comments?post=685"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts\/685\/revisions"}],"predecessor-version":[{"id":688,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/posts\/685\/revisions\/688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/media\/668"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/media?parent=685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/categories?post=685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/tags?post=685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}