{"id":59,"date":"2016-10-11T15:55:10","date_gmt":"2016-10-11T13:55:10","guid":{"rendered":"https:\/\/comunicacity.net\/acerra\/?post_type=turismo&#038;p=59"},"modified":"2016-11-09T01:06:31","modified_gmt":"2016-11-09T00:06:31","slug":"cattedrale","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/cattedrale\/","title":{"rendered":"Cattedrale"},"content":{"rendered":"<p class=\"c490\" style=\"text-align: justify;\">Storia<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">La chiesa cattedrale di Acerra, certamente doveva gi\u00e0 essere costruita nel 1058, in quanto il Papa Niccol\u00f2 II, fermatosi in citt\u00e0, vi ordin\u00f2 cardinale Oderisio dei Conti dei Marsi.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Il Caporale motiva la sua collocazione lungo il cardo con la sovrapposizione del tempio cristiano ad un precedente tempio pagano dedicato ad Ercole, di cui egli trov\u00f2 un&#8217;iscrizione nel 1855, sulla soglia del Seminario: &#8220;Templum Hoc Sacratum Herculi&#8221;.<\/p>\n<p class=\"c492\" style=\"text-align: justify;\">Certamente nel corso dei secoli l&#8217;edificio sub\u00ec notevoli modifiche e da una sua prima descrizione, nel 1583, risulta dedicato all&#8217;Assunta e dotata di dodici cappelle.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Il Pacicchelli nel 1703 racconta che la chiesa, a tre navate, \u00e8 dedicata a S. Michele e la definisce &#8220;oscura e alla antica&#8221; per le sue forme gotiche.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Sui quattordici pilastri che dividevano le navate erano collocati venti dipinti, opera di Luca Giordano (Napoli 1632; ivi 1705), pittore molto attivo a Napoli alla fine del &#8216;600.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Da una successiva descrizione del 1762 si deduce che la chiesa, consacrata all&#8217;Assunta, presentava un numero ridotto di cappelle.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">La Cattedrale era dotata anche di cinque sepolture comuni. Di queste, una apparteneva alla Congregazione della SS. Rosario e le altre quattro al Vescovo: tre erano destinate al popolo (dietro pagamento) ed una ai canonici ed ai Sacerdoti della Cattedrale.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Nel 1789 croll\u00f2 una parte del soffitto e, necessitando interventi urgenti, dopo accese diatribe, si pens\u00f2 di ricostruire la Cattedrale in forme pi\u00f9 grandiose. Si abbatt\u00e9 allora la chiesa gotica e senza alcun progetto compiuto si diede inizio all&#8217;Opera.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">I lavori procedevano lentamente, cos\u00ec dopo trent&#8217;anni, nel 1819, mancando i fondi, venne richiesto l&#8217;intervento del Sovrano che ordin\u00f2 al Comune di contribuire all&#8217;edificazione.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Dopo solo sette anni dal completamento della chiesa prima l&#8217;atrio e poi la cupola minacciarono il crollo, cos\u00ec che quattro archi ed i relativi piedritti dovettero essere smantellati.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">I lavori vennero sospesi e la Cattedrale fu ridotta a due sole cappelle: nella restante parte si era creato un acquitrino.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Bisogn\u00f2 attendere il 15 novembre del 1858 perch\u00e9 venisse finalmente approvato il progetto di un architetto, per la ricostruzione della Cattedrale nelle forme che ancora oggi conserva.<\/p>\n<p class=\"c490\" style=\"text-align: justify;\">Descrizione<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">La Cattedrale \u00e8 arretrata rispetto alla strada, con un sagrato in basalto al centro del quale \u00e8 situata una fontana. La facciata del Tempio presenta forme classicheggianti, con un ordine gigante e timpano, opera di Michele Manlio da Bitonto (Bari). Le otto grandi colonne con capitelli ionici in stucco, poste su un podio cui si accede con gradini, delimitano l&#8217;atrio maestoso, antistante la chiesa, pavimentato con quadrati in basalto (scuro) e pietra calcarea (bianca) a creare una scacchiera.<\/p>\n<p class=\"c492\" style=\"text-align: justify;\"><img decoding=\"async\" src=\"http:\/\/www.comune.acerra.na.it\/data\/img\/orig\/duomo2.jpg\" alt=\"Cattedrale di Acerra\" border=\"0\" \/><\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Il soffitto \u00e8 decorato a lacunari. La chiesa presenta una pianta a croce latina (o a croce immissa) con tre navate, divise da pilastri con cupola.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Nella prima cappella della navata sinistra si conserva una tela rappresentante S. Rocco.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">La seconda cappella custodisce una tela del XVII sec. di G. B. Azzolino (1560 &#8211; dopo 1610), presente nel duomo gi\u00e0 nel 1678, che testimonia l&#8217;efficacia del Rosario.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Fu dipinta per celebrare la costituzione (nel Duomo) di una cappella dedicata alla Vergine del Rosario, ad opera di una Confraternita creata dai Governatori del Monte dei Pegni (Cfr. Monte dei Pegni).<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Sulla tela \u00e8 rappresentato Ges\u00f9 Cristo seduto, dal cui costato fuoriesce un rosario che cola in una coppa di una bilancia, tenuta dall&#8217;Arcangelo Michele. Nell&#8217;altra coppa vi sono le colpe del penitente rappresentato da un uomo seminudo, in ginocchio.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Appoggiata sull&#8217;altare si trova una lapide marmorea, ormai a pezzi, datata 1583. Essa testimonia il privilegio perpetuo concesso in quell&#8217;anno da Papa Gregorio XIII ai sacerdoti che avessero celebrato messe in suffragio delle anime del Purgatorio. Questa lapide era conservata, nella cappella di S. Maria della Bruna.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Su uno dei pilastri della III campata si trova un monumento funebre a Taddeo Gazzillo, cardinale morto nel 1848. Il quadro presente nella III cappella raffigura la Veronica. Nel transetto, coperto con una volta a botte, c&#8217;\u00e8 una tela con la Deposizione, appartenuta al Conte di Acerra, risalente ai primi del &#8216;700, copia di un quadro di pi\u00f9 piccole dimensioni conservato nel Museo Filangieri a Napoli.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Prima di accedere alla Sagrestia si pu\u00f2 contemplare sulla sinistra una pregevole acquasantiera raffigurante l&#8217;Assunzione, risalente al XVI sec. Ai piedi della Vergine Assunta vi sono due gruppi oranti in ginocchio. Alla testa del gruppo di uomini il Caporale individua, nei due personaggi togati, i due Governatori del Monte dei Pegni, mentre le due figure recanti delle coppe nella mano destra testimonierebbero le offerte che la confraternita faceva per il successo della Pia Opera.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Anche questa acquasantiera proviene quindi dalla ex cappella del Rosario sede dell&#8217;omonima Confraternita. La Sagrestia presenta una volta a padiglione e prende luce da una grande apertura sulla parete di fondo, mentre il soffitto e le pareti sono decorate con stucchi che creano un motivo di lesene e riquadri.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Sulla porta c&#8217;\u00e8 una grande tela centinata dell&#8217;Assunta, mentre la parete opposta ospita un&#8217;iscrizione funeraria su marmo risalente alla fine del XV sec.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Passati nel presbiterio troviamo sull&#8217;altare maggiore una tela dell&#8217;Assunta del 1798, opera di Giacinto Diana (1730-1803), pittore attivo a Napoli sul finire del&#8217;700.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Il Grande coro in noce \u00e8 del XIX sec. e fu fatto costruire da Monsignor Magliola. La cattedra Vescovile (da cui il termine &#8220;cattedrale&#8221; per definire la chiesa principale della diocesi che la ospita), ricostruita nel 1800, conserva ancora lo schienale cinquecentesco, realizzato in marmi policromi.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Dal transetto destro si accede alla cappella dedicata al SS. Sacramento.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Alla destra dell&#8217;entrata \u00e8 collocato un fine altorilievo, a decorare la porticina dell&#8217;Olio Santo.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Rappresenta la Vergine con il Bambino ai cui piedi ci sono S. Pietro a destra e S. Paolo a sinistra. In basso vi sono due gruppi di Angeli. La porticina reca la scritta &#8220;Manna Absconditum&#8221;. L&#8217;opera pregevolissima \u00e8 ritenuta della scuola di Giovanni da Nola (Nola 1488 &#8211; Napoli 1558), artista formatosi sulle opere napoletane di A. Rossellino e di Benedetto di Maiano.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Nel transetto \u00e8 conservata una tela che rappresenta il martirio di S. Conone, opera di E. Fiore (1877), ed una reliquia del Santo.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Si tratta di un osso della tibia, collocato in un&#8217;urna di cristallo ed ottone, al di sotto di un baldacchino di forma gotica. La reliquia poggia su due aste d&#8217;argento alle quali \u00e8 legata con due nastri fermati da quattro sigilli del Cardinale di Carpineo, che la don\u00f2 a Monsignor Carlo De Angelis il 13 maggio 1688.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Il 29 maggio dello stesso anno la reliquia fu collocata nell&#8217;urna dove ancor oggi si conserva.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Nella navata destra incontriamo la cappella della Madonna delle Grazie, raffigurata in un quadro con ai piedi S. Girolamo a sinistra, ed il Beato Pietro da Pisa a destra, opera di F. Santafede (1560 &#8211; 1634). Ai lati della cappella sono conservate, dentro nicchie, delle statue in gesso con vestiti di stoffa: l&#8217;Addolorata e S. Rita.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">La cappella successiva contiene una tela con S. Girolamo, atterrito dalla tromba del Giudizio Universale.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">La tela, di buona mano, \u00e8 sicuramente una copia del Ribera che ha affrontato spesso questo soggetto. Nell&#8217;ultima cappella vi \u00e8 un quadro con S. Nicola, patrono degli Ebdomadari che ivi celebravano una messa solenne il 6 dicembre, festa del Santo.<\/p>\n<h5 class=\"western c494\" style=\"text-align: justify;\"><strong>La tela del Rosario della cattedrale di Acerra. L&#8217;iconografia, il tardomanierismo, Azzolino.<\/strong><\/h5>\n<h5 class=\"western c495\" style=\"text-align: justify;\"><strong><em>di Pasquale Addeo<\/em><\/strong><\/h5>\n<p class=\"c491\" style=\"text-align: justify;\">La cattedrale di Acerra \u00e8 certamente il luogo simbolo della religiosit\u00e0 cittadina, punto di riferimento per la devozione di tutti i credenti acerrani. Eppure \u00e8 ancora poco conosciuta e apprezzata dal punto di vista artistico, di grande interesse e ricchezza. Tra le tante opere custodite nella chiesa, \u00e8 possibile ammirare un quadro davvero singolare e capace di suscitare ammirazione e dubbi, anche per l&#8217;iconografia incerta e difficilmente classificabile.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">La tela in questione \u00e8 posta sopra l&#8217;altare della seconda cappella a sinistra, e rappresenta il Cristo al centro, maestosamente seduto con i piedi appoggiati sulle teste di due cherubini (foto 1). Alla sua destra c&#8217;\u00e8 la Madonna che, con un&#8217;intensa espressione del volto, sembra parlargli mentre indica dinanzi a loro l&#8217;anima di un uomo seminudo e con le mani giunte sul petto. Fin qui il soggetto sembra ricalcare lo schema classico dell&#8217;intercessione di Maria presso il Figlio con lo scopo della salvezza di una o pi\u00f9 anime, considerando anche la presenza di San Michele Arcangelo con la bilancia in mano per pesare i peccati.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Eppure c&#8217;\u00e8 un particolare che fa di questo quadro un soggetto iconografico molto raro, ovvero il gesto della Madonna che sfila dal costato del Cristo una corona del Rosario.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Gi\u00e0 Gaetano Caporale, nella met\u00e0 dell&#8217;800, aveva notato questo curioso particolare, tanto che, nel suo libro sulla Diocesi di Acerra, aveva sintomaticamente denominato la tela: &#8220;Efficacia del Rosario&#8221;, legando dunque proprio al Rosario la felice soluzione per la vicenda di quell&#8217;anima in cerca di salvezza.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Non dimentichiamo, inoltre, che nella cattedrale operava, con una cappella di propriet\u00e0, la potente (e attivissima nel &#8216;600) &#8220;Confraternita del Rosario&#8221;, istituzione religiosa che provvedeva alle cure materiali (salute, istruzione, sepoltura) e spirituali dei propri confratelli: \u00e8 molto probabile che proprio la cappella nella quale \u00e8 visibile il quadro appartenesse alla Confraternita.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">\u00c8 dunque interessante notare come il tema del Rosario, accresciuto in importanza grazie all&#8217;opera dei Domenicani dopo la vittoria dei cristiani (che si erano affidati proprio alla Madonna del Rosario) contro i Turchi nella battaglia di Lepanto del 1571, gi\u00e0 nel &#8216;600 si fosse slegato dallo schema iconografico classico della Madonna in trono con Bambino che porge la corona del Rosario a San Domenico e Santa Caterina da Siena.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Il dipinto \u00e8 stilisticamente inseribile in un particolare momento artistico napoletano: il tardomanierismo, corrente nata dal manierismo tosco-romano di met\u00e0 &#8216;500, e molto vitale nella capitale del viceregno anche dopo la rivoluzione naturalistica di Caravaggio di inizio &#8216;600. La tela, infatti, \u00e8 dominata da toni morbidi caratterizzati dalla totale assenza di violenze luministiche, con i personaggi, disposti secondo uno schema simmetrico e armonico, idealizzati nella ricerca di un effetto religioso e devozionale molto spinto. Uno tra i maggiori pittori tardomanieristi attivi a Napoli nella prima met\u00e0 del XVII secolo \u00e8 il siciliano Giovanni Bernardino Azzolino, al quale \u00e8 possibile attribuire il quadro aberrano, non solo per motivi legati allo stile. Infatti, un paio di decenni fa, lo storico dell&#8217;arte Pierluigi Leone de Castris ritrov\u00f2 un documento che testimonia il pagamento, nel 1640, di un dipinto raffigurante il tema del Rosario commesso dal conte di Acerra proprio ad Azzolino: il documento non descrive il quadro, ma \u00e8 altamente ipotizzabile che si tratti della tela custodita in cattedrale, probabilmente donata dal conte alla Confraternita del Rosario qualche tempo dopo.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Inoltre, per verificare l&#8217;attribuzione del dipinto al pittore siciliano, ci viene in aiuto proprio la singolare iconografia di cui ho parlato sopra.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">Nell&#8217;Arciconfraternita dei Santi Giorgio e Caterina dei Genovesi a Cagliari, infatti, \u00e8 presente un quadro dal titolo: &#8220;Cristo e Maria offrono il rosario a Santi Domenicani&#8221; (foto 2), dipinto da Azzolino tra il 1620 e il 1630. Il soggetto rappresentato \u00e8 molto simile all&#8217;iconografia del quadro di Acerra: alcuni Santi Domenicani, tra i quali San Domenico e Santa Caterina, circondano Cristo e la Madonna mentre sfilano il rosario dalle ferite di Ges\u00f9. I due quadri (oltre che iconograficamente anche stilisticamente vicini) testimoniano l&#8217;attivit\u00e0 e l&#8217;originalit\u00e0 di un pittore protagonista di un&#8217;epoca artistica difficile, attraversata dalle agitazioni controriformistiche e permeata dall&#8217;ossessiva idea della colpa: si racconta, infatti, che Azzolino, tormentato dal pensiero del peccato, dipingesse in ginocchio in ossequio alle immagini sacre.<\/p>\n<p class=\"c491\" style=\"text-align: justify;\">L&#8217;attribuzione della tela del Rosario a questo grande artista tardomanierista, dunque, aggiunge un altro tassello di interesse alla storia artistica e culturale di Acerra, una storia affascinante che vale sempre la pena di raccontare. In ogni occasione!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Storia La chiesa cattedrale di Acerra, certamente doveva gi\u00e0 essere costruita nel 1058, in quanto il Papa Niccol\u00f2 II, fermatosi in citt\u00e0, vi ordin\u00f2 cardinale Oderisio dei Conti dei Marsi. [&hellip;]<\/p>\n","protected":false},"featured_media":60,"parent":58,"menu_order":1,"template":"","meta":[],"class_list":["post-59","turismo","type-turismo","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cattedrale - Acerra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/cattedrale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cattedrale - Acerra\" \/>\n<meta property=\"og:description\" content=\"Storia La chiesa cattedrale di Acerra, certamente doveva gi\u00e0 essere costruita nel 1058, in quanto il Papa Niccol\u00f2 II, fermatosi in citt\u00e0, vi ordin\u00f2 cardinale Oderisio dei Conti dei Marsi. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/cattedrale\/\" \/>\n<meta property=\"og:site_name\" content=\"Acerra\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2016-11-09T00:06:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2016\/10\/duomo1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/turismo\\\/chiese\\\/cattedrale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/turismo\\\/chiese\\\/cattedrale\\\/\",\"name\":\"Cattedrale - Acerra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/turismo\\\/chiese\\\/cattedrale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/turismo\\\/chiese\\\/cattedrale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2016\\\/10\\\/duomo1.jpg\",\"datePublished\":\"2016-10-11T13:55:10+00:00\",\"dateModified\":\"2016-11-09T00:06:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/turismo\\\/chiese\\\/cattedrale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/turismo\\\/chiese\\\/cattedrale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/turismo\\\/chiese\\\/cattedrale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2016\\\/10\\\/duomo1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2016\\\/10\\\/duomo1.jpg\",\"width\":500,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/turismo\\\/chiese\\\/cattedrale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chiese\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/turismo\\\/chiese\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cattedrale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/\",\"name\":\"Acerra\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cattedrale - Acerra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/cattedrale\/","og_locale":"it_IT","og_type":"article","og_title":"Cattedrale - Acerra","og_description":"Storia La chiesa cattedrale di Acerra, certamente doveva gi\u00e0 essere costruita nel 1058, in quanto il Papa Niccol\u00f2 II, fermatosi in citt\u00e0, vi ordin\u00f2 cardinale Oderisio dei Conti dei Marsi. [&hellip;]","og_url":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/cattedrale\/","og_site_name":"Acerra","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2016-11-09T00:06:31+00:00","og_image":[{"width":500,"height":375,"url":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2016\/10\/duomo1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/cattedrale\/","url":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/cattedrale\/","name":"Cattedrale - Acerra","isPartOf":{"@id":"https:\/\/comunicacity.net\/acerra\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/cattedrale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/cattedrale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2016\/10\/duomo1.jpg","datePublished":"2016-10-11T13:55:10+00:00","dateModified":"2016-11-09T00:06:31+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/cattedrale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/cattedrale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/cattedrale\/#primaryimage","url":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2016\/10\/duomo1.jpg","contentUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2016\/10\/duomo1.jpg","width":500,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/cattedrale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/acerra\/"},{"@type":"ListItem","position":2,"name":"Chiese","item":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/"},{"@type":"ListItem","position":3,"name":"Cattedrale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/acerra\/#website","url":"https:\/\/comunicacity.net\/acerra\/","name":"Acerra","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/acerra\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/turismo\/59","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/types\/turismo"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/turismo\/58"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/media\/60"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/media?parent=59"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}