{"id":61,"date":"2016-10-11T15:56:57","date_gmt":"2016-10-11T13:56:57","guid":{"rendered":"https:\/\/comunicacity.net\/acerra\/?post_type=turismo&#038;p=61"},"modified":"2016-10-11T15:56:57","modified_gmt":"2016-10-11T13:56:57","slug":"chiesa-dellannunziata","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/chiesa-dellannunziata\/","title":{"rendered":"Chiesa dell&#8217;Annunziata"},"content":{"rendered":"<p class=\"c311\" style=\"text-align: justify;\"><strong>Storia<\/strong><\/p>\n<p class=\"c312\" style=\"text-align: justify;\">La storia della Chiesa dell&#8217;Annunziata \u00e8 strettamente legata a quella della Congregazione della Pace, un&#8217; istituzione filantropica che ha operato ad Acerra dal XV al XIX secolo.<\/p>\n<p class=\"c312\" style=\"text-align: justify;\">La Chiesa probabilmente \u00e8 stata fondata dalla stessa Confraternita anche se non esistono notizie precise circa la sua costruzione.<\/p>\n<p class=\"c312\" style=\"text-align: justify;\">La prima data certa che attesta l&#8217;esistenza della Chiesa \u00e8 riportata da un documento in cui si legge &#8221; &#8230; <i>la detta Cappella di S. Maria della Pace fu dalla disciplina eretta dentro la Chiesa di S. M. Annunciata nella Citt\u00e0 di Acerra nell&#8217;anno 1486<\/i> &#8230;&#8221;.<\/p>\n<p class=\"c312\" style=\"text-align: justify;\">Le prime attivit\u00e0 note della Confraternita risalgono al XVI secolo periodo in cui ebbe rinomanza il cosiddetto &#8220;Ospizio dell&#8217;Annunziata&#8221;. Esso presentava tutte le caratteristiche degli istituti di assistenza, istruzione e carit\u00e0. Alimentava un ospedale, combinava matrimoni alle fanciulle disagiate, distribuiva sussidi in moneta, pagava un maestro pubblico, manteneva il culto nella Chiesa, accoglieva gli Esposti.<\/p>\n<p class=\"c312\" style=\"text-align: justify;\">I bambini introdotti nella Chiesa mediante una ruota girevole (del tipo di quella usata nei conventi di clausura) venivano prelevati per poi essere trasportati a Napoli. La &#8220;ruota degli Esposti&#8221; di Acerra \u00e8 andata in disuso nel secolo scorso tanto che oggi di essa non vi \u00e8 rimasta nessuna traccia; tuttavia esiste ancora il vano che dalla Chiesa porta su via Ferrajolo, in cui una volta era installata la ruota.<\/p>\n<p class=\"c312\" style=\"text-align: justify;\">Nel 1638 Chiesa e Ospizio furono concessi ai PP. Domenicani della Congregazione della Sanit\u00e0 di Napoli; ai Confretelli della Pace fu comunque concesso il privilegio di riunirsi presso la Cappella di M. SS. della Pace. Fu proprio sull&#8217;altare di questa Cappella che nel 1785 Mons. Giordano depose le reliquie dei santi Celestino, Severino e Generoso.<\/p>\n<p class=\"c312\" style=\"text-align: justify;\">Con le soppressioni nel 1806, i Domenicani lasciarono la Chiesa e il convento, che intanto avevano istituito nei vecchi locali dell&#8217;ospedale.<\/p>\n<p class=\"c312\" style=\"text-align: justify;\">La Chiesa dell&#8217;Annunziata fu trasformata in parrocchia solo nel 1933.<\/p>\n<p class=\"c313\" style=\"text-align: justify;\">\n<p class=\"c312\" style=\"text-align: justify;\">Numerosi sono i restauri e i rifacimenti che ha subito l&#8217;edificio della Chiesa. Nel febbraio del 1805 il &#8220;Fabbricatore M. Sorrentino&#8221; ricevette compenso per &#8220;l&#8217;accomodo dell&#8217;intera prospettiva della nostra Chiesa&#8221;.<\/p>\n<p class=\"c312\" style=\"text-align: justify;\">Altri restauri si ebbero nel 1884 e nel 1891. Nel 1915 D. Battaglia esegu\u00ec le decorazioni degli interni.<\/p>\n<p class=\"c314\" style=\"text-align: justify;\"><strong>Descrizione<\/strong><\/p>\n<p class=\"c312\" style=\"text-align: justify;\">La facciata, di gusto classico, si sviluppa su due ordini ed \u00e8 conclusa da un timpano fregiato da stemma. Il ritmo \u00e8 scandito da due coppie di lesene che si alternano a fasce e cornici. La larghezza delle lesene \u00e8 assunta come modulo per proporzionare ogni elemento che disegna il prospetto; ne deriva una composizione formale di particolare eleganza e armonia.<\/p>\n<p class=\"c312\" style=\"text-align: justify;\">Il portale d&#8217;ingresso, di piperno, \u00e8 sormontato da una lunetta, in cui \u00e8 raffigurata l&#8217;Annunciazione. La Chiesa di forma rettangolare, a croce latina, presenta una sola navata con soffitto a volta. In fondo al presbiterio \u00e8 posto l&#8217;altare maggiore, alle spalle del quale \u00e8 una struttura che richiama le forme dei templi classici in cui \u00e8 collocato la copia di un pregevole dipinto d&#8217;et\u00e0 Angioina raffigurante l&#8217;Annunciazione (l&#8217;originale \u00e8 conservato presso la Galleria Nazionale di Capodimonte a Napoli).<\/p>\n<p class=\"c312\" style=\"text-align: justify;\">Si rileva inoltre la presenza di quattro Cappelle lungo il fianco destro della navata e di altrettante sul fianco sinistro, quasi tutte fornite di un altarino.<\/p>\n<p class=\"c312\" style=\"text-align: justify;\">Nel braccio sinistro del transetto trovasi la Cappella dedicata a Maria SS. della Pace, in quello destro la Cappella \u00e8 dedicata alla Vergine del Rosario.<\/p>\n<p class=\"c312\" style=\"text-align: justify;\">La cupola di stile barocco ha pianta circolare. Nell&#8217;intradosso presenta un soffitto piano, decorato da otto dipinti disposti a raggiera, pi\u00f9 uno centrale di forma circolare.<\/p>\n<p class=\"c312\" style=\"text-align: justify;\">Vanno infine ricordati i due locali della Sagrestia le cui volte sono affrescate. Nel primo si pu\u00f2 ammirare una Madonna con Bambino e nell&#8217;altro una Annunciazione e i profeti Isaia, Daniele, Geremia, Ezechiele opere di Acierno (1893).<\/p>\n<p class=\"c315\" style=\"text-align: justify;\">\n<p class=\"c312\" style=\"text-align: justify;\"><b>Il Crocifisso ligneo<\/b> <b>della chiesa dell&#8217;Annunziata di Acerra ed il contesto &#8220;mediterraneo&#8221;<\/b><\/p>\n<p class=\"western c316\" style=\"text-align: justify;\">L&#8217;arte romanica campana \u00e8 un&#8217;arte felicemente sincretica: ombelico del mediterraneo, la Campania convoglia con furiosa forza centripeta verso le sue terre tutte le esperienze culturali che le girano vorticosamente attorno, innestandole su un tronco classico che non \u00e8 supino compiacimento nei riguardi di attardati moduli stilistici, ma anima profonda del fare artistico, ovvero il pensiero che sottende l&#8217;azione.<\/p>\n<p class=\"western c318\" style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"c317 aligncenter\" src=\"http:\/\/www.comune.acerra.na.it\/data\/img\/orig\/55_Crocifisso%20ligneo%20Annunziata.JPG\" alt=\"Crocifisso ligneo della Chiesa dell' Annunziata\" width=\"473\" height=\"471\" border=\"0\" \/><\/p>\n<p class=\"western c319\" style=\"text-align: justify;\">\n<p class=\"western c316\" style=\"text-align: justify;\">Partire da questa definizione dell&#8217;arte romanica campana vuol dire assumere la consapevolezza che la nostra terra \u00e8 luogo di contaminazioni, di esperienze culturali, letterarie e figurative diverse e lontane che, intrecciatesi tra di loro, hanno dato vita alla nostra Civilt\u00e0, con la &#8220;c&#8221; maiuscola, perch\u00e9 \u00e8 davvero difficile trovare un&#8217;altra regione dove, a concorrere alla determinazione di una cultura unitaria e specifica, sono intervenuti apporti tanto distinti e fecondi. Dai Bizantini ai Longobardi ed agli Arabi, l&#8217;arte campana \u00e8 sempre stata un fruttuoso crogiolo di sperimentazioni alle quali questa terra ha continuamente sotteso la peculiarit\u00e0 del proprio fare artistico: il classico, approccio principale delle genti del sud alla cultura. Tra l&#8217;XI ed il XII secolo questa &#8220;polifonia culturale&#8221; si arricchisce di un nuovo e fondamentale contributo: la trasfusione nel gi\u00e0 variegato tessuto artistico delle coeve conquiste figurative transalpine. Dalla Provenza e, soprattutto, dall&#8217;Aquitania, scendevano verso sud (lungo le vie di pellegrinaggio) le esperienze pi\u00f9 &#8220;visionarie ed allucinate&#8221; di tutta l&#8217;arte romanica europea.<\/p>\n<p class=\"western c316\" style=\"text-align: justify;\">Mentre la Provenza, richiamata varie volte per spiegare alcuni moduli formali della plastica campana tra il XII ed il XIII secolo (dal lettorile coi diaconi del pulpito Ajello a Salerno ai capitelli nella cripta della cattedrale di Capua), condivide con la Campania un sostrato classico che \u00e8 individuabile come uno dei comuni denominatori dell&#8217;arte delle due regioni, pi\u00f9 complessa e stimolante sembra essere l&#8217;influenza Tolosano-Aquitanica, che dalla via francigena scende nel meridione italiano innestandosi sulla via Appia e provocando una vera e propria rivoluzione negli stilemi figurativi della Campania ed anche della Puglia.<\/p>\n<p class=\"western c316\" style=\"text-align: justify;\">Il protagonista di questa rivoluzione \u00e8 il fonditore beneventano Oderisio, artista imbevuto dello stile dell&#8217;Occidente romanico &#8220;pi\u00f9 appassionato e stravolto&#8221;, che tra gli anni venti e cinquanta del XII secolo realizza le porte bronzee della cattedrale di Troia, della chiesa capuana di S. Giovanni Battista delle Monache e della cattedrale di S. Bartolomeo a Benevento. Il linguaggio di Oderisio dovette alimentarsi della pi\u00f9 visionaria arte romanica, quali i rilievi del portico di San Pietro a Moissac o certi brani particolarmente accesi del Giudizio Finale scolpito nel timpano del portale di Santa Fede a Conques.<\/p>\n<p class=\"western c316\" style=\"text-align: justify;\">Emblematico ed esemplificativo per valutare la portata della rivoluzione &#8220;romanza&#8221; in Campania, \u00e8 il recupero di una scultura poco nota e studiata: il Crocifisso ligneo della chiesa dell&#8217;Annunziata ad Acerra.<\/p>\n<p class=\"western c316\" style=\"text-align: justify;\">\u00a0Attualmente collocata sopra l&#8217;altare della cappella del transetto sinistro, l&#8217;opera \u00e8 una maestosa rappresentazione del &#8220;Christus Triumphans&#8221;, la tipologia romanica del crocifisso che simboleggia la vittoria del Cristo sulla morte, in perfetta consonanza con il pensiero trascendente e spirituale della cultura medievale nei secoli XI e XII ed in antitesi con il &#8220;Christus Patiens&#8221; dell&#8217;arte gotica: il Cristo che patisce e poi muore, legato alla pi\u00f9 pragmatica concezione dei commercianti e dei banchieri, potenti committenti di opere d&#8217;arte tra il 1200 ed il 1300.<\/p>\n<p class=\"western c316\" style=\"text-align: justify;\">Infatti il Crocifisso di Acerra, scolpito in legno, \u00e8 rappresentato dritto sulla croce, con le braccia tese ed allungate e gli occhi aperti, cos\u00ec come i coevi crocifissi di Sant&#8217;Antimo ed Abbadia San Salvatore in Toscana. La forza della scultura acerrana \u00e8 data dalla particolare cura della muscolatura e delle parti anatomiche: i nervi delle gambe e delle braccia si tendono a sottolineare lo sforzo che deve compiere il Cristo per rimanere dritto e composto, il torace e l&#8217;addome sono sagomati con uno spiccato gusto della realt\u00e0, il perizoma \u00e8 svolto in panneggi sciolti e delicati ed i capelli scendono morbidi sulle spalle. In pi\u00f9 la figura \u00e8 attraversata da una potenza e da una maestosit\u00e0 che vengono direttamente dalla Francia meridionale e che sono praticamente sconosciute in Campania in quegli anni, mentre la si pu\u00f2 accostare alle &#8220;cocenti&#8221; sculture sulle facciate delle chiese romaniche di Terra di Bari.<\/p>\n<p class=\"western c316\" style=\"text-align: justify;\">Posto in relazione al Crocifisso di Mirabella Eclano in Irpinia (a sua volta esemplato su un colossale Crocifisso in legno e rame del primo decennio del XII secolo nella basilica di San Saturnino a Tolosa), dal quale riprende il plasticismo ed il pittoricismo soprattutto nel modellato e nel perizoma, il Crocifisso di Acerra \u00e8, a differenza di quest&#8217;ultimo, sicuramente opera di un&#8217;artista campano che, partendo dalla sua formazione classica, sottolineata dalla serenit\u00e0 e dalla monumentalit\u00e0 quasi ritrattistica del volto, per nulla nervoso rispetto al Crocifisso di Mirabella, arriva ad interpretare in maniera originale ed efficace le spinte innovatrici della cultura figurativa Tolosano-Aquitanica e francese in genere, contribuendo in maniera decisiva allo svolgimento della decorazione artistica nei secoli XII e XIII in Campania.<\/p>\n<p class=\"western c319\" style=\"text-align: justify;\"><span class=\"c320\"><strong>L&#8217; Annunciazione<\/strong>\u00a0<\/span><span class=\"c321\"><i>(Scuola Toscana, prima met\u00e0 del XV secolo)<\/i><\/span><\/p>\n<p class=\"c322\" style=\"text-align: justify;\"><span class=\"c323\">La tavola d&#8217;altare, sicuramente elemento (probabilmente la parte centrale) di un pi\u00f9 ampio impianto pittorico, rappresenta l&#8217;Annunciazione dell&#8217;Arcangelo Gabriele alla Vergine Maria. Il dipinto \u00e8 inquadrabile nel pi\u00f9 ampio movimento del <i>gotico internazionale,<\/i> affermatosi nella prima met\u00e0 del &#8216;400, che prende le mosse dall&#8217;ambiente pittorico degli artisti senesi della fine del 1300. Ne \u00e8 prova l&#8217;utilizzo di una decorazione fortemente lussuosa, con oggetti e vesti in cui primeggia l&#8217;oro, nonch\u00e9 un cromatismo molto accentuato e la scelta di colori, che ricordano da vicino i dipinti dei vari Pietro e Ambrogio Lorenzetti, Simone Martini e soprattutto il maestro riconosciuto del <i>gotico internazionale<\/i>: Lorenzo Monaco. D&#8217;altro canto \u00e8 innegabile un&#8217;impostazione dei personaggi statica e per molti versi troppo arcaica, che contrasta con lo spiccato cromatismo che caratterizza l&#8217;opera.<\/span> <span class=\"c323\">I dubbi circa l&#8217;attribuzione del dipinto sono ancora molti e potrebbero originare un dibattito storiografico molto acceso. Sul nome dell&#8217;autore esiste, al momento, una sola ipotesi avanzata dalla studiosa Fausta Navarro, che indica il pittore fiorentino Dello Delli (1403 &#8211; 1471) di cui \u00e8 attestata la presenza a Napoli negli anni &#8217;40 del &#8216;400 alla corte di Alfonso d&#8217;Aragona. La proposta \u00e8 tutta da verificare per vari motivi: in primo luogo \u00e8 difficile stabilire una relazione tra il pittore, legato agli ambienti castigliano-aragonesi, e una citt\u00e0 come Acerra, in quegli anni ancora fedele alla dinastia angioina. Inoltre se si considera la grande fama che l&#8217;artista raggiunse come architetto gi\u00e0 tra i suoi contemporanei, tanto che il Filarete lo inser\u00ec tra i progettisti della sua citt\u00e0 ideale<i>Sforzinda<\/i>, non si spiega l&#8217;imprecisione prospettica con cui sono rappresentate le strutture architettoniche che fanno da sfondo alla sacra scena. (<\/span><span class=\"c323\">Biagio Perreca &#8211; Pasquale Addeo)<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Storia La storia della Chiesa dell&#8217;Annunziata \u00e8 strettamente legata a quella della Congregazione della Pace, un&#8217; istituzione filantropica che ha operato ad Acerra dal XV al XIX secolo. La Chiesa [&hellip;]<\/p>\n","protected":false},"featured_media":62,"parent":58,"menu_order":2,"template":"","meta":[],"class_list":["post-61","turismo","type-turismo","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chiesa dell&#039;Annunziata - Acerra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/chiesa-dellannunziata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiesa dell&#039;Annunziata - Acerra\" \/>\n<meta property=\"og:description\" content=\"Storia La storia della Chiesa dell&#8217;Annunziata \u00e8 strettamente legata a quella della Congregazione della Pace, un&#8217; istituzione filantropica che ha operato ad Acerra dal XV al XIX secolo. La Chiesa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/chiesa-dellannunziata\/\" \/>\n<meta property=\"og:site_name\" content=\"Acerra\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2016\/10\/Chiesa-Annunziata.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"387\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/turismo\\\/chiese\\\/chiesa-dellannunziata\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/turismo\\\/chiese\\\/chiesa-dellannunziata\\\/\",\"name\":\"Chiesa dell'Annunziata - Acerra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/turismo\\\/chiese\\\/chiesa-dellannunziata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/turismo\\\/chiese\\\/chiesa-dellannunziata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2016\\\/10\\\/Chiesa-Annunziata.jpg\",\"datePublished\":\"2016-10-11T13:56:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/turismo\\\/chiese\\\/chiesa-dellannunziata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/turismo\\\/chiese\\\/chiesa-dellannunziata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/turismo\\\/chiese\\\/chiesa-dellannunziata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2016\\\/10\\\/Chiesa-Annunziata.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/wp-content\\\/uploads\\\/sites\\\/63\\\/2016\\\/10\\\/Chiesa-Annunziata.jpg\",\"width\":387,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/turismo\\\/chiese\\\/chiesa-dellannunziata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chiese\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/turismo\\\/chiese\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chiesa dell&#8217;Annunziata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/\",\"name\":\"Acerra\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/acerra\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiesa dell'Annunziata - Acerra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/chiesa-dellannunziata\/","og_locale":"it_IT","og_type":"article","og_title":"Chiesa dell'Annunziata - Acerra","og_description":"Storia La storia della Chiesa dell&#8217;Annunziata \u00e8 strettamente legata a quella della Congregazione della Pace, un&#8217; istituzione filantropica che ha operato ad Acerra dal XV al XIX secolo. La Chiesa [&hellip;]","og_url":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/chiesa-dellannunziata\/","og_site_name":"Acerra","article_publisher":"http:\/\/facebook.com\/ComunicaCity","og_image":[{"width":387,"height":500,"url":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2016\/10\/Chiesa-Annunziata.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/chiesa-dellannunziata\/","url":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/chiesa-dellannunziata\/","name":"Chiesa dell'Annunziata - Acerra","isPartOf":{"@id":"https:\/\/comunicacity.net\/acerra\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/chiesa-dellannunziata\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/chiesa-dellannunziata\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2016\/10\/Chiesa-Annunziata.jpg","datePublished":"2016-10-11T13:56:57+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/chiesa-dellannunziata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/chiesa-dellannunziata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/chiesa-dellannunziata\/#primaryimage","url":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2016\/10\/Chiesa-Annunziata.jpg","contentUrl":"https:\/\/comunicacity.net\/acerra\/wp-content\/uploads\/sites\/63\/2016\/10\/Chiesa-Annunziata.jpg","width":387,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/chiesa-dellannunziata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/acerra\/"},{"@type":"ListItem","position":2,"name":"Chiese","item":"https:\/\/comunicacity.net\/acerra\/turismo\/chiese\/"},{"@type":"ListItem","position":3,"name":"Chiesa dell&#8217;Annunziata"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/acerra\/#website","url":"https:\/\/comunicacity.net\/acerra\/","name":"Acerra","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/acerra\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/turismo\/61","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/types\/turismo"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/turismo\/58"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/media\/62"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/acerra\/wp-json\/wp\/v2\/media?parent=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}