{"id":167,"date":"2016-11-06T01:00:27","date_gmt":"2016-11-06T00:00:27","guid":{"rendered":"https:\/\/comunicacity.net\/amatrice\/?p=167"},"modified":"2016-11-06T01:01:20","modified_gmt":"2016-11-06T00:01:20","slug":"comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/amatrice\/2016\/11\/06\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\/","title":{"rendered":"Comunicato audio del Sindaco Pirozzi del 5 novembre 2016"},"content":{"rendered":"<p>RADIO AMATRICE: di seguito potete ascoltare il comunicato del 5\u00a0novembre 2016 rilasciato dal Sindaco Pirozzi.<\/p>\n<p><strong>Prima parte<\/strong><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-167-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/11\/pirozzi-05112016-1parte.mp3?_=1\" \/><a href=\"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/11\/pirozzi-05112016-1parte.mp3\">https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/11\/pirozzi-05112016-1parte.mp3<\/a><\/audio>\n<p>&nbsp;<\/p>\n<p><strong>Seconda parte<\/strong><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-167-2\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/11\/pirozzi-05112016-2parte.mp3?_=2\" \/><a href=\"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/11\/pirozzi-05112016-2parte.mp3\">https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/11\/pirozzi-05112016-2parte.mp3<\/a><\/audio>\n<p>&nbsp;<\/p>\n<p><strong>Terza parte<\/strong><\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-167-3\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/11\/pirozzi-05112016-3parte.mp3?_=3\" \/><a href=\"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/11\/pirozzi-05112016-3parte.mp3\">https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/11\/pirozzi-05112016-3parte.mp3<\/a><\/audio>\n","protected":false},"excerpt":{"rendered":"<p>RADIO AMATRICE: di seguito potete ascoltare il comunicato del 5\u00a0novembre 2016 rilasciato dal Sindaco Pirozzi. Prima parte &nbsp; Seconda parte &nbsp; Terza parte<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-167","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comunicato audio del Sindaco Pirozzi del 5 novembre 2016 - Amatrice<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/amatrice\/2016\/11\/06\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunicato audio del Sindaco Pirozzi del 5 novembre 2016 - Amatrice\" \/>\n<meta property=\"og:description\" content=\"RADIO AMATRICE: di seguito potete ascoltare il comunicato del 5\u00a0novembre 2016 rilasciato dal Sindaco Pirozzi. Prima parte &nbsp; Seconda parte &nbsp; Terza parte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/amatrice\/2016\/11\/06\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Amatrice\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-06T00:00:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-11-06T00:01:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/amatrice\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/11\\\/06\\\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/11\\\/06\\\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Comunicato audio del Sindaco Pirozzi del 5 novembre 2016\",\"datePublished\":\"2016-11-06T00:00:27+00:00\",\"dateModified\":\"2016-11-06T00:01:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/11\\\/06\\\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\\\/\"},\"wordCount\":71,\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/11\\\/06\\\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/11\\\/06\\\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\\\/\",\"name\":\"Comunicato audio del Sindaco Pirozzi del 5 novembre 2016 - Amatrice\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#website\"},\"datePublished\":\"2016-11-06T00:00:27+00:00\",\"dateModified\":\"2016-11-06T00:01:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/11\\\/06\\\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/11\\\/06\\\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/11\\\/06\\\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicato audio del Sindaco Pirozzi del 5 novembre 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/\",\"name\":\"Amatrice\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunicato audio del Sindaco Pirozzi del 5 novembre 2016 - Amatrice","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/amatrice\/2016\/11\/06\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\/","og_locale":"it_IT","og_type":"article","og_title":"Comunicato audio del Sindaco Pirozzi del 5 novembre 2016 - Amatrice","og_description":"RADIO AMATRICE: di seguito potete ascoltare il comunicato del 5\u00a0novembre 2016 rilasciato dal Sindaco Pirozzi. Prima parte &nbsp; Seconda parte &nbsp; Terza parte","og_url":"https:\/\/comunicacity.net\/amatrice\/2016\/11\/06\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\/","og_site_name":"Amatrice","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2016-11-06T00:00:27+00:00","article_modified_time":"2016-11-06T00:01:20+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/amatrice\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/amatrice\/2016\/11\/06\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/amatrice\/2016\/11\/06\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/amatrice\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Comunicato audio del Sindaco Pirozzi del 5 novembre 2016","datePublished":"2016-11-06T00:00:27+00:00","dateModified":"2016-11-06T00:01:20+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/amatrice\/2016\/11\/06\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\/"},"wordCount":71,"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/amatrice\/2016\/11\/06\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\/","url":"https:\/\/comunicacity.net\/amatrice\/2016\/11\/06\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\/","name":"Comunicato audio del Sindaco Pirozzi del 5 novembre 2016 - Amatrice","isPartOf":{"@id":"https:\/\/comunicacity.net\/amatrice\/#website"},"datePublished":"2016-11-06T00:00:27+00:00","dateModified":"2016-11-06T00:01:20+00:00","author":{"@id":"https:\/\/comunicacity.net\/amatrice\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/amatrice\/2016\/11\/06\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/amatrice\/2016\/11\/06\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/amatrice\/2016\/11\/06\/comunicato-audio-del-sindaco-pirozzi-del-5-novembre-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/amatrice\/"},{"@type":"ListItem","position":2,"name":"Comunicato audio del Sindaco Pirozzi del 5 novembre 2016"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/amatrice\/#website","url":"https:\/\/comunicacity.net\/amatrice\/","name":"Amatrice","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/amatrice\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/amatrice\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/amatrice\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts\/167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/comments?post=167"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts\/167\/revisions"}],"predecessor-version":[{"id":169,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts\/167\/revisions\/169"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/media?parent=167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/categories?post=167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/tags?post=167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}