{"id":2122,"date":"2018-03-09T14:41:48","date_gmt":"2018-03-09T13:41:48","guid":{"rendered":"https:\/\/comunicacity.net\/amatrice\/?p=2122"},"modified":"2018-03-09T14:45:44","modified_gmt":"2018-03-09T13:45:44","slug":"attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/amatrice\/2018\/03\/09\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\/","title":{"rendered":"ATTUAZIONE AI NUOVI INTERVENTI IN FAVORE DELLE IMPRESE E PROFESSIONISTI LOCALIZZATI NELLA ZONA FRANCA URBANA SISMA CENTRO ITALIA, PREVISTI DALLA LEGGE DI BILANCIO 2018"},"content":{"rendered":"<p>Si segnala che con circolare del 5 marzo 2018, n. 144220, del Ministero dello Sviluppo Economico &#8211; Direzione generale per gli incentivi alle imprese \u00e8 stata data attuazione ai nuovi interventi in favore delle imprese e professionisti localizzati nella Zona Franca Urbana Sisma Centro Italia, previsti dalla legge di Bilancio 2018. La circolare e i moduli per la presentazione delle istanze di accesso alle agevolazioni sono pubblicati nella sezione ZFU SISMA CENTRO ITALIA del sito Internet del Ministero dello Sviluppo Economico, di cui di seguito si riporta il link.<\/p>\n<p>http:\/\/www.sviluppoeconomico.gov.it\/index.php\/it\/incentivi\/impresa\/zone-franche-urbane\/sisma-centro-italia<\/p>\n<p>La circolare ufficiale \u00e8 pubblicata in allegato.\u00a0<a href=\"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2018\/03\/CIRCOLARE-MISE-1.pdf\">CIRCOLARE MISE<\/a><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_2123\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2018\/03\/CIRCOLARE-MISE.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2018\/03\/CIRCOLARE-MISE.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>CIRCOLARE MISE<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si segnala che con circolare del 5 marzo 2018, n. 144220, del Ministero dello Sviluppo Economico &#8211; Direzione generale per gli incentivi alle imprese \u00e8 stata data attuazione ai nuovi [&hellip;]<\/p>\n","protected":false},"author":148,"featured_media":45,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-2122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ATTUAZIONE AI NUOVI INTERVENTI IN FAVORE DELLE IMPRESE E PROFESSIONISTI LOCALIZZATI NELLA ZONA FRANCA URBANA SISMA CENTRO ITALIA, PREVISTI DALLA LEGGE DI BILANCIO 2018 - Amatrice<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/amatrice\/2018\/03\/09\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ATTUAZIONE AI NUOVI INTERVENTI IN FAVORE DELLE IMPRESE E PROFESSIONISTI LOCALIZZATI NELLA ZONA FRANCA URBANA SISMA CENTRO ITALIA, PREVISTI DALLA LEGGE DI BILANCIO 2018 - Amatrice\" \/>\n<meta property=\"og:description\" content=\"Si segnala che con circolare del 5 marzo 2018, n. 144220, del Ministero dello Sviluppo Economico &#8211; Direzione generale per gli incentivi alle imprese \u00e8 stata data attuazione ai nuovi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/amatrice\/2018\/03\/09\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Amatrice\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-09T13:41:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-09T13:45:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/Amatrice-Stemma-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"379\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Segreteria Amatrice\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Segreteria Amatrice\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2018\\\/03\\\/09\\\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2018\\\/03\\\/09\\\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\\\/\"},\"author\":{\"name\":\"Segreteria Amatrice\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#\\\/schema\\\/person\\\/215d6f0d94710fcd0375dd9e96e4ea50\"},\"headline\":\"ATTUAZIONE AI NUOVI INTERVENTI IN FAVORE DELLE IMPRESE E PROFESSIONISTI LOCALIZZATI NELLA ZONA FRANCA URBANA SISMA CENTRO ITALIA, PREVISTI DALLA LEGGE DI BILANCIO 2018\",\"datePublished\":\"2018-03-09T13:41:48+00:00\",\"dateModified\":\"2018-03-09T13:45:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2018\\\/03\\\/09\\\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\\\/\"},\"wordCount\":127,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2018\\\/03\\\/09\\\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/wp-content\\\/uploads\\\/sites\\\/69\\\/2016\\\/10\\\/Amatrice-Stemma-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2018\\\/03\\\/09\\\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2018\\\/03\\\/09\\\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\\\/\",\"name\":\"ATTUAZIONE AI NUOVI INTERVENTI IN FAVORE DELLE IMPRESE E PROFESSIONISTI LOCALIZZATI NELLA ZONA FRANCA URBANA SISMA CENTRO ITALIA, PREVISTI DALLA LEGGE DI BILANCIO 2018 - Amatrice\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2018\\\/03\\\/09\\\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2018\\\/03\\\/09\\\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/wp-content\\\/uploads\\\/sites\\\/69\\\/2016\\\/10\\\/Amatrice-Stemma-1.jpg\",\"datePublished\":\"2018-03-09T13:41:48+00:00\",\"dateModified\":\"2018-03-09T13:45:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#\\\/schema\\\/person\\\/215d6f0d94710fcd0375dd9e96e4ea50\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2018\\\/03\\\/09\\\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2018\\\/03\\\/09\\\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2018\\\/03\\\/09\\\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/wp-content\\\/uploads\\\/sites\\\/69\\\/2016\\\/10\\\/Amatrice-Stemma-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/wp-content\\\/uploads\\\/sites\\\/69\\\/2016\\\/10\\\/Amatrice-Stemma-1.jpg\",\"width\":379,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2018\\\/03\\\/09\\\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ATTUAZIONE AI NUOVI INTERVENTI IN FAVORE DELLE IMPRESE E PROFESSIONISTI LOCALIZZATI NELLA ZONA FRANCA URBANA SISMA CENTRO ITALIA, PREVISTI DALLA LEGGE DI BILANCIO 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/\",\"name\":\"Amatrice\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#\\\/schema\\\/person\\\/215d6f0d94710fcd0375dd9e96e4ea50\",\"name\":\"Segreteria Amatrice\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18db79c8cde836be6cb70e50b711455573733a42f83433b1cbec3d59ea52aff2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18db79c8cde836be6cb70e50b711455573733a42f83433b1cbec3d59ea52aff2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18db79c8cde836be6cb70e50b711455573733a42f83433b1cbec3d59ea52aff2?s=96&d=mm&r=g\",\"caption\":\"Segreteria Amatrice\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/author\\\/segreteriaamatrice\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ATTUAZIONE AI NUOVI INTERVENTI IN FAVORE DELLE IMPRESE E PROFESSIONISTI LOCALIZZATI NELLA ZONA FRANCA URBANA SISMA CENTRO ITALIA, PREVISTI DALLA LEGGE DI BILANCIO 2018 - Amatrice","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/amatrice\/2018\/03\/09\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\/","og_locale":"it_IT","og_type":"article","og_title":"ATTUAZIONE AI NUOVI INTERVENTI IN FAVORE DELLE IMPRESE E PROFESSIONISTI LOCALIZZATI NELLA ZONA FRANCA URBANA SISMA CENTRO ITALIA, PREVISTI DALLA LEGGE DI BILANCIO 2018 - Amatrice","og_description":"Si segnala che con circolare del 5 marzo 2018, n. 144220, del Ministero dello Sviluppo Economico &#8211; Direzione generale per gli incentivi alle imprese \u00e8 stata data attuazione ai nuovi [&hellip;]","og_url":"https:\/\/comunicacity.net\/amatrice\/2018\/03\/09\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\/","og_site_name":"Amatrice","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-03-09T13:41:48+00:00","article_modified_time":"2018-03-09T13:45:44+00:00","og_image":[{"width":379,"height":500,"url":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/Amatrice-Stemma-1.jpg","type":"image\/jpeg"}],"author":"Segreteria Amatrice","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Segreteria Amatrice","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/amatrice\/2018\/03\/09\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/amatrice\/2018\/03\/09\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\/"},"author":{"name":"Segreteria Amatrice","@id":"https:\/\/comunicacity.net\/amatrice\/#\/schema\/person\/215d6f0d94710fcd0375dd9e96e4ea50"},"headline":"ATTUAZIONE AI NUOVI INTERVENTI IN FAVORE DELLE IMPRESE E PROFESSIONISTI LOCALIZZATI NELLA ZONA FRANCA URBANA SISMA CENTRO ITALIA, PREVISTI DALLA LEGGE DI BILANCIO 2018","datePublished":"2018-03-09T13:41:48+00:00","dateModified":"2018-03-09T13:45:44+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/amatrice\/2018\/03\/09\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\/"},"wordCount":127,"image":{"@id":"https:\/\/comunicacity.net\/amatrice\/2018\/03\/09\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/Amatrice-Stemma-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/amatrice\/2018\/03\/09\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\/","url":"https:\/\/comunicacity.net\/amatrice\/2018\/03\/09\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\/","name":"ATTUAZIONE AI NUOVI INTERVENTI IN FAVORE DELLE IMPRESE E PROFESSIONISTI LOCALIZZATI NELLA ZONA FRANCA URBANA SISMA CENTRO ITALIA, PREVISTI DALLA LEGGE DI BILANCIO 2018 - Amatrice","isPartOf":{"@id":"https:\/\/comunicacity.net\/amatrice\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/amatrice\/2018\/03\/09\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/amatrice\/2018\/03\/09\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/Amatrice-Stemma-1.jpg","datePublished":"2018-03-09T13:41:48+00:00","dateModified":"2018-03-09T13:45:44+00:00","author":{"@id":"https:\/\/comunicacity.net\/amatrice\/#\/schema\/person\/215d6f0d94710fcd0375dd9e96e4ea50"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/amatrice\/2018\/03\/09\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/amatrice\/2018\/03\/09\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/amatrice\/2018\/03\/09\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\/#primaryimage","url":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/Amatrice-Stemma-1.jpg","contentUrl":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/Amatrice-Stemma-1.jpg","width":379,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/amatrice\/2018\/03\/09\/attuazione-ai-nuovi-interventi-in-favore-delle-imprese-e-professionisti-localizzati-nella-zona-franca-urbana-sisma-centro-italia-previsti-dalla-legge-di-bilancio-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/amatrice\/"},{"@type":"ListItem","position":2,"name":"ATTUAZIONE AI NUOVI INTERVENTI IN FAVORE DELLE IMPRESE E PROFESSIONISTI LOCALIZZATI NELLA ZONA FRANCA URBANA SISMA CENTRO ITALIA, PREVISTI DALLA LEGGE DI BILANCIO 2018"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/amatrice\/#website","url":"https:\/\/comunicacity.net\/amatrice\/","name":"Amatrice","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/amatrice\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/amatrice\/#\/schema\/person\/215d6f0d94710fcd0375dd9e96e4ea50","name":"Segreteria Amatrice","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/18db79c8cde836be6cb70e50b711455573733a42f83433b1cbec3d59ea52aff2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/18db79c8cde836be6cb70e50b711455573733a42f83433b1cbec3d59ea52aff2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/18db79c8cde836be6cb70e50b711455573733a42f83433b1cbec3d59ea52aff2?s=96&d=mm&r=g","caption":"Segreteria Amatrice"},"url":"https:\/\/comunicacity.net\/amatrice\/author\/segreteriaamatrice\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts\/2122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/users\/148"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/comments?post=2122"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts\/2122\/revisions"}],"predecessor-version":[{"id":2125,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts\/2122\/revisions\/2125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/media\/45"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/media?parent=2122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/categories?post=2122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/tags?post=2122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}