{"id":24,"date":"2016-10-12T16:13:27","date_gmt":"2016-10-12T14:13:27","guid":{"rendered":"https:\/\/comunicacity.net\/amatrice\/?p=24"},"modified":"2016-10-12T16:22:47","modified_gmt":"2016-10-12T14:22:47","slug":"adotta-unopera","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/12\/adotta-unopera\/","title":{"rendered":"Adotta un\u2019opera"},"content":{"rendered":"<p style=\"text-align: justify;\">Il Comune di Amatrice ringrazia di cuore tutti coloro che stanno contribuendo alla raccolta fondi per la ricostruzione e per l\u2019assistenza alla popolazione amatriciana, cos\u00ec duramente colpita dagli eventi del 24 agosto 2016.<\/p>\n<p style=\"text-align: justify;\">Fin dal primo momento il Comune ha richiesto, ai numerosi gruppi pubblici e privati che si sono resi disponibili a fare donazioni, di trattenere i fondi raccolti con la destinazione TERREMOTO AMATRICE \u2013 ADOTTA UN\u2019OPERA e di attendere che il Comune stesso indicasse dove e come destinare tali somme.<\/p>\n<p style=\"text-align: justify;\"><span id=\"more-2086\"><\/span><br \/>\n<strong>COSA E\u2019 ADOTTA UN\u2019OPERA<\/strong><br \/>\nLo spirito della campagna ADOTTA UN\u2019OPERA \u00e8 quello di operare in stretta collaborazione con i donatori, in un ambito di totale trasparenza, seguendo un processo di ricostruzione che coinvolga contemporaneamente il donatore, l\u2019amministrazione e il cittadino di Amatrice.<br \/>\nIn questa fase di programmazione dell\u2019oggi, del domani e del dopodomani, il Comune, in accordo con lo Stato e con la Regione, sta valutando le necessit\u00e0 per far ripartire il territorio, riavviare le attivit\u00e0 commerciali, sostenere gli agricoltori, ricreare gli spazi di aggregazione sociale e di cultura, lo sviluppo di attivit\u00e0 per il turismo montano ed enogastronomico e tutto quanto consenta di guardare il futuro di Amatrice in una ottica di ripresa e sviluppo.<br \/>\nLe esigenze legate alla ripartenza sono individuabili in due grandi categorie: da un lato, l\u2019attivit\u00e0 di ricostruzione dell\u2019esistente e dei grandi monumenti che avr\u00e0 tempi di realizzazione legati alle procedure statali del post terremoto, e, dall\u2019altra, una pianificazione di interventi a breve di nuove iniziative, di recupero delle frazioni e di riavviamento delle attivit\u00e0 commerciali e ricettive che possano costituire per la comunit\u00e0 amatriciana un volano di ripresa gi\u00e0 nell\u2019immediato.<br \/>\nNella prima categoria rientrano le ricostruzioni dei centri storici, degli immobili pubblici o di pubblica utilit\u00e0 e il recupero dei grandi beni artistici e culturali.<br \/>\nNella seconda categoria rientrano le ricostruzioni di nuove aree per esercizi commerciali e spazi di aggregazione, le nuove aree per il turismo, la ricreazione e la ricezione, il recupero dei beni culturali delle frazioni.<br \/>\nSi allega al presente comunicato l\u2019elenco di tutte le opere individuate, in questa prima fase, opere che fanno parte di una attenta pianificazione urbanistica che avr\u00e0 tempi di esecuzione inscindibilmente legati alla definizione del dettaglio e all\u2019ottenimento delle autorizzazioni necessarie.<br \/>\nTale elenco rappresenta la scelta consapevole di un programma di ricostruzione operato secondo le reali necessit\u00e0 e i fabbisogni della locale Comunit\u00e0, concordato con le Istituzioni.<\/p>\n<p style=\"text-align: justify;\"><strong>COME SI ADERISCE<\/strong><br \/>\nIl Comune ha aperto un conto correnti dedicato per chi ha fatto o vuole fare raccolte di denaro finalizzate alla realizzazione di un\u2019opera presso la BCC di Roma<\/p>\n<table width=\"517\">\n<tbody>\n<tr>\n<td><strong>Codice Paese<\/strong><\/td>\n<td><strong>CheckDigit<\/strong><\/td>\n<td><strong>Cin<\/strong><\/td>\n<td><strong>Abi<\/strong><\/td>\n<td><strong>Cab<\/strong><\/td>\n<td><strong>Conto<\/strong><\/td>\n<\/tr>\n<tr>\n<td><strong>IT<\/strong><\/td>\n<td><strong>37<\/strong><\/td>\n<td><strong>O*<\/strong><\/td>\n<td><strong>08327<\/strong><\/td>\n<td><strong>73470<\/strong><\/td>\n<td><strong>000000005400<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\"><strong>(* Lettera O)<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>BIC ROMAITRRXXX<\/strong><br \/>\nChi intende indirizzare la propria raccolta su un progetto specifico potr\u00e0 depositare le somme con la causale di preferenza sull\u2019opera selezionata, specificando nella causale una delle opere dell\u2019elenco. Una volta completata dal Comune la fase di progettazione e autorizzazione, verr\u00e0 comunicata al donatore l\u2019avviamento della realizzazione. Il sito del Comune di Amatrice verr\u00e0 aggiornato, in tempo reale, sullo stato di completamento dell\u2019opera, dall\u2019esecuzione del progetto all\u2019autorizzazione, dalla realizzazione al suo collaudo.<\/p>\n<p style=\"text-align: justify;\">Nel ribadire la nostra grande commozione per la solidariet\u00e0 espressa alla citt\u00e0 di Amatrice da tutte le parti d\u2019Italia e del mondo, invitiamo tutti coloro che vorranno prestare il proprio concreto aiuto a collaborare secondo le procedure che sono state indicate. Siamo sicuri che tale collaborazione, se ben organizzata, contribuir\u00e0 in maniera significativa a consentire a tutti, non solo agli amatriciani, di potere rivedere vivere quello che era, e dovr\u00e0 tornare ad essere, uno dei BORGHI PIU\u2019 BELLI DI ITALIA.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_25\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/Elenco-Opere.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/Elenco-Opere.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Elenco Opere<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di Amatrice ringrazia di cuore tutti coloro che stanno contribuendo alla raccolta fondi per la ricostruzione e per l\u2019assistenza alla popolazione amatriciana, cos\u00ec duramente colpita dagli eventi del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-24","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adotta un\u2019opera - Amatrice<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/amatrice\/2016\/10\/12\/adotta-unopera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adotta un\u2019opera - Amatrice\" \/>\n<meta property=\"og:description\" content=\"Il Comune di Amatrice ringrazia di cuore tutti coloro che stanno contribuendo alla raccolta fondi per la ricostruzione e per l\u2019assistenza alla popolazione amatriciana, cos\u00ec duramente colpita dagli eventi del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/amatrice\/2016\/10\/12\/adotta-unopera\/\" \/>\n<meta property=\"og:site_name\" content=\"Amatrice\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-12T14:13:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-12T14:22:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/amatrice.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/12\\\/adotta-unopera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/12\\\/adotta-unopera\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Adotta un\u2019opera\",\"datePublished\":\"2016-10-12T14:13:27+00:00\",\"dateModified\":\"2016-10-12T14:22:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/12\\\/adotta-unopera\\\/\"},\"wordCount\":607,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/12\\\/adotta-unopera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/wp-content\\\/uploads\\\/sites\\\/69\\\/2016\\\/10\\\/amatrice.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/12\\\/adotta-unopera\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/12\\\/adotta-unopera\\\/\",\"name\":\"Adotta un\u2019opera - Amatrice\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/12\\\/adotta-unopera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/12\\\/adotta-unopera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/wp-content\\\/uploads\\\/sites\\\/69\\\/2016\\\/10\\\/amatrice.jpg\",\"datePublished\":\"2016-10-12T14:13:27+00:00\",\"dateModified\":\"2016-10-12T14:22:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/12\\\/adotta-unopera\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/12\\\/adotta-unopera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/12\\\/adotta-unopera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/wp-content\\\/uploads\\\/sites\\\/69\\\/2016\\\/10\\\/amatrice.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/wp-content\\\/uploads\\\/sites\\\/69\\\/2016\\\/10\\\/amatrice.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/12\\\/adotta-unopera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adotta un\u2019opera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/\",\"name\":\"Amatrice\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adotta un\u2019opera - Amatrice","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/12\/adotta-unopera\/","og_locale":"it_IT","og_type":"article","og_title":"Adotta un\u2019opera - Amatrice","og_description":"Il Comune di Amatrice ringrazia di cuore tutti coloro che stanno contribuendo alla raccolta fondi per la ricostruzione e per l\u2019assistenza alla popolazione amatriciana, cos\u00ec duramente colpita dagli eventi del [&hellip;]","og_url":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/12\/adotta-unopera\/","og_site_name":"Amatrice","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2016-10-12T14:13:27+00:00","article_modified_time":"2016-10-12T14:22:47+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/amatrice.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/12\/adotta-unopera\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/12\/adotta-unopera\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/amatrice\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Adotta un\u2019opera","datePublished":"2016-10-12T14:13:27+00:00","dateModified":"2016-10-12T14:22:47+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/12\/adotta-unopera\/"},"wordCount":607,"image":{"@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/12\/adotta-unopera\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/amatrice.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/12\/adotta-unopera\/","url":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/12\/adotta-unopera\/","name":"Adotta un\u2019opera - Amatrice","isPartOf":{"@id":"https:\/\/comunicacity.net\/amatrice\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/12\/adotta-unopera\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/12\/adotta-unopera\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/amatrice.jpg","datePublished":"2016-10-12T14:13:27+00:00","dateModified":"2016-10-12T14:22:47+00:00","author":{"@id":"https:\/\/comunicacity.net\/amatrice\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/12\/adotta-unopera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/amatrice\/2016\/10\/12\/adotta-unopera\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/12\/adotta-unopera\/#primaryimage","url":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/amatrice.jpg","contentUrl":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/amatrice.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/12\/adotta-unopera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/amatrice\/"},{"@type":"ListItem","position":2,"name":"Adotta un\u2019opera"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/amatrice\/#website","url":"https:\/\/comunicacity.net\/amatrice\/","name":"Amatrice","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/amatrice\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/amatrice\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/amatrice\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/comments?post=24"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts\/24\/revisions"}],"predecessor-version":[{"id":26,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts\/24\/revisions\/26"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/media\/6"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/media?parent=24"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/categories?post=24"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/tags?post=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}