{"id":53,"date":"2016-10-16T10:21:05","date_gmt":"2016-10-16T08:21:05","guid":{"rendered":"https:\/\/comunicacity.net\/amatrice\/?p=53"},"modified":"2016-10-16T15:02:29","modified_gmt":"2016-10-16T13:02:29","slug":"in-diretta-comunicazioni-del-governatore-zingaretti","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/16\/in-diretta-comunicazioni-del-governatore-zingaretti\/","title":{"rendered":"In diretta comunicazioni del Governatore Zingaretti"},"content":{"rendered":"<p style=\"text-align: justify;\">Luned\u00ec 17 ottobre, dalle ore 15.00 circa, in collegamento dalla Pisana, diretta integrale della seduta del Consiglio regionale del Lazio.<\/p>\n<p style=\"text-align: justify;\">L&#8217;Assemblea discuter\u00e0 delle comunicazioni del Presidente Nicola ZINGARETTI riguardanti il terremoto dello scorso 24 agosto.<\/p>\n<p style=\"text-align: justify;\">Nell&#8217;Alta Valle del Velino e del Tronto, MEP Radio Organizzazione \u00e8 ricevibile sui 95.200-96.000-96.800-105.500 MHz FM.<\/p>\n<p style=\"text-align: justify;\">Ulteriori informazioni sulle frequenze di trasmissione e streaming audio su <a href=\"http:\/\/www.mepradio.it\">www.mepradio.it<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luned\u00ec 17 ottobre, dalle ore 15.00 circa, in collegamento dalla Pisana, diretta integrale della seduta del Consiglio regionale del Lazio. L&#8217;Assemblea discuter\u00e0 delle comunicazioni del Presidente Nicola ZINGARETTI riguardanti il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":75,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-53","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>In diretta comunicazioni del Governatore Zingaretti - Amatrice<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/amatrice\/2016\/10\/16\/in-diretta-comunicazioni-del-governatore-zingaretti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In diretta comunicazioni del Governatore Zingaretti - Amatrice\" \/>\n<meta property=\"og:description\" content=\"Luned\u00ec 17 ottobre, dalle ore 15.00 circa, in collegamento dalla Pisana, diretta integrale della seduta del Consiglio regionale del Lazio. L&#8217;Assemblea discuter\u00e0 delle comunicazioni del Presidente Nicola ZINGARETTI riguardanti il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/amatrice\/2016\/10\/16\/in-diretta-comunicazioni-del-governatore-zingaretti\/\" \/>\n<meta property=\"og:site_name\" content=\"Amatrice\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-16T08:21:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-10-16T13:02:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/zingaretti-amatrice-0110.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"428\" \/>\n\t<meta property=\"og:image:height\" content=\"308\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/16\\\/in-diretta-comunicazioni-del-governatore-zingaretti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/16\\\/in-diretta-comunicazioni-del-governatore-zingaretti\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"In diretta comunicazioni del Governatore Zingaretti\",\"datePublished\":\"2016-10-16T08:21:05+00:00\",\"dateModified\":\"2016-10-16T13:02:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/16\\\/in-diretta-comunicazioni-del-governatore-zingaretti\\\/\"},\"wordCount\":68,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/16\\\/in-diretta-comunicazioni-del-governatore-zingaretti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/wp-content\\\/uploads\\\/sites\\\/69\\\/2016\\\/10\\\/zingaretti-amatrice-0110.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/16\\\/in-diretta-comunicazioni-del-governatore-zingaretti\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/16\\\/in-diretta-comunicazioni-del-governatore-zingaretti\\\/\",\"name\":\"In diretta comunicazioni del Governatore Zingaretti - Amatrice\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/16\\\/in-diretta-comunicazioni-del-governatore-zingaretti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/16\\\/in-diretta-comunicazioni-del-governatore-zingaretti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/wp-content\\\/uploads\\\/sites\\\/69\\\/2016\\\/10\\\/zingaretti-amatrice-0110.jpg\",\"datePublished\":\"2016-10-16T08:21:05+00:00\",\"dateModified\":\"2016-10-16T13:02:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/16\\\/in-diretta-comunicazioni-del-governatore-zingaretti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/16\\\/in-diretta-comunicazioni-del-governatore-zingaretti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/16\\\/in-diretta-comunicazioni-del-governatore-zingaretti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/wp-content\\\/uploads\\\/sites\\\/69\\\/2016\\\/10\\\/zingaretti-amatrice-0110.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/wp-content\\\/uploads\\\/sites\\\/69\\\/2016\\\/10\\\/zingaretti-amatrice-0110.jpg\",\"width\":428,\"height\":308},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2016\\\/10\\\/16\\\/in-diretta-comunicazioni-del-governatore-zingaretti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In diretta comunicazioni del Governatore Zingaretti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/\",\"name\":\"Amatrice\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"In diretta comunicazioni del Governatore Zingaretti - Amatrice","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/16\/in-diretta-comunicazioni-del-governatore-zingaretti\/","og_locale":"it_IT","og_type":"article","og_title":"In diretta comunicazioni del Governatore Zingaretti - Amatrice","og_description":"Luned\u00ec 17 ottobre, dalle ore 15.00 circa, in collegamento dalla Pisana, diretta integrale della seduta del Consiglio regionale del Lazio. L&#8217;Assemblea discuter\u00e0 delle comunicazioni del Presidente Nicola ZINGARETTI riguardanti il [&hellip;]","og_url":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/16\/in-diretta-comunicazioni-del-governatore-zingaretti\/","og_site_name":"Amatrice","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2016-10-16T08:21:05+00:00","article_modified_time":"2016-10-16T13:02:29+00:00","og_image":[{"width":428,"height":308,"url":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/zingaretti-amatrice-0110.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/16\/in-diretta-comunicazioni-del-governatore-zingaretti\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/16\/in-diretta-comunicazioni-del-governatore-zingaretti\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/amatrice\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"In diretta comunicazioni del Governatore Zingaretti","datePublished":"2016-10-16T08:21:05+00:00","dateModified":"2016-10-16T13:02:29+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/16\/in-diretta-comunicazioni-del-governatore-zingaretti\/"},"wordCount":68,"image":{"@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/16\/in-diretta-comunicazioni-del-governatore-zingaretti\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/zingaretti-amatrice-0110.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/16\/in-diretta-comunicazioni-del-governatore-zingaretti\/","url":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/16\/in-diretta-comunicazioni-del-governatore-zingaretti\/","name":"In diretta comunicazioni del Governatore Zingaretti - Amatrice","isPartOf":{"@id":"https:\/\/comunicacity.net\/amatrice\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/16\/in-diretta-comunicazioni-del-governatore-zingaretti\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/16\/in-diretta-comunicazioni-del-governatore-zingaretti\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/zingaretti-amatrice-0110.jpg","datePublished":"2016-10-16T08:21:05+00:00","dateModified":"2016-10-16T13:02:29+00:00","author":{"@id":"https:\/\/comunicacity.net\/amatrice\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/16\/in-diretta-comunicazioni-del-governatore-zingaretti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/amatrice\/2016\/10\/16\/in-diretta-comunicazioni-del-governatore-zingaretti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/16\/in-diretta-comunicazioni-del-governatore-zingaretti\/#primaryimage","url":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/zingaretti-amatrice-0110.jpg","contentUrl":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2016\/10\/zingaretti-amatrice-0110.jpg","width":428,"height":308},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/amatrice\/2016\/10\/16\/in-diretta-comunicazioni-del-governatore-zingaretti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/amatrice\/"},{"@type":"ListItem","position":2,"name":"In diretta comunicazioni del Governatore Zingaretti"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/amatrice\/#website","url":"https:\/\/comunicacity.net\/amatrice\/","name":"Amatrice","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/amatrice\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/amatrice\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/amatrice\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts\/53","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/comments?post=53"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts\/53\/revisions"}],"predecessor-version":[{"id":55,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts\/53\/revisions\/55"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/media\/75"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/media?parent=53"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/categories?post=53"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/tags?post=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}