{"id":605,"date":"2017-01-03T23:54:57","date_gmt":"2017-01-03T22:54:57","guid":{"rendered":"https:\/\/comunicacity.net\/amatrice\/?p=605"},"modified":"2017-01-04T16:23:57","modified_gmt":"2017-01-04T15:23:57","slug":"diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/amatrice\/2017\/01\/03\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\/","title":{"rendered":"PAPA FRANCESCO: DIRETTA INTEGRALE DELL&#8217;UDIENZA SPECIALE DEL 5 GENNAIO"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Papa Francesco il prossimo 5 gennaio accoglier\u00e0 in udienza le popolazioni di Amatrice e delle altre zone colpite dal sisma del centro Italia.<\/p>\n<p>L\u2019evento sar\u00e0 trasmesso in diretta integrale, dalle ore 11:00 circa, sulla frequenza FM 105 di Radio Vaticana Italia, ed in diretta streaming (radio e TV) sul sito <a href=\"http:\/\/it.radiovaticana.va\">http:\/\/it.radiovaticana.va<\/a><\/p>\n<p>La diretta sar\u00e0 seguita da un approfondimento, condotto dal giornalista Stefano Leszczynski, con vari ospiti del Comune di Amatrice, che saranno presenti in studio<\/p>\n<p>La diretta integrale dell&#8217;udienza speciale di Papa Francesco\u00a0\u00a0\u00e8 ricevibile, nell&#8217;Alta Valle del Velino e del Tronto, sulle frequenze 95.200-96.000-96.800-105.500 MHz FM. di\u00a0MEP Radio Organizzazione.\u00a0Ulteriori informazioni sulle frequenze di trasmissione e streaming audio su www.mepradio.it<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Papa Francesco il prossimo 5 gennaio accoglier\u00e0 in udienza le popolazioni di Amatrice e delle altre zone colpite dal sisma del centro Italia. L\u2019evento sar\u00e0 trasmesso in diretta integrale, [&hellip;]<\/p>\n","protected":false},"author":148,"featured_media":606,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PAPA FRANCESCO: DIRETTA INTEGRALE DELL&#039;UDIENZA SPECIALE DEL 5 GENNAIO - Amatrice<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/amatrice\/2017\/01\/03\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PAPA FRANCESCO: DIRETTA INTEGRALE DELL&#039;UDIENZA SPECIALE DEL 5 GENNAIO - Amatrice\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Papa Francesco il prossimo 5 gennaio accoglier\u00e0 in udienza le popolazioni di Amatrice e delle altre zone colpite dal sisma del centro Italia. L\u2019evento sar\u00e0 trasmesso in diretta integrale, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/amatrice\/2017\/01\/03\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\/\" \/>\n<meta property=\"og:site_name\" content=\"Amatrice\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-03T22:54:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-01-04T15:23:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2017\/01\/Logo_udienza_speciale_di_papa_francesco_ai_terremotati_2716.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Segreteria Amatrice\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Segreteria Amatrice\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2017\\\/01\\\/03\\\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2017\\\/01\\\/03\\\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\\\/\"},\"author\":{\"name\":\"Segreteria Amatrice\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#\\\/schema\\\/person\\\/215d6f0d94710fcd0375dd9e96e4ea50\"},\"headline\":\"PAPA FRANCESCO: DIRETTA INTEGRALE DELL&#8217;UDIENZA SPECIALE DEL 5 GENNAIO\",\"datePublished\":\"2017-01-03T22:54:57+00:00\",\"dateModified\":\"2017-01-04T15:23:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2017\\\/01\\\/03\\\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\\\/\"},\"wordCount\":125,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2017\\\/01\\\/03\\\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/wp-content\\\/uploads\\\/sites\\\/69\\\/2017\\\/01\\\/Logo_udienza_speciale_di_papa_francesco_ai_terremotati_2716.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2017\\\/01\\\/03\\\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2017\\\/01\\\/03\\\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\\\/\",\"name\":\"PAPA FRANCESCO: DIRETTA INTEGRALE DELL'UDIENZA SPECIALE DEL 5 GENNAIO - Amatrice\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2017\\\/01\\\/03\\\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2017\\\/01\\\/03\\\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/wp-content\\\/uploads\\\/sites\\\/69\\\/2017\\\/01\\\/Logo_udienza_speciale_di_papa_francesco_ai_terremotati_2716.jpg\",\"datePublished\":\"2017-01-03T22:54:57+00:00\",\"dateModified\":\"2017-01-04T15:23:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#\\\/schema\\\/person\\\/215d6f0d94710fcd0375dd9e96e4ea50\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2017\\\/01\\\/03\\\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2017\\\/01\\\/03\\\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2017\\\/01\\\/03\\\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/wp-content\\\/uploads\\\/sites\\\/69\\\/2017\\\/01\\\/Logo_udienza_speciale_di_papa_francesco_ai_terremotati_2716.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/wp-content\\\/uploads\\\/sites\\\/69\\\/2017\\\/01\\\/Logo_udienza_speciale_di_papa_francesco_ai_terremotati_2716.jpg\",\"width\":400,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/2017\\\/01\\\/03\\\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PAPA FRANCESCO: DIRETTA INTEGRALE DELL&#8217;UDIENZA SPECIALE DEL 5 GENNAIO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/\",\"name\":\"Amatrice\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/#\\\/schema\\\/person\\\/215d6f0d94710fcd0375dd9e96e4ea50\",\"name\":\"Segreteria Amatrice\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18db79c8cde836be6cb70e50b711455573733a42f83433b1cbec3d59ea52aff2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18db79c8cde836be6cb70e50b711455573733a42f83433b1cbec3d59ea52aff2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/18db79c8cde836be6cb70e50b711455573733a42f83433b1cbec3d59ea52aff2?s=96&d=mm&r=g\",\"caption\":\"Segreteria Amatrice\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/amatrice\\\/author\\\/segreteriaamatrice\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PAPA FRANCESCO: DIRETTA INTEGRALE DELL'UDIENZA SPECIALE DEL 5 GENNAIO - Amatrice","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/amatrice\/2017\/01\/03\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\/","og_locale":"it_IT","og_type":"article","og_title":"PAPA FRANCESCO: DIRETTA INTEGRALE DELL'UDIENZA SPECIALE DEL 5 GENNAIO - Amatrice","og_description":"&nbsp; Papa Francesco il prossimo 5 gennaio accoglier\u00e0 in udienza le popolazioni di Amatrice e delle altre zone colpite dal sisma del centro Italia. L\u2019evento sar\u00e0 trasmesso in diretta integrale, [&hellip;]","og_url":"https:\/\/comunicacity.net\/amatrice\/2017\/01\/03\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\/","og_site_name":"Amatrice","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-01-03T22:54:57+00:00","article_modified_time":"2017-01-04T15:23:57+00:00","og_image":[{"width":400,"height":300,"url":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2017\/01\/Logo_udienza_speciale_di_papa_francesco_ai_terremotati_2716.jpg","type":"image\/jpeg"}],"author":"Segreteria Amatrice","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Segreteria Amatrice","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/amatrice\/2017\/01\/03\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/amatrice\/2017\/01\/03\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\/"},"author":{"name":"Segreteria Amatrice","@id":"https:\/\/comunicacity.net\/amatrice\/#\/schema\/person\/215d6f0d94710fcd0375dd9e96e4ea50"},"headline":"PAPA FRANCESCO: DIRETTA INTEGRALE DELL&#8217;UDIENZA SPECIALE DEL 5 GENNAIO","datePublished":"2017-01-03T22:54:57+00:00","dateModified":"2017-01-04T15:23:57+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/amatrice\/2017\/01\/03\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\/"},"wordCount":125,"image":{"@id":"https:\/\/comunicacity.net\/amatrice\/2017\/01\/03\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2017\/01\/Logo_udienza_speciale_di_papa_francesco_ai_terremotati_2716.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/amatrice\/2017\/01\/03\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\/","url":"https:\/\/comunicacity.net\/amatrice\/2017\/01\/03\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\/","name":"PAPA FRANCESCO: DIRETTA INTEGRALE DELL'UDIENZA SPECIALE DEL 5 GENNAIO - Amatrice","isPartOf":{"@id":"https:\/\/comunicacity.net\/amatrice\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/amatrice\/2017\/01\/03\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/amatrice\/2017\/01\/03\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2017\/01\/Logo_udienza_speciale_di_papa_francesco_ai_terremotati_2716.jpg","datePublished":"2017-01-03T22:54:57+00:00","dateModified":"2017-01-04T15:23:57+00:00","author":{"@id":"https:\/\/comunicacity.net\/amatrice\/#\/schema\/person\/215d6f0d94710fcd0375dd9e96e4ea50"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/amatrice\/2017\/01\/03\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/amatrice\/2017\/01\/03\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/amatrice\/2017\/01\/03\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\/#primaryimage","url":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2017\/01\/Logo_udienza_speciale_di_papa_francesco_ai_terremotati_2716.jpg","contentUrl":"https:\/\/comunicacity.net\/amatrice\/wp-content\/uploads\/sites\/69\/2017\/01\/Logo_udienza_speciale_di_papa_francesco_ai_terremotati_2716.jpg","width":400,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/amatrice\/2017\/01\/03\/diretta-integrale-dallaula-paolo-delludienza-speciale-di-papa-francesco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/amatrice\/"},{"@type":"ListItem","position":2,"name":"PAPA FRANCESCO: DIRETTA INTEGRALE DELL&#8217;UDIENZA SPECIALE DEL 5 GENNAIO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/amatrice\/#website","url":"https:\/\/comunicacity.net\/amatrice\/","name":"Amatrice","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/amatrice\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/amatrice\/#\/schema\/person\/215d6f0d94710fcd0375dd9e96e4ea50","name":"Segreteria Amatrice","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/18db79c8cde836be6cb70e50b711455573733a42f83433b1cbec3d59ea52aff2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/18db79c8cde836be6cb70e50b711455573733a42f83433b1cbec3d59ea52aff2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/18db79c8cde836be6cb70e50b711455573733a42f83433b1cbec3d59ea52aff2?s=96&d=mm&r=g","caption":"Segreteria Amatrice"},"url":"https:\/\/comunicacity.net\/amatrice\/author\/segreteriaamatrice\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts\/605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/users\/148"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/comments?post=605"}],"version-history":[{"count":5,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts\/605\/revisions"}],"predecessor-version":[{"id":611,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/posts\/605\/revisions\/611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/media\/606"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/media?parent=605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/categories?post=605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/amatrice\/wp-json\/wp\/v2\/tags?post=605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}