{"id":313,"date":"2017-05-24T12:34:14","date_gmt":"2017-05-24T11:34:14","guid":{"rendered":"https:\/\/comunicacity.net\/anci-lazio\/2017\/05\/24\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\/"},"modified":"2017-12-19T21:44:16","modified_gmt":"2017-12-19T20:44:16","slug":"rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/anci-lazio\/2017\/05\/24\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\/","title":{"rendered":"Rigenerazione urbana, le osservazioni di ANCI Lazio alla proposta di legge regionale"},"content":{"rendered":"<div class=\"socialBarFixed\">\n<p>Condividi la notizia<\/p>\n<\/div>\n<p class=\"occhielloPrimoPiano\">Rigenerazione urbana<\/p>\n<h2 class=\"newsTitleMedium newsPageTitle\">Rigenerazione urbana, le osservazioni di ANCI Lazio alla proposta di legge regionale<\/h2>\n<p class=\"italic darkgray grayBorderBottom paddingBottom1em\">ANCI Lazio ha presentato le proprie osservazioni al fine di migliorare la proposta di legge sulla rigenerazione urbana e renderne pi\u00f9 agile e snella la successiva attuazione<\/p>\n<p>Anci Lazio valuta con assoluto favore la proposta legislativa regionale finalizzata a disciplinare gli <strong>interventi di rigenerazione urbana e di recupero del patrimonio edilizio<\/strong> nell\u2019ottica di:<\/p>\n<p><!-- [if !supportLists]-->a)\u00a0\u00a0\u00a0\u00a0 <!--[endif]-->Costituire un\u2019opportunit\u00e0 di intervento sul patrimonio edilizio esistente, da rigenerare e\/o da recuperare ad una funzione attuale, senza ulteriore consumo di territorio;<\/p>\n<p><!-- [if !supportLists]-->b)\u00a0\u00a0\u00a0\u00a0 <!--[endif]-->Offrire l\u2019occasione per concorrere a valorizzare particolari ambiti urbani;<\/p>\n<p><!-- [if !supportLists]-->c)\u00a0\u00a0\u00a0\u00a0 <!--[endif]-->Consentire un\u2019accurata e prudente attivazione dei percorsi di partenariato misto pubblico-privato;<\/p>\n<p><!-- [if !supportLists]-->d)\u00a0\u00a0\u00a0\u00a0 <!--[endif]-->Concorrere a riavviare un ciclo economico legato all\u2019edilizia, oggi quasi spento.<\/p>\n<p>Suggerisce alcune puntuali osservazioni migliorative del testo sottoposto all\u2019approvazione, con l\u2019intento di rendere pi\u00f9 agile e snello il percorso attuativo della legge stessa.<\/p>\n<p>In particolare:<\/p>\n<ol>\n<li>L\u2019esclusione della possibilit\u00e0 di intervento nelle aree naturali protette \u2013 art. 1, comma 2, lettera b) -, si rileva eccessivamente penalizzante, sia perch\u00e9 i piani delle aree naturali protette sono tutti precedenti, ove approvati, a questo provvedimento legislativo; sia perch\u00e9 contraddice le finalit\u00e0 dichiarate dalla proposta, riportate nella relazione allegata (lettere a), b), c) e d)): riqualificazione di aree urbane degradate, qualificazione della citt\u00e0 pubblica esistente con limitazione di ulteriore consumo del suolo, sicurezza statica dei manufatti edilizi e sviluppo dell\u2019efficienza energetica e delle fonti rinnovabili.Dove, se non nelle aree protette, si rilevano ancor pi\u00f9 significativi gli interventi previsti dalla PdL 365\/2017?In questa ottica sarebbe opportuno espungere la lettera b) del comma 2, dell\u2019art. 1; o almeno, se proprio deve restare, si precisi che i Comuni ricadenti in area protetta possono proporre specifici progetti di rigenerazione e di recupero del patrimonio edilizio in accordo con l\u2019Ente gestore dell\u2019area protetta.<\/li>\n<li>La procedura di individuazione delle aree in cui realizzare gli interventi &#8211; art. 2, comma 3 -, si rileva eccessivamente complessa, oltrech\u00e9 appesantita, da una serie di documenti di complessa struttura tecnica, che richiedono l\u2019acquisizione di professionalit\u00e0 esterne al Comune, con tutto quello che ci\u00f2 comporta in termini operativi.Si suggerisce al riguardo di suddividere gli interventi deliberativi del Consiglio Comunale in due tempi.Un primo intervento deliberativo, di carattere ricognitivo-programmatico, ricomprendente gli adempimenti previsti dalle lettere a) e b) del comma in questione.\n<p>Un secondo intervento deliberativo, di carattere dispositivo, finalizzato a definire in maniera dettagliata i singoli aspetti della rigenerazione ricomprendente le lettere c), d), e), f), g) e h) del medesimo comma.<\/p>\n<p>La diversa formulazione del comma, come suggerito, consentir\u00e0 anche ai comuni di media e piccola dimensione, che non dispongono solitamente di uffici tecnici molto strutturati, di avviare la procedura prevista dalla legge regionale, attraverso uno strumento snello di carattere generale, per arrivare poi all\u2019attivazione concreta dei progetti di rigenerazione urbana, sia su iniziativa privata che su iniziativa pubblica.<\/li>\n<li>Si suggerisce di integrare l\u2019intera normativa con un richiamo alla possibilit\u00e0 di intervento mediante la costituzione di partenariati pubblico\/privati, soprattutto in aree in cui, la rigenerazione o gli interventi di recupero, possono avere una stretta integrazione ai fini del miglioramento della citt\u00e0, o comunque del tessuto urbano.<\/li>\n<\/ol>\n<p>Da ultimo preme rilevare come l\u2019evento sismico dell\u2019agosto dello scorso anno abbia evidenziato una marcata debolezza dei borghi antichi della nostra Regione: sono tanti e quasi sempre affetti da una sensibile azione di spopolamento, con un patrimonio edilizio fortemente degradato. Questa legge potrebbe costituire l\u2019occasione per indirizzare specifici interventi di recupero mediante operazioni di semplificazione normativa per i comuni e per i privati, ma anche di incentivazione al recupero:<\/p>\n<ul>\n<li>di carattere finanziario con l\u2019utilizzazione puntuale dei fondi previsti nei programmi operativi dei fondi strutturali, ovvero con altre risorse disponibili;<\/li>\n<li>di carattere normativo, come l\u2019utilizzazione di sottotetti in deroga, la riduzione delle altezze o delle ampiezze minime per l\u2019attivazione di esercizi pubblici, la facolt\u00e0 dei comuni di operare riduzioni dei costi di costruzione o di esonero o riduzione di tasse, ecc.<\/li>\n<\/ul>\n<p>Osservazioni, queste, accolte e fatte proprie anche dal Consiglio delle Autonomie Locali.<\/p>\n<p class=\"italic\">ANCI LAZIO<\/p>\n<p class=\"italic\">\u00a9 ANCI LAZIO<\/p>\n<p class=\"fsize10\">(24 maggio 2017)<\/p>\n<p>\u00a9 RIPRODUZIONE CONSENTITA <a href=\"http:\/\/www.dati.gov.it\/iodl\/2.0\/\" target=\"_blank\">Italian Open Data License 2.0<\/a><br \/>\n(indicazione fonte e, se possibile, link a pagina)<\/p>\n<div class=\"relatedContent\">\n<h4 class=\"centered\">Potrebbe Interessarti<\/h4>\n<\/div>\n<p><img decoding=\"async\" src=\"https:\/\/comunicacity.net\/anci-lazio\/wp-content\/uploads\/sites\/12\/2017\/11\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale.jpg\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Condividi la notizia Rigenerazione urbana Rigenerazione urbana, le osservazioni di ANCI Lazio alla proposta di legge regionale ANCI Lazio ha presentato le proprie osservazioni al fine di migliorare la proposta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":314,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[29],"class_list":["post-313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni","tag-anci-lazio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rigenerazione urbana, le osservazioni di ANCI Lazio alla proposta di legge regionale - ANCI Lazio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/anci-lazio\/2017\/05\/24\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rigenerazione urbana, le osservazioni di ANCI Lazio alla proposta di legge regionale - ANCI Lazio\" \/>\n<meta property=\"og:description\" content=\"Condividi la notizia Rigenerazione urbana Rigenerazione urbana, le osservazioni di ANCI Lazio alla proposta di legge regionale ANCI Lazio ha presentato le proprie osservazioni al fine di migliorare la proposta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/anci-lazio\/2017\/05\/24\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\/\" \/>\n<meta property=\"og:site_name\" content=\"ANCI Lazio\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-24T11:34:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-19T20:44:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/anci-lazio\/wp-content\/uploads\/sites\/12\/2017\/11\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/05\\\/24\\\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/05\\\/24\\\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Rigenerazione urbana, le osservazioni di ANCI Lazio alla proposta di legge regionale\",\"datePublished\":\"2017-05-24T11:34:14+00:00\",\"dateModified\":\"2017-12-19T20:44:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/05\\\/24\\\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\\\/\"},\"wordCount\":713,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/05\\\/24\\\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2017\\\/11\\\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale.jpg\",\"keywords\":[\"anci lazio\"],\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/05\\\/24\\\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/05\\\/24\\\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\\\/\",\"name\":\"Rigenerazione urbana, le osservazioni di ANCI Lazio alla proposta di legge regionale - ANCI Lazio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/05\\\/24\\\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/05\\\/24\\\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2017\\\/11\\\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale.jpg\",\"datePublished\":\"2017-05-24T11:34:14+00:00\",\"dateModified\":\"2017-12-19T20:44:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/05\\\/24\\\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/05\\\/24\\\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/05\\\/24\\\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2017\\\/11\\\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2017\\\/11\\\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/05\\\/24\\\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rigenerazione urbana, le osservazioni di ANCI Lazio alla proposta di legge regionale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/\",\"name\":\"ANCI Lazio\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rigenerazione urbana, le osservazioni di ANCI Lazio alla proposta di legge regionale - ANCI Lazio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/anci-lazio\/2017\/05\/24\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\/","og_locale":"it_IT","og_type":"article","og_title":"Rigenerazione urbana, le osservazioni di ANCI Lazio alla proposta di legge regionale - ANCI Lazio","og_description":"Condividi la notizia Rigenerazione urbana Rigenerazione urbana, le osservazioni di ANCI Lazio alla proposta di legge regionale ANCI Lazio ha presentato le proprie osservazioni al fine di migliorare la proposta [&hellip;]","og_url":"https:\/\/comunicacity.net\/anci-lazio\/2017\/05\/24\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\/","og_site_name":"ANCI Lazio","article_published_time":"2017-05-24T11:34:14+00:00","article_modified_time":"2017-12-19T20:44:16+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/comunicacity.net\/anci-lazio\/wp-content\/uploads\/sites\/12\/2017\/11\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/05\/24\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/05\/24\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/anci-lazio\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Rigenerazione urbana, le osservazioni di ANCI Lazio alla proposta di legge regionale","datePublished":"2017-05-24T11:34:14+00:00","dateModified":"2017-12-19T20:44:16+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/05\/24\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\/"},"wordCount":713,"image":{"@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/05\/24\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/anci-lazio\/wp-content\/uploads\/sites\/12\/2017\/11\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale.jpg","keywords":["anci lazio"],"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/05\/24\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\/","url":"https:\/\/comunicacity.net\/anci-lazio\/2017\/05\/24\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\/","name":"Rigenerazione urbana, le osservazioni di ANCI Lazio alla proposta di legge regionale - ANCI Lazio","isPartOf":{"@id":"https:\/\/comunicacity.net\/anci-lazio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/05\/24\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/05\/24\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/anci-lazio\/wp-content\/uploads\/sites\/12\/2017\/11\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale.jpg","datePublished":"2017-05-24T11:34:14+00:00","dateModified":"2017-12-19T20:44:16+00:00","author":{"@id":"https:\/\/comunicacity.net\/anci-lazio\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/05\/24\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/anci-lazio\/2017\/05\/24\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/05\/24\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\/#primaryimage","url":"https:\/\/comunicacity.net\/anci-lazio\/wp-content\/uploads\/sites\/12\/2017\/11\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale.jpg","contentUrl":"https:\/\/comunicacity.net\/anci-lazio\/wp-content\/uploads\/sites\/12\/2017\/11\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/05\/24\/rigenerazione-urbana-le-osservazioni-di-anci-lazio-alla-proposta-di-legge-regionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/anci-lazio\/"},{"@type":"ListItem","position":2,"name":"Rigenerazione urbana, le osservazioni di ANCI Lazio alla proposta di legge regionale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/anci-lazio\/#website","url":"https:\/\/comunicacity.net\/anci-lazio\/","name":"ANCI Lazio","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/anci-lazio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/anci-lazio\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/anci-lazio\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/posts\/313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/comments?post=313"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/posts\/313\/revisions"}],"predecessor-version":[{"id":402,"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/posts\/313\/revisions\/402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/media\/314"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/media?parent=313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/categories?post=313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/tags?post=313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}