{"id":362,"date":"2017-12-05T14:30:22","date_gmt":"2017-12-05T13:30:22","guid":{"rendered":"https:\/\/comunicacity.net\/anci-lazio\/2017\/12\/05\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\/"},"modified":"2017-12-19T21:52:07","modified_gmt":"2017-12-19T20:52:07","slug":"amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/anci-lazio\/2017\/12\/05\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\/","title":{"rendered":"Amministrative 2018, l&#8217;elenco dei comuni che andranno al voto"},"content":{"rendered":"<div class=\"socialBarFixed\">\n<p>Condividi la notizia<\/p>\n<\/div>\n<p class=\"occhielloPrimoPiano\">Amministrative 2018<\/p>\n<h2 class=\"newsTitleMedium newsPageTitle\">Amministrative 2018, l&#8217;elenco dei comuni che andranno al voto<\/h2>\n<p class=\"italic darkgray grayBorderBottom paddingBottom1em\">L&#8217;elenco dei comuni del Lazio interessati dalle elezioni amministrative del 2018<\/p>\n<p>Le elezioni amministrative 2018 si terranno in una data compresa tra il 15 aprile e il 15 giugno.<\/p>\n<p>Da segnalare che l&#8217;elenco dei comuni \u00e8 ancora provvisorio perch\u00e9 a questi si potrebbero aggiungere altre eventuali amministrazioni i cui consigli comunali\u00a0dovessero essere sciolti entro il 24 febbraio 2018.<\/p>\n<p>L&#8217;elenco \u00e8 disponibile in allegato.<\/p>\n<p class=\"italic\">Anci Lazio<\/p>\n<p class=\"italic\">\u00a9 ANCI LAZIO<\/p>\n<p class=\"fsize10\">(5 dicembre 2017)<\/p>\n<p>\u00a9 RIPRODUZIONE CONSENTITA <a href=\"http:\/\/www.dati.gov.it\/iodl\/2.0\/\" target=\"_blank\">Italian Open Data License 2.0<\/a><br \/>\n(indicazione fonte e, se possibile, link a pagina)<\/p>\n<div class=\"relatedContent\">\n<h4 class=\"centered\">Potrebbe Interessarti<\/h4>\n<div id=\"searchList\"><\/div>\n<\/div>\n<p><img decoding=\"async\" src=\"https:\/\/comunicacity.net\/anci-lazio\/wp-content\/uploads\/sites\/12\/2017\/12\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto.jpg\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Condividi la notizia Amministrative 2018 Amministrative 2018, l&#8217;elenco dei comuni che andranno al voto L&#8217;elenco dei comuni del Lazio interessati dalle elezioni amministrative del 2018 Le elezioni amministrative 2018 si [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":363,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[29],"class_list":["post-362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni","tag-anci-lazio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Amministrative 2018, l&#039;elenco dei comuni che andranno al voto - ANCI Lazio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/anci-lazio\/2017\/12\/05\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amministrative 2018, l&#039;elenco dei comuni che andranno al voto - ANCI Lazio\" \/>\n<meta property=\"og:description\" content=\"Condividi la notizia Amministrative 2018 Amministrative 2018, l&#8217;elenco dei comuni che andranno al voto L&#8217;elenco dei comuni del Lazio interessati dalle elezioni amministrative del 2018 Le elezioni amministrative 2018 si [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/anci-lazio\/2017\/12\/05\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\/\" \/>\n<meta property=\"og:site_name\" content=\"ANCI Lazio\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-05T13:30:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-19T20:52:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/anci-lazio\/wp-content\/uploads\/sites\/12\/2017\/12\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/12\\\/05\\\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/12\\\/05\\\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Amministrative 2018, l&#8217;elenco dei comuni che andranno al voto\",\"datePublished\":\"2017-12-05T13:30:22+00:00\",\"dateModified\":\"2017-12-19T20:52:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/12\\\/05\\\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\\\/\"},\"wordCount\":97,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/12\\\/05\\\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2017\\\/12\\\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto.jpg\",\"keywords\":[\"anci lazio\"],\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/12\\\/05\\\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/12\\\/05\\\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\\\/\",\"name\":\"Amministrative 2018, l'elenco dei comuni che andranno al voto - ANCI Lazio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/12\\\/05\\\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/12\\\/05\\\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2017\\\/12\\\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto.jpg\",\"datePublished\":\"2017-12-05T13:30:22+00:00\",\"dateModified\":\"2017-12-19T20:52:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/12\\\/05\\\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/12\\\/05\\\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/12\\\/05\\\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2017\\\/12\\\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2017\\\/12\\\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto.jpg\",\"width\":800,\"height\":534},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/2017\\\/12\\\/05\\\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amministrative 2018, l&#8217;elenco dei comuni che andranno al voto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/\",\"name\":\"ANCI Lazio\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/anci-lazio\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amministrative 2018, l'elenco dei comuni che andranno al voto - ANCI Lazio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/anci-lazio\/2017\/12\/05\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\/","og_locale":"it_IT","og_type":"article","og_title":"Amministrative 2018, l'elenco dei comuni che andranno al voto - ANCI Lazio","og_description":"Condividi la notizia Amministrative 2018 Amministrative 2018, l&#8217;elenco dei comuni che andranno al voto L&#8217;elenco dei comuni del Lazio interessati dalle elezioni amministrative del 2018 Le elezioni amministrative 2018 si [&hellip;]","og_url":"https:\/\/comunicacity.net\/anci-lazio\/2017\/12\/05\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\/","og_site_name":"ANCI Lazio","article_published_time":"2017-12-05T13:30:22+00:00","article_modified_time":"2017-12-19T20:52:07+00:00","og_image":[{"width":800,"height":534,"url":"https:\/\/comunicacity.net\/anci-lazio\/wp-content\/uploads\/sites\/12\/2017\/12\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/12\/05\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/12\/05\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/anci-lazio\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Amministrative 2018, l&#8217;elenco dei comuni che andranno al voto","datePublished":"2017-12-05T13:30:22+00:00","dateModified":"2017-12-19T20:52:07+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/12\/05\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\/"},"wordCount":97,"image":{"@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/12\/05\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/anci-lazio\/wp-content\/uploads\/sites\/12\/2017\/12\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto.jpg","keywords":["anci lazio"],"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/12\/05\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\/","url":"https:\/\/comunicacity.net\/anci-lazio\/2017\/12\/05\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\/","name":"Amministrative 2018, l'elenco dei comuni che andranno al voto - ANCI Lazio","isPartOf":{"@id":"https:\/\/comunicacity.net\/anci-lazio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/12\/05\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/12\/05\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/anci-lazio\/wp-content\/uploads\/sites\/12\/2017\/12\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto.jpg","datePublished":"2017-12-05T13:30:22+00:00","dateModified":"2017-12-19T20:52:07+00:00","author":{"@id":"https:\/\/comunicacity.net\/anci-lazio\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/12\/05\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/anci-lazio\/2017\/12\/05\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/12\/05\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\/#primaryimage","url":"https:\/\/comunicacity.net\/anci-lazio\/wp-content\/uploads\/sites\/12\/2017\/12\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto.jpg","contentUrl":"https:\/\/comunicacity.net\/anci-lazio\/wp-content\/uploads\/sites\/12\/2017\/12\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto.jpg","width":800,"height":534},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/anci-lazio\/2017\/12\/05\/amministrative-2018-lelenco-dei-comuni-che-andranno-al-voto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/anci-lazio\/"},{"@type":"ListItem","position":2,"name":"Amministrative 2018, l&#8217;elenco dei comuni che andranno al voto"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/anci-lazio\/#website","url":"https:\/\/comunicacity.net\/anci-lazio\/","name":"ANCI Lazio","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/anci-lazio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/anci-lazio\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/anci-lazio\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/posts\/362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/comments?post=362"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/posts\/362\/revisions"}],"predecessor-version":[{"id":414,"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/posts\/362\/revisions\/414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/media\/363"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/media?parent=362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/categories?post=362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/anci-lazio\/wp-json\/wp\/v2\/tags?post=362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}