{"id":1093,"date":"2020-03-05T08:30:10","date_gmt":"2020-03-05T07:30:10","guid":{"rendered":"https:\/\/comunicacity.net\/aquino\/?p=1093"},"modified":"2020-03-04T22:26:23","modified_gmt":"2020-03-04T21:26:23","slug":"coronavirus-le-norme-del-nuovo-decreto-del-governo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/aquino\/2020\/03\/05\/coronavirus-le-norme-del-nuovo-decreto-del-governo\/","title":{"rendered":"Coronavirus, le norme del nuovo decreto del governo"},"content":{"rendered":"<p>Elenco completo delle nuove norme contenute nell&#8217;ultimo decreto del <strong>Presidente del Consiglio dei Ministri<\/strong> per fronteggiare l&#8217;epidemia <strong>Coronavirus<\/strong>.<\/p>\n<p><strong>STOP A CONGRESSI MEDICI<\/strong> &#8211; Sull\u2019intero territorio nazionale sono sospesi i congressi, le riunioni, i meeting e gli eventi sociali, in cui \u00e8 coinvolto personale sanitario o personale incaricato dello svolgimento di servizi pubblici essenziali o di pubblica utilit\u00e0; \u00e8 altres\u00ec differita a data successiva al termine di efficacia del presente decreto ogni altra attivit\u00e0 convegnistica o congressuale.<\/p>\n<p><strong>STOP A MANIFESTAZIONI ED EVENTI<\/strong> &#8211; Sono sospese le manifestazioni e gli eventi di qualsiasi natura, svolti in ogni luogo, sia pubblico sia privato, che comportano affollamento di persone tale da non consentire il rispetto della distanza di sicurezza interpersonale di almeno un metro.<\/p>\n<p><strong>SPORT A PORTE CHIUSE<\/strong> &#8211; Sono sospesi altres\u00ec gli eventi e le competizioni sportive di ogni ordine e disciplina, svolti in ogni luogo, sia pubblico sia privato; resta comunque consentito lo svolgimento dei predetti eventi e competizioni, nonch\u00e9 delle sedute di allenamento degli atleti agonisti, all&#8217;interno di impianti sportivi utilizzati a porte chiuse, ovvero all&#8217;aperto senza la presenza di pubblico; in tutti tali casi, le associazioni e le societ\u00e0 sportive, a mezzo del proprio personale medico, sono tenute ad effettuare i controlli idonei a contenere il rischio di diffusione del virus Covid-19 tra gli atleti, i tecnici, i dirigenti e tutti gli accompagnatori che vi partecipano. Lo sport di base e le attivit\u00e0 motorie in genere, svolte all&#8217;aperto ovvero all&#8217;interno di palestre, piscine e centri sportivi di ogni tipo, sono ammessi esclusivamente a condizione che sia possibile consentire il rispetto della raccomandazione di cui all&#8217;allegato 1, lettera d ovvero il rispetto di norme igieniche.<\/p>\n<p><strong>SCUOLE E UNIVERSIT\u00c0 CHIUSE, POSSIBILE ATTIVIT\u00c0 DIDATTICA A DISTANZA<\/strong> &#8211; Limitatamente al periodo intercorrente dal giorno successivo a quello di efficacia del presente decreto e fino al 15 marzo 2020, sono sospesi i servizi educativi per l\u2019infanzia e le attivit\u00e0 didattiche nelle scuole di ogni ordine e grado, nonch\u00e9 la frequenza delle attivit\u00e0 scolastiche e di formazione superiore, comprese le Universit\u00e0 e le Istituzioni di Alta Formazione Artistica Musicale e Coreutica, di corsi professionali, master e universit\u00e0 per anziani, ferma in ogni caso la possibilit\u00e0 di svolgimento di attivit\u00e0 formative a distanza.<\/p>\n<p><strong>ESCLUSI DA STOP CORSI PER PROFESSIONI SANITARIE<\/strong> &#8211; Sono esclusi dalla sospensione i corsi post universitari connessi con l\u2019esercizio di professioni sanitarie, ivi inclusi quelli per i medici in formazione specialistica, i corsi di formazione specifica in medicina generale, le attivit\u00e0 dei tirocinanti delle professioni sanitarie, nonch\u00e9 le attivit\u00e0 delle scuole di formazione attivate presso i ministeri dell\u2019interno e della difesa.<\/p>\n<p><strong>SOSPESE LE GITE D&#8217;ISTRUZIONE<\/strong> &#8211; Sono sospesi i viaggi d\u2019istruzione, le iniziative di scambio o gemellaggio, le visite guidate e le uscite didattiche comunque denominate, programmate dalle istituzioni scolastiche di ogni ordine e grado.<\/p>\n<p><strong>CERTIFICATO MEDICO DOPO 5 GIORNI DI ASSENZA<\/strong> &#8211; La riammissione nei servizi educativi per l\u2019infanzia e nelle scuole di ogni ordine e grado per assenze dovute a malattia infettiva soggetta a notifica obbligatoria ai sensi del decreto del Ministro della sanit\u00e0 del 15 novembre 1990, pubblicato nella Gazzetta Ufficiale n. 6 dell\u20198 gennaio 1991, di durata superiore a cinque giorni, avviene dietro presentazione di certificato medico, anche in deroga alle disposizioni vigenti.<\/p>\n<p><strong>DIDATTICA A DISTANZA<\/strong> &#8211; I dirigenti scolastici, sentito il collegio dei docenti, attivano, ove possibile e per tutta la durata della sospensione delle attivit\u00e0 didattiche nelle scuole, modalit\u00e0 di didattica a distanza avuto anche riguardo alle specifiche esigenze degli studenti con disabilit\u00e0.<\/p>\n<p><strong>NON CI SARANNO CONSEGUENZE SUGLI ESAMI<\/strong> &#8211; Le assenze maturate dagli studenti a causa dell&#8217;emergenza Coronavirus \u00abnon sono computate ai fini della eventuale ammissione ad esami finali nonch\u00e9 ai fini delle relative valutazioni\u00bb. a beneficio degli studenti ai quali non \u00e8 consentita, per le esigenze connesse all&#8217;emergenza.<\/p>\n<p><strong>NO AD ACCOMPAGNATORI IN PRONTO SOCCORSO, LIMITI ACCESSO IN HOSPICE<\/strong> &#8211; \u00c8 fatto divieto agli accompagnatori dei pazienti di permanere nelle sale di attesa dei dipartimenti emergenze e accettazione e dei pronto soccorso salve specifiche diverse indicazioni del personale sanitario preposto; l\u2019accesso di parenti e visitatori a strutture di ospitalit\u00e0 e lungo degenza, residenze sanitarie assistite e strutture residenziali per anziani, autosufficienti e non, \u00e8 limitata ai soli casi indicati dalla direzione sanitaria della struttura, che \u00e8 tenuta ad adottare le misure necessarie a prevenire possibili trasmissioni di infezione.<\/p>\n<p><strong>SMART WORKING<\/strong> &#8211; La modalit\u00e0 di lavoro agile pu\u00f2 essere applicata, per la durata dello stato di emergenza dai datori di lavoro a ogni rapporto di lavoro subordinato anche in assenza degli accordi individuali ivi previsti.<\/p>\n<p><strong>PRESIDI SANITARI NELLE CARCERI<\/strong> &#8211; Viene assicurato \u00abal Ministero della giustizia idoneo supporto per il contenimento della diffusione del contagio del Covid-19, anche mediante adeguati presidi idonei a garantire, secondo i protocolli sanitari elaborati dalla Direzione generale della prevenzione sanitaria del Ministero della salute, i nuovi ingressi negli istituti penitenziari e negli istituti penali per minorenni sino al termine dello stato di emergenza.<\/p>\n<p><strong>CONSIGLI PER GLI ANZIANI<\/strong> &#8211; \u00c8 fatta espressa raccomandazione a tutte le persone anziane o affette da patologie croniche o con multimorbilit\u00e0 ovvero con stati di immunodepressione congenita o acquisita, di evitare di uscire dalla propria abitazione o dimora fuori dai casi di stretta necessit\u00e0 e di evitare comunque luoghi affollati nei quali non sia possibile mantenere la distanza di sicurezza interpersonale di almeno un metro.<\/p>\n<p><strong>NORME IGIENICHE SANITARIE<\/strong>\u00a0&#8211; Si chiede a i sindaci e associazioni di categoria di promuovere \u00abla diffusione delle informazioni sulle misure di prevenzione igienico sanitarie anche presso gli esercizi commerciali\u00bb. Nelle \u00abpubbliche amministrazioni e, in particolare, nelle aree di accesso alle strutture del servizio sanitario, nonch\u00e9 in tutti i locali aperti al pubblico sono messe a disposizione degli addetti, nonch\u00e9 degli utenti e visitatori, liquidi disinfettanti per l\u2019igiene delle mani. Inoltre, le aziende di trasporto pubblico anche a lunga percorrenza adottano interventi straordinari di sanificazione dei mezzi.<\/p>\n<p><strong>INDICAZIONI PER CHI VIENE DA ZONE A RISCHIO<\/strong> &#8211; &#8216;Chiunque, a partire dal quattordicesimo giorno antecedente la data di pubblicazione del presente decreto, abbia fatto ingresso in Italia dopo aver soggiornato in zone a rischio epidemiologico, come identificate dall&#8217;Organizzazione Mondiale della Sanit\u00e0, o sia transitato o abbia sostato\u00bb nelle zone rosse \u00abdeve comunicare tale circostanza al dipartimento di prevenzione dell\u2019azienda sanitaria competente per territorio nonch\u00e9 al proprio medico di medicina generale ovvero al pediatra di libera scelta.<\/p>\n<p><strong>INDICAZIONI PER OPERATORI SANITARI<\/strong> &#8211; &#8216;L\u2019operatore di sanit\u00e0 pubblica e i servizi di sanit\u00e0 pubblica territorialmente competenti provvedono, alla prescrizione della permanenza domiciliare, secondo le modalit\u00e0 di seguito indicate: a) contattano telefonicamente e assumono informazioni, il pi\u00f9 possibile dettagliate e documentate, sulle zone di soggiorno e sul percorso del viaggio effettuato nei quattordici giorni precedenti, ai fini di una adeguata valutazione del rischio di esposizione; b) accertata la necessit\u00e0 di avviare la sorveglianza sanitaria e l\u2019isolamento fiduciario, informano dettagliatamente l\u2019interessato sulle misure da adottare, illustrandone le modalit\u00e0 e le finalit\u00e0 al fine di assicurare la massima adesione.<\/p>\n<p><strong>RICHIESTA A INPS IN CASO DI QUARANTENA<\/strong> &#8211; L\u2019operatore di sanit\u00e0 pubblica \u00abinforma il medico di medicina generale o il pediatra di libera scelta da cui il soggetto \u00e8 assistito anche ai fini dell\u2019eventuale certificazione ai fini INPS (circolare INPS HERMES 25 febbraio 2020 0000716 del 25 febbraio 2020). In caso di necessit\u00e0 di certificazione ai fini INPS per l\u2019assenza dal lavoro, si procede a rilasciare una dichiarazione indirizzata all&#8217;INPS, al datore di lavoro e al medico di medicina generale o al pediatra di libera scelta in cui si dichiara che per motivi di sanit\u00e0 pubblica \u00e8 stato posto in quarantena, specificandone la data di inizio e fine.<\/p>\n<p><strong>MISURE QUARANTENA<\/strong> &#8211; L\u2019operatore di sanit\u00e0 pubblica deve inoltre: a) accertare l\u2019assenza di febbre o altra sintomatologia del soggetto da porre in isolamento, nonch\u00e9 degli altri eventuali conviventi\u00bb. Misure per la quarantena: a) mantenimento dello stato di isolamento per quattordici giorni dall\u2019ultima esposizione; b) divieto di contatti sociali; c) divieto di spostamenti e viaggi; d) obbligo di rimanere raggiungibile per le attivit\u00e0 di sorveglianza. La mascherina chirurgica va indossata solo da chi manifesta sintomi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elenco completo delle nuove norme contenute nell&#8217;ultimo decreto del Presidente del Consiglio dei Ministri per fronteggiare l&#8217;epidemia Coronavirus. STOP A CONGRESSI MEDICI &#8211; Sull\u2019intero territorio nazionale sono sospesi i congressi, [&hellip;]<\/p>\n","protected":false},"author":248,"featured_media":1094,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-1093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coronavirus, le norme del nuovo decreto del governo - Aquino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/aquino\/2020\/03\/05\/coronavirus-le-norme-del-nuovo-decreto-del-governo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus, le norme del nuovo decreto del governo - Aquino\" \/>\n<meta property=\"og:description\" content=\"Elenco completo delle nuove norme contenute nell&#8217;ultimo decreto del Presidente del Consiglio dei Ministri per fronteggiare l&#8217;epidemia Coronavirus. STOP A CONGRESSI MEDICI &#8211; Sull\u2019intero territorio nazionale sono sospesi i congressi, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/aquino\/2020\/03\/05\/coronavirus-le-norme-del-nuovo-decreto-del-governo\/\" \/>\n<meta property=\"og:site_name\" content=\"Aquino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-05T07:30:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2020\/03\/Coronavirus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1876\" \/>\n\t<meta property=\"og:image:height\" content=\"1158\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aquino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"aquino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/03\\\/05\\\/coronavirus-le-norme-del-nuovo-decreto-del-governo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/03\\\/05\\\/coronavirus-le-norme-del-nuovo-decreto-del-governo\\\/\"},\"author\":{\"name\":\"aquino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/e3e852b37d3ce60420c3c7ae9a53f590\"},\"headline\":\"Coronavirus, le norme del nuovo decreto del governo\",\"datePublished\":\"2020-03-05T07:30:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/03\\\/05\\\/coronavirus-le-norme-del-nuovo-decreto-del-governo\\\/\"},\"wordCount\":1323,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/03\\\/05\\\/coronavirus-le-norme-del-nuovo-decreto-del-governo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2020\\\/03\\\/Coronavirus.jpg\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/03\\\/05\\\/coronavirus-le-norme-del-nuovo-decreto-del-governo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/03\\\/05\\\/coronavirus-le-norme-del-nuovo-decreto-del-governo\\\/\",\"name\":\"Coronavirus, le norme del nuovo decreto del governo - Aquino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/03\\\/05\\\/coronavirus-le-norme-del-nuovo-decreto-del-governo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/03\\\/05\\\/coronavirus-le-norme-del-nuovo-decreto-del-governo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2020\\\/03\\\/Coronavirus.jpg\",\"datePublished\":\"2020-03-05T07:30:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/e3e852b37d3ce60420c3c7ae9a53f590\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/03\\\/05\\\/coronavirus-le-norme-del-nuovo-decreto-del-governo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/03\\\/05\\\/coronavirus-le-norme-del-nuovo-decreto-del-governo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/03\\\/05\\\/coronavirus-le-norme-del-nuovo-decreto-del-governo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2020\\\/03\\\/Coronavirus.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2020\\\/03\\\/Coronavirus.jpg\",\"width\":1876,\"height\":1158},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/03\\\/05\\\/coronavirus-le-norme-del-nuovo-decreto-del-governo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus, le norme del nuovo decreto del governo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/\",\"name\":\"Aquino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/e3e852b37d3ce60420c3c7ae9a53f590\",\"name\":\"aquino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba719a8d79e65e4e71b68983752009483c3f0830c07f656da5511e73ea37178a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba719a8d79e65e4e71b68983752009483c3f0830c07f656da5511e73ea37178a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba719a8d79e65e4e71b68983752009483c3f0830c07f656da5511e73ea37178a?s=96&d=mm&r=g\",\"caption\":\"aquino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/author\\\/aquino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coronavirus, le norme del nuovo decreto del governo - Aquino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/aquino\/2020\/03\/05\/coronavirus-le-norme-del-nuovo-decreto-del-governo\/","og_locale":"it_IT","og_type":"article","og_title":"Coronavirus, le norme del nuovo decreto del governo - Aquino","og_description":"Elenco completo delle nuove norme contenute nell&#8217;ultimo decreto del Presidente del Consiglio dei Ministri per fronteggiare l&#8217;epidemia Coronavirus. STOP A CONGRESSI MEDICI &#8211; Sull\u2019intero territorio nazionale sono sospesi i congressi, [&hellip;]","og_url":"https:\/\/comunicacity.net\/aquino\/2020\/03\/05\/coronavirus-le-norme-del-nuovo-decreto-del-governo\/","og_site_name":"Aquino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-03-05T07:30:10+00:00","og_image":[{"width":1876,"height":1158,"url":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2020\/03\/Coronavirus.jpg","type":"image\/jpeg"}],"author":"aquino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"aquino","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/aquino\/2020\/03\/05\/coronavirus-le-norme-del-nuovo-decreto-del-governo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/aquino\/2020\/03\/05\/coronavirus-le-norme-del-nuovo-decreto-del-governo\/"},"author":{"name":"aquino","@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/e3e852b37d3ce60420c3c7ae9a53f590"},"headline":"Coronavirus, le norme del nuovo decreto del governo","datePublished":"2020-03-05T07:30:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/aquino\/2020\/03\/05\/coronavirus-le-norme-del-nuovo-decreto-del-governo\/"},"wordCount":1323,"image":{"@id":"https:\/\/comunicacity.net\/aquino\/2020\/03\/05\/coronavirus-le-norme-del-nuovo-decreto-del-governo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2020\/03\/Coronavirus.jpg","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/aquino\/2020\/03\/05\/coronavirus-le-norme-del-nuovo-decreto-del-governo\/","url":"https:\/\/comunicacity.net\/aquino\/2020\/03\/05\/coronavirus-le-norme-del-nuovo-decreto-del-governo\/","name":"Coronavirus, le norme del nuovo decreto del governo - Aquino","isPartOf":{"@id":"https:\/\/comunicacity.net\/aquino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/aquino\/2020\/03\/05\/coronavirus-le-norme-del-nuovo-decreto-del-governo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/aquino\/2020\/03\/05\/coronavirus-le-norme-del-nuovo-decreto-del-governo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2020\/03\/Coronavirus.jpg","datePublished":"2020-03-05T07:30:10+00:00","author":{"@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/e3e852b37d3ce60420c3c7ae9a53f590"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/aquino\/2020\/03\/05\/coronavirus-le-norme-del-nuovo-decreto-del-governo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/aquino\/2020\/03\/05\/coronavirus-le-norme-del-nuovo-decreto-del-governo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/aquino\/2020\/03\/05\/coronavirus-le-norme-del-nuovo-decreto-del-governo\/#primaryimage","url":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2020\/03\/Coronavirus.jpg","contentUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2020\/03\/Coronavirus.jpg","width":1876,"height":1158},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/aquino\/2020\/03\/05\/coronavirus-le-norme-del-nuovo-decreto-del-governo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/aquino\/"},{"@type":"ListItem","position":2,"name":"Coronavirus, le norme del nuovo decreto del governo"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/aquino\/#website","url":"https:\/\/comunicacity.net\/aquino\/","name":"Aquino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/aquino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/e3e852b37d3ce60420c3c7ae9a53f590","name":"aquino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ba719a8d79e65e4e71b68983752009483c3f0830c07f656da5511e73ea37178a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ba719a8d79e65e4e71b68983752009483c3f0830c07f656da5511e73ea37178a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ba719a8d79e65e4e71b68983752009483c3f0830c07f656da5511e73ea37178a?s=96&d=mm&r=g","caption":"aquino"},"url":"https:\/\/comunicacity.net\/aquino\/author\/aquino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/1093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/users\/248"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/comments?post=1093"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/1093\/revisions"}],"predecessor-version":[{"id":1097,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/1093\/revisions\/1097"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/media\/1094"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/media?parent=1093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/categories?post=1093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/tags?post=1093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}