{"id":1375,"date":"2020-11-07T11:15:13","date_gmt":"2020-11-07T10:15:13","guid":{"rendered":"https:\/\/comunicacity.net\/aquino\/?p=1375"},"modified":"2020-11-07T11:15:13","modified_gmt":"2020-11-07T10:15:13","slug":"aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/aquino\/2020\/11\/07\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\/","title":{"rendered":"Aquino \u2013 Ultimati i lavori di ampliamento del Cimitero Comunale."},"content":{"rendered":"<h6>Nella giornata dedicata alla festivit\u00e0 dei Santi, l\u2019Amministrazione Comunale di Aquino, presieduta dal Sindaco Libero Mazzaroppi, ha inaugurato il 1\u00b0 lotto funzionale dell\u2019Ampliamento del Nuovo Cimitero cittadino.<\/h6>\n<hr \/>\n<p class=\"caps\">Il Parroco don Tommaso, prima della celebrazione della Santa Messa, alla presenza dell\u2019Amministrazione, dei Comandanti dei Carabinieri Parrillo e della Polizia Locale Fusco, ha impartito la Benedizione alla nuova area recintata e ai loculi di recente realizzazione.<br \/>\nL\u2019individuazione degli spazi destinati all\u2019ampliamento \u00e8 stata portata a termine dopo una lunga serie di interventi, talvolta travagliati ed ostacolati dalla rigida burocrazia, che con saggezza e grande competenza la Giunta aquinate ha saputo gestire e risolvere dopo aver vinto anche una lunga battaglia giudiziaria nei competenti tribunali amministrativi \u2013 si legge in una nota comunale \u2013<br \/>\nOggi l\u2019area, finalmente, dopo aver ottenuto una definitiva variante al Prg \u00e8 rigorosamente prevista negli strumenti urbanistici cittadini e disponibile per ulteriori installazioni e infrastrutture.<br \/>\nIl principio fondamentale che ha guidato la progettazione \u00e8 stato quello di limitare al massimo l\u2019impatto ambientale prevedendo la realizzazione di 3 lotti funzionali oltre a molte porzioni di terreno, messe a disposizione dei privati, ove \u00e8 prevista la possibilit\u00e0 di costruire le Cappelle Gentilizie.<br \/>\nMolte persone hanno partecipato al momento solenne e di preghiera rigorosamente svolto nel massimo rispetto delle normative di sicurezza e di igiene previste in materia di contenimento del Covid19.<br \/>\nPresenti i tecnici che hanno curato la progettazione e la sicurezza Giangrande e Risi oltre alla Responsabile dell\u2019Utc l\u2019ing. Daniela Ciolfi ed al Responsabile dell\u2019impresa esecutrice dei lavori il geom. Nicoletti.<br \/>\nIl Sindaco Libero Mazzaroppi ha espresso la sua soddisfazione con una parola: \u201cfinalmente\u201d.<br \/>\nOggi, con la dovuta serenit\u00e0 e senza fare polemica, mettiamo un punto e scriviamo la parola fine a tanti anni di diatribe ingiuste e, soprattutto, di accuse infondate rivolte alla mia amministrazione.<br \/>\nE\u2019 un fatto importante che portiamo a compimento \u2013 continua il Sindaco \u2013 dato che in pochi credevano nella nostra grande capacit\u00e0 e nella tenacia messa in campo per portare a casa un risultato cos\u00ec importante e vedere realizzata un\u2019opera che i nostri concittadini attendevano da troppo, lungo, tempo.<br \/>\nLegittime parole di compiacimento e sincera partecipazione sono state espresse anche dal delegato alle Politiche Cimiteriali il Pres. Maurizio Gabriele e dall\u2019Ass. ai Lavori Pubblici Andrea Capraro.<br \/>\nGabriele ha detto: ha vinto la squadra e l\u2019intelligenza che abbiamo saputo azionare per gestire una situazione che, in alcuni momenti, aveva assunto dimensioni molto difficili da risolvere. Oggi gioiamo perch\u00e9 siamo certi di aver reso un utile servizio alla Citt\u00e0.<br \/>\nCapraro ha voluto ringraziare tutte le strutture tecniche e amministrative che si sono impegnate nel corso dell\u2019opera non dimenticando di menzionare l\u2019utile lavoro svolto dal Vicesindaco Carlo Risi nel momento in cui la vicenda aveva assunto una dimensione giuridica da valutare con attenzione e competenza.<br \/>\nOggi, quindi, vince Aquino nella sua interezza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella giornata dedicata alla festivit\u00e0 dei Santi, l\u2019Amministrazione Comunale di Aquino, presieduta dal Sindaco Libero Mazzaroppi, ha inaugurato il 1\u00b0 lotto funzionale dell\u2019Ampliamento del Nuovo Cimitero cittadino. Il Parroco don [&hellip;]<\/p>\n","protected":false},"author":247,"featured_media":1376,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aquino \u2013 Ultimati i lavori di ampliamento del Cimitero Comunale. - Aquino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/aquino\/2020\/11\/07\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aquino \u2013 Ultimati i lavori di ampliamento del Cimitero Comunale. - Aquino\" \/>\n<meta property=\"og:description\" content=\"Nella giornata dedicata alla festivit\u00e0 dei Santi, l\u2019Amministrazione Comunale di Aquino, presieduta dal Sindaco Libero Mazzaroppi, ha inaugurato il 1\u00b0 lotto funzionale dell\u2019Ampliamento del Nuovo Cimitero cittadino. Il Parroco don [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/aquino\/2020\/11\/07\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\/\" \/>\n<meta property=\"og:site_name\" content=\"Aquino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-07T10:15:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2020\/11\/3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoaquino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoaquino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/11\\\/07\\\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/11\\\/07\\\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\\\/\"},\"author\":{\"name\":\"sindacoaquino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/505a48e2bc4e4ec4452ec8f55932b961\"},\"headline\":\"Aquino \u2013 Ultimati i lavori di ampliamento del Cimitero Comunale.\",\"datePublished\":\"2020-11-07T10:15:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/11\\\/07\\\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\\\/\"},\"wordCount\":479,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/11\\\/07\\\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2020\\\/11\\\/3.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/11\\\/07\\\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/11\\\/07\\\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\\\/\",\"name\":\"Aquino \u2013 Ultimati i lavori di ampliamento del Cimitero Comunale. - Aquino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/11\\\/07\\\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/11\\\/07\\\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2020\\\/11\\\/3.jpg\",\"datePublished\":\"2020-11-07T10:15:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/505a48e2bc4e4ec4452ec8f55932b961\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/11\\\/07\\\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/11\\\/07\\\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/11\\\/07\\\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2020\\\/11\\\/3.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2020\\\/11\\\/3.jpg\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2020\\\/11\\\/07\\\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aquino \u2013 Ultimati i lavori di ampliamento del Cimitero Comunale.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/\",\"name\":\"Aquino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/505a48e2bc4e4ec4452ec8f55932b961\",\"name\":\"sindacoaquino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g\",\"caption\":\"sindacoaquino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/author\\\/sindacoaquino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aquino \u2013 Ultimati i lavori di ampliamento del Cimitero Comunale. - Aquino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/aquino\/2020\/11\/07\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\/","og_locale":"it_IT","og_type":"article","og_title":"Aquino \u2013 Ultimati i lavori di ampliamento del Cimitero Comunale. - Aquino","og_description":"Nella giornata dedicata alla festivit\u00e0 dei Santi, l\u2019Amministrazione Comunale di Aquino, presieduta dal Sindaco Libero Mazzaroppi, ha inaugurato il 1\u00b0 lotto funzionale dell\u2019Ampliamento del Nuovo Cimitero cittadino. Il Parroco don [&hellip;]","og_url":"https:\/\/comunicacity.net\/aquino\/2020\/11\/07\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\/","og_site_name":"Aquino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-11-07T10:15:13+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2020\/11\/3.jpg","type":"image\/jpeg"}],"author":"sindacoaquino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoaquino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/aquino\/2020\/11\/07\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/aquino\/2020\/11\/07\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\/"},"author":{"name":"sindacoaquino","@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/505a48e2bc4e4ec4452ec8f55932b961"},"headline":"Aquino \u2013 Ultimati i lavori di ampliamento del Cimitero Comunale.","datePublished":"2020-11-07T10:15:13+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/aquino\/2020\/11\/07\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\/"},"wordCount":479,"image":{"@id":"https:\/\/comunicacity.net\/aquino\/2020\/11\/07\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2020\/11\/3.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/aquino\/2020\/11\/07\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\/","url":"https:\/\/comunicacity.net\/aquino\/2020\/11\/07\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\/","name":"Aquino \u2013 Ultimati i lavori di ampliamento del Cimitero Comunale. - Aquino","isPartOf":{"@id":"https:\/\/comunicacity.net\/aquino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/aquino\/2020\/11\/07\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/aquino\/2020\/11\/07\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2020\/11\/3.jpg","datePublished":"2020-11-07T10:15:13+00:00","author":{"@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/505a48e2bc4e4ec4452ec8f55932b961"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/aquino\/2020\/11\/07\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/aquino\/2020\/11\/07\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/aquino\/2020\/11\/07\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\/#primaryimage","url":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2020\/11\/3.jpg","contentUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2020\/11\/3.jpg","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/aquino\/2020\/11\/07\/aquino-ultimati-i-lavori-di-ampliamento-del-cimitero-comunale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/aquino\/"},{"@type":"ListItem","position":2,"name":"Aquino \u2013 Ultimati i lavori di ampliamento del Cimitero Comunale."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/aquino\/#website","url":"https:\/\/comunicacity.net\/aquino\/","name":"Aquino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/aquino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/505a48e2bc4e4ec4452ec8f55932b961","name":"sindacoaquino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g","caption":"sindacoaquino"},"url":"https:\/\/comunicacity.net\/aquino\/author\/sindacoaquino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/1375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/users\/247"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/comments?post=1375"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/1375\/revisions"}],"predecessor-version":[{"id":1377,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/1375\/revisions\/1377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/media\/1376"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/media?parent=1375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/categories?post=1375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/tags?post=1375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}