{"id":1498,"date":"2021-05-01T17:18:32","date_gmt":"2021-05-01T15:18:32","guid":{"rendered":"https:\/\/comunicacity.net\/aquino\/?p=1498"},"modified":"2021-05-01T17:18:32","modified_gmt":"2021-05-01T15:18:32","slug":"aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/aquino\/2021\/05\/01\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\/","title":{"rendered":"Aquino \u2013 La bella storia di Santina, della sua vecchia bici e del Comandante Fusco"},"content":{"rendered":"<header class=\"single-entry-header\">\n<h1 class=\"single-entry-title entry-title\">Le rubano la bici durante la visita a un conoscente, ritrovata grazie alle telecamere<\/h1>\n<div class=\"single-entry-meta\"><span class=\"posted-on\"><a href=\"https:\/\/www.leggocassino.it\/2021\/04\/30\/rubano-la-bici-durante-la-visita-a-un-conoscente-ritrovata-grazie-alle-telecamere\/\" rel=\"bookmark\">30 Aprile 2021<\/a><\/span><span class=\"byline\">\u00a0<span class=\"author vcard\"><a class=\"url fn n\" href=\"https:\/\/www.leggocassino.it\/author\/alberto-simone\/\">Alberto Simone<\/a><\/span><\/span><\/div>\n<\/header>\n<div class=\"entry-content\">\n<p class=\"has-custom-font\"><strong>AQUINO\u00a0<\/strong>\u2013 Il comandante della Polizia Locale, Nello Fusco, ha subito attivato le indagini. Il sindaco: \u201cIl valore affettivo di ogni bene, anche quello apparentemente pi\u00f9 insignificante, talvolta \u00e8 inestimabile\u201d<\/p>\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" class=\"wp-image-12777 lazyloaded\" src=\"https:\/\/www.leggocassino.it\/wp-content\/uploads\/2021\/04\/riconsegna-bici-1024x980.jpg\" alt=\"\" data-src=\"https:\/\/www.leggocassino.it\/wp-content\/uploads\/2021\/04\/riconsegna-bici-1024x980.jpg\" \/><\/figure>\n<p class=\"has-drop-cap\">Una storia a lieto fine. Lo scorso 27 aprile una signora anziana si reca a far visita ad una conoscente in sella alla sua bicicletta. Dopo pochi minuti non trova pi\u00f9 la bicicletta poggiata al cancello dove l\u2019aveva lasciata. Non riesce a trovarla in giro per la citt\u00e0. Informa la Polizia Locale ma non intende sporgere denuncia ed inizia a cercarla con l\u2019aiuto di conoscenti.<\/p>\n<p>Intanto la Polizia Locale si attiva ed inizia le indagini grazie all\u2019impianto di videosorveglianza della citt\u00e0, alle informazioni assunte, ai sopralluoghi degli agenti, la bici viene ritrovata dal Comandante della Polizia Locale abbandonata in un posto impervio e riconsegnata in meno di 48 alla legittima proprietaria nella giornata di ieri.<\/p>\n<p>il valore commerciale della bici \u00e8 irrisorio, quello affettivo incalcolabile, la bici accompagna da oltre 40 anni l\u2019anziana signora. Alla riconsegna, occhi lucidi della signora e del marito (anch\u2019egli amante delle passeggiate in sella alla sua bici ed orfano per un paio di giorni della compagnia della moglie). Curiosit\u00e0: stupore, saluti e sorrisi da parte della cittadinanza vedere transitare il Comandante dei Vigili per le vie cittadine in sella ad una bici \u201cvecchia\u201d dopo il ritrovamento per far ritorno presso gli uffici comunali.<\/p>\n<p>Il Comandante Nello Fusco dice: \u201cIo ed i miei collaboratori, cerchiamo ogni giorno di rendere un servizio utile alla cittadinanza. Alla richiesta di aiuto di una cittadina ci siamo subito adoperati per risolvere quello che a molti \u00e8 sembrata una cosa di poco conto, come pu\u00f2 essere il furto di una vecchia bicicletta, ma che per l\u2019interessata aveva fondamentale importanza. L\u2019aver ridato felicit\u00e0 ad una nostra concittadina ci riempie di orgoglio e ci fa stare bene\u201d.<\/p>\n<p>Il Consigliere delegato Federica Sabatini aggiunge: \u201cVoglio esprimere la mia gratitudine al Comandante e agli Agenti della Polizia Locale per l\u2019impegno profuso costantemente al servizio dell\u2019intera comunit\u00e0. In questi ultimi tempi le situazioni delicate da gestire sono state innumerevoli, soprattutto a causa dell\u2019emergenza sanitaria scoppiata nel nostro paese, e la Polizia Locale ha sempre fatto prevalere, unitamente al rispetto della osservanza delle norme, la capacit\u00e0 di comprensione, tolleranza e solidariet\u00e0\u201d.<\/p>\n<p>Il Sindaco Libero Mazzaroppi chiosa: \u201cIl gesto prezioso del nostro Comandante Nello Fusco impreziosisce la nobilt\u00e0 del suo servizio e di quello dei suoi collaboratori. \u00c8 un momento di vicinanza al cittadino e di umanit\u00e0 che ha ridato gioia e sorriso alla nostra cara Santina. Il valore affettivo di ogni bene, anche quello apparentemente pi\u00f9 insignificante, talvolta \u00e8 inestimabile. Ringrazio quindi il Comandante Fusco che non ha sottovalutato neppure un crimine che, seppur recepito dai pi\u00f9 di poco conto assume invece, anche a mio avviso un carattere essenziale che denota senso del dovere e spirito di servizio davvero encomiabili.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le rubano la bici durante la visita a un conoscente, ritrovata grazie alle telecamere 30 Aprile 2021\u00a0Alberto Simone AQUINO\u00a0\u2013 Il comandante della Polizia Locale, Nello Fusco, ha subito attivato le [&hellip;]<\/p>\n","protected":false},"author":247,"featured_media":1499,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pubblica-sicurezza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aquino \u2013 La bella storia di Santina, della sua vecchia bici e del Comandante Fusco - Aquino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/aquino\/2021\/05\/01\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aquino \u2013 La bella storia di Santina, della sua vecchia bici e del Comandante Fusco - Aquino\" \/>\n<meta property=\"og:description\" content=\"Le rubano la bici durante la visita a un conoscente, ritrovata grazie alle telecamere 30 Aprile 2021\u00a0Alberto Simone AQUINO\u00a0\u2013 Il comandante della Polizia Locale, Nello Fusco, ha subito attivato le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/aquino\/2021\/05\/01\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\/\" \/>\n<meta property=\"og:site_name\" content=\"Aquino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-01T15:18:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2021\/05\/riconsegna-bici-1024x980-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoaquino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoaquino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2021\\\/05\\\/01\\\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2021\\\/05\\\/01\\\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\\\/\"},\"author\":{\"name\":\"sindacoaquino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/505a48e2bc4e4ec4452ec8f55932b961\"},\"headline\":\"Aquino \u2013 La bella storia di Santina, della sua vecchia bici e del Comandante Fusco\",\"datePublished\":\"2021-05-01T15:18:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2021\\\/05\\\/01\\\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\\\/\"},\"wordCount\":505,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2021\\\/05\\\/01\\\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2021\\\/05\\\/riconsegna-bici-1024x980-1.jpg\",\"articleSection\":[\"Pubblica Sicurezza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2021\\\/05\\\/01\\\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2021\\\/05\\\/01\\\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\\\/\",\"name\":\"Aquino \u2013 La bella storia di Santina, della sua vecchia bici e del Comandante Fusco - Aquino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2021\\\/05\\\/01\\\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2021\\\/05\\\/01\\\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2021\\\/05\\\/riconsegna-bici-1024x980-1.jpg\",\"datePublished\":\"2021-05-01T15:18:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/505a48e2bc4e4ec4452ec8f55932b961\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2021\\\/05\\\/01\\\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2021\\\/05\\\/01\\\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2021\\\/05\\\/01\\\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2021\\\/05\\\/riconsegna-bici-1024x980-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2021\\\/05\\\/riconsegna-bici-1024x980-1.jpg\",\"width\":1024,\"height\":980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2021\\\/05\\\/01\\\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aquino \u2013 La bella storia di Santina, della sua vecchia bici e del Comandante Fusco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/\",\"name\":\"Aquino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/505a48e2bc4e4ec4452ec8f55932b961\",\"name\":\"sindacoaquino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g\",\"caption\":\"sindacoaquino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/author\\\/sindacoaquino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aquino \u2013 La bella storia di Santina, della sua vecchia bici e del Comandante Fusco - Aquino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/aquino\/2021\/05\/01\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\/","og_locale":"it_IT","og_type":"article","og_title":"Aquino \u2013 La bella storia di Santina, della sua vecchia bici e del Comandante Fusco - Aquino","og_description":"Le rubano la bici durante la visita a un conoscente, ritrovata grazie alle telecamere 30 Aprile 2021\u00a0Alberto Simone AQUINO\u00a0\u2013 Il comandante della Polizia Locale, Nello Fusco, ha subito attivato le [&hellip;]","og_url":"https:\/\/comunicacity.net\/aquino\/2021\/05\/01\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\/","og_site_name":"Aquino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-05-01T15:18:32+00:00","og_image":[{"width":1024,"height":980,"url":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2021\/05\/riconsegna-bici-1024x980-1.jpg","type":"image\/jpeg"}],"author":"sindacoaquino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoaquino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/aquino\/2021\/05\/01\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/aquino\/2021\/05\/01\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\/"},"author":{"name":"sindacoaquino","@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/505a48e2bc4e4ec4452ec8f55932b961"},"headline":"Aquino \u2013 La bella storia di Santina, della sua vecchia bici e del Comandante Fusco","datePublished":"2021-05-01T15:18:32+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/aquino\/2021\/05\/01\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\/"},"wordCount":505,"image":{"@id":"https:\/\/comunicacity.net\/aquino\/2021\/05\/01\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2021\/05\/riconsegna-bici-1024x980-1.jpg","articleSection":["Pubblica Sicurezza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/aquino\/2021\/05\/01\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\/","url":"https:\/\/comunicacity.net\/aquino\/2021\/05\/01\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\/","name":"Aquino \u2013 La bella storia di Santina, della sua vecchia bici e del Comandante Fusco - Aquino","isPartOf":{"@id":"https:\/\/comunicacity.net\/aquino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/aquino\/2021\/05\/01\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/aquino\/2021\/05\/01\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2021\/05\/riconsegna-bici-1024x980-1.jpg","datePublished":"2021-05-01T15:18:32+00:00","author":{"@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/505a48e2bc4e4ec4452ec8f55932b961"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/aquino\/2021\/05\/01\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/aquino\/2021\/05\/01\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/aquino\/2021\/05\/01\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\/#primaryimage","url":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2021\/05\/riconsegna-bici-1024x980-1.jpg","contentUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2021\/05\/riconsegna-bici-1024x980-1.jpg","width":1024,"height":980},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/aquino\/2021\/05\/01\/aquino-la-bella-storia-di-santina-della-sua-vecchia-bici-e-del-comandante-fusco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/aquino\/"},{"@type":"ListItem","position":2,"name":"Aquino \u2013 La bella storia di Santina, della sua vecchia bici e del Comandante Fusco"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/aquino\/#website","url":"https:\/\/comunicacity.net\/aquino\/","name":"Aquino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/aquino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/505a48e2bc4e4ec4452ec8f55932b961","name":"sindacoaquino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g","caption":"sindacoaquino"},"url":"https:\/\/comunicacity.net\/aquino\/author\/sindacoaquino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/1498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/users\/247"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/comments?post=1498"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/1498\/revisions"}],"predecessor-version":[{"id":1500,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/1498\/revisions\/1500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/media\/1499"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/media?parent=1498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/categories?post=1498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/tags?post=1498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}