{"id":163,"date":"2016-06-02T15:45:32","date_gmt":"2016-06-02T13:45:32","guid":{"rendered":"https:\/\/comunicacity.net\/aquino\/?p=163"},"modified":"2016-06-02T15:45:32","modified_gmt":"2016-06-02T13:45:32","slug":"comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/aquino\/2016\/06\/02\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\/","title":{"rendered":"Comune di Aquino: commemorato il 70 anniversario della Repubblica con i ragazzi della Citt\u00e0."},"content":{"rendered":"<p style=\"text-align: justify\">L\u2019Amministrazione Comunale e la comunit\u00e0 aquinate, in una partecipata manifestazione tenutasi ieri in Comune hanno celebrato e commemorato la ricorrenza del 02 giugno, data che segna il 70\u00b0 anniversario della Repubblica Italiana.<\/p>\n<p style=\"text-align: justify\">L\u2019evento, svoltosi, nella Sala Consiliare della Citt\u00e0 di San Tommaso, \u00e8 stato organizzato e presieduto dal dott. Antonio Morelli, neo Presidente del Consiglio Comunale.<\/p>\n<p style=\"text-align: justify\">Come evidenziato a pi\u00f9 riprese nel corso degli interventi che si sono succeduti, \u00e8 stata una giornata diversa dalle solite nel corso della quale \u00e8 stata messa da parte la retorica ed il desiderio di apparire per far vincere i sentimenti puri della memoria ed i valori fondanti della carta costituzionale da trasmettere alle generazioni future.<\/p>\n<p style=\"text-align: justify\">I veri protagonisti, infatti, sono stati i giovani studenti frequentanti l\u2019Istituto Comprensivo di Aquino i quali, dopo una breve introduzione del Presidente Morelli, il suono di inni patriottici e di quello nazionale curati dalla neo costituita Banda Musicale Citt\u00e0 di Aquino, divenuta ormai una solida realt\u00e0, hanno partecipato al dibattito intervenendo con una apprezzata intervista ideale proiettata a cittadini dell\u2019epoca.<\/p>\n<p style=\"text-align: justify\">Si sono succeduti gli interventi del Sindaco di Aquino Libero Mazzaroppi, del Vicesindaco Carlo Risi, della Dirigente Scolastica Marianna Ladisi e del Presidente dell\u2019Anpi di Frosinone Giovanni Morsillo.<\/p>\n<p style=\"text-align: justify\">Presenti all\u2019evento numerosi concittadini, genitori dei ragazzi e l\u2019intero Consiglio Comunale dei Ragazzi guidato dal Sindaco baby Giannicola Magliulo.<\/p>\n<p style=\"text-align: justify\">Hanno vinto i sentimenti, le riflessioni e i ricordi e sono stati evidenziati fattori importanti come il voto alle donne, fino ad allora non consentito, unitamente al sacrificio dell\u2019esistenza di molti giovani donne e uomini.<\/p>\n<p style=\"text-align: justify\">Molto appassionate e competenti le riflessioni proposte dal delegato alla Cultura Risi, da Giovanni Morsillo e dalla Dirigente Ladisi.<\/p>\n<p style=\"text-align: justify\">Il Sindaco ha invitato a rispettare i valori della Costituzione per poter guardare negli occhi quelli che hanno lottato per donarceli senza dover abbassare lo sguardo.<\/p>\n<p style=\"text-align: justify\">I<em> ragazzi devono amare e difendere le istituzioni, e farlo insieme ai pi\u00f9 grandi; solo cos\u00ec<\/em> \u2013 ha continuato Mazzaroppi &#8211; <em>saremo in grado di recuperare i sentimenti di solidariet\u00e0 e speranza che hanno animato le\u00a0 sofferenze e le lotte di quei tempi.<\/em><em>&#8220;Con il\u00a0 sorriso sulle labbra e la fede nel cuore&#8221; dobbiamo lavorare, ognuno per il proprio ruolo e con le proprie responsabilit\u00e0, per migliorare la nostra grande Italia e questa nostra meravigliosa Citt\u00e0.<\/em><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Amministrazione Comunale e la comunit\u00e0 aquinate, in una partecipata manifestazione tenutasi ieri in Comune hanno celebrato e commemorato la ricorrenza del 02 giugno, data che segna il 70\u00b0 anniversario della [&hellip;]<\/p>\n","protected":false},"author":81,"featured_media":164,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comune di Aquino: commemorato il 70 anniversario della Repubblica con i ragazzi della Citt\u00e0. - Aquino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/aquino\/2016\/06\/02\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comune di Aquino: commemorato il 70 anniversario della Repubblica con i ragazzi della Citt\u00e0. - Aquino\" \/>\n<meta property=\"og:description\" content=\"L\u2019Amministrazione Comunale e la comunit\u00e0 aquinate, in una partecipata manifestazione tenutasi ieri in Comune hanno celebrato e commemorato la ricorrenza del 02 giugno, data che segna il 70\u00b0 anniversario della [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/aquino\/2016\/06\/02\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\/\" \/>\n<meta property=\"og:site_name\" content=\"Aquino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-02T13:45:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2016\/06\/2-giugno.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"286\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"villidinardi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"villidinardi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2016\\\/06\\\/02\\\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2016\\\/06\\\/02\\\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\\\/\"},\"author\":{\"name\":\"villidinardi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/125e25d30cc92889f27f09c8914cefc6\"},\"headline\":\"Comune di Aquino: commemorato il 70 anniversario della Repubblica con i ragazzi della Citt\u00e0.\",\"datePublished\":\"2016-06-02T13:45:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2016\\\/06\\\/02\\\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\\\/\"},\"wordCount\":390,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2016\\\/06\\\/02\\\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2016\\\/06\\\/2-giugno.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2016\\\/06\\\/02\\\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2016\\\/06\\\/02\\\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\\\/\",\"name\":\"Comune di Aquino: commemorato il 70 anniversario della Repubblica con i ragazzi della Citt\u00e0. - Aquino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2016\\\/06\\\/02\\\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2016\\\/06\\\/02\\\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2016\\\/06\\\/2-giugno.jpg\",\"datePublished\":\"2016-06-02T13:45:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/125e25d30cc92889f27f09c8914cefc6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2016\\\/06\\\/02\\\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2016\\\/06\\\/02\\\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2016\\\/06\\\/02\\\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2016\\\/06\\\/2-giugno.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2016\\\/06\\\/2-giugno.jpg\",\"width\":286,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2016\\\/06\\\/02\\\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comune di Aquino: commemorato il 70 anniversario della Repubblica con i ragazzi della Citt\u00e0.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/\",\"name\":\"Aquino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/125e25d30cc92889f27f09c8914cefc6\",\"name\":\"villidinardi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/954d3e3f098ecfec563d16759ea515dfa968d8ea17a8bc9c4ccbfc38c6275f14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/954d3e3f098ecfec563d16759ea515dfa968d8ea17a8bc9c4ccbfc38c6275f14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/954d3e3f098ecfec563d16759ea515dfa968d8ea17a8bc9c4ccbfc38c6275f14?s=96&d=mm&r=g\",\"caption\":\"villidinardi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/author\\\/villidinardi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comune di Aquino: commemorato il 70 anniversario della Repubblica con i ragazzi della Citt\u00e0. - Aquino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/aquino\/2016\/06\/02\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\/","og_locale":"it_IT","og_type":"article","og_title":"Comune di Aquino: commemorato il 70 anniversario della Repubblica con i ragazzi della Citt\u00e0. - Aquino","og_description":"L\u2019Amministrazione Comunale e la comunit\u00e0 aquinate, in una partecipata manifestazione tenutasi ieri in Comune hanno celebrato e commemorato la ricorrenza del 02 giugno, data che segna il 70\u00b0 anniversario della [&hellip;]","og_url":"https:\/\/comunicacity.net\/aquino\/2016\/06\/02\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\/","og_site_name":"Aquino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2016-06-02T13:45:32+00:00","og_image":[{"width":286,"height":400,"url":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2016\/06\/2-giugno.jpg","type":"image\/jpeg"}],"author":"villidinardi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"villidinardi","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/aquino\/2016\/06\/02\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/aquino\/2016\/06\/02\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\/"},"author":{"name":"villidinardi","@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/125e25d30cc92889f27f09c8914cefc6"},"headline":"Comune di Aquino: commemorato il 70 anniversario della Repubblica con i ragazzi della Citt\u00e0.","datePublished":"2016-06-02T13:45:32+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/aquino\/2016\/06\/02\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\/"},"wordCount":390,"image":{"@id":"https:\/\/comunicacity.net\/aquino\/2016\/06\/02\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2016\/06\/2-giugno.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/aquino\/2016\/06\/02\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\/","url":"https:\/\/comunicacity.net\/aquino\/2016\/06\/02\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\/","name":"Comune di Aquino: commemorato il 70 anniversario della Repubblica con i ragazzi della Citt\u00e0. - Aquino","isPartOf":{"@id":"https:\/\/comunicacity.net\/aquino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/aquino\/2016\/06\/02\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/aquino\/2016\/06\/02\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2016\/06\/2-giugno.jpg","datePublished":"2016-06-02T13:45:32+00:00","author":{"@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/125e25d30cc92889f27f09c8914cefc6"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/aquino\/2016\/06\/02\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/aquino\/2016\/06\/02\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/aquino\/2016\/06\/02\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\/#primaryimage","url":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2016\/06\/2-giugno.jpg","contentUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2016\/06\/2-giugno.jpg","width":286,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/aquino\/2016\/06\/02\/comune-di-aquino-commemorato-il-70-anniversario-della-repubblica-con-i-ragazzi-della-citta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/aquino\/"},{"@type":"ListItem","position":2,"name":"Comune di Aquino: commemorato il 70 anniversario della Repubblica con i ragazzi della Citt\u00e0."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/aquino\/#website","url":"https:\/\/comunicacity.net\/aquino\/","name":"Aquino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/aquino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/125e25d30cc92889f27f09c8914cefc6","name":"villidinardi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/954d3e3f098ecfec563d16759ea515dfa968d8ea17a8bc9c4ccbfc38c6275f14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/954d3e3f098ecfec563d16759ea515dfa968d8ea17a8bc9c4ccbfc38c6275f14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/954d3e3f098ecfec563d16759ea515dfa968d8ea17a8bc9c4ccbfc38c6275f14?s=96&d=mm&r=g","caption":"villidinardi"},"url":"https:\/\/comunicacity.net\/aquino\/author\/villidinardi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/users\/81"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/comments?post=163"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/163\/revisions"}],"predecessor-version":[{"id":168,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/163\/revisions\/168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/media\/164"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/media?parent=163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/categories?post=163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/tags?post=163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}