{"id":341,"date":"2018-01-22T12:21:48","date_gmt":"2018-01-22T11:21:48","guid":{"rendered":"https:\/\/comunicacity.net\/aquino\/?p=341"},"modified":"2018-01-22T12:21:48","modified_gmt":"2018-01-22T11:21:48","slug":"aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/aquino\/2018\/01\/22\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\/","title":{"rendered":"Aquino: Rendere funzionale la Casa di San Tommaso d\u2019Aquino. Il 10 marzo prossimo si inaugura. Soddisfazione del Comune per la firma dell\u2019Accordo di Valorizzazione sottoscritto tra la Proloco e il Polo Museale del Lazio."},"content":{"rendered":"<p>Aquino \u2013 Da lunghissimo tempo il Sindaco Mazzaroppi aveva investito della questione il Ministro dei Beni Culturali On. Dario Franceschini e la Dirigenza del Polo Museale con l\u2019intento di ridare vita, alla Casa di San Tommaso d\u2019Aquino, uno dei complessi monumentali pi\u00f9 affascinanti della Citt\u00e0.<\/p>\n<p>La sfida lanciata dal Comune, che nel corso degli anni aveva incontrato molti ostacoli dovuti a vecchie incrostazioni o sacche di resistenza che sono state pi\u00f9 volte evidenziate e rappresentate agli uffici competenti, finalmente diventa una missione possibile da realizzare perch\u00e9 assolutamente condivisa dalle istituzioni e dal mondo dell\u2019associazionismo.<\/p>\n<p>Infatti, gioved\u00ec 18 gennaio, nelle suggestive stanze di Palazzo Venezia a Roma, \u00e8 stato sottoscritto un importante Accordo di Valorizzazione tra il Polo Museale del Lazio e la Proloco di Aquino.<\/p>\n<p>Alla presenza del Sindaco della Citt\u00e0 di San Tommaso Libero Mazzaroppi, la dott.ssa Edith Gabrielli Direttrice del Polo e il Presidente Pompeo Pellegrini hanno apposto la loro firma in calce ad un documento che i cittadini di Aquino attendevano da sempre.<\/p>\n<p>E\u2019 stato, quindi, un pomeriggio importante, una data storica e densa di significati, perch\u00e9 con questa sinergia, con questa indispensabile concertazione istituzionale si avvia una fase nuova, per lo storico edificio, che si propone di perseguire un programma ed un percorso di valorizzazione a fini culturali e turistici, assicurando anche una gestione efficace e sostenibile sotto varie forme.<\/p>\n<p>Il Sindaco di Aquino \u2013 Libero Mazzaroppi \u2013 ha dichiarato: non nascondo la gioia che provo e con me quella dei miei concittadini per il risultato ottenuto che ci libera da opportunistiche e ormai retrodatate resistenze di parte. Devo dire grazie al Ministro Dario Franceschini per aver dato ascolto alle nostre sollecitazioni, alla dott.ssa Edith Gabrielli (Direttrice del Polo) e al dott. Petrocchi (neo direttore della Casa di San Tommaso) che in pochissimo tempo hanno dimostrato capacit\u00e0, voglia di fare e competenza nel realizzare il progetto e predisporre il piano di intervento.<\/p>\n<p>Abbiamo ottenuto, per la Proloco aquinate, un Accordo che prevede il riuso del complesso, un programma di valorizzazione che insieme a tutti gli obiettivi prefissati potr\u00e0 realizzarsi attraverso la localizzazione di molte nuove funzioni, che si ispirano ad una condivisa vocazione culturale e coerenti con i progetti degli Enti coinvolti, in materia di promozione della cultura e di sviluppo turistico del territorio.<\/p>\n<p>La fruizione pubblica della Casa del Sommo Dottore della Chiesa e di tutte le attivit\u00e0 connesse saranno garantite dalla Proloco che potr\u00e0 avvalersi di personale preparato ad hoc dai funzionari del Polo Museale.<\/p>\n<p>Pompeo Pellegrini, presidente della Proloco, nel dichiararsi felice e soddisfatto per aver sottoscritto un atto che pu\u00f2 definirsi storico per la Citt\u00e0, ha ringraziato tutti ed in particolare il Sindaco Mazzaroppi per aver creduto nelle capacit\u00e0 del sodalizio, ed ha evidenziato che d\u2019ora in avanti sar\u00e0 straordinario poter godere della Casa del nostro Concittadino pi\u00f9 illustre.<\/p>\n<p>Ha assicurato, inoltre, il massimo impegno da parte dei suoi collaboratori e ribadito la gioia di poter formare giovani del posto alla gestione delle attivit\u00e0 che si organizzeranno d\u2019intesa con il Polo Museale e il Comune di Aquino.<\/p>\n<p>Appuntamento, quindi, al 10 marzo 2018 per l\u2019inaugurazione ufficiale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aquino \u2013 Da lunghissimo tempo il Sindaco Mazzaroppi aveva investito della questione il Ministro dei Beni Culturali On. Dario Franceschini e la Dirigenza del Polo Museale con l\u2019intento di ridare [&hellip;]<\/p>\n","protected":false},"author":247,"featured_media":342,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aquino: Rendere funzionale la Casa di San Tommaso d\u2019Aquino. Il 10 marzo prossimo si inaugura. Soddisfazione del Comune per la firma dell\u2019Accordo di Valorizzazione sottoscritto tra la Proloco e il Polo Museale del Lazio. - Aquino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/aquino\/2018\/01\/22\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aquino: Rendere funzionale la Casa di San Tommaso d\u2019Aquino. Il 10 marzo prossimo si inaugura. Soddisfazione del Comune per la firma dell\u2019Accordo di Valorizzazione sottoscritto tra la Proloco e il Polo Museale del Lazio. - Aquino\" \/>\n<meta property=\"og:description\" content=\"Aquino \u2013 Da lunghissimo tempo il Sindaco Mazzaroppi aveva investito della questione il Ministro dei Beni Culturali On. Dario Franceschini e la Dirigenza del Polo Museale con l\u2019intento di ridare [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/aquino\/2018\/01\/22\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\/\" \/>\n<meta property=\"og:site_name\" content=\"Aquino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-22T11:21:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2018\/01\/2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"584\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoaquino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoaquino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/01\\\/22\\\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/01\\\/22\\\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\\\/\"},\"author\":{\"name\":\"sindacoaquino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/505a48e2bc4e4ec4452ec8f55932b961\"},\"headline\":\"Aquino: Rendere funzionale la Casa di San Tommaso d\u2019Aquino. Il 10 marzo prossimo si inaugura. Soddisfazione del Comune per la firma dell\u2019Accordo di Valorizzazione sottoscritto tra la Proloco e il Polo Museale del Lazio.\",\"datePublished\":\"2018-01-22T11:21:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/01\\\/22\\\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\\\/\"},\"wordCount\":550,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/01\\\/22\\\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2018\\\/01\\\/2.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/01\\\/22\\\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/01\\\/22\\\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\\\/\",\"name\":\"Aquino: Rendere funzionale la Casa di San Tommaso d\u2019Aquino. Il 10 marzo prossimo si inaugura. Soddisfazione del Comune per la firma dell\u2019Accordo di Valorizzazione sottoscritto tra la Proloco e il Polo Museale del Lazio. - Aquino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/01\\\/22\\\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/01\\\/22\\\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2018\\\/01\\\/2.jpg\",\"datePublished\":\"2018-01-22T11:21:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/505a48e2bc4e4ec4452ec8f55932b961\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/01\\\/22\\\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/01\\\/22\\\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/01\\\/22\\\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2018\\\/01\\\/2.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2018\\\/01\\\/2.jpg\",\"width\":960,\"height\":584},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/01\\\/22\\\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aquino: Rendere funzionale la Casa di San Tommaso d\u2019Aquino. Il 10 marzo prossimo si inaugura. Soddisfazione del Comune per la firma dell\u2019Accordo di Valorizzazione sottoscritto tra la Proloco e il Polo Museale del Lazio.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/\",\"name\":\"Aquino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/505a48e2bc4e4ec4452ec8f55932b961\",\"name\":\"sindacoaquino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g\",\"caption\":\"sindacoaquino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/author\\\/sindacoaquino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aquino: Rendere funzionale la Casa di San Tommaso d\u2019Aquino. Il 10 marzo prossimo si inaugura. Soddisfazione del Comune per la firma dell\u2019Accordo di Valorizzazione sottoscritto tra la Proloco e il Polo Museale del Lazio. - Aquino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/aquino\/2018\/01\/22\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\/","og_locale":"it_IT","og_type":"article","og_title":"Aquino: Rendere funzionale la Casa di San Tommaso d\u2019Aquino. Il 10 marzo prossimo si inaugura. Soddisfazione del Comune per la firma dell\u2019Accordo di Valorizzazione sottoscritto tra la Proloco e il Polo Museale del Lazio. - Aquino","og_description":"Aquino \u2013 Da lunghissimo tempo il Sindaco Mazzaroppi aveva investito della questione il Ministro dei Beni Culturali On. Dario Franceschini e la Dirigenza del Polo Museale con l\u2019intento di ridare [&hellip;]","og_url":"https:\/\/comunicacity.net\/aquino\/2018\/01\/22\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\/","og_site_name":"Aquino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-01-22T11:21:48+00:00","og_image":[{"width":960,"height":584,"url":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2018\/01\/2.jpg","type":"image\/jpeg"}],"author":"sindacoaquino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoaquino","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/aquino\/2018\/01\/22\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/01\/22\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\/"},"author":{"name":"sindacoaquino","@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/505a48e2bc4e4ec4452ec8f55932b961"},"headline":"Aquino: Rendere funzionale la Casa di San Tommaso d\u2019Aquino. Il 10 marzo prossimo si inaugura. Soddisfazione del Comune per la firma dell\u2019Accordo di Valorizzazione sottoscritto tra la Proloco e il Polo Museale del Lazio.","datePublished":"2018-01-22T11:21:48+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/01\/22\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\/"},"wordCount":550,"image":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/01\/22\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2018\/01\/2.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/aquino\/2018\/01\/22\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\/","url":"https:\/\/comunicacity.net\/aquino\/2018\/01\/22\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\/","name":"Aquino: Rendere funzionale la Casa di San Tommaso d\u2019Aquino. Il 10 marzo prossimo si inaugura. Soddisfazione del Comune per la firma dell\u2019Accordo di Valorizzazione sottoscritto tra la Proloco e il Polo Museale del Lazio. - Aquino","isPartOf":{"@id":"https:\/\/comunicacity.net\/aquino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/01\/22\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/01\/22\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2018\/01\/2.jpg","datePublished":"2018-01-22T11:21:48+00:00","author":{"@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/505a48e2bc4e4ec4452ec8f55932b961"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/01\/22\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/aquino\/2018\/01\/22\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/aquino\/2018\/01\/22\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\/#primaryimage","url":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2018\/01\/2.jpg","contentUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2018\/01\/2.jpg","width":960,"height":584},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/aquino\/2018\/01\/22\/aquino-rendere-funzionale-la-casa-di-san-tommaso-daquino-il-10-marzo-prossimo-si-inaugura-soddisfazione-del-comune-per-la-firma-dellaccordo-di-valorizzazione-sottoscritto-tra-la-p\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/aquino\/"},{"@type":"ListItem","position":2,"name":"Aquino: Rendere funzionale la Casa di San Tommaso d\u2019Aquino. Il 10 marzo prossimo si inaugura. Soddisfazione del Comune per la firma dell\u2019Accordo di Valorizzazione sottoscritto tra la Proloco e il Polo Museale del Lazio."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/aquino\/#website","url":"https:\/\/comunicacity.net\/aquino\/","name":"Aquino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/aquino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/505a48e2bc4e4ec4452ec8f55932b961","name":"sindacoaquino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g","caption":"sindacoaquino"},"url":"https:\/\/comunicacity.net\/aquino\/author\/sindacoaquino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/users\/247"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/comments?post=341"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/341\/revisions"}],"predecessor-version":[{"id":343,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/341\/revisions\/343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/media\/342"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/media?parent=341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/categories?post=341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/tags?post=341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}