{"id":47,"date":"2015-12-04T12:24:19","date_gmt":"2015-12-04T11:24:19","guid":{"rendered":"https:\/\/comunicacity.net\/aquino\/?p=47"},"modified":"2015-12-04T12:25:29","modified_gmt":"2015-12-04T11:25:29","slug":"analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/aquino\/2015\/12\/04\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\/","title":{"rendered":"Analisi del sangue a domicilio. Nuovo servizio promosso dal Comune."},"content":{"rendered":"<p style=\"text-align: justify\" align=\"right\">L\u2019Amministrazione Comunale di Aquino guidata dal Sindaco Libero Mazzaroppi informa tutta la cittadinanza che, a seguito dell\u2019approvazione della delibera di giunta nr. 185 del 04.novembre.2015, nei prossimi giorni, nella Citt\u00e0 di Aquino, sar\u00e0 attivo un nuovo servizio che consentir\u00e0 i prelievi ematici a domicilio.<\/p>\n<p style=\"text-align: justify\">Il Comune ha stabilito un rapporto di collaborazione con il Laboratorio Analisi Cliniche San Marco e la Cooperativa Sociale ONLUS Santa Lucia Life che provveder\u00e0 ad effettuare tale attivit\u00e0 con suo personale infermieristico specializzato in quanto autorizzata dalla Regione Lazio a fornire servizi e prestazioni socio-sanitarie a domicilio.Tale attivit\u00e0 di Assistenza Domiciliare \u00e8 rivolta e destinata ad anziani, invalidi parziali o totalmente non autosufficienti, impossibilitati, quindi, a raggiungere i punti accreditati per i prelievi in maniera autonoma.<\/p>\n<p style=\"text-align: justify\">Questo nuovo ed utile servizio \u2013 come puntualizzato dal primo cittadino aquinate Libero Mazzaroppi \u2013\u00a0 realizzato in virt\u00f9 della stipula di una apposita convenzione, completamente gratuito per il Comune, si pone l\u2019obiettivo di mantenere, migliorare e promuovere le condizioni di vita indipendente delle persone bisognose, garantendo, in ogni caso, il benessere senza intaccare la loro autonomia di scelta.<\/p>\n<p style=\"text-align: justify\"><strong>Saranno erogate al solo costo del ticket ordinario le seguenti prestazioni:<\/strong> prelievi ematici domiciliari gratuiti agli aventi diritto e presso un punto prelievo che dovr\u00e0 essere localizzato nel tempo; prestazioni sanitarie domiciliari con una scoutistica del 20%.Va precisato, per sgomberare ogni dubbio, che il servizio di prelievo (sia domiciliare che nell\u2019eventuale punto di prelievo) \u00e8 totalmente gratuito, con il solo pagamento dell\u2019eventuale ticket previsto dalla normativa di settore. Nei prossimi forniremo\u00a0 ulteriori indicazioni sulle modalit\u00e0 di prenotazione, che in ogni caso saranno curate dal servizi sociali del Comune di Aquino e sui giorni di prelievo che verr\u00e0 eseguito nelle prime ore della giornata e da cui sono esclusi i bambini fino ad otto anni.<\/p>\n<p style=\"text-align: justify\">\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Amministrazione Comunale di Aquino guidata dal Sindaco Libero Mazzaroppi informa tutta la cittadinanza che, a seguito dell\u2019approvazione della delibera di giunta nr. 185 del 04.novembre.2015, nei prossimi giorni, nella Citt\u00e0 [&hellip;]<\/p>\n","protected":false},"author":81,"featured_media":48,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-47","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Analisi del sangue a domicilio. Nuovo servizio promosso dal Comune. - Aquino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/aquino\/2015\/12\/04\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Analisi del sangue a domicilio. Nuovo servizio promosso dal Comune. - Aquino\" \/>\n<meta property=\"og:description\" content=\"L\u2019Amministrazione Comunale di Aquino guidata dal Sindaco Libero Mazzaroppi informa tutta la cittadinanza che, a seguito dell\u2019approvazione della delibera di giunta nr. 185 del 04.novembre.2015, nei prossimi giorni, nella Citt\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/aquino\/2015\/12\/04\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\/\" \/>\n<meta property=\"og:site_name\" content=\"Aquino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-04T11:24:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-12-04T11:25:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2015\/12\/analisi-del-sangue-complete.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"villidinardi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"villidinardi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2015\\\/12\\\/04\\\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2015\\\/12\\\/04\\\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\\\/\"},\"author\":{\"name\":\"villidinardi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/125e25d30cc92889f27f09c8914cefc6\"},\"headline\":\"Analisi del sangue a domicilio. Nuovo servizio promosso dal Comune.\",\"datePublished\":\"2015-12-04T11:24:19+00:00\",\"dateModified\":\"2015-12-04T11:25:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2015\\\/12\\\/04\\\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\\\/\"},\"wordCount\":304,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2015\\\/12\\\/04\\\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2015\\\/12\\\/analisi-del-sangue-complete.jpg\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2015\\\/12\\\/04\\\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2015\\\/12\\\/04\\\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\\\/\",\"name\":\"Analisi del sangue a domicilio. Nuovo servizio promosso dal Comune. - Aquino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2015\\\/12\\\/04\\\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2015\\\/12\\\/04\\\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2015\\\/12\\\/analisi-del-sangue-complete.jpg\",\"datePublished\":\"2015-12-04T11:24:19+00:00\",\"dateModified\":\"2015-12-04T11:25:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/125e25d30cc92889f27f09c8914cefc6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2015\\\/12\\\/04\\\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2015\\\/12\\\/04\\\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2015\\\/12\\\/04\\\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2015\\\/12\\\/analisi-del-sangue-complete.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2015\\\/12\\\/analisi-del-sangue-complete.jpg\",\"width\":300,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2015\\\/12\\\/04\\\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Analisi del sangue a domicilio. Nuovo servizio promosso dal Comune.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/\",\"name\":\"Aquino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/125e25d30cc92889f27f09c8914cefc6\",\"name\":\"villidinardi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/954d3e3f098ecfec563d16759ea515dfa968d8ea17a8bc9c4ccbfc38c6275f14?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/954d3e3f098ecfec563d16759ea515dfa968d8ea17a8bc9c4ccbfc38c6275f14?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/954d3e3f098ecfec563d16759ea515dfa968d8ea17a8bc9c4ccbfc38c6275f14?s=96&d=mm&r=g\",\"caption\":\"villidinardi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/author\\\/villidinardi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Analisi del sangue a domicilio. Nuovo servizio promosso dal Comune. - Aquino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/aquino\/2015\/12\/04\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\/","og_locale":"it_IT","og_type":"article","og_title":"Analisi del sangue a domicilio. Nuovo servizio promosso dal Comune. - Aquino","og_description":"L\u2019Amministrazione Comunale di Aquino guidata dal Sindaco Libero Mazzaroppi informa tutta la cittadinanza che, a seguito dell\u2019approvazione della delibera di giunta nr. 185 del 04.novembre.2015, nei prossimi giorni, nella Citt\u00e0 [&hellip;]","og_url":"https:\/\/comunicacity.net\/aquino\/2015\/12\/04\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\/","og_site_name":"Aquino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2015-12-04T11:24:19+00:00","article_modified_time":"2015-12-04T11:25:29+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2015\/12\/analisi-del-sangue-complete.jpg","type":"image\/jpeg"}],"author":"villidinardi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"villidinardi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/aquino\/2015\/12\/04\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/aquino\/2015\/12\/04\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\/"},"author":{"name":"villidinardi","@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/125e25d30cc92889f27f09c8914cefc6"},"headline":"Analisi del sangue a domicilio. Nuovo servizio promosso dal Comune.","datePublished":"2015-12-04T11:24:19+00:00","dateModified":"2015-12-04T11:25:29+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/aquino\/2015\/12\/04\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\/"},"wordCount":304,"image":{"@id":"https:\/\/comunicacity.net\/aquino\/2015\/12\/04\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2015\/12\/analisi-del-sangue-complete.jpg","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/aquino\/2015\/12\/04\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\/","url":"https:\/\/comunicacity.net\/aquino\/2015\/12\/04\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\/","name":"Analisi del sangue a domicilio. Nuovo servizio promosso dal Comune. - Aquino","isPartOf":{"@id":"https:\/\/comunicacity.net\/aquino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/aquino\/2015\/12\/04\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/aquino\/2015\/12\/04\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2015\/12\/analisi-del-sangue-complete.jpg","datePublished":"2015-12-04T11:24:19+00:00","dateModified":"2015-12-04T11:25:29+00:00","author":{"@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/125e25d30cc92889f27f09c8914cefc6"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/aquino\/2015\/12\/04\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/aquino\/2015\/12\/04\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/aquino\/2015\/12\/04\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\/#primaryimage","url":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2015\/12\/analisi-del-sangue-complete.jpg","contentUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2015\/12\/analisi-del-sangue-complete.jpg","width":300,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/aquino\/2015\/12\/04\/analisi-del-sangue-a-domicio-nuovo-servizio-promosso-dal-comune\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/aquino\/"},{"@type":"ListItem","position":2,"name":"Analisi del sangue a domicilio. Nuovo servizio promosso dal Comune."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/aquino\/#website","url":"https:\/\/comunicacity.net\/aquino\/","name":"Aquino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/aquino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/125e25d30cc92889f27f09c8914cefc6","name":"villidinardi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/954d3e3f098ecfec563d16759ea515dfa968d8ea17a8bc9c4ccbfc38c6275f14?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/954d3e3f098ecfec563d16759ea515dfa968d8ea17a8bc9c4ccbfc38c6275f14?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/954d3e3f098ecfec563d16759ea515dfa968d8ea17a8bc9c4ccbfc38c6275f14?s=96&d=mm&r=g","caption":"villidinardi"},"url":"https:\/\/comunicacity.net\/aquino\/author\/villidinardi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/users\/81"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/comments?post=47"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/47\/revisions"}],"predecessor-version":[{"id":50,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/47\/revisions\/50"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/media\/48"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/media?parent=47"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/categories?post=47"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/tags?post=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}