{"id":474,"date":"2018-11-03T10:15:39","date_gmt":"2018-11-03T09:15:39","guid":{"rendered":"https:\/\/comunicacity.net\/aquino\/?p=474"},"modified":"2018-11-03T10:37:16","modified_gmt":"2018-11-03T09:37:16","slug":"aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/aquino\/2018\/11\/03\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\/","title":{"rendered":"Aquino &#8211; Il Ricordo e la Memoria per pensare al Futuro. ( domenica 4 novembre in Piazza San Tommaso si svolger\u00e0 la Festa dell\u2019Unit\u00e0 Nazionale e delle Forze Armate )."},"content":{"rendered":"<p>Anche quest\u2019anno, come di consueto, l\u2019amministrazione comunale guidata dal Sindaco Libero Mazzaroppi render\u00e0 onore alla memoria dei Caduti di tutte le Guerre, militari e civili, e far\u00e0 sentire forte il senso di appartenenza e il ringraziamento alle istituzioni militari dello Stato esaltando il ruolo essenziale svolto dalle Forze Armate.<br \/>\nLa tradizionale cerimonia avr\u00e0 inizio alle ore 09.15, nella centralissima Piazza San Tommaso d\u2019Aquino, con la partecipazione delle autorit\u00e0 civili e religiose, delle rappresentanze delle Associazioni d\u2019Arma e di categoria, dei militari del Comando di Stazione dei Carabinieri e Polizia Locale.<br \/>\nAll\u2019inizio della commemorazione saranno resi gli onori alle Vittime Civili, con una deposizione di un omaggio floreale, presso il Cippo dedicato sito nell\u2019area a ridosso della Madonna dell\u2019Immacolata.<br \/>\nSuccessivamente il Corteo si recher\u00e0 nella Basilica \u2013 Concattedrale ove verr\u00e0 celebrata la Santa Messa in onore dei Caduti dal Parroco Mons. Don Tommaso Del Sorbo.<br \/>\nAl termine il Sindaco Libero Mazzaroppi, unitamente alle massime autorit\u00e0 militari, deporr\u00e0 una corona di alloro ai piedi del Monumento ai Caduti, dando successivamente lettura del messaggio del Capo dello Stato.<br \/>\nDopo un momento di riflessione e preghiera ed un saluto del Sindaco dei ragazzi Martina Gneo, accompagnata dal neo eletto Consiglio, seguir\u00e0 poi la lettura, del messaggio del Ministro della Difesa alle Forze Armate, nonch\u00e9 le allocuzioni del Generale dell\u2019Esercito Italiano Mario Venditti (di origini aquinati) e del Sindaco del Comune di Aquino.<br \/>\nAl termine della manifestazione, saranno resi gli onori ai Caduti con la lettura dell\u2019appello.<br \/>\nE\u2019 assicurata la partecipazione delle rappresentanze dell\u2019ICS di Aquino e dei volontari.<br \/>\nInterverranno, come di consueto, le Associazioni Combattentistiche con i rispettivi Labari e i brani musicali e patriottici saranno eseguiti a cura della Banda Musicale \u201cDavide Delle Cese\u201d del Maestro Gianpaolo Ciccone.<br \/>\nIl servizio di vigilanza dinamica alla bandiera verr\u00e0 garantito dal Comando di Polizia Locale con la collaborazione dell\u2019Associazione Nazionale dei Carabinieri.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Anche quest\u2019anno, come di consueto, l\u2019amministrazione comunale guidata dal Sindaco Libero Mazzaroppi render\u00e0 onore alla memoria dei Caduti di tutte le Guerre, militari e civili, e far\u00e0 sentire forte il [&hellip;]<\/p>\n","protected":false},"author":247,"featured_media":240,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aquino - Il Ricordo e la Memoria per pensare al Futuro. ( domenica 4 novembre in Piazza San Tommaso si svolger\u00e0 la Festa dell\u2019Unit\u00e0 Nazionale e delle Forze Armate ). - Aquino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/aquino\/2018\/11\/03\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aquino - Il Ricordo e la Memoria per pensare al Futuro. ( domenica 4 novembre in Piazza San Tommaso si svolger\u00e0 la Festa dell\u2019Unit\u00e0 Nazionale e delle Forze Armate ). - Aquino\" \/>\n<meta property=\"og:description\" content=\"Anche quest\u2019anno, come di consueto, l\u2019amministrazione comunale guidata dal Sindaco Libero Mazzaroppi render\u00e0 onore alla memoria dei Caduti di tutte le Guerre, militari e civili, e far\u00e0 sentire forte il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/aquino\/2018\/11\/03\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\/\" \/>\n<meta property=\"og:site_name\" content=\"Aquino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-03T09:15:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-03T09:37:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2016\/11\/Foto-Sindaco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"326\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoaquino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoaquino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/03\\\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/03\\\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\\\/\"},\"author\":{\"name\":\"sindacoaquino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/505a48e2bc4e4ec4452ec8f55932b961\"},\"headline\":\"Aquino &#8211; Il Ricordo e la Memoria per pensare al Futuro. ( domenica 4 novembre in Piazza San Tommaso si svolger\u00e0 la Festa dell\u2019Unit\u00e0 Nazionale e delle Forze Armate ).\",\"datePublished\":\"2018-11-03T09:15:39+00:00\",\"dateModified\":\"2018-11-03T09:37:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/03\\\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\\\/\"},\"wordCount\":343,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/03\\\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2016\\\/11\\\/Foto-Sindaco.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/03\\\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/03\\\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\\\/\",\"name\":\"Aquino - Il Ricordo e la Memoria per pensare al Futuro. ( domenica 4 novembre in Piazza San Tommaso si svolger\u00e0 la Festa dell\u2019Unit\u00e0 Nazionale e delle Forze Armate ). - Aquino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/03\\\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/03\\\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2016\\\/11\\\/Foto-Sindaco.jpg\",\"datePublished\":\"2018-11-03T09:15:39+00:00\",\"dateModified\":\"2018-11-03T09:37:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/505a48e2bc4e4ec4452ec8f55932b961\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/03\\\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/03\\\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/03\\\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2016\\\/11\\\/Foto-Sindaco.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2016\\\/11\\\/Foto-Sindaco.jpg\",\"width\":326,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/03\\\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aquino &#8211; Il Ricordo e la Memoria per pensare al Futuro. ( domenica 4 novembre in Piazza San Tommaso si svolger\u00e0 la Festa dell\u2019Unit\u00e0 Nazionale e delle Forze Armate ).\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/\",\"name\":\"Aquino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/505a48e2bc4e4ec4452ec8f55932b961\",\"name\":\"sindacoaquino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g\",\"caption\":\"sindacoaquino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/author\\\/sindacoaquino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aquino - Il Ricordo e la Memoria per pensare al Futuro. ( domenica 4 novembre in Piazza San Tommaso si svolger\u00e0 la Festa dell\u2019Unit\u00e0 Nazionale e delle Forze Armate ). - Aquino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/aquino\/2018\/11\/03\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\/","og_locale":"it_IT","og_type":"article","og_title":"Aquino - Il Ricordo e la Memoria per pensare al Futuro. ( domenica 4 novembre in Piazza San Tommaso si svolger\u00e0 la Festa dell\u2019Unit\u00e0 Nazionale e delle Forze Armate ). - Aquino","og_description":"Anche quest\u2019anno, come di consueto, l\u2019amministrazione comunale guidata dal Sindaco Libero Mazzaroppi render\u00e0 onore alla memoria dei Caduti di tutte le Guerre, militari e civili, e far\u00e0 sentire forte il [&hellip;]","og_url":"https:\/\/comunicacity.net\/aquino\/2018\/11\/03\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\/","og_site_name":"Aquino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-11-03T09:15:39+00:00","article_modified_time":"2018-11-03T09:37:16+00:00","og_image":[{"width":326,"height":800,"url":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2016\/11\/Foto-Sindaco.jpg","type":"image\/jpeg"}],"author":"sindacoaquino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoaquino","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/03\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/03\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\/"},"author":{"name":"sindacoaquino","@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/505a48e2bc4e4ec4452ec8f55932b961"},"headline":"Aquino &#8211; Il Ricordo e la Memoria per pensare al Futuro. ( domenica 4 novembre in Piazza San Tommaso si svolger\u00e0 la Festa dell\u2019Unit\u00e0 Nazionale e delle Forze Armate ).","datePublished":"2018-11-03T09:15:39+00:00","dateModified":"2018-11-03T09:37:16+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/03\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\/"},"wordCount":343,"image":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/03\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2016\/11\/Foto-Sindaco.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/03\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\/","url":"https:\/\/comunicacity.net\/aquino\/2018\/11\/03\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\/","name":"Aquino - Il Ricordo e la Memoria per pensare al Futuro. ( domenica 4 novembre in Piazza San Tommaso si svolger\u00e0 la Festa dell\u2019Unit\u00e0 Nazionale e delle Forze Armate ). - Aquino","isPartOf":{"@id":"https:\/\/comunicacity.net\/aquino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/03\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/03\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2016\/11\/Foto-Sindaco.jpg","datePublished":"2018-11-03T09:15:39+00:00","dateModified":"2018-11-03T09:37:16+00:00","author":{"@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/505a48e2bc4e4ec4452ec8f55932b961"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/03\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/aquino\/2018\/11\/03\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/03\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\/#primaryimage","url":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2016\/11\/Foto-Sindaco.jpg","contentUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2016\/11\/Foto-Sindaco.jpg","width":326,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/03\/aquino-il-ricordo-e-la-memoria-per-pensare-al-futuro-domenica-4-novembre-in-piazza-san-tommaso-si-svolgera-la-festa-dellunita-nazionale-e-delle-forze-armate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/aquino\/"},{"@type":"ListItem","position":2,"name":"Aquino &#8211; Il Ricordo e la Memoria per pensare al Futuro. ( domenica 4 novembre in Piazza San Tommaso si svolger\u00e0 la Festa dell\u2019Unit\u00e0 Nazionale e delle Forze Armate )."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/aquino\/#website","url":"https:\/\/comunicacity.net\/aquino\/","name":"Aquino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/aquino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/505a48e2bc4e4ec4452ec8f55932b961","name":"sindacoaquino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g","caption":"sindacoaquino"},"url":"https:\/\/comunicacity.net\/aquino\/author\/sindacoaquino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/users\/247"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/comments?post=474"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/474\/revisions"}],"predecessor-version":[{"id":475,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/474\/revisions\/475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/media\/240"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/media?parent=474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/categories?post=474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/tags?post=474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}