{"id":528,"date":"2018-11-24T10:43:07","date_gmt":"2018-11-24T09:43:07","guid":{"rendered":"https:\/\/comunicacity.net\/aquino\/?p=528"},"modified":"2018-11-24T10:43:07","modified_gmt":"2018-11-24T09:43:07","slug":"giornata-internazionale-contro-la-violenza-sulle-donne","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/aquino\/2018\/11\/24\/giornata-internazionale-contro-la-violenza-sulle-donne\/","title":{"rendered":"Giornata Internazionale contro la Violenza sulle Donne."},"content":{"rendered":"<p>Il 25 novembre si celebra la Giornata Internazionale per l\u2019eliminazione della violenza contro le donne.<br \/>\nTale importante ricorrenza, istituita dall\u2019Assemblea dell\u2019ONU (Organizzazione Nazioni Unite) nel 1999, vuole essere un monito per raggiungere un traguardo fondamentale nell\u2019ambito dei diritti umani: non lasciare pi\u00f9 NESSUNA DONNA SOLA, mettendo finalmente fine agli abusi e alle violenze di ogni tipo.<br \/>\nIn linea con l\u2019ANCI (Associazione Nazionale dei Comuni Italiani) che chiede attenzione al fenomeno, evidenziando che i delitti contro le donne sono in sensibile aumento, il Comune di Aquino desidera celebrare questa giornata esponendo, in segno di lutto, la bandiera a mezz\u2019asta, promuovendo ed incentivando l\u2019adozione di decisioni e comportamenti ispirati ai principi di rispetto, dignit\u00e0 e correttezza, affinch\u00e9 in una societ\u00e0 civile e democratica non trovino posto alcuno i soprusi ed i maltrattamenti contro le donne.<\/p>\n<p>Assessore Alessia Del Duca<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 25 novembre si celebra la Giornata Internazionale per l\u2019eliminazione della violenza contro le donne. Tale importante ricorrenza, istituita dall\u2019Assemblea dell\u2019ONU (Organizzazione Nazioni Unite) nel 1999, vuole essere un monito [&hellip;]<\/p>\n","protected":false},"author":247,"featured_media":529,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giornata Internazionale contro la Violenza sulle Donne. - Aquino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/aquino\/2018\/11\/24\/giornata-internazionale-contro-la-violenza-sulle-donne\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giornata Internazionale contro la Violenza sulle Donne. - Aquino\" \/>\n<meta property=\"og:description\" content=\"Il 25 novembre si celebra la Giornata Internazionale per l\u2019eliminazione della violenza contro le donne. Tale importante ricorrenza, istituita dall\u2019Assemblea dell\u2019ONU (Organizzazione Nazioni Unite) nel 1999, vuole essere un monito [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/aquino\/2018\/11\/24\/giornata-internazionale-contro-la-violenza-sulle-donne\/\" \/>\n<meta property=\"og:site_name\" content=\"Aquino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-24T09:43:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2018\/11\/viol.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"958\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoaquino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoaquino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/24\\\/giornata-internazionale-contro-la-violenza-sulle-donne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/24\\\/giornata-internazionale-contro-la-violenza-sulle-donne\\\/\"},\"author\":{\"name\":\"sindacoaquino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/505a48e2bc4e4ec4452ec8f55932b961\"},\"headline\":\"Giornata Internazionale contro la Violenza sulle Donne.\",\"datePublished\":\"2018-11-24T09:43:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/24\\\/giornata-internazionale-contro-la-violenza-sulle-donne\\\/\"},\"wordCount\":149,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/24\\\/giornata-internazionale-contro-la-violenza-sulle-donne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2018\\\/11\\\/viol.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/24\\\/giornata-internazionale-contro-la-violenza-sulle-donne\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/24\\\/giornata-internazionale-contro-la-violenza-sulle-donne\\\/\",\"name\":\"Giornata Internazionale contro la Violenza sulle Donne. - Aquino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/24\\\/giornata-internazionale-contro-la-violenza-sulle-donne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/24\\\/giornata-internazionale-contro-la-violenza-sulle-donne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2018\\\/11\\\/viol.jpg\",\"datePublished\":\"2018-11-24T09:43:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/505a48e2bc4e4ec4452ec8f55932b961\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/24\\\/giornata-internazionale-contro-la-violenza-sulle-donne\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/24\\\/giornata-internazionale-contro-la-violenza-sulle-donne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/24\\\/giornata-internazionale-contro-la-violenza-sulle-donne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2018\\\/11\\\/viol.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2018\\\/11\\\/viol.jpg\",\"width\":958,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/11\\\/24\\\/giornata-internazionale-contro-la-violenza-sulle-donne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giornata Internazionale contro la Violenza sulle Donne.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/\",\"name\":\"Aquino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/505a48e2bc4e4ec4452ec8f55932b961\",\"name\":\"sindacoaquino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g\",\"caption\":\"sindacoaquino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/author\\\/sindacoaquino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giornata Internazionale contro la Violenza sulle Donne. - Aquino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/aquino\/2018\/11\/24\/giornata-internazionale-contro-la-violenza-sulle-donne\/","og_locale":"it_IT","og_type":"article","og_title":"Giornata Internazionale contro la Violenza sulle Donne. - Aquino","og_description":"Il 25 novembre si celebra la Giornata Internazionale per l\u2019eliminazione della violenza contro le donne. Tale importante ricorrenza, istituita dall\u2019Assemblea dell\u2019ONU (Organizzazione Nazioni Unite) nel 1999, vuole essere un monito [&hellip;]","og_url":"https:\/\/comunicacity.net\/aquino\/2018\/11\/24\/giornata-internazionale-contro-la-violenza-sulle-donne\/","og_site_name":"Aquino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-11-24T09:43:07+00:00","og_image":[{"width":958,"height":450,"url":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2018\/11\/viol.jpg","type":"image\/jpeg"}],"author":"sindacoaquino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoaquino","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/24\/giornata-internazionale-contro-la-violenza-sulle-donne\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/24\/giornata-internazionale-contro-la-violenza-sulle-donne\/"},"author":{"name":"sindacoaquino","@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/505a48e2bc4e4ec4452ec8f55932b961"},"headline":"Giornata Internazionale contro la Violenza sulle Donne.","datePublished":"2018-11-24T09:43:07+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/24\/giornata-internazionale-contro-la-violenza-sulle-donne\/"},"wordCount":149,"image":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/24\/giornata-internazionale-contro-la-violenza-sulle-donne\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2018\/11\/viol.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/24\/giornata-internazionale-contro-la-violenza-sulle-donne\/","url":"https:\/\/comunicacity.net\/aquino\/2018\/11\/24\/giornata-internazionale-contro-la-violenza-sulle-donne\/","name":"Giornata Internazionale contro la Violenza sulle Donne. - Aquino","isPartOf":{"@id":"https:\/\/comunicacity.net\/aquino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/24\/giornata-internazionale-contro-la-violenza-sulle-donne\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/24\/giornata-internazionale-contro-la-violenza-sulle-donne\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2018\/11\/viol.jpg","datePublished":"2018-11-24T09:43:07+00:00","author":{"@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/505a48e2bc4e4ec4452ec8f55932b961"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/24\/giornata-internazionale-contro-la-violenza-sulle-donne\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/aquino\/2018\/11\/24\/giornata-internazionale-contro-la-violenza-sulle-donne\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/24\/giornata-internazionale-contro-la-violenza-sulle-donne\/#primaryimage","url":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2018\/11\/viol.jpg","contentUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2018\/11\/viol.jpg","width":958,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/aquino\/2018\/11\/24\/giornata-internazionale-contro-la-violenza-sulle-donne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/aquino\/"},{"@type":"ListItem","position":2,"name":"Giornata Internazionale contro la Violenza sulle Donne."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/aquino\/#website","url":"https:\/\/comunicacity.net\/aquino\/","name":"Aquino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/aquino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/505a48e2bc4e4ec4452ec8f55932b961","name":"sindacoaquino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g","caption":"sindacoaquino"},"url":"https:\/\/comunicacity.net\/aquino\/author\/sindacoaquino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/users\/247"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/comments?post=528"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/528\/revisions"}],"predecessor-version":[{"id":530,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/528\/revisions\/530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/media\/529"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/media?parent=528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/categories?post=528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/tags?post=528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}