{"id":593,"date":"2018-12-31T12:24:03","date_gmt":"2018-12-31T11:24:03","guid":{"rendered":"https:\/\/comunicacity.net\/aquino\/?p=593"},"modified":"2018-12-31T12:24:03","modified_gmt":"2018-12-31T11:24:03","slug":"saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/aquino\/2018\/12\/31\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\/","title":{"rendered":"Saluto di Fine Anno del Sindaco Libero Mazzaroppi."},"content":{"rendered":"<p>Care concittadine e cari concittadini,<br \/>\n\u00e8 con particolare affetto e gratitudine che rivolgo a tutti voi un caloroso saluto, un augurio per l\u2019anno che ci attende e un breve e positivo consuntivo per l\u2019intera comunit\u00e0.<br \/>\nQuesto, ormai per me, tradizionale appuntamento, vi confesso, assume stavolta un significato un po&#8217; speciale perch\u00e9 segue, di pochi mesi, la straordinaria conferma elettorale che avete voluto generosamente accordare alla mia persona, al mio agire amministrativo, al Gruppo Aquino nel cuore, affidandoci l\u2019altissimo onore di governare la nostra amata Aquino per altri cinque anni.<br \/>\nNon voglio cimentarmi con approfondite analisi politiche, tantomeno con l\u2019elenco dettagliato delle opere realizzate e degli interventi operati a favore della crescita socio \u2013 economica della nostra Citt\u00e0 (non sarebbero sufficienti pochi spazi) per cui voglio limitarmi soltanto a qualche interessante spunto di riflessione da condividere con ognuno di voi. Da sempre ho rappresentato la nostra esperienza amministrativa pensando all\u2019idea di un cammino verso l\u2019Aquino del futuro.<br \/>\nEbbene, voglio rassicurarvi sul fatto che, anche superando momenti difficili, passaggi impervi, cagionati da irresponsabili e arrivisti, con questa nuova, leale, motivata e seria maggioranza amministrativa, stiamo percorrendo questa strada con tenacia, con impegno, con passione, senza mai perderci d\u2019animo o farci sopraffare dallo sconforto.<br \/>\nAbbiamo profuso energie, senza soste, per disegnare il progetto di Citt\u00e0 che avevamo in mente e lo abbiamo fatto \u201candando avanti insieme\u201d a donne e uomini capaci, con la loro vita e con il loro lavoro, di erigersi ad esempio, da imitare e apprezzare, tanto da delineare i tratti essenziali del nostro tessuto locale a livello economico, industriale, commerciale, culturale e del mondo del volontariato e dell\u2019associazionismo.<br \/>\nRicorreva, nell\u2019anno 2018, il 70\u00b0 anniversario della Costituzione Italiana, quella Carta fondamentale cui ho, da sempre, conformato il mio comportamento da primo cittadino, da uomo, da soldato, agendo nel rispetto di quei principi di disciplina ed onore che prescrive.<br \/>\nRegistro nei rapporti istituzionali con il Consiglio Comunale appena insediato, al di l\u00e0 della dialettica politica e delle inevitabili posizioni di parte, un clima tutto sommato corretto e costruttivo, fattori determinanti e caratterizzanti che, fin dal primo giorno di insediamento, ho sempre auspicato.<br \/>\nE\u2019 fondamentale, infatti, a mio avviso, lasciarci alle spalle pregiudiziali e conflitti, invidie e allergie, assolutamente deleteri per inseguire il bene comune, la crescita e il progresso.<br \/>\nQuando esiste un clima sereno, e vale sia nella gestione della vita quotidiana che in quella pubblica, si dispiega un rapporto costruttivo tra le parti che aiuta tutti.<br \/>\nNonostante quasi tutti i Comuni della Nazione affrontano situazioni finanziarie molto difficili che non rendono fluido il cammino delle amministrazioni, posso certificare che l\u2019azione della compagine che mi pregio di guidare si \u00e8 distinta per la sintonia con gli enti sovraordinati e intermedi, assicurando agli aquinati un marcato sviluppo economico, un riconosciuto sostegno di solidariet\u00e0 sociale, oltre che una ricchissima e qualitativa offerta culturale.<br \/>\nInfatti, con questi presupposti, siamo certi di poter affrontare ragionevolmente e con una sicura fiducia il futuro che ci attende.<br \/>\nSolo alcuni dati: confermiamo, come rilevato dal \u201cSole 24 ore\u201d, il 4\u00b0 posto, nel contesto provinciale, per tassi di crescita finanziaria ed economica; continua ad elevarsi e migliorare, nel settore della soddisfazione turistica, la forza attrattiva della nostra Citt\u00e0, anche grazie al benefico influsso esercitato dai grandi eventi che proponiamo quali il Palio della Contea di Aquino, il Villaggio di Babbo Natale, le Luminarie e tanto altro ancora, organizzati con passione e con l\u2019indispensabile supporto della Proloco, del Comitato Palio, di cui ringrazio i Presidenti Pompeo Pellegrini e Pierluigi Vellone oltre che i loro nutriti e motivati staff unitamente alle tante altre associazioni che operano sul territorio tra cui spicca Rete Imprese Yes Aquino guidata dal Presidente Tonino Magnapera.<br \/>\nTorna il Calcio che conta con la neo costituita societ\u00e0 guidata da Alessandro Vigliotta senza dimenticare il grande servizio reso da chi educa, a tale disciplina, le giovani generazioni come il Centro Formazione Lazio. Continua, incessantemente, a crescere il nostro Museo che ottiene ulteriori successi e prestigiosi riconoscimenti quali \u201cAquino Citt\u00e0 che legge\u201d e conferma, unico nel territorio, l\u2019ambito Marchio di Qualit\u00e0. Ottimizzata la gestione delle risorse, sono stati migliorati i processi della macchina amministrativa comunale e sono stati resi pi\u00f9 efficienti i servizi erogati alle persone rimuovendo, di conseguenza, grazie a iniziative che sostengono bisogno e povert\u00e0, diseguaglianze sociali.<\/p>\n<p>L\u2019amministrazione continua a collaborare in maniera feconda con l\u2019Istituto Comprensivo Statale di Aquino, per questo il mio grato pensiero va alla Dirigente Marianna Ladisi e si estende a tutti coloro, docenti e amministrativi, per l\u2019elevata e nobile funzione che svolgono per formare le generazioni che seguiranno alle nostre.<br \/>\nUn saluto colmo di affetto lo rivolgo, a nome di tutti gli aquinati, al nostro caro Vescovo Gerardo Antonazzo, che opera un\u2019attivit\u00e0 pastorale con intensa spiritualit\u00e0 manifestandoci, in ogni occasione, paterna vicinanza. Estendo il mio saluto al nostro Parroco Don Tommaso Del Sorbo e a tutte le realt\u00e0 che operano, con virt\u00f9, nella Chiesa di Aquino.<br \/>\nUn augurio molto sincero di buon lavoro lo rivolgo a S. E. il neo Prefetto di Frosinone, dott. Ignazio Portelli unitamente a tutte le autorit\u00e0 militari e civili che dispiegano la loro azione nel territorio per esercitare il delicato compito istituzionale di cui sono investiti. Ringrazio il Comandante della Compagnia dei Carabinieri Cap. Tamara Nicolai e il M.llo Sergio Parrillo, unitamente ai loro collaboratori, per l\u2019impegno costante che dimostrano nel controllo del territorio a tutela della sicurezza dei cittadini.<br \/>\nMai dimenticare di rinnovare l\u2019affetto di Aquino ai cittadini onorari e a quelli benemeriti oltre che alle comunit\u00e0 di Crotta D\u2019Adda, Grumello Cremonese e San Bassano, Comuni gemellati, per la preziosa e generosa ospitalit\u00e0 accordata ai nostri Sfollati di Guerra, con la viva preghiera rivolta ai Sindaci Gerevini, Scio e Bassanetti di estendere i nostri sentimenti ai loro concittadini.<br \/>\nChiudo questo mio breve saluto ringraziando la mia Giunta i Consiglieri Comunali, per la dedizione e l\u2019impegno costante che, unitamente ai dipendenti comunali tutti, azionano per consentire il raggiungimento degli obiettivi prefissati e dei dati positivi che abbiamo evidenziato. Siamo coscienti che ci sono tante cose ancora da fare per ottimizzare il buon andamento e la tenuta di una Citt\u00e0 ma voglio assicurare, con tutta l\u2019onest\u00e0 intellettuale e morale di cui dispongo, che faremo il nostro dovere per tutti.<br \/>\nSono convinto che, specie per chi vive momenti di difficolt\u00e0, proprio ora, bisogna rimanere vincolati e coesi a quei valori di unione che, in questi anni, abbiamo agevolato e hanno contraddistinto la nostra azione. Non deve mai prendere il sopravvento la paura, non dobbiamo mai perdere la speranza, deve vincere la voglia di riscatto, per cancellare la demagogia, il cinismo, lo scontro personale, il cattivo gusto, il populismo. Nessuno deve risparmiarsi in impegno civico, rispetto della persona, educazione. A tutti gli aquinati, a quelli che vivono in Italia e nel mondo il mio, il nostro augurio di un anno di pace, gioie, salute e crescita da condividere con quelli che hanno nel cuore. Anche per me l\u2019auspicio di continuare a profondere energie, passione e sempre con maggior forza e intensit\u00e0 l\u2019attenzione e l\u2019amore che nutro per gli altri e per questa Citt\u00e0 per guardare al futuro con rinnovato ottimismo. Buon 2019. Vi voglio bene, andiamo avanti insieme.<br \/>\nAquino, 30.12.2018<br \/>\nIl Sindaco<br \/>\nLibero Mazzaroppi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Care concittadine e cari concittadini, \u00e8 con particolare affetto e gratitudine che rivolgo a tutti voi un caloroso saluto, un augurio per l\u2019anno che ci attende e un breve e [&hellip;]<\/p>\n","protected":false},"author":247,"featured_media":594,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Saluto di Fine Anno del Sindaco Libero Mazzaroppi. - Aquino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/aquino\/2018\/12\/31\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saluto di Fine Anno del Sindaco Libero Mazzaroppi. - Aquino\" \/>\n<meta property=\"og:description\" content=\"Care concittadine e cari concittadini, \u00e8 con particolare affetto e gratitudine che rivolgo a tutti voi un caloroso saluto, un augurio per l\u2019anno che ci attende e un breve e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/aquino\/2018\/12\/31\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Aquino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-31T11:24:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2018\/12\/sindaco-lm.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"954\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sindacoaquino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"sindacoaquino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/12\\\/31\\\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/12\\\/31\\\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\\\/\"},\"author\":{\"name\":\"sindacoaquino\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/505a48e2bc4e4ec4452ec8f55932b961\"},\"headline\":\"Saluto di Fine Anno del Sindaco Libero Mazzaroppi.\",\"datePublished\":\"2018-12-31T11:24:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/12\\\/31\\\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\\\/\"},\"wordCount\":1216,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/12\\\/31\\\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2018\\\/12\\\/sindaco-lm.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/12\\\/31\\\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/12\\\/31\\\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\\\/\",\"name\":\"Saluto di Fine Anno del Sindaco Libero Mazzaroppi. - Aquino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/12\\\/31\\\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/12\\\/31\\\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2018\\\/12\\\/sindaco-lm.jpg\",\"datePublished\":\"2018-12-31T11:24:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/505a48e2bc4e4ec4452ec8f55932b961\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/12\\\/31\\\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/12\\\/31\\\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/12\\\/31\\\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2018\\\/12\\\/sindaco-lm.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/wp-content\\\/uploads\\\/sites\\\/41\\\/2018\\\/12\\\/sindaco-lm.jpg\",\"width\":954,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/2018\\\/12\\\/31\\\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saluto di Fine Anno del Sindaco Libero Mazzaroppi.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/\",\"name\":\"Aquino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/#\\\/schema\\\/person\\\/505a48e2bc4e4ec4452ec8f55932b961\",\"name\":\"sindacoaquino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g\",\"caption\":\"sindacoaquino\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/aquino\\\/author\\\/sindacoaquino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Saluto di Fine Anno del Sindaco Libero Mazzaroppi. - Aquino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/aquino\/2018\/12\/31\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\/","og_locale":"it_IT","og_type":"article","og_title":"Saluto di Fine Anno del Sindaco Libero Mazzaroppi. - Aquino","og_description":"Care concittadine e cari concittadini, \u00e8 con particolare affetto e gratitudine che rivolgo a tutti voi un caloroso saluto, un augurio per l\u2019anno che ci attende e un breve e [&hellip;]","og_url":"https:\/\/comunicacity.net\/aquino\/2018\/12\/31\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\/","og_site_name":"Aquino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-12-31T11:24:03+00:00","og_image":[{"width":954,"height":960,"url":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2018\/12\/sindaco-lm.jpg","type":"image\/jpeg"}],"author":"sindacoaquino","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"sindacoaquino","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/aquino\/2018\/12\/31\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/12\/31\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\/"},"author":{"name":"sindacoaquino","@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/505a48e2bc4e4ec4452ec8f55932b961"},"headline":"Saluto di Fine Anno del Sindaco Libero Mazzaroppi.","datePublished":"2018-12-31T11:24:03+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/12\/31\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\/"},"wordCount":1216,"image":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/12\/31\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2018\/12\/sindaco-lm.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/aquino\/2018\/12\/31\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\/","url":"https:\/\/comunicacity.net\/aquino\/2018\/12\/31\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\/","name":"Saluto di Fine Anno del Sindaco Libero Mazzaroppi. - Aquino","isPartOf":{"@id":"https:\/\/comunicacity.net\/aquino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/12\/31\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/12\/31\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2018\/12\/sindaco-lm.jpg","datePublished":"2018-12-31T11:24:03+00:00","author":{"@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/505a48e2bc4e4ec4452ec8f55932b961"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/aquino\/2018\/12\/31\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/aquino\/2018\/12\/31\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/aquino\/2018\/12\/31\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\/#primaryimage","url":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2018\/12\/sindaco-lm.jpg","contentUrl":"https:\/\/comunicacity.net\/aquino\/wp-content\/uploads\/sites\/41\/2018\/12\/sindaco-lm.jpg","width":954,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/aquino\/2018\/12\/31\/saluto-di-fine-anno-del-sindaco-libero-mazzaroppi-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/aquino\/"},{"@type":"ListItem","position":2,"name":"Saluto di Fine Anno del Sindaco Libero Mazzaroppi."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/aquino\/#website","url":"https:\/\/comunicacity.net\/aquino\/","name":"Aquino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/aquino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/aquino\/#\/schema\/person\/505a48e2bc4e4ec4452ec8f55932b961","name":"sindacoaquino","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ee956baaedeba57dd40a220683b6042c1df967344615ad37d2b7cfa7ffb5020?s=96&d=mm&r=g","caption":"sindacoaquino"},"url":"https:\/\/comunicacity.net\/aquino\/author\/sindacoaquino\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/users\/247"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/comments?post=593"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/593\/revisions"}],"predecessor-version":[{"id":595,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/posts\/593\/revisions\/595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/media\/594"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/media?parent=593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/categories?post=593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/aquino\/wp-json\/wp\/v2\/tags?post=593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}