{"id":70,"date":"2016-07-13T16:58:52","date_gmt":"2016-07-13T14:58:52","guid":{"rendered":"https:\/\/comunicacity.net\/arpino\/?post_type=info&#038;p=70"},"modified":"2016-07-13T16:58:52","modified_gmt":"2016-07-13T14:58:52","slug":"info-generali","status":"publish","type":"info","link":"https:\/\/comunicacity.net\/arpino\/info\/info-generali\/","title":{"rendered":"Info generali"},"content":{"rendered":"<div class=\"list\">\n<div class=\"item\">\n<p>Provincia<\/p>\n<h2 class=\"ccBold\">Frosinone<\/h2>\n<\/div>\n<div class=\"item\">\n<p>Regione<\/p>\n<h2 class=\"ccBold\">Lazio<\/h2>\n<\/div>\n<div class=\"item\">\n<p>Popolazione Residente<\/p>\n<h2 class=\"ccBold\"><b>7.286<\/b><\/h2>\n<\/div>\n<div class=\"item\">\n<p>CAP<\/p>\n<h2 class=\"ccBold\">03033<\/h2>\n<\/div>\n<div class=\"item\">\n<p>Prefisso Telefonico<\/p>\n<h2 class=\"ccBold\">0776<\/h2>\n<\/div>\n<div class=\"item\">\n<p>Denominazione Abitanti<\/p>\n<h2 class=\"ccBold\"><b>Arpinati<\/b><\/h2>\n<\/div>\n<div class=\"item\">\n<p>Santo Patrono<\/p>\n<h2 class=\"ccBold\">Madonna di Loreto<\/h2>\n<\/div>\n<div class=\"item\">\n<p>Festa Patronale<\/p>\n<h2 class=\"ccBold\">10 dicembre<\/h2>\n<\/div>\n<div class=\"item\">\n<p>Giorno di Mercato Settimanale<\/p>\n<h2 class=\"ccBold\"><\/h2>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Provincia Frosinone Regione Lazio Popolazione Residente 7.286 CAP 03033 Prefisso Telefonico 0776 Denominazione Abitanti Arpinati Santo Patrono Madonna di Loreto Festa Patronale 10 dicembre Giorno di Mercato Settimanale<\/p>\n","protected":false},"featured_media":5,"parent":0,"menu_order":1,"template":"","meta":[],"class_list":["post-70","info","type-info","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Info generali - Arpino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/arpino\/info\/info-generali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Info generali - Arpino\" \/>\n<meta property=\"og:description\" content=\"Provincia Frosinone Regione Lazio Popolazione Residente 7.286 CAP 03033 Prefisso Telefonico 0776 Denominazione Abitanti Arpinati Santo Patrono Madonna di Loreto Festa Patronale 10 dicembre Giorno di Mercato Settimanale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/arpino\/info\/info-generali\/\" \/>\n<meta property=\"og:site_name\" content=\"Arpino\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/arpino\/wp-content\/uploads\/sites\/58\/2016\/04\/arpino.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arpino\\\/info\\\/info-generali\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/arpino\\\/info\\\/info-generali\\\/\",\"name\":\"Info generali - Arpino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arpino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arpino\\\/info\\\/info-generali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arpino\\\/info\\\/info-generali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/arpino\\\/wp-content\\\/uploads\\\/sites\\\/58\\\/2016\\\/04\\\/arpino.jpg\",\"datePublished\":\"2016-07-13T14:58:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arpino\\\/info\\\/info-generali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/arpino\\\/info\\\/info-generali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arpino\\\/info\\\/info-generali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/arpino\\\/wp-content\\\/uploads\\\/sites\\\/58\\\/2016\\\/04\\\/arpino.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/arpino\\\/wp-content\\\/uploads\\\/sites\\\/58\\\/2016\\\/04\\\/arpino.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arpino\\\/info\\\/info-generali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/arpino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Info generali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arpino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/arpino\\\/\",\"name\":\"Arpino\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/arpino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Info generali - Arpino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/arpino\/info\/info-generali\/","og_locale":"it_IT","og_type":"article","og_title":"Info generali - Arpino","og_description":"Provincia Frosinone Regione Lazio Popolazione Residente 7.286 CAP 03033 Prefisso Telefonico 0776 Denominazione Abitanti Arpinati Santo Patrono Madonna di Loreto Festa Patronale 10 dicembre Giorno di Mercato Settimanale","og_url":"https:\/\/comunicacity.net\/arpino\/info\/info-generali\/","og_site_name":"Arpino","article_publisher":"http:\/\/facebook.com\/ComunicaCity","og_image":[{"width":300,"height":300,"url":"https:\/\/comunicacity.net\/arpino\/wp-content\/uploads\/sites\/58\/2016\/04\/arpino.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/arpino\/info\/info-generali\/","url":"https:\/\/comunicacity.net\/arpino\/info\/info-generali\/","name":"Info generali - Arpino","isPartOf":{"@id":"https:\/\/comunicacity.net\/arpino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/arpino\/info\/info-generali\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/arpino\/info\/info-generali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/arpino\/wp-content\/uploads\/sites\/58\/2016\/04\/arpino.jpg","datePublished":"2016-07-13T14:58:52+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/arpino\/info\/info-generali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/arpino\/info\/info-generali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/arpino\/info\/info-generali\/#primaryimage","url":"https:\/\/comunicacity.net\/arpino\/wp-content\/uploads\/sites\/58\/2016\/04\/arpino.jpg","contentUrl":"https:\/\/comunicacity.net\/arpino\/wp-content\/uploads\/sites\/58\/2016\/04\/arpino.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/arpino\/info\/info-generali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/arpino\/"},{"@type":"ListItem","position":2,"name":"Info generali"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/arpino\/#website","url":"https:\/\/comunicacity.net\/arpino\/","name":"Arpino","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/arpino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/arpino\/wp-json\/wp\/v2\/info\/70","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/arpino\/wp-json\/wp\/v2\/info"}],"about":[{"href":"https:\/\/comunicacity.net\/arpino\/wp-json\/wp\/v2\/types\/info"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/arpino\/wp-json\/wp\/v2\/media\/5"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/arpino\/wp-json\/wp\/v2\/media?parent=70"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}