{"id":1086,"date":"2019-05-06T09:43:40","date_gmt":"2019-05-06T07:43:40","guid":{"rendered":"https:\/\/comunicacity.net\/arquatadeltronto\/?p=1086"},"modified":"2019-05-06T09:43:40","modified_gmt":"2019-05-06T07:43:40","slug":"domenica-12-maggio-tiziano-day","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/05\/06\/domenica-12-maggio-tiziano-day\/","title":{"rendered":"Domenica 12 maggio: Tiziano DAY"},"content":{"rendered":"<div>\n<div id=\"article\" class=\"system exported\" style=\"font-size: 1.2em;font-family: -apple-system-font;margin: 0px;line-height: 1.5em;padding: 0px\" role=\"article\">\n<div class=\"page\">\n<h1 class=\"title\" style=\"font-size: 1.95em;margin-bottom: 0.5em;max-width: 100%;margin-top: 0px;font-weight: bold;line-height: 1.21em\">DOMENICA 12 MAGGIO: TIZIANO DAY<\/h1>\n<p><img decoding=\"async\" style=\"max-width: 100%;height: auto;margin: 0.5em auto\" src=\"http:\/\/caiascoli.it\/images\/tiziano_day_2019.jpg\" alt=\"\" \/><\/p>\n<p>Condividiamo con voi il messaggio pervenuto da Paola Romanucci Presidente della sezione CAI Ascoli Piceno.<\/p>\n<p>Cari amici,<br \/>\nci piacerebbe trascorrere assieme a voi la giornata di <b>Domenica 12 Maggio<\/b>, ventennale della scomparsa di Tiziano Cantalamessa.\u00a0 Un\u2019occasione per stare in allegra compagnia, come sarebbe piaciuto a lui: chi lo ha conosciuto lo ricorder\u00e0 come preferisce, chi non lo conosceva avr\u00e0 occasione di sentirne parlare dai suoi stessi amici e compagni di scalate.<br style=\"max-width: 100%\" \/><u>La mattina sar\u00e0 possibile partecipare a <b>escursioni<\/b><\/u> in zona monte Vettore con la Sezione CAI di Ascoli Piceno, oppure con la Guida alpina Tito Ciarma, sui monti della Laga.<br \/>\n<u style=\"max-width: 100%\">Dalle <b>ore 16<\/b> ci ritroveremo ad <b>Arquata del Tronto nel centro polifunzionale realizzato dall\u2019A.N.A.<\/b> presso il villaggio di Borgo 2<\/u>, dove Gino appronter\u00e0 una merenda per la quale vi chiederemo un piccolo contributo.\u00a0 Ci saranno racconti, foto &#8230; e anche una piccola sorpresa editoriale, grazie al patrocinio del Collegio regionale delle Guide Alpine e del Soccorso Alpino e Speleo Marche.<br \/>\n<u style=\"max-width: 100%\">Per ragioni organizzative, vi chiediamo di <b style=\"max-width: 100%\">prenotarvi sia per le escursioni<\/b><\/u> (per i Sibillini: sez. CAI di Ascoli, mercoled\u00ec e venerd\u00ec h.19-20, tel. <a style=\"text-decoration: underline;max-width: 100%;color: #416ed2\" href=\"tel:073645158\">073645158<\/a>; per la Laga: Tito Ciarma, tel. <a style=\"text-decoration: underline;max-width: 100%;color: #416ed2\" href=\"tel:3286004225\">3286004225<\/a>), <b><u style=\"max-width: 100%\">sia per l&#8217;incontro pomeridiano<\/u><\/b> (tel. a sezione CAI Ascoli), <u>entro mercoled\u00ec 8 maggio<\/u>.\u00a0\u00a0 Grazie.<br \/>\nVi aspettiamo.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>DOMENICA 12 MAGGIO: TIZIANO DAY Condividiamo con voi il messaggio pervenuto da Paola Romanucci Presidente della sezione CAI Ascoli Piceno. Cari amici, ci piacerebbe trascorrere assieme a voi la giornata [&hellip;]<\/p>\n","protected":false},"author":150,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1086","post","type-post","status-publish","format-standard","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Domenica 12 maggio: Tiziano DAY - Arquata del Tronto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/05\/06\/domenica-12-maggio-tiziano-day\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Domenica 12 maggio: Tiziano DAY - Arquata del Tronto\" \/>\n<meta property=\"og:description\" content=\"DOMENICA 12 MAGGIO: TIZIANO DAY Condividiamo con voi il messaggio pervenuto da Paola Romanucci Presidente della sezione CAI Ascoli Piceno. Cari amici, ci piacerebbe trascorrere assieme a voi la giornata [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/05\/06\/domenica-12-maggio-tiziano-day\/\" \/>\n<meta property=\"og:site_name\" content=\"Arquata del Tronto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-06T07:43:40+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/caiascoli.it\/images\/tiziano_day_2019.jpg\" \/>\n<meta name=\"author\" content=\"michelefranchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"michelefranchi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/05\\\/06\\\/domenica-12-maggio-tiziano-day\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/05\\\/06\\\/domenica-12-maggio-tiziano-day\\\/\"},\"author\":{\"name\":\"michelefranchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#\\\/schema\\\/person\\\/2299898234ba3e69036271223b5f55af\"},\"headline\":\"Domenica 12 maggio: Tiziano DAY\",\"datePublished\":\"2019-05-06T07:43:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/05\\\/06\\\/domenica-12-maggio-tiziano-day\\\/\"},\"wordCount\":213,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/05\\\/06\\\/domenica-12-maggio-tiziano-day\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/caiascoli.it\\\/images\\\/tiziano_day_2019.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/05\\\/06\\\/domenica-12-maggio-tiziano-day\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/05\\\/06\\\/domenica-12-maggio-tiziano-day\\\/\",\"name\":\"Domenica 12 maggio: Tiziano DAY - Arquata del Tronto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/05\\\/06\\\/domenica-12-maggio-tiziano-day\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/05\\\/06\\\/domenica-12-maggio-tiziano-day\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/caiascoli.it\\\/images\\\/tiziano_day_2019.jpg\",\"datePublished\":\"2019-05-06T07:43:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#\\\/schema\\\/person\\\/2299898234ba3e69036271223b5f55af\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/05\\\/06\\\/domenica-12-maggio-tiziano-day\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/05\\\/06\\\/domenica-12-maggio-tiziano-day\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/05\\\/06\\\/domenica-12-maggio-tiziano-day\\\/#primaryimage\",\"url\":\"http:\\\/\\\/caiascoli.it\\\/images\\\/tiziano_day_2019.jpg\",\"contentUrl\":\"http:\\\/\\\/caiascoli.it\\\/images\\\/tiziano_day_2019.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/05\\\/06\\\/domenica-12-maggio-tiziano-day\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Domenica 12 maggio: Tiziano DAY\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/\",\"name\":\"Arquata del Tronto\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#\\\/schema\\\/person\\\/2299898234ba3e69036271223b5f55af\",\"name\":\"michelefranchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g\",\"caption\":\"michelefranchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/author\\\/michelefranchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Domenica 12 maggio: Tiziano DAY - Arquata del Tronto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/05\/06\/domenica-12-maggio-tiziano-day\/","og_locale":"it_IT","og_type":"article","og_title":"Domenica 12 maggio: Tiziano DAY - Arquata del Tronto","og_description":"DOMENICA 12 MAGGIO: TIZIANO DAY Condividiamo con voi il messaggio pervenuto da Paola Romanucci Presidente della sezione CAI Ascoli Piceno. Cari amici, ci piacerebbe trascorrere assieme a voi la giornata [&hellip;]","og_url":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/05\/06\/domenica-12-maggio-tiziano-day\/","og_site_name":"Arquata del Tronto","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-05-06T07:43:40+00:00","og_image":[{"url":"http:\/\/caiascoli.it\/images\/tiziano_day_2019.jpg","type":"","width":"","height":""}],"author":"michelefranchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"michelefranchi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/05\/06\/domenica-12-maggio-tiziano-day\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/05\/06\/domenica-12-maggio-tiziano-day\/"},"author":{"name":"michelefranchi","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#\/schema\/person\/2299898234ba3e69036271223b5f55af"},"headline":"Domenica 12 maggio: Tiziano DAY","datePublished":"2019-05-06T07:43:40+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/05\/06\/domenica-12-maggio-tiziano-day\/"},"wordCount":213,"image":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/05\/06\/domenica-12-maggio-tiziano-day\/#primaryimage"},"thumbnailUrl":"http:\/\/caiascoli.it\/images\/tiziano_day_2019.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/05\/06\/domenica-12-maggio-tiziano-day\/","url":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/05\/06\/domenica-12-maggio-tiziano-day\/","name":"Domenica 12 maggio: Tiziano DAY - Arquata del Tronto","isPartOf":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/05\/06\/domenica-12-maggio-tiziano-day\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/05\/06\/domenica-12-maggio-tiziano-day\/#primaryimage"},"thumbnailUrl":"http:\/\/caiascoli.it\/images\/tiziano_day_2019.jpg","datePublished":"2019-05-06T07:43:40+00:00","author":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#\/schema\/person\/2299898234ba3e69036271223b5f55af"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/05\/06\/domenica-12-maggio-tiziano-day\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/arquatadeltronto\/2019\/05\/06\/domenica-12-maggio-tiziano-day\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/05\/06\/domenica-12-maggio-tiziano-day\/#primaryimage","url":"http:\/\/caiascoli.it\/images\/tiziano_day_2019.jpg","contentUrl":"http:\/\/caiascoli.it\/images\/tiziano_day_2019.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/05\/06\/domenica-12-maggio-tiziano-day\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/arquatadeltronto\/"},{"@type":"ListItem","position":2,"name":"Domenica 12 maggio: Tiziano DAY"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#website","url":"https:\/\/comunicacity.net\/arquatadeltronto\/","name":"Arquata del Tronto","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/arquatadeltronto\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#\/schema\/person\/2299898234ba3e69036271223b5f55af","name":"michelefranchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g","caption":"michelefranchi"},"url":"https:\/\/comunicacity.net\/arquatadeltronto\/author\/michelefranchi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts\/1086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/users\/150"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/comments?post=1086"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts\/1086\/revisions"}],"predecessor-version":[{"id":1087,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts\/1086\/revisions\/1087"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/media?parent=1086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/categories?post=1086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/tags?post=1086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}