{"id":1140,"date":"2019-07-09T11:55:03","date_gmt":"2019-07-09T09:55:03","guid":{"rendered":"https:\/\/comunicacity.net\/arquatadeltronto\/?p=1140"},"modified":"2019-07-09T11:55:33","modified_gmt":"2019-07-09T09:55:33","slug":"spettacolo-liceo-licos-teatri-in-movimento","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/07\/09\/spettacolo-liceo-licos-teatri-in-movimento\/","title":{"rendered":"Spettacolo Liceo Licos &#8211; TEATRI IN MOVIMENTO"},"content":{"rendered":"<p>Nell&#8217;ambito del progetto &#8220;Teatri in movimento&#8221; venerd\u00ec 12 luglio 2019 alle ore 21:15 presso la Sala Polivalente di Pretare si svolger\u00e0 lo spettacolo degli studenti del liceo Licos di Milano<\/p>\n<p>La cittadinanza \u00e8 invitata a partecipare.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>In allegato la locandina dell&#8217;evento.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_1141\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/uploads\/sites\/65\/2019\/07\/licos.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/uploads\/sites\/65\/2019\/07\/licos.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>licos<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nell&#8217;ambito del progetto &#8220;Teatri in movimento&#8221; venerd\u00ec 12 luglio 2019 alle ore 21:15 presso la Sala Polivalente di Pretare si svolger\u00e0 lo spettacolo degli studenti del liceo Licos di Milano [&hellip;]<\/p>\n","protected":false},"author":150,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1140","post","type-post","status-publish","format-standard","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spettacolo Liceo Licos - TEATRI IN MOVIMENTO - Arquata del Tronto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/07\/09\/spettacolo-liceo-licos-teatri-in-movimento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spettacolo Liceo Licos - TEATRI IN MOVIMENTO - Arquata del Tronto\" \/>\n<meta property=\"og:description\" content=\"Nell&#8217;ambito del progetto &#8220;Teatri in movimento&#8221; venerd\u00ec 12 luglio 2019 alle ore 21:15 presso la Sala Polivalente di Pretare si svolger\u00e0 lo spettacolo degli studenti del liceo Licos di Milano [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/07\/09\/spettacolo-liceo-licos-teatri-in-movimento\/\" \/>\n<meta property=\"og:site_name\" content=\"Arquata del Tronto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-09T09:55:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-09T09:55:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/eventi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"michelefranchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"michelefranchi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/07\\\/09\\\/spettacolo-liceo-licos-teatri-in-movimento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/07\\\/09\\\/spettacolo-liceo-licos-teatri-in-movimento\\\/\"},\"author\":{\"name\":\"michelefranchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#\\\/schema\\\/person\\\/2299898234ba3e69036271223b5f55af\"},\"headline\":\"Spettacolo Liceo Licos &#8211; TEATRI IN MOVIMENTO\",\"datePublished\":\"2019-07-09T09:55:03+00:00\",\"dateModified\":\"2019-07-09T09:55:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/07\\\/09\\\/spettacolo-liceo-licos-teatri-in-movimento\\\/\"},\"wordCount\":46,\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/07\\\/09\\\/spettacolo-liceo-licos-teatri-in-movimento\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/07\\\/09\\\/spettacolo-liceo-licos-teatri-in-movimento\\\/\",\"name\":\"Spettacolo Liceo Licos - TEATRI IN MOVIMENTO - Arquata del Tronto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#website\"},\"datePublished\":\"2019-07-09T09:55:03+00:00\",\"dateModified\":\"2019-07-09T09:55:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#\\\/schema\\\/person\\\/2299898234ba3e69036271223b5f55af\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/07\\\/09\\\/spettacolo-liceo-licos-teatri-in-movimento\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/07\\\/09\\\/spettacolo-liceo-licos-teatri-in-movimento\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2019\\\/07\\\/09\\\/spettacolo-liceo-licos-teatri-in-movimento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spettacolo Liceo Licos &#8211; TEATRI IN MOVIMENTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/\",\"name\":\"Arquata del Tronto\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#\\\/schema\\\/person\\\/2299898234ba3e69036271223b5f55af\",\"name\":\"michelefranchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g\",\"caption\":\"michelefranchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/author\\\/michelefranchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spettacolo Liceo Licos - TEATRI IN MOVIMENTO - Arquata del Tronto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/07\/09\/spettacolo-liceo-licos-teatri-in-movimento\/","og_locale":"it_IT","og_type":"article","og_title":"Spettacolo Liceo Licos - TEATRI IN MOVIMENTO - Arquata del Tronto","og_description":"Nell&#8217;ambito del progetto &#8220;Teatri in movimento&#8221; venerd\u00ec 12 luglio 2019 alle ore 21:15 presso la Sala Polivalente di Pretare si svolger\u00e0 lo spettacolo degli studenti del liceo Licos di Milano [&hellip;]","og_url":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/07\/09\/spettacolo-liceo-licos-teatri-in-movimento\/","og_site_name":"Arquata del Tronto","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-07-09T09:55:03+00:00","article_modified_time":"2019-07-09T09:55:33+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/eventi.png","height":600,"width":1200,"type":""}],"author":"michelefranchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"michelefranchi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/07\/09\/spettacolo-liceo-licos-teatri-in-movimento\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/07\/09\/spettacolo-liceo-licos-teatri-in-movimento\/"},"author":{"name":"michelefranchi","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#\/schema\/person\/2299898234ba3e69036271223b5f55af"},"headline":"Spettacolo Liceo Licos &#8211; TEATRI IN MOVIMENTO","datePublished":"2019-07-09T09:55:03+00:00","dateModified":"2019-07-09T09:55:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/07\/09\/spettacolo-liceo-licos-teatri-in-movimento\/"},"wordCount":46,"articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/07\/09\/spettacolo-liceo-licos-teatri-in-movimento\/","url":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/07\/09\/spettacolo-liceo-licos-teatri-in-movimento\/","name":"Spettacolo Liceo Licos - TEATRI IN MOVIMENTO - Arquata del Tronto","isPartOf":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#website"},"datePublished":"2019-07-09T09:55:03+00:00","dateModified":"2019-07-09T09:55:33+00:00","author":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#\/schema\/person\/2299898234ba3e69036271223b5f55af"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/07\/09\/spettacolo-liceo-licos-teatri-in-movimento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/arquatadeltronto\/2019\/07\/09\/spettacolo-liceo-licos-teatri-in-movimento\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2019\/07\/09\/spettacolo-liceo-licos-teatri-in-movimento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/arquatadeltronto\/"},{"@type":"ListItem","position":2,"name":"Spettacolo Liceo Licos &#8211; TEATRI IN MOVIMENTO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#website","url":"https:\/\/comunicacity.net\/arquatadeltronto\/","name":"Arquata del Tronto","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/arquatadeltronto\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#\/schema\/person\/2299898234ba3e69036271223b5f55af","name":"michelefranchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g","caption":"michelefranchi"},"url":"https:\/\/comunicacity.net\/arquatadeltronto\/author\/michelefranchi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts\/1140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/users\/150"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/comments?post=1140"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts\/1140\/revisions"}],"predecessor-version":[{"id":1143,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts\/1140\/revisions\/1143"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/media?parent=1140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/categories?post=1140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/tags?post=1140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}