{"id":2321,"date":"2023-11-30T09:29:20","date_gmt":"2023-11-30T08:29:20","guid":{"rendered":"https:\/\/comunicacity.net\/arquatadeltronto\/?p=2321"},"modified":"2023-11-30T09:29:20","modified_gmt":"2023-11-30T08:29:20","slug":"rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/arquatadeltronto\/2023\/11\/30\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\/","title":{"rendered":"Rischio sismico &#8211; Attivit\u00e0 di informazione alla popolazione &#8211; Progetto Firespil"},"content":{"rendered":"<p>La Direzione Protezione Civile della Regione Marche, all\u2019interno del \u201cProgramma di Cooperazione transfrontaliera Italia-Croazia\u201d, ha partecipato ad un progetto, denominato Firespill che ha previsto, tra le varie attivit\u00e0, la realizzazione di materiali volti a favorire una maggiore consapevolezza della cittadinanza sul rischio terremoto.<\/p>\n<div>Si allegano i link dei video ed i file dei poster, stampabili in formato A3, relativi ai comportamenti da tenere in caso di terremoto,<\/p>\n<div><\/div>\n<\/div>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_2322\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/uploads\/sites\/65\/2023\/11\/Regione-Marche_poster-Earthquake-Italian.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/uploads\/sites\/65\/2023\/11\/Regione-Marche_poster-Earthquake-Italian.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Regione Marche_poster Earthquake Italian<\/a><\/li>\n<li><a id=\"wpba_attachment_list_2323\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/uploads\/sites\/65\/2023\/11\/Regione-Marche_poster-Earthquake.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/uploads\/sites\/65\/2023\/11\/Regione-Marche_poster-Earthquake.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Regione Marche_poster Earthquake<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Direzione Protezione Civile della Regione Marche, all\u2019interno del \u201cProgramma di Cooperazione transfrontaliera Italia-Croazia\u201d, ha partecipato ad un progetto, denominato Firespill che ha previsto, tra le varie attivit\u00e0, la realizzazione [&hellip;]<\/p>\n","protected":false},"author":150,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-2321","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rischio sismico - Attivit\u00e0 di informazione alla popolazione - Progetto Firespil - Arquata del Tronto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/arquatadeltronto\/2023\/11\/30\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rischio sismico - Attivit\u00e0 di informazione alla popolazione - Progetto Firespil - Arquata del Tronto\" \/>\n<meta property=\"og:description\" content=\"La Direzione Protezione Civile della Regione Marche, all\u2019interno del \u201cProgramma di Cooperazione transfrontaliera Italia-Croazia\u201d, ha partecipato ad un progetto, denominato Firespill che ha previsto, tra le varie attivit\u00e0, la realizzazione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/arquatadeltronto\/2023\/11\/30\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\/\" \/>\n<meta property=\"og:site_name\" content=\"Arquata del Tronto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-30T08:29:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"michelefranchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"michelefranchi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2023\\\/11\\\/30\\\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2023\\\/11\\\/30\\\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\\\/\"},\"author\":{\"name\":\"michelefranchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#\\\/schema\\\/person\\\/2299898234ba3e69036271223b5f55af\"},\"headline\":\"Rischio sismico &#8211; Attivit\u00e0 di informazione alla popolazione &#8211; Progetto Firespil\",\"datePublished\":\"2023-11-30T08:29:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2023\\\/11\\\/30\\\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\\\/\"},\"wordCount\":79,\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2023\\\/11\\\/30\\\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2023\\\/11\\\/30\\\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\\\/\",\"name\":\"Rischio sismico - Attivit\u00e0 di informazione alla popolazione - Progetto Firespil - Arquata del Tronto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#website\"},\"datePublished\":\"2023-11-30T08:29:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#\\\/schema\\\/person\\\/2299898234ba3e69036271223b5f55af\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2023\\\/11\\\/30\\\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2023\\\/11\\\/30\\\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2023\\\/11\\\/30\\\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rischio sismico &#8211; Attivit\u00e0 di informazione alla popolazione &#8211; Progetto Firespil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/\",\"name\":\"Arquata del Tronto\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#\\\/schema\\\/person\\\/2299898234ba3e69036271223b5f55af\",\"name\":\"michelefranchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g\",\"caption\":\"michelefranchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/author\\\/michelefranchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rischio sismico - Attivit\u00e0 di informazione alla popolazione - Progetto Firespil - Arquata del Tronto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/arquatadeltronto\/2023\/11\/30\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\/","og_locale":"it_IT","og_type":"article","og_title":"Rischio sismico - Attivit\u00e0 di informazione alla popolazione - Progetto Firespil - Arquata del Tronto","og_description":"La Direzione Protezione Civile della Regione Marche, all\u2019interno del \u201cProgramma di Cooperazione transfrontaliera Italia-Croazia\u201d, ha partecipato ad un progetto, denominato Firespill che ha previsto, tra le varie attivit\u00e0, la realizzazione [&hellip;]","og_url":"https:\/\/comunicacity.net\/arquatadeltronto\/2023\/11\/30\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\/","og_site_name":"Arquata del Tronto","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-11-30T08:29:20+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"michelefranchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"michelefranchi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2023\/11\/30\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2023\/11\/30\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\/"},"author":{"name":"michelefranchi","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#\/schema\/person\/2299898234ba3e69036271223b5f55af"},"headline":"Rischio sismico &#8211; Attivit\u00e0 di informazione alla popolazione &#8211; Progetto Firespil","datePublished":"2023-11-30T08:29:20+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2023\/11\/30\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\/"},"wordCount":79,"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2023\/11\/30\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\/","url":"https:\/\/comunicacity.net\/arquatadeltronto\/2023\/11\/30\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\/","name":"Rischio sismico - Attivit\u00e0 di informazione alla popolazione - Progetto Firespil - Arquata del Tronto","isPartOf":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#website"},"datePublished":"2023-11-30T08:29:20+00:00","author":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#\/schema\/person\/2299898234ba3e69036271223b5f55af"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2023\/11\/30\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/arquatadeltronto\/2023\/11\/30\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2023\/11\/30\/rischio-sismico-attivita-di-informazione-alla-popolazione-progetto-firespil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/arquatadeltronto\/"},{"@type":"ListItem","position":2,"name":"Rischio sismico &#8211; Attivit\u00e0 di informazione alla popolazione &#8211; Progetto Firespil"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#website","url":"https:\/\/comunicacity.net\/arquatadeltronto\/","name":"Arquata del Tronto","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/arquatadeltronto\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#\/schema\/person\/2299898234ba3e69036271223b5f55af","name":"michelefranchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g","caption":"michelefranchi"},"url":"https:\/\/comunicacity.net\/arquatadeltronto\/author\/michelefranchi\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts\/2321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/users\/150"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/comments?post=2321"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts\/2321\/revisions"}],"predecessor-version":[{"id":2324,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts\/2321\/revisions\/2324"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/media?parent=2321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/categories?post=2321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/tags?post=2321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}