{"id":3280,"date":"2026-03-30T09:12:47","date_gmt":"2026-03-30T07:12:47","guid":{"rendered":"https:\/\/comunicacity.net\/arquatadeltronto\/?p=3280"},"modified":"2026-03-30T09:51:01","modified_gmt":"2026-03-30T07:51:01","slug":"avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/arquatadeltronto\/2026\/03\/30\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\/","title":{"rendered":"AVVISO DI SELEZIONE, PER ESAMI, PER L&#8217;ASSUNZIONE A TEMPO PIENO E INDETERMINATO DI UN OPERATORE ESPERTO, CON PROFILO DI COLLABORATORE PROFESSIONALE \u2013 OPERAIO SPECIALIZZATO\/CANTONIERE \u2013 DA ASSEGNARE AL SETTORE TECNICO."},"content":{"rendered":"<p>In esecuzione alla determinazione del Responsabile del Settore Segreteria Generale n. 11 R.G. n. 94 del 26.03.2026 \u00e8 indetta selezione pubblica, per esami, per l\u2019assunzione a tempo pieno e indeterminato di un Operatore esperto ai sensi dell\u2019articolo 12 del C.C.N.L. Funzioni locali 16.11.2022, con il profilo di \u201cCollaboratore professionale \u2013 Operaio specializzato\/cantoniere\u201d \u2013 da assegnare al Settore Tecnico.<\/p>\n<p>I candidati dovranno far pervenire la domanda unicamente in via telematica tramite il Portale Unico di Reclutamento della Funzione Pubblica raggiungibile al link:\u00a0<a href=\"https:\/\/www.inpa.gov.it\/\">https:\/\/www.inpa.gov.it\/<\/a>\u00a0non oltre il trentesimo giorno successivo alla data di pubblicazione dell&#8217;avviso sul portale indicato ed all&#8217;albo pretorio del Comune di Arquata del Tronto: quindi,\u00a0<strong>non oltre le ore 23:59 del giorno 29\/04\/2026.<\/strong><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_3281\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/uploads\/sites\/65\/2026\/03\/avviso-selezione-operatore-esperto-arquata-del-tronto.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/uploads\/sites\/65\/2026\/03\/avviso-selezione-operatore-esperto-arquata-del-tronto.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>avviso selezione operatore esperto arquata del tronto<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In esecuzione alla determinazione del Responsabile del Settore Segreteria Generale n. 11 R.G. n. 94 del 26.03.2026 \u00e8 indetta selezione pubblica, per esami, per l\u2019assunzione a tempo pieno e indeterminato [&hellip;]<\/p>\n","protected":false},"author":150,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-3280","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO DI SELEZIONE, PER ESAMI, PER L&#039;ASSUNZIONE A TEMPO PIENO E INDETERMINATO DI UN OPERATORE ESPERTO, CON PROFILO DI COLLABORATORE PROFESSIONALE \u2013 OPERAIO SPECIALIZZATO\/CANTONIERE \u2013 DA ASSEGNARE AL SETTORE TECNICO. - Arquata del Tronto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/arquatadeltronto\/2026\/03\/30\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO DI SELEZIONE, PER ESAMI, PER L&#039;ASSUNZIONE A TEMPO PIENO E INDETERMINATO DI UN OPERATORE ESPERTO, CON PROFILO DI COLLABORATORE PROFESSIONALE \u2013 OPERAIO SPECIALIZZATO\/CANTONIERE \u2013 DA ASSEGNARE AL SETTORE TECNICO. - Arquata del Tronto\" \/>\n<meta property=\"og:description\" content=\"In esecuzione alla determinazione del Responsabile del Settore Segreteria Generale n. 11 R.G. n. 94 del 26.03.2026 \u00e8 indetta selezione pubblica, per esami, per l\u2019assunzione a tempo pieno e indeterminato [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/arquatadeltronto\/2026\/03\/30\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\/\" \/>\n<meta property=\"og:site_name\" content=\"Arquata del Tronto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-30T07:12:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T07:51:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"michelefranchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"michelefranchi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2026\\\/03\\\/30\\\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2026\\\/03\\\/30\\\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\\\/\"},\"author\":{\"name\":\"michelefranchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#\\\/schema\\\/person\\\/2299898234ba3e69036271223b5f55af\"},\"headline\":\"AVVISO DI SELEZIONE, PER ESAMI, PER L&#8217;ASSUNZIONE A TEMPO PIENO E INDETERMINATO DI UN OPERATORE ESPERTO, CON PROFILO DI COLLABORATORE PROFESSIONALE \u2013 OPERAIO SPECIALIZZATO\\\/CANTONIERE \u2013 DA ASSEGNARE AL SETTORE TECNICO.\",\"datePublished\":\"2026-03-30T07:12:47+00:00\",\"dateModified\":\"2026-03-30T07:51:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2026\\\/03\\\/30\\\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\\\/\"},\"wordCount\":144,\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2026\\\/03\\\/30\\\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2026\\\/03\\\/30\\\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\\\/\",\"name\":\"AVVISO DI SELEZIONE, PER ESAMI, PER L'ASSUNZIONE A TEMPO PIENO E INDETERMINATO DI UN OPERATORE ESPERTO, CON PROFILO DI COLLABORATORE PROFESSIONALE \u2013 OPERAIO SPECIALIZZATO\\\/CANTONIERE \u2013 DA ASSEGNARE AL SETTORE TECNICO. - Arquata del Tronto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#website\"},\"datePublished\":\"2026-03-30T07:12:47+00:00\",\"dateModified\":\"2026-03-30T07:51:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#\\\/schema\\\/person\\\/2299898234ba3e69036271223b5f55af\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2026\\\/03\\\/30\\\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2026\\\/03\\\/30\\\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2026\\\/03\\\/30\\\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO DI SELEZIONE, PER ESAMI, PER L&#8217;ASSUNZIONE A TEMPO PIENO E INDETERMINATO DI UN OPERATORE ESPERTO, CON PROFILO DI COLLABORATORE PROFESSIONALE \u2013 OPERAIO SPECIALIZZATO\\\/CANTONIERE \u2013 DA ASSEGNARE AL SETTORE TECNICO.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/\",\"name\":\"Arquata del Tronto\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#\\\/schema\\\/person\\\/2299898234ba3e69036271223b5f55af\",\"name\":\"michelefranchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g\",\"caption\":\"michelefranchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/author\\\/michelefranchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO DI SELEZIONE, PER ESAMI, PER L'ASSUNZIONE A TEMPO PIENO E INDETERMINATO DI UN OPERATORE ESPERTO, CON PROFILO DI COLLABORATORE PROFESSIONALE \u2013 OPERAIO SPECIALIZZATO\/CANTONIERE \u2013 DA ASSEGNARE AL SETTORE TECNICO. - Arquata del Tronto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/arquatadeltronto\/2026\/03\/30\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO DI SELEZIONE, PER ESAMI, PER L'ASSUNZIONE A TEMPO PIENO E INDETERMINATO DI UN OPERATORE ESPERTO, CON PROFILO DI COLLABORATORE PROFESSIONALE \u2013 OPERAIO SPECIALIZZATO\/CANTONIERE \u2013 DA ASSEGNARE AL SETTORE TECNICO. - Arquata del Tronto","og_description":"In esecuzione alla determinazione del Responsabile del Settore Segreteria Generale n. 11 R.G. n. 94 del 26.03.2026 \u00e8 indetta selezione pubblica, per esami, per l\u2019assunzione a tempo pieno e indeterminato [&hellip;]","og_url":"https:\/\/comunicacity.net\/arquatadeltronto\/2026\/03\/30\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\/","og_site_name":"Arquata del Tronto","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-03-30T07:12:47+00:00","article_modified_time":"2026-03-30T07:51:01+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"michelefranchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"michelefranchi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2026\/03\/30\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2026\/03\/30\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\/"},"author":{"name":"michelefranchi","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#\/schema\/person\/2299898234ba3e69036271223b5f55af"},"headline":"AVVISO DI SELEZIONE, PER ESAMI, PER L&#8217;ASSUNZIONE A TEMPO PIENO E INDETERMINATO DI UN OPERATORE ESPERTO, CON PROFILO DI COLLABORATORE PROFESSIONALE \u2013 OPERAIO SPECIALIZZATO\/CANTONIERE \u2013 DA ASSEGNARE AL SETTORE TECNICO.","datePublished":"2026-03-30T07:12:47+00:00","dateModified":"2026-03-30T07:51:01+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2026\/03\/30\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\/"},"wordCount":144,"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2026\/03\/30\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\/","url":"https:\/\/comunicacity.net\/arquatadeltronto\/2026\/03\/30\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\/","name":"AVVISO DI SELEZIONE, PER ESAMI, PER L'ASSUNZIONE A TEMPO PIENO E INDETERMINATO DI UN OPERATORE ESPERTO, CON PROFILO DI COLLABORATORE PROFESSIONALE \u2013 OPERAIO SPECIALIZZATO\/CANTONIERE \u2013 DA ASSEGNARE AL SETTORE TECNICO. - Arquata del Tronto","isPartOf":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#website"},"datePublished":"2026-03-30T07:12:47+00:00","dateModified":"2026-03-30T07:51:01+00:00","author":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#\/schema\/person\/2299898234ba3e69036271223b5f55af"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2026\/03\/30\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/arquatadeltronto\/2026\/03\/30\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2026\/03\/30\/avviso-di-selezione-per-esami-per-lassunzione-a-tempo-pieno-e-indeterminato-di-un-operatore-esperto-con-profilo-di-collaboratore-professionale-operaio-specializzato-cantoniere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/arquatadeltronto\/"},{"@type":"ListItem","position":2,"name":"AVVISO DI SELEZIONE, PER ESAMI, PER L&#8217;ASSUNZIONE A TEMPO PIENO E INDETERMINATO DI UN OPERATORE ESPERTO, CON PROFILO DI COLLABORATORE PROFESSIONALE \u2013 OPERAIO SPECIALIZZATO\/CANTONIERE \u2013 DA ASSEGNARE AL SETTORE TECNICO."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#website","url":"https:\/\/comunicacity.net\/arquatadeltronto\/","name":"Arquata del Tronto","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/arquatadeltronto\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#\/schema\/person\/2299898234ba3e69036271223b5f55af","name":"michelefranchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g","caption":"michelefranchi"},"url":"https:\/\/comunicacity.net\/arquatadeltronto\/author\/michelefranchi\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts\/3280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/users\/150"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/comments?post=3280"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts\/3280\/revisions"}],"predecessor-version":[{"id":3282,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts\/3280\/revisions\/3282"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/media?parent=3280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/categories?post=3280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/tags?post=3280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}