{"id":540,"date":"2017-10-27T12:26:37","date_gmt":"2017-10-27T10:26:37","guid":{"rendered":"https:\/\/comunicacity.net\/arquatadeltronto\/?p=540"},"modified":"2017-10-27T12:26:37","modified_gmt":"2017-10-27T10:26:37","slug":"presentazione-libro-la-torre-civica-di-arquata-del-tronto","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/arquatadeltronto\/2017\/10\/27\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\/","title":{"rendered":"Presentazione libro &#8220;La Torre Civica di Arquata del Tronto&#8221;"},"content":{"rendered":"<p>Domenica 29 (Prima della Sagra Marrone che Passione) dalle ore 11 alle ore 12 a Borgo presso il Centro Pastorale &#8220;Agor\u00e0&#8221; l&#8217;Associazione Arquata Potest organizza la presentazione del libro &#8220;La Torre Civica di Arquata del Tronto&#8221;.<\/p>\n<p>&nbsp;<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Domenica 29 (Prima della Sagra Marrone che Passione) dalle ore 11 alle ore 12 a Borgo presso il Centro Pastorale &#8220;Agor\u00e0&#8221; l&#8217;Associazione Arquata Potest organizza la presentazione del libro &#8220;La [&hellip;]<\/p>\n","protected":false},"author":150,"featured_media":541,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentazione libro &quot;La Torre Civica di Arquata del Tronto&quot; - Arquata del Tronto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/arquatadeltronto\/2017\/10\/27\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentazione libro &quot;La Torre Civica di Arquata del Tronto&quot; - Arquata del Tronto\" \/>\n<meta property=\"og:description\" content=\"Domenica 29 (Prima della Sagra Marrone che Passione) dalle ore 11 alle ore 12 a Borgo presso il Centro Pastorale &#8220;Agor\u00e0&#8221; l&#8217;Associazione Arquata Potest organizza la presentazione del libro &#8220;La [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/arquatadeltronto\/2017\/10\/27\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\/\" \/>\n<meta property=\"og:site_name\" content=\"Arquata del Tronto\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-27T10:26:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/uploads\/sites\/65\/2017\/10\/ARQUATA-POTEST.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"553\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"michelefranchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"michelefranchi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2017\\\/10\\\/27\\\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2017\\\/10\\\/27\\\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\\\/\"},\"author\":{\"name\":\"michelefranchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#\\\/schema\\\/person\\\/2299898234ba3e69036271223b5f55af\"},\"headline\":\"Presentazione libro &#8220;La Torre Civica di Arquata del Tronto&#8221;\",\"datePublished\":\"2017-10-27T10:26:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2017\\\/10\\\/27\\\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\\\/\"},\"wordCount\":43,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2017\\\/10\\\/27\\\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/wp-content\\\/uploads\\\/sites\\\/65\\\/2017\\\/10\\\/ARQUATA-POTEST.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2017\\\/10\\\/27\\\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2017\\\/10\\\/27\\\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\\\/\",\"name\":\"Presentazione libro \\\"La Torre Civica di Arquata del Tronto\\\" - Arquata del Tronto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2017\\\/10\\\/27\\\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2017\\\/10\\\/27\\\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/wp-content\\\/uploads\\\/sites\\\/65\\\/2017\\\/10\\\/ARQUATA-POTEST.jpg\",\"datePublished\":\"2017-10-27T10:26:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#\\\/schema\\\/person\\\/2299898234ba3e69036271223b5f55af\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2017\\\/10\\\/27\\\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2017\\\/10\\\/27\\\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2017\\\/10\\\/27\\\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/wp-content\\\/uploads\\\/sites\\\/65\\\/2017\\\/10\\\/ARQUATA-POTEST.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/wp-content\\\/uploads\\\/sites\\\/65\\\/2017\\\/10\\\/ARQUATA-POTEST.jpg\",\"width\":553,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/2017\\\/10\\\/27\\\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentazione libro &#8220;La Torre Civica di Arquata del Tronto&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/\",\"name\":\"Arquata del Tronto\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/#\\\/schema\\\/person\\\/2299898234ba3e69036271223b5f55af\",\"name\":\"michelefranchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g\",\"caption\":\"michelefranchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/arquatadeltronto\\\/author\\\/michelefranchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentazione libro \"La Torre Civica di Arquata del Tronto\" - Arquata del Tronto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/arquatadeltronto\/2017\/10\/27\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\/","og_locale":"it_IT","og_type":"article","og_title":"Presentazione libro \"La Torre Civica di Arquata del Tronto\" - Arquata del Tronto","og_description":"Domenica 29 (Prima della Sagra Marrone che Passione) dalle ore 11 alle ore 12 a Borgo presso il Centro Pastorale &#8220;Agor\u00e0&#8221; l&#8217;Associazione Arquata Potest organizza la presentazione del libro &#8220;La [&hellip;]","og_url":"https:\/\/comunicacity.net\/arquatadeltronto\/2017\/10\/27\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\/","og_site_name":"Arquata del Tronto","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-10-27T10:26:37+00:00","og_image":[{"width":553,"height":800,"url":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/uploads\/sites\/65\/2017\/10\/ARQUATA-POTEST.jpg","type":"image\/jpeg"}],"author":"michelefranchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"michelefranchi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2017\/10\/27\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2017\/10\/27\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\/"},"author":{"name":"michelefranchi","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#\/schema\/person\/2299898234ba3e69036271223b5f55af"},"headline":"Presentazione libro &#8220;La Torre Civica di Arquata del Tronto&#8221;","datePublished":"2017-10-27T10:26:37+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2017\/10\/27\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\/"},"wordCount":43,"image":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2017\/10\/27\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/uploads\/sites\/65\/2017\/10\/ARQUATA-POTEST.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2017\/10\/27\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\/","url":"https:\/\/comunicacity.net\/arquatadeltronto\/2017\/10\/27\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\/","name":"Presentazione libro \"La Torre Civica di Arquata del Tronto\" - Arquata del Tronto","isPartOf":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2017\/10\/27\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2017\/10\/27\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/uploads\/sites\/65\/2017\/10\/ARQUATA-POTEST.jpg","datePublished":"2017-10-27T10:26:37+00:00","author":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#\/schema\/person\/2299898234ba3e69036271223b5f55af"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2017\/10\/27\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/arquatadeltronto\/2017\/10\/27\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2017\/10\/27\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\/#primaryimage","url":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/uploads\/sites\/65\/2017\/10\/ARQUATA-POTEST.jpg","contentUrl":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-content\/uploads\/sites\/65\/2017\/10\/ARQUATA-POTEST.jpg","width":553,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/2017\/10\/27\/presentazione-libro-la-torre-civica-di-arquata-del-tronto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/arquatadeltronto\/"},{"@type":"ListItem","position":2,"name":"Presentazione libro &#8220;La Torre Civica di Arquata del Tronto&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#website","url":"https:\/\/comunicacity.net\/arquatadeltronto\/","name":"Arquata del Tronto","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/arquatadeltronto\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/arquatadeltronto\/#\/schema\/person\/2299898234ba3e69036271223b5f55af","name":"michelefranchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a93579d846d56901c40174d251b3e3cba7f8484b656c24bc4eef0703500acbd1?s=96&d=mm&r=g","caption":"michelefranchi"},"url":"https:\/\/comunicacity.net\/arquatadeltronto\/author\/michelefranchi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts\/540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/users\/150"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/comments?post=540"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts\/540\/revisions"}],"predecessor-version":[{"id":542,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/posts\/540\/revisions\/542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/media\/541"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/media?parent=540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/categories?post=540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/arquatadeltronto\/wp-json\/wp\/v2\/tags?post=540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}