{"id":19058,"date":"2026-05-13T13:27:45","date_gmt":"2026-05-13T11:27:45","guid":{"rendered":"https:\/\/comunicacity.net\/belmontecastello\/2026\/05\/13\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\/"},"modified":"2026-05-13T13:31:07","modified_gmt":"2026-05-13T11:31:07","slug":"avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/belmontecastello\/2026\/05\/13\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\/","title":{"rendered":"AVVISO &#8211; Poste Italiane Progetto POLIS &#8211; Servizio rilascio passaporto elettronico"},"content":{"rendered":"<p><em>Nel Comune di Belmonte Castello l&#8217;ufficio postale, incluso nel progetto POLIS, \u00e8 abilitato al servizio di richiesta di rilascio o rinnovo del passaporto.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Nel Comune di Belmonte Castello l&#8217;ufficio postale, incluso nel progetto POLIS, \u00e8 abilitato al servizio di richiesta di rilascio o rinnovo del passaporto. Tutte le informazioni, nonch\u00e8 la documentazione necessaria sono reperibili sul sito <a href=\"https:\/\/www.poste.it\/polis-passaporto-elettronico\/\">https:\/\/www.poste.it\/polis-passaporto-elettronico<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel Comune di Belmonte Castello l&#8217;ufficio postale, incluso nel progetto POLIS, \u00e8 abilitato al servizio di richiesta di rilascio o rinnovo del passaporto.&nbsp; Descrizione&nbsp; Nel Comune di Belmonte Castello l&#8217;ufficio [&hellip;]<\/p>\n","protected":false},"author":371,"featured_media":19060,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-19058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO - Poste Italiane Progetto POLIS - Servizio rilascio passaporto elettronico - Belmonte Castello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/belmontecastello\/2026\/05\/13\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO - Poste Italiane Progetto POLIS - Servizio rilascio passaporto elettronico - Belmonte Castello\" \/>\n<meta property=\"og:description\" content=\"Nel Comune di Belmonte Castello l&#8217;ufficio postale, incluso nel progetto POLIS, \u00e8 abilitato al servizio di richiesta di rilascio o rinnovo del passaporto.&nbsp; Descrizione&nbsp; Nel Comune di Belmonte Castello l&#8217;ufficio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/belmontecastello\/2026\/05\/13\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\/\" \/>\n<meta property=\"og:site_name\" content=\"Belmonte Castello\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T11:27:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T11:31:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/belmontecastello\/wp-content\/uploads\/sites\/39\/2026\/05\/Passaporto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"255\" \/>\n\t<meta property=\"og:image:height\" content=\"148\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Danilo Iannarelli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Danilo Iannarelli\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/2026\\\/05\\\/13\\\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/2026\\\/05\\\/13\\\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\\\/\"},\"author\":{\"name\":\"Danilo Iannarelli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/#\\\/schema\\\/person\\\/9b6fedaff3e611ad42223a390511e32c\"},\"headline\":\"AVVISO &#8211; Poste Italiane Progetto POLIS &#8211; Servizio rilascio passaporto elettronico\",\"datePublished\":\"2026-05-13T11:27:45+00:00\",\"dateModified\":\"2026-05-13T11:31:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/2026\\\/05\\\/13\\\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\\\/\"},\"wordCount\":74,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/2026\\\/05\\\/13\\\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/wp-content\\\/uploads\\\/sites\\\/39\\\/2026\\\/05\\\/Passaporto.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/2026\\\/05\\\/13\\\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/2026\\\/05\\\/13\\\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\\\/\",\"name\":\"AVVISO - Poste Italiane Progetto POLIS - Servizio rilascio passaporto elettronico - Belmonte Castello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/2026\\\/05\\\/13\\\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/2026\\\/05\\\/13\\\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/wp-content\\\/uploads\\\/sites\\\/39\\\/2026\\\/05\\\/Passaporto.jpg\",\"datePublished\":\"2026-05-13T11:27:45+00:00\",\"dateModified\":\"2026-05-13T11:31:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/#\\\/schema\\\/person\\\/9b6fedaff3e611ad42223a390511e32c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/2026\\\/05\\\/13\\\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/2026\\\/05\\\/13\\\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/2026\\\/05\\\/13\\\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/wp-content\\\/uploads\\\/sites\\\/39\\\/2026\\\/05\\\/Passaporto.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/wp-content\\\/uploads\\\/sites\\\/39\\\/2026\\\/05\\\/Passaporto.jpg\",\"width\":255,\"height\":148},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/2026\\\/05\\\/13\\\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO &#8211; Poste Italiane Progetto POLIS &#8211; Servizio rilascio passaporto elettronico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/\",\"name\":\"Belmonte Castello\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/#\\\/schema\\\/person\\\/9b6fedaff3e611ad42223a390511e32c\",\"name\":\"Danilo Iannarelli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0f763981020ad49bc811ad443fbc52f2dec4656f2abba1ee8f207c986aea7a78?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0f763981020ad49bc811ad443fbc52f2dec4656f2abba1ee8f207c986aea7a78?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0f763981020ad49bc811ad443fbc52f2dec4656f2abba1ee8f207c986aea7a78?s=96&d=mm&r=g\",\"caption\":\"Danilo Iannarelli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/belmontecastello\\\/author\\\/daniloiannarelli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO - Poste Italiane Progetto POLIS - Servizio rilascio passaporto elettronico - Belmonte Castello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/belmontecastello\/2026\/05\/13\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO - Poste Italiane Progetto POLIS - Servizio rilascio passaporto elettronico - Belmonte Castello","og_description":"Nel Comune di Belmonte Castello l&#8217;ufficio postale, incluso nel progetto POLIS, \u00e8 abilitato al servizio di richiesta di rilascio o rinnovo del passaporto.&nbsp; Descrizione&nbsp; Nel Comune di Belmonte Castello l&#8217;ufficio [&hellip;]","og_url":"https:\/\/comunicacity.net\/belmontecastello\/2026\/05\/13\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\/","og_site_name":"Belmonte Castello","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-05-13T11:27:45+00:00","article_modified_time":"2026-05-13T11:31:07+00:00","og_image":[{"width":255,"height":148,"url":"https:\/\/comunicacity.net\/belmontecastello\/wp-content\/uploads\/sites\/39\/2026\/05\/Passaporto.jpg","type":"image\/jpeg"}],"author":"Danilo Iannarelli","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Danilo Iannarelli"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/belmontecastello\/2026\/05\/13\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/belmontecastello\/2026\/05\/13\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\/"},"author":{"name":"Danilo Iannarelli","@id":"https:\/\/comunicacity.net\/belmontecastello\/#\/schema\/person\/9b6fedaff3e611ad42223a390511e32c"},"headline":"AVVISO &#8211; Poste Italiane Progetto POLIS &#8211; Servizio rilascio passaporto elettronico","datePublished":"2026-05-13T11:27:45+00:00","dateModified":"2026-05-13T11:31:07+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/belmontecastello\/2026\/05\/13\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\/"},"wordCount":74,"image":{"@id":"https:\/\/comunicacity.net\/belmontecastello\/2026\/05\/13\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/belmontecastello\/wp-content\/uploads\/sites\/39\/2026\/05\/Passaporto.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/belmontecastello\/2026\/05\/13\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\/","url":"https:\/\/comunicacity.net\/belmontecastello\/2026\/05\/13\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\/","name":"AVVISO - Poste Italiane Progetto POLIS - Servizio rilascio passaporto elettronico - Belmonte Castello","isPartOf":{"@id":"https:\/\/comunicacity.net\/belmontecastello\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/belmontecastello\/2026\/05\/13\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/belmontecastello\/2026\/05\/13\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/belmontecastello\/wp-content\/uploads\/sites\/39\/2026\/05\/Passaporto.jpg","datePublished":"2026-05-13T11:27:45+00:00","dateModified":"2026-05-13T11:31:07+00:00","author":{"@id":"https:\/\/comunicacity.net\/belmontecastello\/#\/schema\/person\/9b6fedaff3e611ad42223a390511e32c"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/belmontecastello\/2026\/05\/13\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/belmontecastello\/2026\/05\/13\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/belmontecastello\/2026\/05\/13\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\/#primaryimage","url":"https:\/\/comunicacity.net\/belmontecastello\/wp-content\/uploads\/sites\/39\/2026\/05\/Passaporto.jpg","contentUrl":"https:\/\/comunicacity.net\/belmontecastello\/wp-content\/uploads\/sites\/39\/2026\/05\/Passaporto.jpg","width":255,"height":148},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/belmontecastello\/2026\/05\/13\/avviso-poste-italiane-progetto-polis-servizio-rilascio-passaporto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/belmontecastello\/"},{"@type":"ListItem","position":2,"name":"AVVISO &#8211; Poste Italiane Progetto POLIS &#8211; Servizio rilascio passaporto elettronico"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/belmontecastello\/#website","url":"https:\/\/comunicacity.net\/belmontecastello\/","name":"Belmonte Castello","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/belmontecastello\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/belmontecastello\/#\/schema\/person\/9b6fedaff3e611ad42223a390511e32c","name":"Danilo Iannarelli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/0f763981020ad49bc811ad443fbc52f2dec4656f2abba1ee8f207c986aea7a78?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0f763981020ad49bc811ad443fbc52f2dec4656f2abba1ee8f207c986aea7a78?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0f763981020ad49bc811ad443fbc52f2dec4656f2abba1ee8f207c986aea7a78?s=96&d=mm&r=g","caption":"Danilo Iannarelli"},"url":"https:\/\/comunicacity.net\/belmontecastello\/author\/daniloiannarelli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001684"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/belmontecastello\/wp-json\/wp\/v2\/posts\/19058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/belmontecastello\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/belmontecastello\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/belmontecastello\/wp-json\/wp\/v2\/users\/371"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/belmontecastello\/wp-json\/wp\/v2\/comments?post=19058"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/belmontecastello\/wp-json\/wp\/v2\/posts\/19058\/revisions"}],"predecessor-version":[{"id":19059,"href":"https:\/\/comunicacity.net\/belmontecastello\/wp-json\/wp\/v2\/posts\/19058\/revisions\/19059"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/belmontecastello\/wp-json\/wp\/v2\/media\/19060"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/belmontecastello\/wp-json\/wp\/v2\/media?parent=19058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/belmontecastello\/wp-json\/wp\/v2\/categories?post=19058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/belmontecastello\/wp-json\/wp\/v2\/tags?post=19058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}