{"id":45,"date":"2016-07-14T14:46:13","date_gmt":"2016-07-14T12:46:13","guid":{"rendered":"https:\/\/comunicacity.net\/broccostella\/?post_type=turismo&#038;p=45"},"modified":"2016-08-03T17:25:25","modified_gmt":"2016-08-03T15:25:25","slug":"chiesa-madonna-della-stella","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/broccostella\/turismo\/cosa-visitare\/chiesa-madonna-della-stella\/","title":{"rendered":"Chiesa Madonna Della Stella"},"content":{"rendered":"<p style=\"text-align: justify;\">Realizzata per iniziativa del parroco don Domenico Cardi, la chiesa parrocchiale dedicata alla Vergine del territorio di Broccostella \u00e8 situata nel centro del paese.<\/p>\n<p style=\"text-align: justify;\">L&#8217;edificio sacro fu progettato negli anni 1963-1964 dall&#8217;architetto Giuseppe Zander, fu costruito nel 1967 e consacrato il 28 settembre 1968 con una solenne cerimonia presieduta dal vescovo di Sora Biagio Musto. Connotata da nitide geometrie, la chiesa si presenta all&#8217;esterno rivestita interamente in mattoni con il prospetto segnato nella parte superiore da una vetrata a forma di croce ed un portico in cemento armato a tre campate che segna il punto di contatto della chiesa con il circostante paese; l&#8217;interno \u00e8 costituito da un capiente impianto longitudinale attraversato dalla ritmica di quattro portali trasversali in cemento armato che percorrono l&#8217;unica navata.<\/p>\n<p style=\"text-align: justify;\">Nel presbiterio l&#8217;architetto Zander ha riproposto in modo concentrato il tema presente nell&#8217;aula con un portale trasversale di contenute dimensioni che enfatizza lo spazio della celebrazione. Al 1972 risale il campanile, progettato dal medesimmo architetto, ubicato a sei metri di distanza dalla chiesa. Dopo pi\u00f9 di quarant&#8217;anni di vita, la chiesa di Santa Maria della Stella necessitava di interventi intesi dapprima in funzione di semplici lavori di manutenzione straordinaria e poi sviluppati, in una versione molto ampliata grazie alla disponibilit\u00e0 resa dall&#8217;attuale parroco don Tommaso Del Sorbo coadiuvato dal Consiglio Parrocchiale, come impegnativo e complesso progetto concentrato su un vero adeguamento liturgico, spaziale ed impiantistico progettato dall&#8217;architetto Laura Scrimieri.<\/p>\n<p style=\"text-align: justify;\">La chiesa \u00e8 stata cos\u00ec dotata di una nuova pavimentazione che cela un sofisticato impianto di riscaldamento, di un nuovo impianto elettrico, di pannelli isolanti sulle pareti laterali posizionati per ottenere l&#8217;isolamento termico, di un nuovo impianto di diffusione sonora, di nuovi arredi lignei e di una nuova cromia. Il punto generatore di tutta la progettazione dell&#8217;arch. Laura Scrimieri \u00e8 stato quello degli arredi liturgici costruiti in travertino rosso persiano misto a travertino sbozzato.<\/p>\n<p style=\"text-align: justify;\">L&#8217;altare \u00e8 stato cos\u00ec concepito dalla progettista in una contenuta forma cubica attraversato dal disegno di una scala in un significativo richiamo iconografico che associa la scala di Giacobbe al Cristo e in particolare alla funzione stessa dell&#8217;altare inteso cos\u00ec nella doppia valenza di luogo dove attraverso il Cristo scende da Dio la Salvezza e dall&#8217;uomo sale a Dio la lode perfetta.<\/p>\n<p style=\"text-align: justify;\">L&#8217;ambone, luogo dell&#8217;Annuncio della Parola di Dio, \u00e8 stato interpretato quale monumento alla Risurrezione del Salvatore: il sudario di Cristo scolpito nel travertino si riversa sul fronte di esso ed i sottostanti simboli del vaso, del pesce e della colomba incisi sulla pietra alludono al Mistero Pasquale. Infine il fonte battesimale, collocato pi\u00f9 in basso rispetto alla quota della pavimentazione, in significativo richiamo all&#8217;immersione del catecumeno che muore e risorge a vita nuova per mezzo del battesimo, \u00e8 stato impostato seguendo una forma cubica in collegamento all&#8217;iconografia battesimale come avvento del Mistero nel contesto terreno. Splendidi nei materiali e nelle iconografie sono i tre brani musivi del maestro Augusto Ranocchi che da oggi impreziosiscono la chiesa parrocchiale di Broccostella. Rispettivamente a destra ed a sinistra della zona inferiore del portale che precede l&#8217;abside si trovano la scena del Battesimo di Cristo ed una Gloria degli Angeli che contemplano la bronzea custodia eucaristica opera dello stesso Ranocchi. Al centro della zona presbiteriale si apre la grande illustrazione liturgica della chiesa ossia il mosaico rappresentante la Madonna della Stella pronta ad accogliere il fedele nel suo incidere lungo la navata.<\/p>\n<p style=\"text-align: justify;\">Tali opere costituicono, con le loro considerevoli dimensioni, tre urgenze vigorose e pulsanti che, come accadeva in passato nei luoghi di culto decorati con questa tecnica, esprimono efficaci similitudini del sacro: calamite che attirano la vista per poi rapire l&#8217;anima. La realizzazione di un cos\u00ec impegnativo risultato \u00e8 stato frutto di anni di lavori praticati sul sacro edificio.<br \/>\nLa riapertura e dedicazione del nuovo altare della chiesa parrocchiale \u00e8 avvenuta il 5 settembre 2010 in una solenne celebrazione presieduta dal vescovo di Sora, Aquino e Pontecorvo, S. E. Mons. Filippo Iannone.<\/p>\n<p style=\"text-align: justify;\">La storica portata dell&#8217;evento \u00e8 stata celebrata con tre giorni di festeggiamenti di cui si segnala la presentazione del libro scritto dal Dott. Stefano Di Palma dal titolo La chiesa di Santa Maria della Stella: dalle origini all&#8217;adeguamento liturgico, (Prefazione Prof.ssa Maria Antonietta Crippa), Isola del Liri, 2010, (180pp.) avvenuta lo scorso 3 settembre 2010 presso il &#8220;Palasport&#8221; di Broccostella.<\/p>\n<p style=\"text-align: justify;\">Il volume, patrocinato dalla Regione Lazio, la Provincia di Frosinone ed il Comune di Broccostella, \u00e8 disponibile gratuitamente previa richiesta al parroco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Realizzata per iniziativa del parroco don Domenico Cardi, la chiesa parrocchiale dedicata alla Vergine del territorio di Broccostella \u00e8 situata nel centro del paese. L&#8217;edificio sacro fu progettato negli anni [&hellip;]<\/p>\n","protected":false},"featured_media":50,"parent":44,"menu_order":1,"template":"","meta":[],"class_list":["post-45","turismo","type-turismo","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chiesa Madonna Della Stella - Broccostella<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/broccostella\/turismo\/cosa-visitare\/chiesa-madonna-della-stella\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiesa Madonna Della Stella - Broccostella\" \/>\n<meta property=\"og:description\" content=\"Realizzata per iniziativa del parroco don Domenico Cardi, la chiesa parrocchiale dedicata alla Vergine del territorio di Broccostella \u00e8 situata nel centro del paese. L&#8217;edificio sacro fu progettato negli anni [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/broccostella\/turismo\/cosa-visitare\/chiesa-madonna-della-stella\/\" \/>\n<meta property=\"og:site_name\" content=\"Broccostella\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-03T15:25:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/broccostella\/wp-content\/uploads\/sites\/34\/2016\/07\/260.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/broccostella\\\/turismo\\\/cosa-visitare\\\/chiesa-madonna-della-stella\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/broccostella\\\/turismo\\\/cosa-visitare\\\/chiesa-madonna-della-stella\\\/\",\"name\":\"Chiesa Madonna Della Stella - Broccostella\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/broccostella\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/broccostella\\\/turismo\\\/cosa-visitare\\\/chiesa-madonna-della-stella\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/broccostella\\\/turismo\\\/cosa-visitare\\\/chiesa-madonna-della-stella\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/broccostella\\\/wp-content\\\/uploads\\\/sites\\\/34\\\/2016\\\/07\\\/260.jpg\",\"datePublished\":\"2016-07-14T12:46:13+00:00\",\"dateModified\":\"2016-08-03T15:25:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/broccostella\\\/turismo\\\/cosa-visitare\\\/chiesa-madonna-della-stella\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/broccostella\\\/turismo\\\/cosa-visitare\\\/chiesa-madonna-della-stella\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/broccostella\\\/turismo\\\/cosa-visitare\\\/chiesa-madonna-della-stella\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/broccostella\\\/wp-content\\\/uploads\\\/sites\\\/34\\\/2016\\\/07\\\/260.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/broccostella\\\/wp-content\\\/uploads\\\/sites\\\/34\\\/2016\\\/07\\\/260.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/broccostella\\\/turismo\\\/cosa-visitare\\\/chiesa-madonna-della-stella\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/broccostella\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cosa Visitare\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/broccostella\\\/turismo\\\/cosa-visitare\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chiesa Madonna Della Stella\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/broccostella\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/broccostella\\\/\",\"name\":\"Broccostella\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/broccostella\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiesa Madonna Della Stella - Broccostella","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/broccostella\/turismo\/cosa-visitare\/chiesa-madonna-della-stella\/","og_locale":"it_IT","og_type":"article","og_title":"Chiesa Madonna Della Stella - Broccostella","og_description":"Realizzata per iniziativa del parroco don Domenico Cardi, la chiesa parrocchiale dedicata alla Vergine del territorio di Broccostella \u00e8 situata nel centro del paese. L&#8217;edificio sacro fu progettato negli anni [&hellip;]","og_url":"https:\/\/comunicacity.net\/broccostella\/turismo\/cosa-visitare\/chiesa-madonna-della-stella\/","og_site_name":"Broccostella","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2016-08-03T15:25:25+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/broccostella\/wp-content\/uploads\/sites\/34\/2016\/07\/260.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/broccostella\/turismo\/cosa-visitare\/chiesa-madonna-della-stella\/","url":"https:\/\/comunicacity.net\/broccostella\/turismo\/cosa-visitare\/chiesa-madonna-della-stella\/","name":"Chiesa Madonna Della Stella - Broccostella","isPartOf":{"@id":"https:\/\/comunicacity.net\/broccostella\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/broccostella\/turismo\/cosa-visitare\/chiesa-madonna-della-stella\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/broccostella\/turismo\/cosa-visitare\/chiesa-madonna-della-stella\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/broccostella\/wp-content\/uploads\/sites\/34\/2016\/07\/260.jpg","datePublished":"2016-07-14T12:46:13+00:00","dateModified":"2016-08-03T15:25:25+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/broccostella\/turismo\/cosa-visitare\/chiesa-madonna-della-stella\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/broccostella\/turismo\/cosa-visitare\/chiesa-madonna-della-stella\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/broccostella\/turismo\/cosa-visitare\/chiesa-madonna-della-stella\/#primaryimage","url":"https:\/\/comunicacity.net\/broccostella\/wp-content\/uploads\/sites\/34\/2016\/07\/260.jpg","contentUrl":"https:\/\/comunicacity.net\/broccostella\/wp-content\/uploads\/sites\/34\/2016\/07\/260.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/broccostella\/turismo\/cosa-visitare\/chiesa-madonna-della-stella\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/broccostella\/"},{"@type":"ListItem","position":2,"name":"Cosa Visitare","item":"https:\/\/comunicacity.net\/broccostella\/turismo\/cosa-visitare\/"},{"@type":"ListItem","position":3,"name":"Chiesa Madonna Della Stella"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/broccostella\/#website","url":"https:\/\/comunicacity.net\/broccostella\/","name":"Broccostella","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/broccostella\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/broccostella\/wp-json\/wp\/v2\/turismo\/45","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/broccostella\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/broccostella\/wp-json\/wp\/v2\/types\/turismo"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/broccostella\/wp-json\/wp\/v2\/turismo\/44"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/broccostella\/wp-json\/wp\/v2\/media\/50"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/broccostella\/wp-json\/wp\/v2\/media?parent=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}