{"id":17517,"date":"2024-07-11T15:50:10","date_gmt":"2024-07-11T13:50:10","guid":{"rendered":"https:\/\/comunicacity.net\/buonabitacolo\/2024\/07\/11\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\/"},"modified":"2024-07-11T15:50:10","modified_gmt":"2024-07-11T13:50:10","slug":"manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/buonabitacolo\/2024\/07\/11\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\/","title":{"rendered":"Manifestazione di interesse per l\u2019individuazione di beneficiari tirocini"},"content":{"rendered":"<p><em>finalizzati all\u2019inclusione sociale (Accordo tra Governo e Regioni n. 7\/CSR del 22\/01\/2015) retribuiti della Regione Campania.<br \/>\nScadenza 19\/07\/2024 ore 13.00<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Con decreto Direttoriale n. 73 del 01.07.2024 \u00e8 indetto Avviso pubblico per l\u2019individuazione di potenziali beneficiari per l\u2019attivazione del<br \/>\nPercorso 4 \u201cLavoro e Inclusione\u201d Programma \u201cGaranzia di Occupabilit\u00e0 dei Lavoratori\u201d finalizzato all\u2019avvio di tirocini di inclusione sociale per<br \/>\npersone residenti nei Comuni di Atena Lucana, Auletta,\u00a0<span class=\"il\">Buonabitacolo<\/span>, Casalbuono, Monte San Giacomo, Pertosa, Petina, Polla, Sala Consilina,<br \/>\nSan Pietro al Tanagro, Sassano, Salvitelle, Sanza, San Rufo, Teggiano per la durata di 12 mensilit\u00e0 da svolgersi presso i comuni sopra<br \/>\nindicati.<\/p>\n<p>Possono partecipare alla manifestazione di interesse le persone fino a 65 anni di et\u00e0, residenti e\/o domiciliate in Regione Campania, in carico<br \/>\nai servizi sociali dell\u2019Ambito S10 e che si trovino alternativamente, in almeno una delle seguenti situazioni:<\/p>\n<ul>\n<li>Beneficiari di ammortizzatori sociali in costanza di rapporto di lavoro: le specifiche categorie di lavoratori sono individuate dalla<br \/>\nLegge di Bilancio 2022;<\/li>\n<li>Beneficiari di ammortizzatori sociali in assenza di rapporto di lavoro: disoccupati percettori di NASPI o DIS-COLL;<\/li>\n<li>Beneficiari di sostegno al reddito di natura assistenziale: percettori dell\u2019Assegno di inclusione;<\/li>\n<li>Lavoratori fragili o vulnerabili: giovani NEET (meno di 30 anni), donne in condizioni di svantaggio, persone con disabilit\u00e0, lavoratori<br \/>\nmaturi (55 anni e oltre), persone che sono in carico o sono segnalate dagli enti che operano nel sistema dei servizi sociali o sociosanitari<br \/>\ne\/o sono inserite in progetti\/interventi di inclusione sociale;<\/li>\n<li>Disoccupati senza sostegno al reddito: disoccupati da almeno sei mesi, altri lavoratori con minori opportunit\u00e0 occupazionali (giovani e donne,<br \/>\nanche non in condizioni di fragilit\u00e0), lavoratori autonomi che cessano l\u2019attivit\u00e0 o con redditi molto bassi;<\/li>\n<li>Lavoratori con redditi molto bassi (i cosiddetti working poor): il cui reddito da lavoro dipendente o autonomo sia inferiore alla soglia<br \/>\ndell\u2019incapienza secondo la disciplina fiscale.<\/li>\n<\/ul>\n<p>La manifestazione di interesse deve essere presentata attraverso apposito modello sottoscritto (allegato al presente avviso), muniti di<br \/>\ndocumenti di riconoscimento e modello ISEE aggiornato.<\/p>\n<p>Il suddetto modello \u00e8 scaricabile al seguente sito web: <a href=\"https:\/\/www.halleyweb.com\/csvdtgabr\/po\/mostra_news.php?id=180&amp;area=H\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.halleyweb.com\/csvdtgabr\/po\/mostra_news.php?id%3D180%26area%3DH&amp;source=gmail&amp;ust=1720781710151000&amp;usg=AOvVaw3ri97R8qmHy4zx0VGNI083\">https:\/\/www.halleyweb.com\/csvdtgabr\/po\/mostra_news.php?id=180&amp;area=H<\/a><br \/>\noppure \u00e8 possibile ritirarlo presso l\u2019ufficio protocollo del Comune di <span class=\"il\">Buonabitacolo<\/span>.<\/p>\n<p>La documentazione deve essere consegnata a mano presso lo Sportello Sociale del proprio comune di residenza a far data dal 08.07.2024 e fino<br \/>\nalle ore 13:00 del 19.07.2024 salvo eventuale proroga.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>finalizzati all\u2019inclusione sociale (Accordo tra Governo e Regioni n. 7\/CSR del 22\/01\/2015) retribuiti della Regione Campania. Scadenza 19\/07\/2024 ore 13.00&nbsp; Descrizione&nbsp; Con decreto Direttoriale n. 73 del 01.07.2024 \u00e8 indetto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17518,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-17517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manifestazione di interesse per l\u2019individuazione di beneficiari tirocini - Buonabitacolo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/buonabitacolo\/2024\/07\/11\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manifestazione di interesse per l\u2019individuazione di beneficiari tirocini - Buonabitacolo\" \/>\n<meta property=\"og:description\" content=\"finalizzati all\u2019inclusione sociale (Accordo tra Governo e Regioni n. 7\/CSR del 22\/01\/2015) retribuiti della Regione Campania. Scadenza 19\/07\/2024 ore 13.00&nbsp; Descrizione&nbsp; Con decreto Direttoriale n. 73 del 01.07.2024 \u00e8 indetto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/buonabitacolo\/2024\/07\/11\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\/\" \/>\n<meta property=\"og:site_name\" content=\"Buonabitacolo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-11T13:50:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/buonabitacolo\/wp-content\/uploads\/sites\/196\/2024\/07\/comune-di-buonabitacolo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2024\\\/07\\\/11\\\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2024\\\/07\\\/11\\\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Manifestazione di interesse per l\u2019individuazione di beneficiari tirocini\",\"datePublished\":\"2024-07-11T13:50:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2024\\\/07\\\/11\\\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\\\/\"},\"wordCount\":394,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2024\\\/07\\\/11\\\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/wp-content\\\/uploads\\\/sites\\\/196\\\/2024\\\/07\\\/comune-di-buonabitacolo.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2024\\\/07\\\/11\\\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2024\\\/07\\\/11\\\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\\\/\",\"name\":\"Manifestazione di interesse per l\u2019individuazione di beneficiari tirocini - Buonabitacolo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2024\\\/07\\\/11\\\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2024\\\/07\\\/11\\\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/wp-content\\\/uploads\\\/sites\\\/196\\\/2024\\\/07\\\/comune-di-buonabitacolo.jpg\",\"datePublished\":\"2024-07-11T13:50:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2024\\\/07\\\/11\\\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2024\\\/07\\\/11\\\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2024\\\/07\\\/11\\\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/wp-content\\\/uploads\\\/sites\\\/196\\\/2024\\\/07\\\/comune-di-buonabitacolo.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/wp-content\\\/uploads\\\/sites\\\/196\\\/2024\\\/07\\\/comune-di-buonabitacolo.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2024\\\/07\\\/11\\\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manifestazione di interesse per l\u2019individuazione di beneficiari tirocini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/\",\"name\":\"Buonabitacolo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/wp-content\\\/uploads\\\/sites\\\/196\\\/2021\\\/02\\\/Buonabitacolo-800x582-1.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/wp-content\\\/uploads\\\/sites\\\/196\\\/2021\\\/02\\\/Buonabitacolo-800x582-1.png\",\"width\":800,\"height\":582,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manifestazione di interesse per l\u2019individuazione di beneficiari tirocini - Buonabitacolo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/buonabitacolo\/2024\/07\/11\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\/","og_locale":"it_IT","og_type":"article","og_title":"Manifestazione di interesse per l\u2019individuazione di beneficiari tirocini - Buonabitacolo","og_description":"finalizzati all\u2019inclusione sociale (Accordo tra Governo e Regioni n. 7\/CSR del 22\/01\/2015) retribuiti della Regione Campania. Scadenza 19\/07\/2024 ore 13.00&nbsp; Descrizione&nbsp; Con decreto Direttoriale n. 73 del 01.07.2024 \u00e8 indetto [&hellip;]","og_url":"https:\/\/comunicacity.net\/buonabitacolo\/2024\/07\/11\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\/","og_site_name":"Buonabitacolo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-07-11T13:50:10+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/comunicacity.net\/buonabitacolo\/wp-content\/uploads\/sites\/196\/2024\/07\/comune-di-buonabitacolo.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/buonabitacolo\/2024\/07\/11\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/2024\/07\/11\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/buonabitacolo\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Manifestazione di interesse per l\u2019individuazione di beneficiari tirocini","datePublished":"2024-07-11T13:50:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/2024\/07\/11\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\/"},"wordCount":394,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/2024\/07\/11\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/buonabitacolo\/wp-content\/uploads\/sites\/196\/2024\/07\/comune-di-buonabitacolo.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/buonabitacolo\/2024\/07\/11\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\/","url":"https:\/\/comunicacity.net\/buonabitacolo\/2024\/07\/11\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\/","name":"Manifestazione di interesse per l\u2019individuazione di beneficiari tirocini - Buonabitacolo","isPartOf":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/2024\/07\/11\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/2024\/07\/11\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/buonabitacolo\/wp-content\/uploads\/sites\/196\/2024\/07\/comune-di-buonabitacolo.jpg","datePublished":"2024-07-11T13:50:10+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/2024\/07\/11\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/buonabitacolo\/2024\/07\/11\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/buonabitacolo\/2024\/07\/11\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\/#primaryimage","url":"https:\/\/comunicacity.net\/buonabitacolo\/wp-content\/uploads\/sites\/196\/2024\/07\/comune-di-buonabitacolo.jpg","contentUrl":"https:\/\/comunicacity.net\/buonabitacolo\/wp-content\/uploads\/sites\/196\/2024\/07\/comune-di-buonabitacolo.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/buonabitacolo\/2024\/07\/11\/manifestazione-di-interesse-per-lindividuazione-di-beneficiari-tirocini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/buonabitacolo\/"},{"@type":"ListItem","position":2,"name":"Manifestazione di interesse per l\u2019individuazione di beneficiari tirocini"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/buonabitacolo\/#website","url":"https:\/\/comunicacity.net\/buonabitacolo\/","name":"Buonabitacolo","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/buonabitacolo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/buonabitacolo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/buonabitacolo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/buonabitacolo\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/buonabitacolo\/wp-content\/uploads\/sites\/196\/2021\/02\/Buonabitacolo-800x582-1.png","contentUrl":"https:\/\/comunicacity.net\/buonabitacolo\/wp-content\/uploads\/sites\/196\/2021\/02\/Buonabitacolo-800x582-1.png","width":800,"height":582,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/buonabitacolo\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/buonabitacolo\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001586"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/posts\/17517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/comments?post=17517"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/posts\/17517\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/media\/17518"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/media?parent=17517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/categories?post=17517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/tags?post=17517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}