{"id":17659,"date":"2026-01-23T11:49:48","date_gmt":"2026-01-23T10:49:48","guid":{"rendered":"https:\/\/comunicacity.net\/buonabitacolo\/2026\/01\/23\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\/"},"modified":"2026-01-23T11:49:48","modified_gmt":"2026-01-23T10:49:48","slug":"referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/buonabitacolo\/2026\/01\/23\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\/","title":{"rendered":"Referendum 22 e 23 Marzo 2026 : Opzione degli elettori residenti all&#8217;estero"},"content":{"rendered":"<p><em>In occasione del prossimo Referendum Costituzionale confermativo indetto per i giorni 22 e 23 marzo 2026, i cittadini italiani residenti all&#8217;estero hanno la possibilit\u00e0 di scegliere come esercitare il proprio diritto di voto.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>In allegato il modulo da compilare in ogni sua parte.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_17661\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/buonabitacolo\/wp-content\/uploads\/sites\/196\/2026\/01\/modulo-di-opzione-referendum-2026.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/buonabitacolo\/wp-content\/uploads\/sites\/196\/2026\/01\/modulo-di-opzione-referendum-2026.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>modulo di opzione referendum 2026<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In occasione del prossimo Referendum Costituzionale confermativo indetto per i giorni 22 e 23 marzo 2026, i cittadini italiani residenti all&#8217;estero hanno la possibilit\u00e0 di scegliere come esercitare il proprio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17660,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-17659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Referendum 22 e 23 Marzo 2026 : Opzione degli elettori residenti all&#039;estero - Buonabitacolo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/buonabitacolo\/2026\/01\/23\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Referendum 22 e 23 Marzo 2026 : Opzione degli elettori residenti all&#039;estero - Buonabitacolo\" \/>\n<meta property=\"og:description\" content=\"In occasione del prossimo Referendum Costituzionale confermativo indetto per i giorni 22 e 23 marzo 2026, i cittadini italiani residenti all&#8217;estero hanno la possibilit\u00e0 di scegliere come esercitare il proprio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/buonabitacolo\/2026\/01\/23\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\/\" \/>\n<meta property=\"og:site_name\" content=\"Buonabitacolo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-23T10:49:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/buonabitacolo\/wp-content\/uploads\/sites\/196\/2026\/01\/elezioni-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1829\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2026\\\/01\\\/23\\\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2026\\\/01\\\/23\\\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Referendum 22 e 23 Marzo 2026 : Opzione degli elettori residenti all&#8217;estero\",\"datePublished\":\"2026-01-23T10:49:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2026\\\/01\\\/23\\\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\\\/\"},\"wordCount\":51,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2026\\\/01\\\/23\\\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/wp-content\\\/uploads\\\/sites\\\/196\\\/2026\\\/01\\\/elezioni-scaled-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2026\\\/01\\\/23\\\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2026\\\/01\\\/23\\\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\\\/\",\"name\":\"Referendum 22 e 23 Marzo 2026 : Opzione degli elettori residenti all'estero - Buonabitacolo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2026\\\/01\\\/23\\\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2026\\\/01\\\/23\\\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/wp-content\\\/uploads\\\/sites\\\/196\\\/2026\\\/01\\\/elezioni-scaled-1.jpg\",\"datePublished\":\"2026-01-23T10:49:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2026\\\/01\\\/23\\\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2026\\\/01\\\/23\\\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2026\\\/01\\\/23\\\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/wp-content\\\/uploads\\\/sites\\\/196\\\/2026\\\/01\\\/elezioni-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/wp-content\\\/uploads\\\/sites\\\/196\\\/2026\\\/01\\\/elezioni-scaled-1.jpg\",\"width\":2560,\"height\":1829},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/2026\\\/01\\\/23\\\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referendum 22 e 23 Marzo 2026 : Opzione degli elettori residenti all&#8217;estero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/\",\"name\":\"Buonabitacolo\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/wp-content\\\/uploads\\\/sites\\\/196\\\/2021\\\/02\\\/Buonabitacolo-800x582-1.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/wp-content\\\/uploads\\\/sites\\\/196\\\/2021\\\/02\\\/Buonabitacolo-800x582-1.png\",\"width\":800,\"height\":582,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/buonabitacolo\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Referendum 22 e 23 Marzo 2026 : Opzione degli elettori residenti all'estero - Buonabitacolo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/buonabitacolo\/2026\/01\/23\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\/","og_locale":"it_IT","og_type":"article","og_title":"Referendum 22 e 23 Marzo 2026 : Opzione degli elettori residenti all'estero - Buonabitacolo","og_description":"In occasione del prossimo Referendum Costituzionale confermativo indetto per i giorni 22 e 23 marzo 2026, i cittadini italiani residenti all&#8217;estero hanno la possibilit\u00e0 di scegliere come esercitare il proprio [&hellip;]","og_url":"https:\/\/comunicacity.net\/buonabitacolo\/2026\/01\/23\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\/","og_site_name":"Buonabitacolo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-01-23T10:49:48+00:00","og_image":[{"width":2560,"height":1829,"url":"https:\/\/comunicacity.net\/buonabitacolo\/wp-content\/uploads\/sites\/196\/2026\/01\/elezioni-scaled-1.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/buonabitacolo\/2026\/01\/23\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/2026\/01\/23\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/buonabitacolo\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Referendum 22 e 23 Marzo 2026 : Opzione degli elettori residenti all&#8217;estero","datePublished":"2026-01-23T10:49:48+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/2026\/01\/23\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\/"},"wordCount":51,"publisher":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/2026\/01\/23\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/buonabitacolo\/wp-content\/uploads\/sites\/196\/2026\/01\/elezioni-scaled-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/buonabitacolo\/2026\/01\/23\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\/","url":"https:\/\/comunicacity.net\/buonabitacolo\/2026\/01\/23\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\/","name":"Referendum 22 e 23 Marzo 2026 : Opzione degli elettori residenti all'estero - Buonabitacolo","isPartOf":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/2026\/01\/23\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/2026\/01\/23\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/buonabitacolo\/wp-content\/uploads\/sites\/196\/2026\/01\/elezioni-scaled-1.jpg","datePublished":"2026-01-23T10:49:48+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/2026\/01\/23\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/buonabitacolo\/2026\/01\/23\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/buonabitacolo\/2026\/01\/23\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\/#primaryimage","url":"https:\/\/comunicacity.net\/buonabitacolo\/wp-content\/uploads\/sites\/196\/2026\/01\/elezioni-scaled-1.jpg","contentUrl":"https:\/\/comunicacity.net\/buonabitacolo\/wp-content\/uploads\/sites\/196\/2026\/01\/elezioni-scaled-1.jpg","width":2560,"height":1829},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/buonabitacolo\/2026\/01\/23\/referendum-22-e-23-marzo-2026-opzione-degli-elettori-residenti-allestero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/buonabitacolo\/"},{"@type":"ListItem","position":2,"name":"Referendum 22 e 23 Marzo 2026 : Opzione degli elettori residenti all&#8217;estero"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/buonabitacolo\/#website","url":"https:\/\/comunicacity.net\/buonabitacolo\/","name":"Buonabitacolo","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/buonabitacolo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/buonabitacolo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/buonabitacolo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/buonabitacolo\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/buonabitacolo\/wp-content\/uploads\/sites\/196\/2021\/02\/Buonabitacolo-800x582-1.png","contentUrl":"https:\/\/comunicacity.net\/buonabitacolo\/wp-content\/uploads\/sites\/196\/2021\/02\/Buonabitacolo-800x582-1.png","width":800,"height":582,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/buonabitacolo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/buonabitacolo\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/buonabitacolo\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001786"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/posts\/17659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/comments?post=17659"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/posts\/17659\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/media\/17660"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/media?parent=17659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/categories?post=17659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/buonabitacolo\/wp-json\/wp\/v2\/tags?post=17659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}