{"id":15,"date":"2017-01-20T15:37:33","date_gmt":"2017-01-20T14:37:33","guid":{"rendered":"https:\/\/comunicacity.net\/butera\/?post_type=turismo&#038;p=15"},"modified":"2017-01-20T15:37:33","modified_gmt":"2017-01-20T14:37:33","slug":"omphake","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/butera\/turismo\/omphake\/","title":{"rendered":"OMPHAKE"},"content":{"rendered":"<p style=\"text-align: justify;\">La leggenda di Cocalo Si dice che Cocalo, venuto in Sicilia, nel 1300 a.C. re dei Sicani, avesse abitato ed avesse posto la sua reggia ad Omphake. Presso Cocalo arriv\u00f2 Dedalo, fuggito da Creta per liberarsi da Minosse, perch\u00e9 voleva ucciderlo per la morte del Minotauro. (Il Minotauro era nato da Pasifae, moglie di Minosse, attraverso un accoppiamento con un toro, personaggio dal corpo umano e testa taurina).<\/p>\n<p style=\"text-align: justify;\">Poich\u00e9 Minosse venne a cercarlo in Sicilia e chiese a Cocalo la consegna di Dedalo, Cocalo si rifiut\u00f2 e cos\u00ec venne attaccato assieme a Dedalo da Minosse. Cocalo con inganno, mentre Minosse inseguiva Dedalo, lo fece cadere in un lebete di acqua bollente, ove Minosse mori, (ad Omphake). Si crede che Omphake sia Butera, ove Cocalo aveva la sua reggia e possibilmente doveva essere tra Piano della Fiera e Fontana Calda, nome derivato forse dalla leggenda della morte di Minosse nel lebete d\u2019acqua bollente. Ad Omphake esisteva una sorgente la cui acqua bevuta da donne sterili, le rendeva prolifere e la conferma l\u2019abbiamo avuta attraverso gli scavi condotti dal Prof. Adamasteanu con il ritrovamento di statuette votive di donne gravide nel tempio rilevato sopra Fontana Calda, il santuario campestre di Fontana Calda, sempre nel territorio di Butera. Morto Minosse, i suoi soldati non ritornarono in patria, ma si sparsero in Sicilia e cos\u00ec abbiamo il primo insediamento cretese in Sicilia. Questo \u00e8 il periodo in cui la Sicilia fu chiamata Sicania, l\u2019isola di Cocalo e Minosse. Io penso che Omphake possa essere stato il primo nome che abbia avuto la citt\u00e0 di Butera. Omphake che pu\u00f2 essere anche Omphakeo il cui significato sarebbe succo di acini dell\u2019uva non ancora matura, o di Omphakinoo il cui significato sarebbe il ricavato della spremu ta delle olive non ancora mature, e il territorio di Butera era ed \u00e8 ricco di questi prodotti. Potrebbe essere ancora una derivazione da Omphalos ombelico. Gli antichi greci designavano una sacra pietra che si trovava nel santuario di Apollo a Delfi e segnava il centro della terra.<\/p>\n<p style=\"text-align: justify;\">Dalle antiche descrizioni e figurazioni vascolari, e da un modello ritrovato a Delfi, si ricava che Omphalo era una pietra conica, dalla sommit\u00e0 ricoperta di lana intrecciata, due aquile d\u2019oro le stavano a lato. Rohde ed Harrison credettero che Omphalo inizialmente rappresentasse la pietra sulla tomba &#8230;; Roscher ed altri considerarono originario il significato di centro del mondo. Eliade, infine, ha sostenuto -che le due spiegazioni non si escludono a vicenda, ma si integrano; una tomba sacra, quale punto d\u2019interferenza del mondo dei morti con il mondo dei vivi; \u00e8 un centro simbolico e mistico. Sembra inoltre indubbio che Omphalo delfico appartenesse alla originaria religione ctonia del santuario, il nuovo culto di Omphalo si annesse il simbolo del suo valore sacrale,presso l\u2019Omphalo di Delfi, luogo di rigenerazione per eccellenza, Oreste fu purificato da Apollo. Omphalos = Protuberdnza nel mezzo di una superficie, punto centrale, centro, centro della terra abitata. Io penso che Butera abbia tutte queste caratteristiche, per qual motivo non avrebbe potuto essere Omphake? Dedalo, grato verso Cocalo gli edific\u00f2 la fortezza, il tortuoso ed inespugnabile Castello ed un\u2019ampia muraglia ove Cocalo trasfer\u00ec la sua reggia ed i tesori, compreso il capolavoro della statua di Giunone, venerata dai Siculi di quella citt\u00e0.<\/p>\n<p style=\"text-align: justify;\">La statua \u00e8 definita capolavoro perch\u00e9 si allontana dalle normali, non \u00e8 pi\u00f9 un\u2019immagine a lunga veste talare ove compaiono i soli piedi, Dedalo volle creare la statua con gli occhi dischiusi, braccia alzate e gambe aperte come per camminare, innovando dai goffi fantocci con piedi giunti e braccia attaccate al petto, a lui anteriori, che Diodoro ci descrive con parole perfettamente adatte ai primordiali Xoana (Dedaliche Parevan, sculture in legno. La tradizione ricorda un attacco ad Omphake comandato dall\u2019ecista Antifemo durante la prima generazione della colonia greca in Sicilia, ed i segni di ellenizzazione pi\u00f9 o meno contemporanei ai ritrovamenti dei greci di Gela, appartenenti al periodo della fondazione, appaiono anche a Butera, \u00e8 possibile che inizialmente possa esserci stata una fase di coabitazione ad Omphake tra Sicani e Cretesi, comunque questo sarebbe stato il primo sito indigeno entro l\u2019orbita geloa. Ritornando ad Antifemo, aggiungo che prima di arrivare a Gela, aveva distrutto Omphake, asportandone la famosa statua di Giunone, venerata dai Siculi di quella citt\u00e0 trasportandola nella nuova citt\u00e0 che chiam\u00f2 Lindia. I Cretesi dal canto loro s\u2019impadronirono della restante parte del territorio e fondarono una citt\u00e0 che chiamarono Eraclea, dal nome della loro capitale dell\u2019isola di Creta. (Holm-Pace, gli archeologi Orsi -Griffo-Adamasteanu-Orlandini).<\/p>\n<p style=\"text-align: justify;\">Venuti in Sicilia i Siculi, nel 1050, guidati da Siculo, figlio del Re Italo, di stirpe Osco-Ausonia e contemporaneamente i Liguri, di elementi comuni, ma con religione propria, con il culto dei Palici e cli Adrano ed influssi greco-italici, Sicani e Siculi vennero in lotte continue ed avendo vinto i Siculi, per prima cosa, cambiarono il nome dell\u2019isola e da Sicania la chiamarono Sichelia. Le lotte continuarono ancora fino a che non furono segnati i loro confini. I Sicani vennero ad occupare la parte occidentale dell\u2019isola, mentre i Siculi occuparono la parte orientale. Omphake, Butera, fu abitata dai Sicani i quali erano sparsi in tutto il territorio circostante. Abitazioni Sicane abbiamo nelle contrade di Consi, Piano della Fiera, Fontana Calda, Nostra Donna, S. Giorgio, Bosco Littorio, Santa Maria Dell\u2019Alto, Spinello, Desusino, Milinciana, Gurgazzi, Diliella, Suor Marchesa, Priorato, S. Cusumano, Bommara, Sgricciolo, Pispisella, Disueri (si desume esserci stato a Disueri un grosso centro abitato, e si dovrebbero riprendere gli scavi), ecc. Ci\u00f2 avvenne quando la popolazione fu costretta a portarsi sulle alture o in promontori verso l\u2019interno ove vennero a formarsi dei piccoli centri abitati. Dopo i Sicani ed i Siculi abbiamo l\u2019arrivo dei Greci e dei Fenici e la nascita di molte citt\u00e0 greche, (VIII sec. a.C.). Zancle fu fondata nel 700 a.C, Leontini nel 729, Megara nel 728, Gela nel 689, Acre nel 664, Casmene nel 644, Selinunte nel 599, Camerina nel 599, Agrigento nel 581 dalla colonia Gelese. I coloni di Gela, avendo trovato la piana costiera disabitata, vi si insediarono e negli anni seguenti respinsero gli indigeni a Nord della cerchia di colline e occuparono vari luoghi situati in posizioni strategiche, come Mactorium nel 635. Il primo signore di Gela fu Cleandro Partareo, 505 a.C., che estese il suo territorio dal fiume Dirillo, presso Camarina, al fiume Imera, Salso, presso Licata, ma in questo territorio era compreso anche quello posseduto dagli indigeni all\u2019interno e sui monti. In questo periodo un numero di Gelesi, appartenenti al partito vinto, si ritirarono a Mactorium, Butera, luogo posto sopra Gela e presero posizione minacciosa contro Gela, ma Feline, il cui avo era venuto a fondare Gela assieme ai Rodi e Cretesi, si rec\u00f2 dai ribelli e li indusse a tornare a Gela. Erodoto dice: \u00abQuidam viri Geloni profugerunt in Mactorium Urbem quae sita est super Gelam\u00bb; e Fazello: \u00abnel medesimo paese era Mactorium a sei miglia lontano da Terranova, su la riva si trova la bocca delfiume Naufrius il quale nasce sotto Butera, dove piglia il nome, e cento passi appresso segue la bocca del fiume larubba (Carruba), il quale nasce da San Pietro, che \u00e8 lontano quattro miglia dalla foce, e a questo \u00e8 vicino, due miglia Falconara, la quale \u00e8 una rocca d\u2019architettura regia, ancor che ella sia moderna. Dalla rocca di Falconara a dieci miglia \u00e8 Butera e a diciotto Terranova.\u00bb Continuando a parlare di Omphake sulla lotta coi Sicani, combattuta dal fondatore di Gela, Antifemo, per la conquista di Omphake, citt\u00e0 appollaiata su una collina che domina la pianura, \u00e8 certamente un episodio di quella pressione a Nord-Ovest che doveva portare l\u2019influenza diretta dello stato Gelese attraverso l\u2019intermedio territorio collinoso, sull\u2019altra pianura alla foce dell\u2019alytos, Salso. Pi\u00f9 diretta era l\u2019azione Greca sui villaggi Siculi e Sicani che occupavano i colli ed i poggi che cingono la pianura gelese, ovunque il rilievo del sito offrisse propizie condizioni, e dei quali Omphake non era che uno dei tanti luoghi ricercati, per circostanze speciali della tradizione. Dobbiamo pensare che codesti antichi Sicani tornassero la sera, come con deplorevole tecnica avviene ancor oggi in tante parti della Sicilia, dal lavoro dei campi nella bella pianura, alla casa raccolta sul montano villaggio. Giacomo Caputo vuole collocare la vecchia capitale Sicana di Cocalo, nella necropoli di Sant\u2019Angelo.<\/p>\n<p style=\"text-align: justify;\">Pace, in nota n. 1 a pag. 338 del V.I., sulla &#8220;Storia di Sicilia&#8221; scrive: \u00abTutte le notizie degli antichi si attagliano a questa idea, in attesa del lavoro del Caputo che sar\u00e0 pubblicato in redazione Lincei, si pu\u00f2 vedere, per le precedenti ipotesi sul sito di Camico, Holm, VI a pag. 134; il lavoro pi\u00f9 notevole \u00e8 quello dello Schubring, che ha idendificato Camico con Triocola, e l\u2019ha collocato a Caltabellotta. Ma tanto questa ipotesi quanto quella che colloca Camico a Sutera, muovono dall\u2019idea di trovare per essa un sito inaccessibile, il quale \u00e8 vero soltanto se inteso in senso relativo, mentre l\u2019altra racca di 5. Paolino di Sutera come quella di Caltabellotta, sono inaccessibili in modo pressoch\u00e9 assoluto, il che \u00e8 incompatibile con un luogo di residenza e di dominio. \u00bb Io voglio aggiungere, se Antifemo, fondatore di Gela, per conquistare la citt\u00e0 appollaiata su una collina che domina la pianura di Gela, ha dovuto combattere Omphake, e dopo aver conquistata la forte borgata indigena di Omphake, ne asport\u00f2 la statua scolpita da Dedalo, come mai la sede regia di Cocalo da Omphake possa trovarsi altrove? Si legge ancora nella storia che per essere grato a Cocalo, Dedalo gli costru\u00ec un castello, il castello non potrebbe essere quello di Omphake denominato poi Camico datoch\u00e9 Omphake non si riscontra pi\u00f9 nella storia? Pace in nota n. 1, pag. 201, dice: \u00abFilistro, apd. Stef. Bis. Sv. per la vecchia identificazione di codesta localit\u00e0 c\u00ecf. Amico, alle varie voci &#8211; Omphake appare negli eventi del 461 \/60 a. C. La sua identificazione con l\u2019aspra rocca di Butera resa improbabile dall\u2019assenza di avanzi Siculi; c\u00ecfr. Orsi, NS. 1900. Per le medesime ragioni \u00e8 impossibile riconoscere a Butera una Ibla. Con gli scavi del 195 1\/58, Adamasteanu ha trovato la testimonianza che non ha dato allora l\u2019Orsi, si pu\u00f2 definire tanto il sito di Omphake, quanto il sito di Ibla Herea (la citt\u00e0 di Desusino in contrada di Butera). Esistendo ormai, quell\u2019anticaglia non trovata dall\u2019Orsi, la svolta della storia dovrebbe dare una nuova indicazione, facendo entrare Butera, in quei periodi di lunga assenza, dalla denominazione di Omphake al riconoscimento di Mactorium in Butera, sino alla conquista Araba, Butera \u00e8 stata ignorata per la mancanza di anticaglia e per un principio poco concepibile dell\u2019Orsi che a Butera non vi fosse stata &#8220;veruna traccia di necropoli Sicula sulle alte rupi che circondano la borgata Le ricerche archeologiche iniziate su Gela da Orsi, riprese dal Griffa, Adamasteanu e Orlandini permettono di conoscere le linee principali di sviluppo. Questi storici (archeologi) concludono dicendo che fu un processo bifronte di occupazione militare e di penetrazione periferica &#8230; ma per assicurare il possesso di questa xwpa (terra) agricola fu necessario occupare alcuni punti strategici sui colli soprastanti. Dicono che la tradizione ricorda un attacco al centro indigeno di Omphake comandato dall\u2019ecista Antifemo durante la prima generazione della colonia greca. Holm dice: \u00abGela si deve considerare la citt\u00e0 Sicana di Omphake che la conquist\u00f2 e fra le prede trasse una statua scolpita da Dedalo\u00bb.<\/p>\n<p style=\"text-align: justify;\">Anche Pace dice: \u00abLa statuetta portata in Gela dall\u2019arcageta Antifemo quando conquist\u00f2 la forte borgata indigena a Omphake, opera di Dedalo, \u00e8 stato il primo .. . . Fazello dice: \u00abLa mia opinione paia che s\u2019accosti a quella di Tucidide il quale pone nel medesimo paese di Gela ed Erodoto che nel medesimo paese era Mactorium\u00bb, e Fazello conclude che: \u00abnel medesimo paese era Mactorium a sei miglia lontano da Terranova in su la riva\u00bb. A questo punto credo che non vi fosse alcun dubbio nel voler confermare che Omphake fosse Butera. Non esiste nessuna documentazione storica su Butera sino alla dominazione degli Arabi. Sappiamo solo che Butera durante il periodo Bizantino, fu militarmente una citt\u00e0 importante e strategicamente sicura ed il Castello ben fortificato. Dice Edrisi: \u00abButera, rocca valida assai, di gran momento e di molta fama, \u00e8 il pia bel soggiorno che si trovi presso nomadi o cittadini, quel che pia rassomiglia alle grandi e popolose citt\u00e0. Ben edificata e decorata con eleganza, ha dei palagi splendidissimi, dei mercati ben disposti e spaziosi, delle Moschee da farvi le preghiere pubbliche, un bagno e alberghi. La gira intorno un fiume dei pi\u00f9 grossi dell\u2019isola, il quale \u00e8 fiancheggiato sempre da giardini. 11 territorio d\u00e0 frutta squisita e abbondante e mirabile di produzione d\u2019ogni maniera. Da Butera al mare sette miglia a un dipresso. \u00bb Alla estremit\u00e0 meridionale della rocca di Butera c\u2019\u00e8 il fortissimo Castello ricostruito da Guglielmo Il, dopo la distruzione di Guglielmo I, il Malo, nel 1161. Restaurato nel 1897 da Patricolo che dat\u00f2 le volte dell\u2019ultima elevazione alla fine del XV sec. d.C., in relazione alla concessione del Castello nel 1392 da Re Martino ad Ugo Santapau. Nel 1904 croll\u00f2 il terrazzo e nel 1924 la parte occidentale della torre, a causa dello spianamento dell\u2019area sottostante per il realizzo della Piazza Vittoria.<\/p>\n<p style=\"text-align: justify;\">Nel 1935 venne ricostruita, dal Genio Civile, la parte occidentale. Restaurato nel 1958, parzialmente dalla soprintendenza di Palermo, nello stesso anno fu restaurato con i fondi dell\u2019Assessorato Regionale del Turismo che dovr\u00e0 interessarsi per il completo recupero dell\u2019area del cortile fortificato, dal quale si gode un magnifico panorama sulla costa meridionale da Punta Braccetto al Castello di Palma Montechiaro, per essere destinato a Museo archeologico. La citt\u00e0 esclusivamente Indigena \u00e8 testimoniata soprattutto nello strato pi\u00f9 antico della necropoli Buterese di Piano della Fiera, con tombe relative alla fase di Pantalica sud e ceramiche a decorazione dipinta, legata alle contemporanee culture della Sicilia occidentale. La posizione dominante della citt\u00e0 Sicana doveva costituire una incombente minaccia per la sicurezza del possesso della pianura da parte dei coloni geloi i quali ben presto, 660\/625 a.C. conquistarono ed occuparono definitivamente il centro indigeno di Butera. Tale precoce ellenizzazione, documentata dal secondo strato della necropoli di Piano della Fiera e insieme la forte posizione strategica del sito, hanno fatto proporre la sua identificazione con il centro indigeno di Omphake che, secondo Pausania, venne conquistato dallo stesso Antifemo, fondatore di Gela. La citt\u00e0 continu\u00f2 a vivere per tutto il VI e V sec. a.C. ed ebbe una vigorosa ripresa nella seconda met\u00e0 del III sec. a.C. Abbiamo detto che il primo nome di Butera era Omphake, dopo fu chiamata Mactorium. Nel periodo bizantino, forse ebbe mutato il nome.<\/p>\n<p style=\"text-align: justify;\">Dagli Arabi in un documento dell\u2019845 dopo l\u2019occupazione Butera viene citata come Bothirah, in seguito Buthir. Nel 1093 fu dato il nome di Butera, la cui derivazione sarebbe: per Edrisi Butirah; per Ulmar B(u)tirah; per Maqquadosi Butirah; La fortezza di Butera tenuta dai Bizantini, venne conquistata dagli Arabi 23 anni dopo l\u2019occupazione di Palermo. Butera circondata da valide mura e da formidabili torri, permetteva l\u2019adito solamente per due porte, dette l\u2019una San Pietro, rivolta a settentrione, l\u2019altra Reale a Greco, allorch\u00e9 invidiata dai Musulmani venne, per comando del Saraceno Zaidet-allah-ebn-Ibrahim, presa nell\u2019anno 827 da Adelcamo. Durante il periodo romano nascono due vie di comunicazione: Agrigento-Catania, ed Agrigento-Siracusa, con stazionamento, punto di unione delle due vie a Suor Marchesa, territorio di Butera, ove si trasferisce l\u2019abitato dei casali che vengono in questo periodo spostati. A Suor Marchesa e a Perni abbiamo due stazionamenti per le vie di comunicazione verso Agrigento e la parte occidentale. In queste due stazioni vi erano tanti fondaci e luoghi di ristoro e grandi fattorie per la gente che ivi transitava. 1\u00b3 giusto ricordare che nel periodo che corre dal 652 al 669 gli Arabi hanno effettuato moltissime scorrerie in Sicilia, ma i tentativi di sbarco vero e proprio vanno dal 704 in poi. Nel 704 gli Arabi sbarcano in Sicilia e dopo avere invaso una citt\u00e0 ne prendono il bottino e ripartono. Nel 727 la Sicilia viene assediata da Bisr-Ibn-Safwan che ritorna in Africa con molti prigionieri.<\/p>\n<p style=\"text-align: justify;\">Nel 728\/29 sbarca in Sicilia un\u2019armata con Utman-Ibn-Ubaydah. Nel 729\/30 ritornano in Sicilia con Al-Hurayti ed assediano alcune citt\u00e0. Nel 730\/31 venne ancora a far bottino Tabit-Ibn-Htiaym di Urdum in Siria. Nel 732\/33 venne ancora a far bottino e prigionieri Abd-Al-MalitIbn-Qatan. Nel 733\/34 Abu-Bakr-Suwyd, mandato da Ubaydah prendeva al-quante navi. Nel 734\/35 gli Arabi in Sicilia subirono una sconfitta. Nel 740 Abd-Ar-Rahman correva vittorioso per le vie della Sicilia, a Siracusa sconfisse ed uccise la gente, strinse d\u2019assedio la citt\u00e0 e diede terrore sino a sottometterla, ma dovendo ritornare in Africa, per una ribellione ivi avvenuta lasci\u00f2 Siracusa che restava salva. Nell\u2019819\/20 la Sicilia subiva un incursione da Muhammad-IbnAbd-allah e Ibn-al-Aglab. Questi occupata Mazara, vi lasciava un presidio e dopo avere occupato molti altri Castelli ed assicurata la linea d\u2019operazione dell\u2019esercito, Assad pigli\u00f2 la via dei monti che portano a Siracusa, lungo la marina di Terranova e di l\u00ec continu\u00f2 tra i monti in linea retta. Nelle campagne di Butera Abbas venne in battaglia con i Bizantini, ove caddero da nove a diecimila Bizantini, non combattendo ma fuggendo, ed i Musulmani confermano che solo tre credenti incontrarono la morte, il luogo di questa battaglia, assegnato da Ibn-Al-Atir, \u00e8Butirah. Dice Amari: \u00abche il luogo \u00e8 un nome non dissimile, ma poco leggibile. Gli elementi calligrafici e topografici mi portano alla lettura probabilissima di Butirah (Butera). \u00bb Butera fu una forte citt\u00e0 al tempo dei Musulmani, splendida e famosa nei feudi, che ottenne il primo titolo del regno fino alla riforma del 1848, nella quale il Parlamento Siciliano abol\u00ec la Parla ereditaria. Codesto nome geografico non appare pi\u00f9 prima del IX sec. n\u00e8 fabbriche o altri avanzi mostrano abitato il luogo; in et\u00e0 pi\u00f9 antica fu cambiato solamente il nome sotto i Bizantini. La citt\u00e0 sorge in cima ad un colle, a pochi miglia dal mare e dal fiume Imera, Salso; domina il fertile paese che gli antichi chiamavano campi geloi, fu in guerra un naturale rifugio per quella popolazione agricola nei tempi di selvaggio, albergo dei suoi oppressori. Sembra che alla prima scorreria dei cavalli Musulmani di Noto, quei villici pi\u00f9 volte si fossero rifugiati in quella rocca, ma nell\u2019anno 853, Al-Abbas, vedendoli affollati al solito covile, pens\u00f2 di prenderli in rete. Assedi\u00f2 strettamente Butera per oltre cinque mesi, infine pattui con i terrazzani che gli consegnassero cinque-sei mila capi, scrive la cronaca, come se fossero capi d\u2019armento, e l\u2019esercito, portandosi dietro tanta torma di schiavi, se ne torn\u00f2 a Palermo. Amari sostiene che sia Butera, perch\u00e9 la cronaca d\u00e0 a questo luogo il titolo di citt\u00e0, poich\u00e9 altre non se ne trovano i Sicilia antica n\u00e9 moderna da potersi adattare quelle lettere al suo nome. Nell\u2019855 Abbas inviava una lettera a Mulci-Mahammed-DerrAbn-el-Abbas, ove fra tutte le altre cose sommariamente diceva: \u00abarrivammo ad un quarto d\u2019ora di cammino lontano da Butera, feci riposare la gente e diedi loro da mangiare, e dopo aver dato ordine di non risparmiare a nessuno la morte, c\u2019incamminammo, e giunti a mezzogiorno abbiamo dato l\u2019assalto a quella citt\u00e0 che \u00e8 assai grande. Un \u2018ora prima di calare il sole eravamo padroni del castello, mi hanno regalato 600 monete d\u2019argento e 100 d\u2019oro, 100 buoi e 50 montoni da ammazzare e dare da mangiare agli uomini, e dopo aver fatto accomodare le rovine del Castello e lasciati 2.000 uomini di guarnigione, per poterli difendere, mi partii. \u00bb La grande e popolosa citt\u00e0 di Butera, cadeva definitivamente e passava sotto il dominio degli Arabi. L\u2019assedio era durato cinque mesi.<\/p>\n<p style=\"text-align: justify;\">Durante la dominazione Araba prosperarono i seguenti poeti Buteresi: 1) Abu-Zakaryya, fece la raccolta di tradizioni canoniche a cui dette il titolo &#8220;Il giardino dilettevole&#8221;; 2) Lbn-Abd-Rahman al Buthiri, operatore di Butera e recitatore del Corano, originario di Butera, fiorentissimo fin dall\u2019epoca Araba; 3) Ibn-Muhammed al Buthiri, ha celebrato la persona del Re e lo splendore dei suoi possessi; 4) Ibn-Omar al Buthiri, emiro capostipite della dinastia degli Amoravidi che domin\u00f2 il Marocco, l\u2019Africa e parte della Spagna; 5)Abd-Ar-Rahman al Buthiri, oltre che poeta fu anche ottimo epistolografo e prosatore, da non confondersi con un omonimo di Trapani. Fu Segretario della corte ruggeriana, scrisse versi sulle ville e palazzi palermitani del Re. Le opere Arabe che sono rimaste a Butera, dopo la distruzione della citt\u00e0 da parte di Guglielmo il Malo, sono: Il gigantesco e formidabile castello fabbricato verso la parte meridionale del Paese, con una porta d\u2019accesso rivolta a settentrione, esiste solo la parte di una torre. Mostrasi di origine remotissima, le sue muraglia forti abbastanza e solide nella larghezza di 18 palmi, sostengono cinque ordini di volte. Internamente riscontransi, in un cortile di vastissimo spazio, magazzini per la conserva di orzo, frumento, riposti per armi, stalle per cavalli, profonde e spaziose fosse per ogni altro genere di alimentazione. Un insigne cisterna superava ogni aspettazione, era di forma ovale, con grande artefizio compatta, appoggiava al suolo e soltanto esternamente acuminata, dagli altri due lati stando da s\u00e9 sola sembrava quasi del tutto opera di un solo masso. Le fonti esterne della fortezza erano da ogni parte inaccessibili; I resti di una torre a settentrione, in una propriet\u00e0 di Provinzano, questi si possono vedere dalla Villetta di Dezia; Una torretta, ancora esistente, nel fabbricato Boscaglia, sarebbe al centro di Butera ed in mezzo alle due torri principali; Un\u2019ampia porta di stile Arabo che immette nella sede del Municipio, ci porta ad immaginare l\u2019esistenza di un importante palazzo che doveva servire forse da abitazione all\u2019Emiro o, stando alla relazione di Edrisi, era una Moschea, aperta alla pubblica venerazione.<\/p>\n<p style=\"text-align: justify;\">A Butera, come detto altrove, sino al 1150 d.C. esisteva una Moschea, la terza Moschea costruita in Sicilia, dopo quelle di Palermo e di Catania; in questa Moschea oltre al culto si esercitava l\u2019insegnamento per i giovani.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La leggenda di Cocalo Si dice che Cocalo, venuto in Sicilia, nel 1300 a.C. re dei Sicani, avesse abitato ed avesse posto la sua reggia ad Omphake. Presso Cocalo arriv\u00f2 [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":8,"template":"","meta":[],"class_list":["post-15","turismo","type-turismo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OMPHAKE - Butera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/butera\/turismo\/omphake\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OMPHAKE - Butera\" \/>\n<meta property=\"og:description\" content=\"La leggenda di Cocalo Si dice che Cocalo, venuto in Sicilia, nel 1300 a.C. re dei Sicani, avesse abitato ed avesse posto la sua reggia ad Omphake. Presso Cocalo arriv\u00f2 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/butera\/turismo\/omphake\/\" \/>\n<meta property=\"og:site_name\" content=\"Butera\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/butera\/wp-content\/uploads\/sites\/94\/2017\/01\/butera.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"50\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"18 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/butera\\\/turismo\\\/omphake\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/butera\\\/turismo\\\/omphake\\\/\",\"name\":\"OMPHAKE - Butera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/butera\\\/#website\"},\"datePublished\":\"2017-01-20T14:37:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/butera\\\/turismo\\\/omphake\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/butera\\\/turismo\\\/omphake\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/butera\\\/turismo\\\/omphake\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/butera\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OMPHAKE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/butera\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/butera\\\/\",\"name\":\"Butera\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/butera\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OMPHAKE - Butera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/butera\/turismo\/omphake\/","og_locale":"it_IT","og_type":"article","og_title":"OMPHAKE - Butera","og_description":"La leggenda di Cocalo Si dice che Cocalo, venuto in Sicilia, nel 1300 a.C. re dei Sicani, avesse abitato ed avesse posto la sua reggia ad Omphake. Presso Cocalo arriv\u00f2 [&hellip;]","og_url":"https:\/\/comunicacity.net\/butera\/turismo\/omphake\/","og_site_name":"Butera","article_publisher":"http:\/\/facebook.com\/ComunicaCity","og_image":[{"url":"https:\/\/comunicacity.net\/butera\/wp-content\/uploads\/sites\/94\/2017\/01\/butera.jpg","height":50,"width":50,"type":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"18 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/butera\/turismo\/omphake\/","url":"https:\/\/comunicacity.net\/butera\/turismo\/omphake\/","name":"OMPHAKE - Butera","isPartOf":{"@id":"https:\/\/comunicacity.net\/butera\/#website"},"datePublished":"2017-01-20T14:37:33+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/butera\/turismo\/omphake\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/butera\/turismo\/omphake\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/butera\/turismo\/omphake\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/butera\/"},{"@type":"ListItem","position":2,"name":"OMPHAKE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/butera\/#website","url":"https:\/\/comunicacity.net\/butera\/","name":"Butera","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/butera\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/butera\/wp-json\/wp\/v2\/turismo\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/butera\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/butera\/wp-json\/wp\/v2\/types\/turismo"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/butera\/wp-json\/wp\/v2\/media?parent=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}