{"id":147,"date":"2019-05-04T14:28:26","date_gmt":"2019-05-04T12:28:26","guid":{"rendered":"https:\/\/comunicacity.net\/camaiore\/?post_type=turismo&#038;p=147"},"modified":"2019-05-04T14:28:26","modified_gmt":"2019-05-04T12:28:26","slug":"museo-di-arte-sacra","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/camaiore\/turismo\/i-luoghi-della-cultura\/museo-di-arte-sacra\/","title":{"rendered":"Museo di Arte Sacra"},"content":{"rendered":"<p>Il museo sar\u00e0 aperto nei giorni festivi infrasettimanali e in occasione di manifestazioni cittadine di rilievo. Per le scuole, previo accordo, \u00e8 prevista l&#8217;apertura al mattino. Il museo istituito nel 1936 nella sede della Confraternita del Santissimo Sacramento, di San Michele e San Vincenzo, edificio del XVII secolo, nasce come luogo di raccolta e deposito di arredi, dipinti, paramenti, suppellettili sacre dal XIV al XVI secolo.<\/p>\n<p>Attualmente \u00e8 oggetto di un vasto programma di riordino e riallestimento la cui prima fase ha riguardato l&#8217;ampliamento della struttura espositiva con due nuove sale al pian terreno. Qui sono presentate sculture lignee, tavole dipinte e preziose oreficerie. Al piano superiore, nella sala della confraternita arredata con gli stalli realizzati nel Settecento, \u00e8 esposto un grande arazzo fiammingo del 1516; nelle altre sale sono in mostra numerosi dipinti, corredi processionali in legno, parati liturgici e le suppellettili sacre in argento realizzate dalle pi\u00f9 importanti botteghe lucchesi settecentesche.<\/p>\n<p>L&#8217;esposizione si apre al pian terreno con una piccola Madonna col Bambino lignea, della fine del Duecento; sono anche esposti calici a smalto di cultura senese e la croce astile a sbalzo della chiesa di S. Maria Albiano dei primi del trecento. Altre croci astili a sbalzo, il calice, il Sant&#8217;Antonio Abate ligneo e il polittico dell&#8217;Anguilla testimoniano, con altre opere tuttora esistenti nelle varie chiese di Camaiore, la forza di penetrazione anche nel contado della cultura artistica sviluppatasi in Lucca tra la fine del Trecento e il nuovo secolo.<\/p>\n<p><a href=\"http:\/\/www.comune.camaiore.lu.it\/it\/sezioni-turismo-e-cultura\/830-camaiore-virtual-tour-a-360\/3642-virtual-tour-museo-d-arte-sacra\">Virtual Tour Museo d\\&#8217;Arte Sacra<\/a><\/p>\n<p>E&#8217; online il\u00a0nuovo sito del\u00a0<strong>Museo d\u2019Arte Sacra di Camaiore<\/strong>, realizzato dal\u00a0<strong>LIMES &#8211; Laboratorio di Metodologie Informatiche per la Storia dell&#8217;Arte\u00a0<\/strong>dell&#8217;Universit\u00e0 di Pisa.<br \/>\nIl sito \u00e8 stato realizzato con il coordinamento della professoressa Sonia Maffei, docente di Storia della critica d&#8217;arte all\u2019Universit\u00e0 di Pisa e realizzato dagli studenti del laboratorio.<br \/>\nUn team di lavoro estremamente variegato che ha permesso di realizzare un portale generalista, creato con tecnologie open source, dove si possono reperire le informazioni logistiche, sulla collezione e le attivit\u00e0 didattiche del museo a cui si affiancano quattro approfondimenti (tessuti, oreficeria, il polittico di Francesco di Andrea Anguilla e la Vergine Annunziata di Matteo Civitali) proposti dagli studenti del corso di \u201cInformatica per i beni culturali\u201d della \u201cScuola di Specializzazione in Beni Storico-Artistici\u201d.\u00a0<strong>Il portale contiene oltre 180 pagine, 718 immagini\u00a0<\/strong>&#8211; realizzate nel corso di un\u2019apposita campagna dal Laboratorio di fotografia dell\u2019Universit\u00e0 &#8211;<strong>\u00a0e tre video\u00a0<\/strong>prodotti in collaborazione il Laboratorio audiovisivi dell\u2019Universit\u00e0.<br \/>\n<em>Il sito \u00e8 visitabile cliccando sull&#8217;immagine qua sotto.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il museo sar\u00e0 aperto nei giorni festivi infrasettimanali e in occasione di manifestazioni cittadine di rilievo. Per le scuole, previo accordo, \u00e8 prevista l&#8217;apertura al mattino. Il museo istituito nel [&hellip;]<\/p>\n","protected":false},"featured_media":148,"parent":144,"menu_order":2,"template":"","meta":[],"plugin_turismo":[],"class_list":["post-147","turismo","type-turismo","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Museo di Arte Sacra - Camaiore<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/camaiore\/turismo\/i-luoghi-della-cultura\/museo-di-arte-sacra\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Museo di Arte Sacra - Camaiore\" \/>\n<meta property=\"og:description\" content=\"Il museo sar\u00e0 aperto nei giorni festivi infrasettimanali e in occasione di manifestazioni cittadine di rilievo. Per le scuole, previo accordo, \u00e8 prevista l&#8217;apertura al mattino. Il museo istituito nel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/camaiore\/turismo\/i-luoghi-della-cultura\/museo-di-arte-sacra\/\" \/>\n<meta property=\"og:site_name\" content=\"Camaiore\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/camaiore\/wp-content\/uploads\/sites\/165\/2019\/05\/Museo-di-Arte-Sacra.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"380\" \/>\n\t<meta property=\"og:image:height\" content=\"254\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/camaiore\\\/turismo\\\/i-luoghi-della-cultura\\\/museo-di-arte-sacra\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/camaiore\\\/turismo\\\/i-luoghi-della-cultura\\\/museo-di-arte-sacra\\\/\",\"name\":\"Museo di Arte Sacra - Camaiore\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/camaiore\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/camaiore\\\/turismo\\\/i-luoghi-della-cultura\\\/museo-di-arte-sacra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/camaiore\\\/turismo\\\/i-luoghi-della-cultura\\\/museo-di-arte-sacra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/camaiore\\\/wp-content\\\/uploads\\\/sites\\\/165\\\/2019\\\/05\\\/Museo-di-Arte-Sacra.jpg\",\"datePublished\":\"2019-05-04T12:28:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/camaiore\\\/turismo\\\/i-luoghi-della-cultura\\\/museo-di-arte-sacra\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/camaiore\\\/turismo\\\/i-luoghi-della-cultura\\\/museo-di-arte-sacra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/camaiore\\\/turismo\\\/i-luoghi-della-cultura\\\/museo-di-arte-sacra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/camaiore\\\/wp-content\\\/uploads\\\/sites\\\/165\\\/2019\\\/05\\\/Museo-di-Arte-Sacra.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/camaiore\\\/wp-content\\\/uploads\\\/sites\\\/165\\\/2019\\\/05\\\/Museo-di-Arte-Sacra.jpg\",\"width\":380,\"height\":254},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/camaiore\\\/turismo\\\/i-luoghi-della-cultura\\\/museo-di-arte-sacra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/camaiore\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I luoghi della Cultura\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/camaiore\\\/turismo\\\/i-luoghi-della-cultura\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Museo di Arte Sacra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/camaiore\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/camaiore\\\/\",\"name\":\"Camaiore\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/camaiore\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Museo di Arte Sacra - Camaiore","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/camaiore\/turismo\/i-luoghi-della-cultura\/museo-di-arte-sacra\/","og_locale":"it_IT","og_type":"article","og_title":"Museo di Arte Sacra - Camaiore","og_description":"Il museo sar\u00e0 aperto nei giorni festivi infrasettimanali e in occasione di manifestazioni cittadine di rilievo. Per le scuole, previo accordo, \u00e8 prevista l&#8217;apertura al mattino. Il museo istituito nel [&hellip;]","og_url":"https:\/\/comunicacity.net\/camaiore\/turismo\/i-luoghi-della-cultura\/museo-di-arte-sacra\/","og_site_name":"Camaiore","article_publisher":"http:\/\/facebook.com\/ComunicaCity","og_image":[{"width":380,"height":254,"url":"https:\/\/comunicacity.net\/camaiore\/wp-content\/uploads\/sites\/165\/2019\/05\/Museo-di-Arte-Sacra.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/camaiore\/turismo\/i-luoghi-della-cultura\/museo-di-arte-sacra\/","url":"https:\/\/comunicacity.net\/camaiore\/turismo\/i-luoghi-della-cultura\/museo-di-arte-sacra\/","name":"Museo di Arte Sacra - Camaiore","isPartOf":{"@id":"https:\/\/comunicacity.net\/camaiore\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/camaiore\/turismo\/i-luoghi-della-cultura\/museo-di-arte-sacra\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/camaiore\/turismo\/i-luoghi-della-cultura\/museo-di-arte-sacra\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/camaiore\/wp-content\/uploads\/sites\/165\/2019\/05\/Museo-di-Arte-Sacra.jpg","datePublished":"2019-05-04T12:28:26+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/camaiore\/turismo\/i-luoghi-della-cultura\/museo-di-arte-sacra\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/camaiore\/turismo\/i-luoghi-della-cultura\/museo-di-arte-sacra\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/camaiore\/turismo\/i-luoghi-della-cultura\/museo-di-arte-sacra\/#primaryimage","url":"https:\/\/comunicacity.net\/camaiore\/wp-content\/uploads\/sites\/165\/2019\/05\/Museo-di-Arte-Sacra.jpg","contentUrl":"https:\/\/comunicacity.net\/camaiore\/wp-content\/uploads\/sites\/165\/2019\/05\/Museo-di-Arte-Sacra.jpg","width":380,"height":254},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/camaiore\/turismo\/i-luoghi-della-cultura\/museo-di-arte-sacra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/camaiore\/"},{"@type":"ListItem","position":2,"name":"I luoghi della Cultura","item":"https:\/\/comunicacity.net\/camaiore\/turismo\/i-luoghi-della-cultura\/"},{"@type":"ListItem","position":3,"name":"Museo di Arte Sacra"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/camaiore\/#website","url":"https:\/\/comunicacity.net\/camaiore\/","name":"Camaiore","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/camaiore\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/camaiore\/wp-json\/wp\/v2\/turismo\/147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/camaiore\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/camaiore\/wp-json\/wp\/v2\/types\/turismo"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/camaiore\/wp-json\/wp\/v2\/turismo\/144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/camaiore\/wp-json\/wp\/v2\/media\/148"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/camaiore\/wp-json\/wp\/v2\/media?parent=147"}],"wp:term":[{"taxonomy":"plugin_turismo","embeddable":true,"href":"https:\/\/comunicacity.net\/camaiore\/wp-json\/wp\/v2\/plugin_turismo?post=147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}