{"id":11,"date":"2017-08-11T14:15:25","date_gmt":"2017-08-11T12:15:25","guid":{"rendered":"https:\/\/comunicacity.net\/campodimele\/?post_type=info&#038;p=11"},"modified":"2017-08-11T14:15:25","modified_gmt":"2017-08-11T12:15:25","slug":"biblioteca","status":"publish","type":"info","link":"https:\/\/comunicacity.net\/campodimele\/info\/biblioteca\/","title":{"rendered":"Biblioteca"},"content":{"rendered":"<p><strong>Sistema Bibliotecario \u2033Sud Pontino\u2033 &#8211; Biblioteca<\/strong><br \/>\nResponsabile: Pierluigi Moschitti<br \/>\nEmail: <a href=\"mailto:moschitti@email.it\">moschitti@email.it<\/a><\/p>\n<p>Orario di apertuta luned\u00ec mercoled\u00ec e venerd\u00ec dalle 09.00 alle 12.30<br \/>\nmarted\u00ec e gioved\u00ec dalle 15.00 alle 16.30<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sistema Bibliotecario \u2033Sud Pontino\u2033 &#8211; Biblioteca Responsabile: Pierluigi Moschitti Email: moschitti@email.it Orario di apertuta luned\u00ec mercoled\u00ec e venerd\u00ec dalle 09.00 alle 12.30 marted\u00ec e gioved\u00ec dalle 15.00 alle 16.30<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":30,"template":"","meta":[],"plugin_info":[],"class_list":["post-11","info","type-info","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biblioteca - Campodimele<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/campodimele\/info\/biblioteca\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biblioteca - Campodimele\" \/>\n<meta property=\"og:description\" content=\"Sistema Bibliotecario \u2033Sud Pontino\u2033 &#8211; Biblioteca Responsabile: Pierluigi Moschitti Email: moschitti@email.it Orario di apertuta luned\u00ec mercoled\u00ec e venerd\u00ec dalle 09.00 alle 12.30 marted\u00ec e gioved\u00ec dalle 15.00 alle 16.30\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/campodimele\/info\/biblioteca\/\" \/>\n<meta property=\"og:site_name\" content=\"Campodimele\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2017\/08\/campodimele.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"50\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/info\\\/biblioteca\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/info\\\/biblioteca\\\/\",\"name\":\"Biblioteca - Campodimele\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#website\"},\"datePublished\":\"2017-08-11T12:15:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/info\\\/biblioteca\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/info\\\/biblioteca\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/info\\\/biblioteca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biblioteca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/\",\"name\":\"Campodimele\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biblioteca - Campodimele","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/campodimele\/info\/biblioteca\/","og_locale":"it_IT","og_type":"article","og_title":"Biblioteca - Campodimele","og_description":"Sistema Bibliotecario \u2033Sud Pontino\u2033 &#8211; Biblioteca Responsabile: Pierluigi Moschitti Email: moschitti@email.it Orario di apertuta luned\u00ec mercoled\u00ec e venerd\u00ec dalle 09.00 alle 12.30 marted\u00ec e gioved\u00ec dalle 15.00 alle 16.30","og_url":"https:\/\/comunicacity.net\/campodimele\/info\/biblioteca\/","og_site_name":"Campodimele","article_publisher":"http:\/\/facebook.com\/ComunicaCity","og_image":[{"url":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2017\/08\/campodimele.jpg","height":50,"width":50,"type":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/campodimele\/info\/biblioteca\/","url":"https:\/\/comunicacity.net\/campodimele\/info\/biblioteca\/","name":"Biblioteca - Campodimele","isPartOf":{"@id":"https:\/\/comunicacity.net\/campodimele\/#website"},"datePublished":"2017-08-11T12:15:25+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/campodimele\/info\/biblioteca\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/campodimele\/info\/biblioteca\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/campodimele\/info\/biblioteca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/campodimele\/"},{"@type":"ListItem","position":2,"name":"Biblioteca"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/campodimele\/#website","url":"https:\/\/comunicacity.net\/campodimele\/","name":"Campodimele","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/campodimele\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/info\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/info"}],"about":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/types\/info"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/media?parent=11"}],"wp:term":[{"taxonomy":"plugin_info","embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/plugin_info?post=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}