{"id":15236,"date":"2024-10-03T12:38:59","date_gmt":"2024-10-03T10:38:59","guid":{"rendered":"https:\/\/comunicacity.net\/campodimele\/2024\/10\/03\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\/"},"modified":"2024-10-03T12:38:59","modified_gmt":"2024-10-03T10:38:59","slug":"aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/campodimele\/2024\/10\/03\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\/","title":{"rendered":"Aggiornamento Albo Presidenti ed Albo scrutatori di seggio &#8211; Anno 2024"},"content":{"rendered":"<p><em>Sono aperti i bandi per gli albi dei presidenti e degli scrutatori di seggio. Come ogni anno, le scadenze previste sono il 31 ottobre per l\u2019albo dei presidenti di seggio e il 30 novembre per quello degli scrutatori.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<article id=\"descrizione\" class=\"it-page-section anchor-offset mb-30\" data-audio=\"\">\n<div class=\"richtext-wrapper lora\">\n<p style=\"text-align: center\"><strong>AVVISO<\/strong><\/p>\n<p>L\u2019Amministrazione Comunale\u00a0 ricorda che, come ogni anno, sono aperte dal 1\u00b0 ottobre le iscrizioni agli Albi dei presidenti e degli scrutatori dei seggi elettorali.<\/p>\n<p>E\u2019 possibile fare domanda di iscrizione all\u2019Albo dei presidenti di seggio elettorale fino al 31 ottobre e a quello degli scrutatori fino al 30 novembre <em>(scadenze previste dalla legge).\u00a0<\/em><\/p>\n<p>L&#8217;<strong>Ufficio Elettorale<\/strong> \u00e8 a disposizione al numero telefonico 0771598013 interno 1 per fornire tutte le informazioni e per l\u2019eventuale invio via mail dei moduli per la presentazione delle domande di iscrizione agli Albi<\/p>\n<p><em><strong>Se la domanda viene accolta, l&#8217;iscrizione rimane valida anche negli anni successivi, a meno che non si perdano i requisiti, o se ne chieda la cancellazione.<\/strong><\/em><\/p>\n<p>Gli Albi vengono aggiornati ogni anno nel mese di gennaio con le richieste di iscrizione o di cancellazione pervenute all&#8217;Ufficio elettorale comunale.<\/p>\n<p><strong>REQUISITI PER L\u2019ISCRIZIONE AGLI ALBI<\/strong><\/p>\n<p>Per essere ammessi nell&#8217;<strong>Albo degli scrutatori di seggio elettorale<\/strong>, bisogna essere elettori del Comune in cui si fa la domanda e avere assolto gli obblighi scolastici.<\/p>\n<p>Per l&#8217;iscrizione all&#8217;<strong>Albo dei presidenti di seggio elettorale<\/strong>, oltre ad essere elettori del Comune, \u00e8 necessario avere conseguito il diploma di istruzione secondaria di secondo grado e, come richiesto dalla circolare annuale della Prefettura di Latina, \u00e8 raccomandabile aver gi\u00e0 svolto incarico presso i seggi elettorali con funzioni di vice presidente di seggio, segretario o scrutatore.<\/p>\n<p><strong>Non possono esercitare le funzioni di presidente di ufficio elettorale di sezione, di scrutatore e di segretario<\/strong>\u00a0le persone che appartengono alle seguenti categorie:<\/p>\n<ul>\n<li>i dipendenti dei Ministeri dell&#8217;Interno, delle Poste e Telecomunicazioni e dei Trasporti;<\/li>\n<li>gli appartenenti alle Forze Armate in servizio;<\/li>\n<li>i medici provinciali, gli ufficiali sanitari e i medici condotti;<\/li>\n<li>i segretari comunali ed i dipendenti dei Comuni, addetti o comandati a prestare servizio negli Uffici elettorali comunali;<\/li>\n<li>i candidati alle elezioni per le quali si svolge la votazione <em>(art. 23 del T.U. 570\/1960 delle leggi per la composizione e la elezione delle amministrazioni comunali e art. 38 del T.U. 361\/1957 delle leggi recanti norme per la elezione della Camera dei Deputati).<\/em><\/li>\n<\/ul>\n<\/div>\n<\/article>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_15238\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2024\/10\/Avviso-Scritatori.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2024\/10\/Avviso-Scritatori.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Avviso Scritatori<\/a><\/li>\n<li><a id=\"wpba_attachment_list_15239\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2024\/10\/Avviso-Presidente-di-Seggio.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2024\/10\/Avviso-Presidente-di-Seggio.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Avviso Presidente di Seggio<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sono aperti i bandi per gli albi dei presidenti e degli scrutatori di seggio. Come ogni anno, le scadenze previste sono il 31 ottobre per l\u2019albo dei presidenti di seggio [&hellip;]<\/p>\n","protected":false},"author":242,"featured_media":15237,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-15236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aggiornamento Albo Presidenti ed Albo scrutatori di seggio - Anno 2024 - Campodimele<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/campodimele\/2024\/10\/03\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aggiornamento Albo Presidenti ed Albo scrutatori di seggio - Anno 2024 - Campodimele\" \/>\n<meta property=\"og:description\" content=\"Sono aperti i bandi per gli albi dei presidenti e degli scrutatori di seggio. Come ogni anno, le scadenze previste sono il 31 ottobre per l\u2019albo dei presidenti di seggio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/campodimele\/2024\/10\/03\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Campodimele\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-03T10:38:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2024\/10\/albo_scrutatori_e_presidenti.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"campodimele\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"campodimele\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/10\\\/03\\\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/10\\\/03\\\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\\\/\"},\"author\":{\"name\":\"campodimele\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#\\\/schema\\\/person\\\/707b1b5905116ac44a5a52a8f829f0da\"},\"headline\":\"Aggiornamento Albo Presidenti ed Albo scrutatori di seggio &#8211; Anno 2024\",\"datePublished\":\"2024-10-03T10:38:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/10\\\/03\\\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\\\/\"},\"wordCount\":381,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/10\\\/03\\\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2024\\\/10\\\/albo_scrutatori_e_presidenti.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/10\\\/03\\\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/10\\\/03\\\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\\\/\",\"name\":\"Aggiornamento Albo Presidenti ed Albo scrutatori di seggio - Anno 2024 - Campodimele\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/10\\\/03\\\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/10\\\/03\\\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2024\\\/10\\\/albo_scrutatori_e_presidenti.png\",\"datePublished\":\"2024-10-03T10:38:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#\\\/schema\\\/person\\\/707b1b5905116ac44a5a52a8f829f0da\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/10\\\/03\\\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/10\\\/03\\\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/10\\\/03\\\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2024\\\/10\\\/albo_scrutatori_e_presidenti.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2024\\\/10\\\/albo_scrutatori_e_presidenti.png\",\"width\":640,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/10\\\/03\\\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aggiornamento Albo Presidenti ed Albo scrutatori di seggio &#8211; Anno 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/\",\"name\":\"Campodimele\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#\\\/schema\\\/person\\\/707b1b5905116ac44a5a52a8f829f0da\",\"name\":\"campodimele\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g\",\"caption\":\"campodimele\"},\"sameAs\":[\"http:\\\/\\\/www.comune.campodimele.lt.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/author\\\/campodimele\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aggiornamento Albo Presidenti ed Albo scrutatori di seggio - Anno 2024 - Campodimele","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/campodimele\/2024\/10\/03\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\/","og_locale":"it_IT","og_type":"article","og_title":"Aggiornamento Albo Presidenti ed Albo scrutatori di seggio - Anno 2024 - Campodimele","og_description":"Sono aperti i bandi per gli albi dei presidenti e degli scrutatori di seggio. Come ogni anno, le scadenze previste sono il 31 ottobre per l\u2019albo dei presidenti di seggio [&hellip;]","og_url":"https:\/\/comunicacity.net\/campodimele\/2024\/10\/03\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\/","og_site_name":"Campodimele","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-10-03T10:38:59+00:00","og_image":[{"width":640,"height":360,"url":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2024\/10\/albo_scrutatori_e_presidenti.png","type":"image\/png"}],"author":"campodimele","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"campodimele","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/campodimele\/2024\/10\/03\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/campodimele\/2024\/10\/03\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\/"},"author":{"name":"campodimele","@id":"https:\/\/comunicacity.net\/campodimele\/#\/schema\/person\/707b1b5905116ac44a5a52a8f829f0da"},"headline":"Aggiornamento Albo Presidenti ed Albo scrutatori di seggio &#8211; Anno 2024","datePublished":"2024-10-03T10:38:59+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/campodimele\/2024\/10\/03\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\/"},"wordCount":381,"commentCount":0,"image":{"@id":"https:\/\/comunicacity.net\/campodimele\/2024\/10\/03\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2024\/10\/albo_scrutatori_e_presidenti.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/campodimele\/2024\/10\/03\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\/","url":"https:\/\/comunicacity.net\/campodimele\/2024\/10\/03\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\/","name":"Aggiornamento Albo Presidenti ed Albo scrutatori di seggio - Anno 2024 - Campodimele","isPartOf":{"@id":"https:\/\/comunicacity.net\/campodimele\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/campodimele\/2024\/10\/03\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/campodimele\/2024\/10\/03\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2024\/10\/albo_scrutatori_e_presidenti.png","datePublished":"2024-10-03T10:38:59+00:00","author":{"@id":"https:\/\/comunicacity.net\/campodimele\/#\/schema\/person\/707b1b5905116ac44a5a52a8f829f0da"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/campodimele\/2024\/10\/03\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/campodimele\/2024\/10\/03\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/campodimele\/2024\/10\/03\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\/#primaryimage","url":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2024\/10\/albo_scrutatori_e_presidenti.png","contentUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2024\/10\/albo_scrutatori_e_presidenti.png","width":640,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/campodimele\/2024\/10\/03\/aggiornamento-albo-presidenti-ed-albo-scrutatori-di-seggio-anno-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/campodimele\/"},{"@type":"ListItem","position":2,"name":"Aggiornamento Albo Presidenti ed Albo scrutatori di seggio &#8211; Anno 2024"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/campodimele\/#website","url":"https:\/\/comunicacity.net\/campodimele\/","name":"Campodimele","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/campodimele\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/campodimele\/#\/schema\/person\/707b1b5905116ac44a5a52a8f829f0da","name":"campodimele","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g","caption":"campodimele"},"sameAs":["http:\/\/www.comune.campodimele.lt.it"],"url":"https:\/\/comunicacity.net\/campodimele\/author\/campodimele\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002655"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts\/15236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/users\/242"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/comments?post=15236"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts\/15236\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/media\/15237"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/media?parent=15236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/categories?post=15236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/tags?post=15236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}