{"id":15361,"date":"2024-12-20T14:51:51","date_gmt":"2024-12-20T13:51:51","guid":{"rendered":"https:\/\/comunicacity.net\/campodimele\/?p=15361"},"modified":"2024-12-20T14:51:54","modified_gmt":"2024-12-20T13:51:54","slug":"convocazione-consiglio-comunale-del-28-12-2024","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/campodimele\/2024\/12\/20\/convocazione-consiglio-comunale-del-28-12-2024\/","title":{"rendered":"Convocazione Consiglio Comunale del 28.12.2024"},"content":{"rendered":"<p><em>Si partecipa la S.V. che il Consiglio Comunale \u00e8 convocato, in seduta ordinaria, nella Sala Marino Pecchia, il giorno 28.12.2024 in prima convocazione alle ore 11:00<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p style=\"text-align: center\"><strong>CONVOCAZIONE DEL CONSIGLIO COMUNALE<\/strong><\/p>\n<p>Si partecipa la S.V. che il Consiglio Comunale \u00e8 convocato, in seduta ordinaria, nella Sala Marino Pecchia, il giorno 28.12.2024 in prima convocazione alle ore 11:00 per discutere il seguente ordine del giorno:<\/p>\n<ol>\n<li>Lettura ed approvazione verbali della seduta del 26.09.2024;<\/li>\n<li>Ratifica delibera di G.C. n. 67 del 30.10.2024 ad oggetto &#8220;Variazione d&#8217;urgenza al bilancio di previsione finanziario (Art. 175, comma 4, del D.Lgs.n.267\/2000)&#8221;;<\/li>\n<li>Aggiornamento programma triennale delle opere pubbliche 2024\/2026 ed elenco annuale 2024. Modifiche ed approvazione;<\/li>\n<li>Ratifica delibera di G.C. n. 82 del 29.11.2024 ad oggetto \u201cVariazione d&#8217;urgenza al bilancio di previsione finanziario 2024\/2026 (art.175, comma 4, del d.lgs. n.267\/2000)\u201d;<\/li>\n<li>Ricognizione dei beni immobili di propriet\u00e0 comunale suscettibili di alienazione e\/o valorizzazione (art.58 l.n.133\/2008) individuazione degli immobili disponibili. Approvazione piano alienazioni 2025;<\/li>\n<li>Approvazione aliquote (e detrazione d&#8217;imposta) I.M.U. per l&#8217;anno 2025;<\/li>\n<li>Proposta programmi di incarichi di studi, di ricerca e di consulenze;<\/li>\n<li>Programma triennale dei lavori pubblici 2025\/2027 e dell&#8217;elenco annuale dei lavori per l&#8217;anno 2025 art. 37 del d.lgs. n. 36\/2023. Determinazioni;<\/li>\n<li>Programma triennale degli acquisti di beni e servizi 2025\/2027 art. 37 del d.lgs. n. 36\/2023. Determinazioni;<\/li>\n<li>Nota di aggiornamento al D.U.P. (Documento Unico di Programmazione) 2025\/2027. Modifiche ed approvazione;<\/li>\n<li>Bilancio di previsione finanziario 2025\/2027 (art.151 del d.lgs. n.267\/2000 e art.10 d.lgs. n.118\/2011).Approvazione;<\/li>\n<li>Revisione periodiche delle partecipazioni ex art.20 del d.lgs. 19 agosto 2016 n.175 e ss.mm.ii. ricognizione partecipazione possedute al 31.12.2023. Determinazioni;<\/li>\n<li>Acquisto ulteriore quota del 10% di partecipazione nella societ\u00e0 <em>in house providing<\/em> \u201cENERGIE COMUNI S.r.l.\u201d .<\/li>\n<\/ol>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_15371\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2024\/12\/Prot_Par-0004364-del-20-12-2024-Documento-doc20241220145855-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2024\/12\/Prot_Par-0004364-del-20-12-2024-Documento-doc20241220145855-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Prot_Par 0004364 del 20-12-2024 &#8211; Documento doc20241220145855<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si partecipa la S.V. che il Consiglio Comunale \u00e8 convocato, in seduta ordinaria, nella Sala Marino Pecchia, il giorno 28.12.2024 in prima convocazione alle ore 11:00&nbsp; Descrizione&nbsp; CONVOCAZIONE DEL CONSIGLIO [&hellip;]<\/p>\n","protected":false},"author":242,"featured_media":15370,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-15361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convocazione Consiglio Comunale del 28.12.2024 - Campodimele<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/campodimele\/2024\/12\/20\/convocazione-consiglio-comunale-del-28-12-2024\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convocazione Consiglio Comunale del 28.12.2024 - Campodimele\" \/>\n<meta property=\"og:description\" content=\"Si partecipa la S.V. che il Consiglio Comunale \u00e8 convocato, in seduta ordinaria, nella Sala Marino Pecchia, il giorno 28.12.2024 in prima convocazione alle ore 11:00&nbsp; Descrizione&nbsp; CONVOCAZIONE DEL CONSIGLIO [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/campodimele\/2024\/12\/20\/convocazione-consiglio-comunale-del-28-12-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Campodimele\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-20T13:51:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-20T13:51:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2024\/12\/Convocazione-consiglio-comunale-e1715858474883-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"230\" \/>\n\t<meta property=\"og:image:height\" content=\"153\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"campodimele\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"campodimele\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/12\\\/20\\\/convocazione-consiglio-comunale-del-28-12-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/12\\\/20\\\/convocazione-consiglio-comunale-del-28-12-2024\\\/\"},\"author\":{\"name\":\"campodimele\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#\\\/schema\\\/person\\\/707b1b5905116ac44a5a52a8f829f0da\"},\"headline\":\"Convocazione Consiglio Comunale del 28.12.2024\",\"datePublished\":\"2024-12-20T13:51:51+00:00\",\"dateModified\":\"2024-12-20T13:51:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/12\\\/20\\\/convocazione-consiglio-comunale-del-28-12-2024\\\/\"},\"wordCount\":270,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/12\\\/20\\\/convocazione-consiglio-comunale-del-28-12-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2024\\\/12\\\/Convocazione-consiglio-comunale-e1715858474883-1.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/12\\\/20\\\/convocazione-consiglio-comunale-del-28-12-2024\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/12\\\/20\\\/convocazione-consiglio-comunale-del-28-12-2024\\\/\",\"name\":\"Convocazione Consiglio Comunale del 28.12.2024 - Campodimele\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/12\\\/20\\\/convocazione-consiglio-comunale-del-28-12-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/12\\\/20\\\/convocazione-consiglio-comunale-del-28-12-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2024\\\/12\\\/Convocazione-consiglio-comunale-e1715858474883-1.png\",\"datePublished\":\"2024-12-20T13:51:51+00:00\",\"dateModified\":\"2024-12-20T13:51:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#\\\/schema\\\/person\\\/707b1b5905116ac44a5a52a8f829f0da\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/12\\\/20\\\/convocazione-consiglio-comunale-del-28-12-2024\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/12\\\/20\\\/convocazione-consiglio-comunale-del-28-12-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/12\\\/20\\\/convocazione-consiglio-comunale-del-28-12-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2024\\\/12\\\/Convocazione-consiglio-comunale-e1715858474883-1.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2024\\\/12\\\/Convocazione-consiglio-comunale-e1715858474883-1.png\",\"width\":230,\"height\":153},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2024\\\/12\\\/20\\\/convocazione-consiglio-comunale-del-28-12-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convocazione Consiglio Comunale del 28.12.2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/\",\"name\":\"Campodimele\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#\\\/schema\\\/person\\\/707b1b5905116ac44a5a52a8f829f0da\",\"name\":\"campodimele\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g\",\"caption\":\"campodimele\"},\"sameAs\":[\"http:\\\/\\\/www.comune.campodimele.lt.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/author\\\/campodimele\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convocazione Consiglio Comunale del 28.12.2024 - Campodimele","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/campodimele\/2024\/12\/20\/convocazione-consiglio-comunale-del-28-12-2024\/","og_locale":"it_IT","og_type":"article","og_title":"Convocazione Consiglio Comunale del 28.12.2024 - Campodimele","og_description":"Si partecipa la S.V. che il Consiglio Comunale \u00e8 convocato, in seduta ordinaria, nella Sala Marino Pecchia, il giorno 28.12.2024 in prima convocazione alle ore 11:00&nbsp; Descrizione&nbsp; CONVOCAZIONE DEL CONSIGLIO [&hellip;]","og_url":"https:\/\/comunicacity.net\/campodimele\/2024\/12\/20\/convocazione-consiglio-comunale-del-28-12-2024\/","og_site_name":"Campodimele","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-12-20T13:51:51+00:00","article_modified_time":"2024-12-20T13:51:54+00:00","og_image":[{"width":230,"height":153,"url":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2024\/12\/Convocazione-consiglio-comunale-e1715858474883-1.png","type":"image\/png"}],"author":"campodimele","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"campodimele","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/campodimele\/2024\/12\/20\/convocazione-consiglio-comunale-del-28-12-2024\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/campodimele\/2024\/12\/20\/convocazione-consiglio-comunale-del-28-12-2024\/"},"author":{"name":"campodimele","@id":"https:\/\/comunicacity.net\/campodimele\/#\/schema\/person\/707b1b5905116ac44a5a52a8f829f0da"},"headline":"Convocazione Consiglio Comunale del 28.12.2024","datePublished":"2024-12-20T13:51:51+00:00","dateModified":"2024-12-20T13:51:54+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/campodimele\/2024\/12\/20\/convocazione-consiglio-comunale-del-28-12-2024\/"},"wordCount":270,"image":{"@id":"https:\/\/comunicacity.net\/campodimele\/2024\/12\/20\/convocazione-consiglio-comunale-del-28-12-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2024\/12\/Convocazione-consiglio-comunale-e1715858474883-1.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/campodimele\/2024\/12\/20\/convocazione-consiglio-comunale-del-28-12-2024\/","url":"https:\/\/comunicacity.net\/campodimele\/2024\/12\/20\/convocazione-consiglio-comunale-del-28-12-2024\/","name":"Convocazione Consiglio Comunale del 28.12.2024 - Campodimele","isPartOf":{"@id":"https:\/\/comunicacity.net\/campodimele\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/campodimele\/2024\/12\/20\/convocazione-consiglio-comunale-del-28-12-2024\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/campodimele\/2024\/12\/20\/convocazione-consiglio-comunale-del-28-12-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2024\/12\/Convocazione-consiglio-comunale-e1715858474883-1.png","datePublished":"2024-12-20T13:51:51+00:00","dateModified":"2024-12-20T13:51:54+00:00","author":{"@id":"https:\/\/comunicacity.net\/campodimele\/#\/schema\/person\/707b1b5905116ac44a5a52a8f829f0da"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/campodimele\/2024\/12\/20\/convocazione-consiglio-comunale-del-28-12-2024\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/campodimele\/2024\/12\/20\/convocazione-consiglio-comunale-del-28-12-2024\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/campodimele\/2024\/12\/20\/convocazione-consiglio-comunale-del-28-12-2024\/#primaryimage","url":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2024\/12\/Convocazione-consiglio-comunale-e1715858474883-1.png","contentUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2024\/12\/Convocazione-consiglio-comunale-e1715858474883-1.png","width":230,"height":153},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/campodimele\/2024\/12\/20\/convocazione-consiglio-comunale-del-28-12-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/campodimele\/"},{"@type":"ListItem","position":2,"name":"Convocazione Consiglio Comunale del 28.12.2024"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/campodimele\/#website","url":"https:\/\/comunicacity.net\/campodimele\/","name":"Campodimele","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/campodimele\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/campodimele\/#\/schema\/person\/707b1b5905116ac44a5a52a8f829f0da","name":"campodimele","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g","caption":"campodimele"},"sameAs":["http:\/\/www.comune.campodimele.lt.it"],"url":"https:\/\/comunicacity.net\/campodimele\/author\/campodimele\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002719"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts\/15361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/users\/242"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/comments?post=15361"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts\/15361\/revisions"}],"predecessor-version":[{"id":15369,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts\/15361\/revisions\/15369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/media\/15370"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/media?parent=15361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/categories?post=15361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/tags?post=15361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}