{"id":15813,"date":"2025-07-25T20:28:15","date_gmt":"2025-07-25T18:28:15","guid":{"rendered":"https:\/\/comunicacity.net\/campodimele\/?p=15813"},"modified":"2025-07-25T20:28:18","modified_gmt":"2025-07-25T18:28:18","slug":"ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/campodimele\/2025\/07\/25\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\/","title":{"rendered":"Ordinanza sindacale per l\u2019adozione di misure urgenti di prevenzione e controllo del Virus West Nile (WNV) e, pi\u00f9 in generale, di altre malattie virali trasmesse da insetti vettori, con particolare riferimento alle zanzare."},"content":{"rendered":"<p><em>Misure per prevenire e contenere la diffusione del Virus West Nile e di altre malattie trasmesse da zanzare.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p style=\"text-align: center\" data-start=\"179\" data-end=\"298\"><strong data-start=\"179\" data-end=\"207\">AVVISO ALLA CITTADINANZA<\/strong><br data-start=\"207\" data-end=\"210\" \/><strong data-start=\"210\" data-end=\"298\">MISURE URGENTI DI PREVENZIONE E CONTROLLO DELLA DIFFUSIONE DEL VIRUS WEST NILE (WNV)<\/strong><\/p>\n<p data-start=\"300\" data-end=\"613\">Si informa la cittadinanza che, con comunicazione della ASL di Latina \u2013 Dipartimento di Prevenzione UOC Igiene e Sanit\u00e0 Pubblica (prot. n. 2554 del 21.07.2025), \u00e8 stata segnalata la recente identificazione di <strong data-start=\"509\" data-end=\"555\">casi di infezione da Virus West Nile (WNV)<\/strong> nella provincia di Latina. In particolare, si registrano:<\/p>\n<ul data-start=\"615\" data-end=\"863\">\n<li data-start=\"615\" data-end=\"671\">\n<p data-start=\"617\" data-end=\"671\"><strong data-start=\"617\" data-end=\"670\">due casi autoctoni confermati di infezione da WNV<\/strong>;<\/p>\n<\/li>\n<li data-start=\"672\" data-end=\"782\">\n<p data-start=\"674\" data-end=\"782\"><strong data-start=\"674\" data-end=\"695\">tre casi sospetti<\/strong> (di cui due in cittadini e uno in un cavallo), attualmente in fase di approfondimento;<\/p>\n<\/li>\n<li data-start=\"783\" data-end=\"863\">\n<p data-start=\"785\" data-end=\"863\"><strong data-start=\"785\" data-end=\"862\">presenza del virus riscontrata in zanzare raccolte nel Comune di Pontinia<\/strong>.<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"865\" data-end=\"1065\">Il <strong data-start=\"868\" data-end=\"887\">Virus West Nile<\/strong> \u00e8 trasmesso esclusivamente dalla <strong data-start=\"921\" data-end=\"951\">puntura di zanzare infette<\/strong> (soprattutto del genere <em data-start=\"976\" data-end=\"983\">Culex<\/em>) e <strong data-start=\"987\" data-end=\"1064\">non si trasmette da persona a persona n\u00e9 per contatto diretto con animali<\/strong>.<\/p>\n<h3 data-start=\"1067\" data-end=\"1093\"><\/h3>\n<h3 style=\"text-align: center\" data-start=\"1067\" data-end=\"1093\">INFORMAZIONI SANITARIE<\/h3>\n<p data-start=\"1095\" data-end=\"1362\">Secondo quanto indicato dalla ASL di Latina, <strong data-start=\"1140\" data-end=\"1191\">la maggior parte delle infezioni \u00e8 asintomatica<\/strong>. In alcuni casi si possono manifestare <strong data-start=\"1231\" data-end=\"1266\">lievi sintomi simil-influenzali<\/strong>, mentre le complicanze gravi sono rare e interessano principalmente soggetti anziani o fragili.<\/p>\n<h3 data-start=\"1364\" data-end=\"1389\"><\/h3>\n<h3 style=\"text-align: center\" data-start=\"1364\" data-end=\"1389\">MISURE DI PREVENZIONE<\/h3>\n<p data-start=\"1391\" data-end=\"1673\">Il Comune di Campodimele, gi\u00e0 attivo con interventi ordinari di disinfestazione, <strong data-start=\"1472\" data-end=\"1532\">invita tutti i cittadini e i soggetti pubblici e privati<\/strong> a collaborare attivamente alla <strong data-start=\"1564\" data-end=\"1620\">prevenzione e riduzione della popolazione di zanzare<\/strong>, osservando le seguenti <strong data-start=\"1645\" data-end=\"1672\">disposizioni principali<\/strong>:<\/p>\n<ul data-start=\"1675\" data-end=\"2469\">\n<li data-start=\"1675\" data-end=\"1803\">\n<p data-start=\"1677\" data-end=\"1803\"><strong data-start=\"1677\" data-end=\"1722\">Eliminare qualsiasi oggetto o contenitore<\/strong> che possa raccogliere acqua stagnante (es. secchi, sottovasi, pneumatici, ecc.).<\/p>\n<\/li>\n<li data-start=\"1804\" data-end=\"1884\">\n<p data-start=\"1806\" data-end=\"1884\"><strong data-start=\"1806\" data-end=\"1857\">Mantenere puliti cortili, giardini e aree verdi<\/strong>, evitando ristagni idrici.<\/p>\n<\/li>\n<li data-start=\"1885\" data-end=\"2020\">\n<p data-start=\"1887\" data-end=\"2020\"><strong data-start=\"1887\" data-end=\"1922\">Trattare con prodotti larvicidi<\/strong> tombini, pozzetti, fontane non in uso, piscine non attive, e tutti i contenitori non eliminabili.<\/p>\n<\/li>\n<li data-start=\"2021\" data-end=\"2119\">\n<p data-start=\"2023\" data-end=\"2119\"><strong data-start=\"2023\" data-end=\"2061\">Copertura ermetica dei contenitori<\/strong> utilizzati con acqua, o svuotamento almeno ogni 5 giorni.<\/p>\n<\/li>\n<li data-start=\"2120\" data-end=\"2224\">\n<p data-start=\"2122\" data-end=\"2224\"><strong data-start=\"2122\" data-end=\"2138\">Nei cimiteri<\/strong>, riempire i vasi portafiori con sabbia o trattare regolarmente l\u2019acqua con larvicidi.<\/p>\n<\/li>\n<li data-start=\"2225\" data-end=\"2353\">\n<p data-start=\"2227\" data-end=\"2353\"><strong data-start=\"2227\" data-end=\"2303\">Operatori agricoli, vivai, florovivaisti, cantieri e attivit\u00e0 produttive<\/strong> devono programmare adeguati interventi larvicidi.<\/p>\n<\/li>\n<li data-start=\"2354\" data-end=\"2469\">\n<p data-start=\"2356\" data-end=\"2469\"><strong data-start=\"2356\" data-end=\"2410\">Segnalare la presenza di uccelli morti o moribondi<\/strong> all\u2019Ufficio Ambiente (0771.598013) e alla ASL (0773.6551).<\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"2471\" data-end=\"2507\"><\/h3>\n<h3 style=\"text-align: center\" data-start=\"2471\" data-end=\"2507\">RACCOMANDAZIONI ALLA POPOLAZIONE<\/h3>\n<p data-start=\"2509\" data-end=\"2539\">Per proteggersi dalle punture:<\/p>\n<ul data-start=\"2541\" data-end=\"2897\">\n<li data-start=\"2541\" data-end=\"2627\">\n<p data-start=\"2543\" data-end=\"2627\">Indossare <strong data-start=\"2553\" data-end=\"2598\">abbigliamento coprente e di colore chiaro<\/strong> nelle ore serali e notturne.<\/p>\n<\/li>\n<li data-start=\"2628\" data-end=\"2715\">\n<p data-start=\"2630\" data-end=\"2715\">Utilizzare <strong data-start=\"2641\" data-end=\"2663\">repellenti cutanei<\/strong> con cautela e nel rispetto delle indicazioni d\u2019uso.<\/p>\n<\/li>\n<li data-start=\"2716\" data-end=\"2766\">\n<p data-start=\"2718\" data-end=\"2766\">Installare <strong data-start=\"2729\" data-end=\"2743\">zanzariere<\/strong> alle finestre e porte.<\/p>\n<\/li>\n<li data-start=\"2767\" data-end=\"2897\">\n<p data-start=\"2769\" data-end=\"2897\">In presenza di zanzare in ambienti interni, <strong data-start=\"2813\" data-end=\"2852\">usare spray o diffusori insetticidi<\/strong>, arieggiando i locali prima di soggiornarvi.<\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"2899\" data-end=\"2922\"><\/h3>\n<h3 style=\"text-align: center\" data-start=\"2899\" data-end=\"2922\">INTERVENTI COMUNALI<\/h3>\n<p data-start=\"2924\" data-end=\"2945\">Il Comune provveder\u00e0:<\/p>\n<ul data-start=\"2947\" data-end=\"3191\">\n<li data-start=\"2947\" data-end=\"3057\">\n<p data-start=\"2949\" data-end=\"3057\">al potenziamento degli interventi di disinfestazione <strong data-start=\"3002\" data-end=\"3056\">con trattamenti larvicidi e di bonifica ambientale<\/strong>;<\/p>\n<\/li>\n<li data-start=\"3058\" data-end=\"3191\">\n<p data-start=\"3060\" data-end=\"3191\">alla valutazione di interventi <strong data-start=\"3091\" data-end=\"3117\">adulticidi localizzati<\/strong> in presenza di soggetti fragili o in occasione di eventi pubblici serali.<\/p>\n<\/li>\n<\/ul>\n<h3 data-start=\"3193\" data-end=\"3222\"><\/h3>\n<h3 style=\"text-align: center\" data-start=\"3193\" data-end=\"3222\">SANZIONI E RESPONSABILIT\u00c0<\/h3>\n<p data-start=\"3224\" data-end=\"3451\">La mancata osservanza dell\u2019ordinanza \u00e8 sanzionabile ai sensi dell\u2019art. 7 bis del D.Lgs. 267\/2000. La responsabilit\u00e0 \u00e8 attribuita ai soggetti che, a qualunque titolo, dispongano dell\u2019area dove verranno riscontrate le violazioni.<\/p>\n<p data-start=\"3458\" data-end=\"3582\">\n<p data-start=\"3458\" data-end=\"3582\"><strong>L\u2019Amministrazione comunale confida nella collaborazione attiva di tutti i cittadini per la tutela della salute pubblica.<\/strong><\/p>\n<p data-start=\"3584\" data-end=\"3669\">Il presente avviso ha efficacia immediata e rimane valido fino a nuove comunicazioni.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_15820\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/07\/Atto-originale.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/07\/Atto-originale.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Atto originale<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Misure per prevenire e contenere la diffusione del Virus West Nile e di altre malattie trasmesse da zanzare.&nbsp; Descrizione&nbsp; AVVISO ALLA CITTADINANZAMISURE URGENTI DI PREVENZIONE E CONTROLLO DELLA DIFFUSIONE DEL [&hellip;]<\/p>\n","protected":false},"author":242,"featured_media":15819,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-15813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ordinanza sindacale per l\u2019adozione di misure urgenti di prevenzione e controllo del Virus West Nile (WNV) e, pi\u00f9 in generale, di altre malattie virali trasmesse da insetti vettori, con particolare riferimento alle zanzare. - Campodimele<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/campodimele\/2025\/07\/25\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ordinanza sindacale per l\u2019adozione di misure urgenti di prevenzione e controllo del Virus West Nile (WNV) e, pi\u00f9 in generale, di altre malattie virali trasmesse da insetti vettori, con particolare riferimento alle zanzare. - Campodimele\" \/>\n<meta property=\"og:description\" content=\"Misure per prevenire e contenere la diffusione del Virus West Nile e di altre malattie trasmesse da zanzare.&nbsp; Descrizione&nbsp; AVVISO ALLA CITTADINANZAMISURE URGENTI DI PREVENZIONE E CONTROLLO DELLA DIFFUSIONE DEL [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/campodimele\/2025\/07\/25\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\/\" \/>\n<meta property=\"og:site_name\" content=\"Campodimele\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-25T18:28:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-25T18:28:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/07\/west-nile-virus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"950\" \/>\n\t<meta property=\"og:image:height\" content=\"705\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"campodimele\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"campodimele\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/07\\\/25\\\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/07\\\/25\\\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\\\/\"},\"author\":{\"name\":\"campodimele\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#\\\/schema\\\/person\\\/707b1b5905116ac44a5a52a8f829f0da\"},\"headline\":\"Ordinanza sindacale per l\u2019adozione di misure urgenti di prevenzione e controllo del Virus West Nile (WNV) e, pi\u00f9 in generale, di altre malattie virali trasmesse da insetti vettori, con particolare riferimento alle zanzare.\",\"datePublished\":\"2025-07-25T18:28:15+00:00\",\"dateModified\":\"2025-07-25T18:28:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/07\\\/25\\\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\\\/\"},\"wordCount\":511,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/07\\\/25\\\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2025\\\/07\\\/west-nile-virus.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/07\\\/25\\\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/07\\\/25\\\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\\\/\",\"name\":\"Ordinanza sindacale per l\u2019adozione di misure urgenti di prevenzione e controllo del Virus West Nile (WNV) e, pi\u00f9 in generale, di altre malattie virali trasmesse da insetti vettori, con particolare riferimento alle zanzare. - Campodimele\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/07\\\/25\\\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/07\\\/25\\\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2025\\\/07\\\/west-nile-virus.jpg\",\"datePublished\":\"2025-07-25T18:28:15+00:00\",\"dateModified\":\"2025-07-25T18:28:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#\\\/schema\\\/person\\\/707b1b5905116ac44a5a52a8f829f0da\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/07\\\/25\\\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/07\\\/25\\\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/07\\\/25\\\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2025\\\/07\\\/west-nile-virus.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2025\\\/07\\\/west-nile-virus.jpg\",\"width\":950,\"height\":705},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/07\\\/25\\\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ordinanza sindacale per l\u2019adozione di misure urgenti di prevenzione e controllo del Virus West Nile (WNV) e, pi\u00f9 in generale, di altre malattie virali trasmesse da insetti vettori, con particolare riferimento alle zanzare.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/\",\"name\":\"Campodimele\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#\\\/schema\\\/person\\\/707b1b5905116ac44a5a52a8f829f0da\",\"name\":\"campodimele\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g\",\"caption\":\"campodimele\"},\"sameAs\":[\"http:\\\/\\\/www.comune.campodimele.lt.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/author\\\/campodimele\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ordinanza sindacale per l\u2019adozione di misure urgenti di prevenzione e controllo del Virus West Nile (WNV) e, pi\u00f9 in generale, di altre malattie virali trasmesse da insetti vettori, con particolare riferimento alle zanzare. - Campodimele","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/campodimele\/2025\/07\/25\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\/","og_locale":"it_IT","og_type":"article","og_title":"Ordinanza sindacale per l\u2019adozione di misure urgenti di prevenzione e controllo del Virus West Nile (WNV) e, pi\u00f9 in generale, di altre malattie virali trasmesse da insetti vettori, con particolare riferimento alle zanzare. - Campodimele","og_description":"Misure per prevenire e contenere la diffusione del Virus West Nile e di altre malattie trasmesse da zanzare.&nbsp; Descrizione&nbsp; AVVISO ALLA CITTADINANZAMISURE URGENTI DI PREVENZIONE E CONTROLLO DELLA DIFFUSIONE DEL [&hellip;]","og_url":"https:\/\/comunicacity.net\/campodimele\/2025\/07\/25\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\/","og_site_name":"Campodimele","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-07-25T18:28:15+00:00","article_modified_time":"2025-07-25T18:28:18+00:00","og_image":[{"width":950,"height":705,"url":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/07\/west-nile-virus.jpg","type":"image\/jpeg"}],"author":"campodimele","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"campodimele","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/campodimele\/2025\/07\/25\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/campodimele\/2025\/07\/25\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\/"},"author":{"name":"campodimele","@id":"https:\/\/comunicacity.net\/campodimele\/#\/schema\/person\/707b1b5905116ac44a5a52a8f829f0da"},"headline":"Ordinanza sindacale per l\u2019adozione di misure urgenti di prevenzione e controllo del Virus West Nile (WNV) e, pi\u00f9 in generale, di altre malattie virali trasmesse da insetti vettori, con particolare riferimento alle zanzare.","datePublished":"2025-07-25T18:28:15+00:00","dateModified":"2025-07-25T18:28:18+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/campodimele\/2025\/07\/25\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\/"},"wordCount":511,"image":{"@id":"https:\/\/comunicacity.net\/campodimele\/2025\/07\/25\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/07\/west-nile-virus.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/campodimele\/2025\/07\/25\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\/","url":"https:\/\/comunicacity.net\/campodimele\/2025\/07\/25\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\/","name":"Ordinanza sindacale per l\u2019adozione di misure urgenti di prevenzione e controllo del Virus West Nile (WNV) e, pi\u00f9 in generale, di altre malattie virali trasmesse da insetti vettori, con particolare riferimento alle zanzare. - Campodimele","isPartOf":{"@id":"https:\/\/comunicacity.net\/campodimele\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/campodimele\/2025\/07\/25\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/campodimele\/2025\/07\/25\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/07\/west-nile-virus.jpg","datePublished":"2025-07-25T18:28:15+00:00","dateModified":"2025-07-25T18:28:18+00:00","author":{"@id":"https:\/\/comunicacity.net\/campodimele\/#\/schema\/person\/707b1b5905116ac44a5a52a8f829f0da"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/campodimele\/2025\/07\/25\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/campodimele\/2025\/07\/25\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/campodimele\/2025\/07\/25\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\/#primaryimage","url":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/07\/west-nile-virus.jpg","contentUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/07\/west-nile-virus.jpg","width":950,"height":705},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/campodimele\/2025\/07\/25\/ordinanza-sindacale-per-ladozione-di-misure-urgenti-di-prevenzione-e-controllo-del-virus-west-nile-wnv-e-piu-in-generale-di-altre-malattie-virali-trasmesse-da-insetti-vettori-con-partico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/campodimele\/"},{"@type":"ListItem","position":2,"name":"Ordinanza sindacale per l\u2019adozione di misure urgenti di prevenzione e controllo del Virus West Nile (WNV) e, pi\u00f9 in generale, di altre malattie virali trasmesse da insetti vettori, con particolare riferimento alle zanzare."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/campodimele\/#website","url":"https:\/\/comunicacity.net\/campodimele\/","name":"Campodimele","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/campodimele\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/campodimele\/#\/schema\/person\/707b1b5905116ac44a5a52a8f829f0da","name":"campodimele","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g","caption":"campodimele"},"sameAs":["http:\/\/www.comune.campodimele.lt.it"],"url":"https:\/\/comunicacity.net\/campodimele\/author\/campodimele\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002920"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts\/15813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/users\/242"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/comments?post=15813"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts\/15813\/revisions"}],"predecessor-version":[{"id":15816,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts\/15813\/revisions\/15816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/media\/15819"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/media?parent=15813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/categories?post=15813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/tags?post=15813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}