{"id":15853,"date":"2025-08-26T18:49:43","date_gmt":"2025-08-26T16:49:43","guid":{"rendered":"https:\/\/comunicacity.net\/campodimele\/?p=15853"},"modified":"2025-08-26T18:49:42","modified_gmt":"2025-08-26T16:49:42","slug":"corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/campodimele\/2025\/08\/26\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\/","title":{"rendered":"Corso di formazione micologica per la raccolta di funghi epigei spontanei"},"content":{"rendered":"<p><em>Corso di formazione micologica per la raccolta di funghi epigei spontanei. Info e iscrizioni: Giulia Mariani (WhatsApp 329 256 4454), Presidente Ass. In Sana Terra.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<h3 style=\"text-align: center\" data-start=\"108\" data-end=\"138\">AVVISO ALLA CITTADINANZA<\/h3>\n<p style=\"text-align: center\" data-start=\"139\" data-end=\"218\"><strong data-start=\"139\" data-end=\"216\">Corso di formazione micologica per la raccolta di funghi epigei spontanei<\/strong><\/p>\n<p data-start=\"220\" data-end=\"592\">Il Comune di Campodimele patrocina il <strong data-start=\"258\" data-end=\"335\">Corso di formazione micologica per la raccolta di funghi epigei spontanei<\/strong>, organizzato e gestito dall\u2019Associazione <em data-start=\"377\" data-end=\"392\">In Sana Terra<\/em>.<br data-start=\"393\" data-end=\"396\" \/>Il corso \u00e8 valido per l\u2019abilitazione alla raccolta dei funghi epigei spontanei e di altri prodotti del sottobosco, ai sensi della normativa regionale vigente (L.R. Lazio n. 32\/1998 e ss.mm.ii.).<\/p>\n<p data-start=\"594\" data-end=\"624\"><strong data-start=\"594\" data-end=\"622\">Calendario delle lezioni<\/strong><\/p>\n<ul data-start=\"625\" data-end=\"796\">\n<li data-start=\"625\" data-end=\"692\">\n<p data-start=\"627\" data-end=\"692\">1, 3, 5, 8 e 10 settembre 2025 \u2013 dalle ore 17:00 alle ore 19:20<\/p>\n<\/li>\n<li data-start=\"693\" data-end=\"796\">\n<p data-start=\"695\" data-end=\"796\">12 settembre 2025 \u2013 dalle ore 9:00 alle ore 12:00: escursione didattica sulla Piana di Sant\u2019Onofrio<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"798\" data-end=\"876\"><strong data-start=\"798\" data-end=\"816\">Sede del corso<\/strong>: Palazzo della Cultura, Viale Glorioso \u2013 Campodimele (LT)<\/p>\n<p data-start=\"878\" data-end=\"927\"><strong data-start=\"878\" data-end=\"889\">Docenza<\/strong>: esperto micologo Franco Carnevale.<\/p>\n<p data-start=\"929\" data-end=\"1073\">L\u2019iniziativa \u00e8 <strong data-start=\"944\" data-end=\"966\">aperta al pubblico<\/strong> e rappresenta un\u2019importante occasione di formazione e conoscenza del patrimonio naturale del territorio.<\/p>\n<p data-start=\"1075\" data-end=\"1254\">\u2139\ufe0f <strong data-start=\"1078\" data-end=\"1114\">Informazioni, iscrizioni e costi<\/strong><br data-start=\"1114\" data-end=\"1117\" \/>Contattare <strong data-start=\"1128\" data-end=\"1146\">Giulia Mariani<\/strong>, Presidente dell\u2019Associazione <em data-start=\"1177\" data-end=\"1192\">In Sana Terra<\/em> (preferibilmente via WhatsApp), al numero <strong data-start=\"1235\" data-end=\"1251\">329 256 4454<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corso di formazione micologica per la raccolta di funghi epigei spontanei. Info e iscrizioni: Giulia Mariani (WhatsApp 329 256 4454), Presidente Ass. In Sana Terra.&nbsp; Descrizione&nbsp; AVVISO ALLA CITTADINANZA Corso [&hellip;]<\/p>\n","protected":false},"author":242,"featured_media":15857,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-15853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corso di formazione micologica per la raccolta di funghi epigei spontanei - Campodimele<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/campodimele\/2025\/08\/26\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corso di formazione micologica per la raccolta di funghi epigei spontanei - Campodimele\" \/>\n<meta property=\"og:description\" content=\"Corso di formazione micologica per la raccolta di funghi epigei spontanei. Info e iscrizioni: Giulia Mariani (WhatsApp 329 256 4454), Presidente Ass. In Sana Terra.&nbsp; Descrizione&nbsp; AVVISO ALLA CITTADINANZA Corso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/campodimele\/2025\/08\/26\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\/\" \/>\n<meta property=\"og:site_name\" content=\"Campodimele\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-26T16:49:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/08\/whatsapp-image-2025-07-24-at-08.38.00-1-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1414\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"campodimele\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"campodimele\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/08\\\/26\\\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/08\\\/26\\\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\\\/\"},\"author\":{\"name\":\"campodimele\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#\\\/schema\\\/person\\\/707b1b5905116ac44a5a52a8f829f0da\"},\"headline\":\"Corso di formazione micologica per la raccolta di funghi epigei spontanei\",\"datePublished\":\"2025-08-26T16:49:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/08\\\/26\\\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\\\/\"},\"wordCount\":180,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/08\\\/26\\\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2025\\\/08\\\/whatsapp-image-2025-07-24-at-08.38.00-1-2.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/08\\\/26\\\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/08\\\/26\\\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\\\/\",\"name\":\"Corso di formazione micologica per la raccolta di funghi epigei spontanei - Campodimele\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/08\\\/26\\\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/08\\\/26\\\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2025\\\/08\\\/whatsapp-image-2025-07-24-at-08.38.00-1-2.jpeg\",\"datePublished\":\"2025-08-26T16:49:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#\\\/schema\\\/person\\\/707b1b5905116ac44a5a52a8f829f0da\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/08\\\/26\\\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/08\\\/26\\\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/08\\\/26\\\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2025\\\/08\\\/whatsapp-image-2025-07-24-at-08.38.00-1-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2025\\\/08\\\/whatsapp-image-2025-07-24-at-08.38.00-1-2.jpeg\",\"width\":1414,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/08\\\/26\\\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corso di formazione micologica per la raccolta di funghi epigei spontanei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/\",\"name\":\"Campodimele\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#\\\/schema\\\/person\\\/707b1b5905116ac44a5a52a8f829f0da\",\"name\":\"campodimele\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g\",\"caption\":\"campodimele\"},\"sameAs\":[\"http:\\\/\\\/www.comune.campodimele.lt.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/author\\\/campodimele\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corso di formazione micologica per la raccolta di funghi epigei spontanei - Campodimele","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/campodimele\/2025\/08\/26\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\/","og_locale":"it_IT","og_type":"article","og_title":"Corso di formazione micologica per la raccolta di funghi epigei spontanei - Campodimele","og_description":"Corso di formazione micologica per la raccolta di funghi epigei spontanei. Info e iscrizioni: Giulia Mariani (WhatsApp 329 256 4454), Presidente Ass. In Sana Terra.&nbsp; Descrizione&nbsp; AVVISO ALLA CITTADINANZA Corso [&hellip;]","og_url":"https:\/\/comunicacity.net\/campodimele\/2025\/08\/26\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\/","og_site_name":"Campodimele","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-08-26T16:49:43+00:00","og_image":[{"width":1414,"height":2000,"url":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/08\/whatsapp-image-2025-07-24-at-08.38.00-1-2.jpeg","type":"image\/jpeg"}],"author":"campodimele","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"campodimele","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/campodimele\/2025\/08\/26\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/campodimele\/2025\/08\/26\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\/"},"author":{"name":"campodimele","@id":"https:\/\/comunicacity.net\/campodimele\/#\/schema\/person\/707b1b5905116ac44a5a52a8f829f0da"},"headline":"Corso di formazione micologica per la raccolta di funghi epigei spontanei","datePublished":"2025-08-26T16:49:43+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/campodimele\/2025\/08\/26\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\/"},"wordCount":180,"image":{"@id":"https:\/\/comunicacity.net\/campodimele\/2025\/08\/26\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/08\/whatsapp-image-2025-07-24-at-08.38.00-1-2.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/campodimele\/2025\/08\/26\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\/","url":"https:\/\/comunicacity.net\/campodimele\/2025\/08\/26\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\/","name":"Corso di formazione micologica per la raccolta di funghi epigei spontanei - Campodimele","isPartOf":{"@id":"https:\/\/comunicacity.net\/campodimele\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/campodimele\/2025\/08\/26\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/campodimele\/2025\/08\/26\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/08\/whatsapp-image-2025-07-24-at-08.38.00-1-2.jpeg","datePublished":"2025-08-26T16:49:43+00:00","author":{"@id":"https:\/\/comunicacity.net\/campodimele\/#\/schema\/person\/707b1b5905116ac44a5a52a8f829f0da"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/campodimele\/2025\/08\/26\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/campodimele\/2025\/08\/26\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/campodimele\/2025\/08\/26\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\/#primaryimage","url":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/08\/whatsapp-image-2025-07-24-at-08.38.00-1-2.jpeg","contentUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/08\/whatsapp-image-2025-07-24-at-08.38.00-1-2.jpeg","width":1414,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/campodimele\/2025\/08\/26\/corso-di-formazione-micologica-per-la-raccolta-di-funghi-epigei-spontanei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/campodimele\/"},{"@type":"ListItem","position":2,"name":"Corso di formazione micologica per la raccolta di funghi epigei spontanei"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/campodimele\/#website","url":"https:\/\/comunicacity.net\/campodimele\/","name":"Campodimele","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/campodimele\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/campodimele\/#\/schema\/person\/707b1b5905116ac44a5a52a8f829f0da","name":"campodimele","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g","caption":"campodimele"},"sameAs":["http:\/\/www.comune.campodimele.lt.it"],"url":"https:\/\/comunicacity.net\/campodimele\/author\/campodimele\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002940"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts\/15853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/users\/242"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/comments?post=15853"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts\/15853\/revisions"}],"predecessor-version":[{"id":15856,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts\/15853\/revisions\/15856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/media\/15857"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/media?parent=15853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/categories?post=15853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/tags?post=15853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}