{"id":16129,"date":"2025-12-24T14:16:34","date_gmt":"2025-12-24T13:16:34","guid":{"rendered":"https:\/\/comunicacity.net\/campodimele\/2025\/12\/24\/convocazione-consiglio-comunale-del-29-12-2025\/"},"modified":"2025-12-24T14:16:34","modified_gmt":"2025-12-24T13:16:34","slug":"convocazione-consiglio-comunale-del-29-12-2025","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/campodimele\/2025\/12\/24\/convocazione-consiglio-comunale-del-29-12-2025\/","title":{"rendered":"Convocazione Consiglio comunale del 29.12.2025"},"content":{"rendered":"<p><em>Convocazione del Consiglio Comunale in seduta ordinaria per il giorno 29 dicembre 2025, alle ore 16:00, presso la Sala Marino Pecchia<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p style=\"text-align: center\"><strong>CONVOCAZIONE DEL CONSIGLIO COMUNALE<\/strong><\/p>\n<p>Si partecipa la S.V. che il Consiglio Comunale \u00e8 convocato, in seduta ordinaria, nella Sala Consiliare <em>\u201cMarino Pecchia\u201d<\/em>, sita in Piazza Municipio 4, il giorno luned\u00ec 29.12.2025 in prima convocazione alle ore 16:00 per discutere il seguente ordine del giorno:<\/p>\n<ol>\n<li>Lettura ed approvazione verbali della seduta del 29.09.2025;<\/li>\n<li>Ratifica delibera di G.C. n. 72 del 24.11.2025 avente ad oggetto:<em>\u201cAdozione di variazione d\u2019urgenza al bilancio di previsione finanziario 2025-2027, adottata ai sensi e per gli effetti dell\u2019art. 175, comma 4, del D. Lgs. n. 267\/2000 (T.U.E.L.)\u201d<\/em>;<\/li>\n<li>Revisione periodica delle partecipazioni ex art. 20 del D. Lgs. 19 agosto 20216 n. 175 e ss.mm.ii. Ricognizione partecipazioni possedute al 23.12.2024.Determinazioni;<\/li>\n<li>Presa d\u2019atto della Delibera di G.C. n. 62 del 23.10.2025 e consequenziali deliberazioni per l\u2019approvazione del Progetto esecutivo ai sensi del D. Lgs. 36\/2023 e del Piano particellare d\u2019esproprio dell\u2019intervento denominato \u201c<em>Realizzazione di nuovi parcheggi pubblici, opere di arredo urbano, viabilit\u00e0 di accesso, illuminazione pubblica e punti di ricarica per veicoli elettrici lungo la strada regionale 82, nel perimetro urbano della Frazione Taverna. CUP: H39J25000970002\u201d<\/em>;<\/li>\n<li>Aggiornamento Annuale del &#8220;<em>Catasto delle aree percorse dal fuoco<\/em>&#8221; ai sensi dell&#8217;art. 10 comma 2 legge 21 novembre 2000, n. 353 &#8220;<em>Legge quadro in materia di incendi boschivi<\/em>&#8221; annualit\u00e0 2024. Approvazione;<\/li>\n<li>Ricognizione dei beni immobili di propriet\u00e0 comunale suscettibili di alienazione e\/o valorizzazione (art. 58 L. n. 133\/2008). Individuazione degli immobili disponibili. Approvazione Piano Alienazioni 2026;<\/li>\n<li>Adozione del Piano Comunale di Eliminazione delle Barriere Architettoniche (P.E.B.A.) ai sensi dell&#8217;art. 32, comma 21, della legge n. 41\/1986, dellart. 3-bis della l.r. lazio n. 74\/1989 e s.m.i., della d.g.r. Lazio n. 40\/2020 e del d.m. 14 giugno 1989, n. 236. approvazione degli elaborati tecnici costitutivi. Approvazione definitiva da parte del consiglio comunale;<\/li>\n<li>Approvazione aliquote (e detrazione d\u2019imposta) I.M.U. per l\u2019anno 2026;<\/li>\n<li>Proposta programmi di incarichi di studi, di ricerca e di consulenze;<\/li>\n<li>Adozione Programma Triennale dei Lavori Pubblici 2026\/2028 e dell\u2019elenco annuale dei lavori per l\u2019anno 2026, art. 37 del D. Lgs. n. 36\/2023. Determinazioni;<\/li>\n<li>Adozione Programma Triennale degli acquisti di beni e servizi 2026\/2028, art. 37 del D. Lgs. n. 36\/2023. Determinazioni;<\/li>\n<li>Nota di aggiornamento al D.U.P. (Documento Unico di Programmazione) 2026\/2028. Modifiche ed approvazione;<\/li>\n<li>Bilancio di previsione finanziario 2026\/2028 (art. 151 del D. Lgs. n. 267\/2000) e art. 10 del D. Lgs. n. 118\/2011). Approvazione.<\/li>\n<\/ol>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_16131\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/12\/prot_par-0004415-del-23-12-2025-documento-convocazione-consiglio-comunale-del-29.12.2025-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/12\/prot_par-0004415-del-23-12-2025-documento-convocazione-consiglio-comunale-del-29.12.2025-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>prot_par 0004415 del 23-12-2025 &#8211; documento convocazione consiglio comunale del 29.12.2025 (1)<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Convocazione del Consiglio Comunale in seduta ordinaria per il giorno 29 dicembre 2025, alle ore 16:00, presso la Sala Marino Pecchia&nbsp; Descrizione&nbsp; CONVOCAZIONE DEL CONSIGLIO COMUNALE Si partecipa la S.V. [&hellip;]<\/p>\n","protected":false},"author":242,"featured_media":16130,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-16129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convocazione Consiglio comunale del 29.12.2025 - Campodimele<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/campodimele\/2025\/12\/24\/convocazione-consiglio-comunale-del-29-12-2025\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convocazione Consiglio comunale del 29.12.2025 - Campodimele\" \/>\n<meta property=\"og:description\" content=\"Convocazione del Consiglio Comunale in seduta ordinaria per il giorno 29 dicembre 2025, alle ore 16:00, presso la Sala Marino Pecchia&nbsp; Descrizione&nbsp; CONVOCAZIONE DEL CONSIGLIO COMUNALE Si partecipa la S.V. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/campodimele\/2025\/12\/24\/convocazione-consiglio-comunale-del-29-12-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Campodimele\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-24T13:16:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/12\/Convocazione-consiglio-comunale-e1715858474883.png\" \/>\n\t<meta property=\"og:image:width\" content=\"230\" \/>\n\t<meta property=\"og:image:height\" content=\"153\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"campodimele\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"campodimele\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/12\\\/24\\\/convocazione-consiglio-comunale-del-29-12-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/12\\\/24\\\/convocazione-consiglio-comunale-del-29-12-2025\\\/\"},\"author\":{\"name\":\"campodimele\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#\\\/schema\\\/person\\\/707b1b5905116ac44a5a52a8f829f0da\"},\"headline\":\"Convocazione Consiglio comunale del 29.12.2025\",\"datePublished\":\"2025-12-24T13:16:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/12\\\/24\\\/convocazione-consiglio-comunale-del-29-12-2025\\\/\"},\"wordCount\":391,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/12\\\/24\\\/convocazione-consiglio-comunale-del-29-12-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2025\\\/12\\\/Convocazione-consiglio-comunale-e1715858474883.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/12\\\/24\\\/convocazione-consiglio-comunale-del-29-12-2025\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/12\\\/24\\\/convocazione-consiglio-comunale-del-29-12-2025\\\/\",\"name\":\"Convocazione Consiglio comunale del 29.12.2025 - Campodimele\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/12\\\/24\\\/convocazione-consiglio-comunale-del-29-12-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/12\\\/24\\\/convocazione-consiglio-comunale-del-29-12-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2025\\\/12\\\/Convocazione-consiglio-comunale-e1715858474883.png\",\"datePublished\":\"2025-12-24T13:16:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#\\\/schema\\\/person\\\/707b1b5905116ac44a5a52a8f829f0da\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/12\\\/24\\\/convocazione-consiglio-comunale-del-29-12-2025\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/12\\\/24\\\/convocazione-consiglio-comunale-del-29-12-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/12\\\/24\\\/convocazione-consiglio-comunale-del-29-12-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2025\\\/12\\\/Convocazione-consiglio-comunale-e1715858474883.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2025\\\/12\\\/Convocazione-consiglio-comunale-e1715858474883.png\",\"width\":230,\"height\":153},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2025\\\/12\\\/24\\\/convocazione-consiglio-comunale-del-29-12-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convocazione Consiglio comunale del 29.12.2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/\",\"name\":\"Campodimele\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#\\\/schema\\\/person\\\/707b1b5905116ac44a5a52a8f829f0da\",\"name\":\"campodimele\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g\",\"caption\":\"campodimele\"},\"sameAs\":[\"http:\\\/\\\/www.comune.campodimele.lt.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/author\\\/campodimele\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convocazione Consiglio comunale del 29.12.2025 - Campodimele","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/campodimele\/2025\/12\/24\/convocazione-consiglio-comunale-del-29-12-2025\/","og_locale":"it_IT","og_type":"article","og_title":"Convocazione Consiglio comunale del 29.12.2025 - Campodimele","og_description":"Convocazione del Consiglio Comunale in seduta ordinaria per il giorno 29 dicembre 2025, alle ore 16:00, presso la Sala Marino Pecchia&nbsp; Descrizione&nbsp; CONVOCAZIONE DEL CONSIGLIO COMUNALE Si partecipa la S.V. [&hellip;]","og_url":"https:\/\/comunicacity.net\/campodimele\/2025\/12\/24\/convocazione-consiglio-comunale-del-29-12-2025\/","og_site_name":"Campodimele","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-12-24T13:16:34+00:00","og_image":[{"width":230,"height":153,"url":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/12\/Convocazione-consiglio-comunale-e1715858474883.png","type":"image\/png"}],"author":"campodimele","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"campodimele","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/campodimele\/2025\/12\/24\/convocazione-consiglio-comunale-del-29-12-2025\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/campodimele\/2025\/12\/24\/convocazione-consiglio-comunale-del-29-12-2025\/"},"author":{"name":"campodimele","@id":"https:\/\/comunicacity.net\/campodimele\/#\/schema\/person\/707b1b5905116ac44a5a52a8f829f0da"},"headline":"Convocazione Consiglio comunale del 29.12.2025","datePublished":"2025-12-24T13:16:34+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/campodimele\/2025\/12\/24\/convocazione-consiglio-comunale-del-29-12-2025\/"},"wordCount":391,"image":{"@id":"https:\/\/comunicacity.net\/campodimele\/2025\/12\/24\/convocazione-consiglio-comunale-del-29-12-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/12\/Convocazione-consiglio-comunale-e1715858474883.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/campodimele\/2025\/12\/24\/convocazione-consiglio-comunale-del-29-12-2025\/","url":"https:\/\/comunicacity.net\/campodimele\/2025\/12\/24\/convocazione-consiglio-comunale-del-29-12-2025\/","name":"Convocazione Consiglio comunale del 29.12.2025 - Campodimele","isPartOf":{"@id":"https:\/\/comunicacity.net\/campodimele\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/campodimele\/2025\/12\/24\/convocazione-consiglio-comunale-del-29-12-2025\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/campodimele\/2025\/12\/24\/convocazione-consiglio-comunale-del-29-12-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/12\/Convocazione-consiglio-comunale-e1715858474883.png","datePublished":"2025-12-24T13:16:34+00:00","author":{"@id":"https:\/\/comunicacity.net\/campodimele\/#\/schema\/person\/707b1b5905116ac44a5a52a8f829f0da"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/campodimele\/2025\/12\/24\/convocazione-consiglio-comunale-del-29-12-2025\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/campodimele\/2025\/12\/24\/convocazione-consiglio-comunale-del-29-12-2025\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/campodimele\/2025\/12\/24\/convocazione-consiglio-comunale-del-29-12-2025\/#primaryimage","url":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/12\/Convocazione-consiglio-comunale-e1715858474883.png","contentUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2025\/12\/Convocazione-consiglio-comunale-e1715858474883.png","width":230,"height":153},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/campodimele\/2025\/12\/24\/convocazione-consiglio-comunale-del-29-12-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/campodimele\/"},{"@type":"ListItem","position":2,"name":"Convocazione Consiglio comunale del 29.12.2025"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/campodimele\/#website","url":"https:\/\/comunicacity.net\/campodimele\/","name":"Campodimele","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/campodimele\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/campodimele\/#\/schema\/person\/707b1b5905116ac44a5a52a8f829f0da","name":"campodimele","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g","caption":"campodimele"},"sameAs":["http:\/\/www.comune.campodimele.lt.it"],"url":"https:\/\/comunicacity.net\/campodimele\/author\/campodimele\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00003088"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts\/16129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/users\/242"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/comments?post=16129"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts\/16129\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/media\/16130"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/media?parent=16129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/categories?post=16129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/tags?post=16129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}