{"id":16170,"date":"2026-04-21T11:58:44","date_gmt":"2026-04-21T09:58:44","guid":{"rendered":"https:\/\/comunicacity.net\/campodimele\/?p=16170"},"modified":"2026-04-21T12:00:55","modified_gmt":"2026-04-21T10:00:55","slug":"avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/campodimele\/2026\/04\/21\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\/","title":{"rendered":"AVVISO PUBBLICO &#8211; INTERVENTI A SOSTEGNO DELLE FAMIGLIE DEI MINORI AUTISTICI TRA IL DODICESIMO E IL DICIASSETTESIMO ANNO DI ET\u00c0."},"content":{"rendered":"<p><em>Aperti i termini per l&#8217;accesso agli interventi a sostegno delle famiglie dei minori autistici tra il dodicesimo e il diciassettesimo anno di et\u00e0.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Il<strong>\u00a0Distretto Socio Sanitario LT4<\/strong>\u00a0ha pubblicato l&#8217;avviso pubblico per l&#8217;accesso agli\u00a0<strong>interventi a sostegno delle famiglie dei minori autistici tra il dodicesimo e il diciassettesimo anno di et\u00e0<\/strong>.<\/p>\n<p>Il\u00a0<strong>Distretto Socio Sanitario LT4<\/strong>\u00a0&#8211; che comprende i Comuni di Campodimele, Fondi, Lenola, Monte San Biagio, San Felice Circeo, Sperlonga e Terracina &#8211; utilizza una quota parte delle risorse del fondo per l&#8217;inclusione delle persone con disabilit\u00e0, assegnate dalla Regione Lazio, per realizzare interventi a sostegno delle famiglie dei minori autistici tra il dodicesimo e il diciassettesimo anno di et\u00e0.<\/p>\n<p>I\u00a0<strong>destinatari<\/strong>\u00a0degli interventi previsti sono le famiglie con minori tra il dodicesimo e il diciassettesimo anno di et\u00e0 (dal 12\u00b0 anno e 1 giorno fino ai 17 anni e 364 giorni compiuti, nel periodo dal 1\u00b0 giugno 2025 al 31 maggio 2026), con diagnosi di disturbo dello spettro autistico, residenti nei Comuni del Distretto Socio Sanitario LT4.<\/p>\n<p>La domanda per l&#8217;ammissione alla misura di sostegno deve essere presentata dal genitore (o dal tutore minorile, eventualmente nominato) del minore autistico,\u00a0<strong>esclusivamente per via telematica<\/strong>\u00a0attraverso la piattaforma\u00a0<strong>Rete del Sociale<\/strong>\u00a0del Distretto Socio Sanitario LT4, raggiungibile al seguente link:\u00a0<a href=\"https:\/\/fondi.retedelsociale.it\/\" target=\"_blank\" rel=\"noopener\">https:\/\/fondi.retedelsociale.it<\/a>, <strong>entro e non oltre il 30 giugno 2026<\/strong>.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_16182\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2026\/04\/61676584464avviso_pubblico_spettro_autistico_1217_anni_16042026.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2026\/04\/61676584464avviso_pubblico_spettro_autistico_1217_anni_16042026.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>avviso_pubblico_spettro_autistico_1217_anni_16042026<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aperti i termini per l&#8217;accesso agli interventi a sostegno delle famiglie dei minori autistici tra il dodicesimo e il diciassettesimo anno di et\u00e0.&nbsp; Descrizione&nbsp; Il\u00a0Distretto Socio Sanitario LT4\u00a0ha pubblicato l&#8217;avviso [&hellip;]<\/p>\n","protected":false},"author":242,"featured_media":16181,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-16170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO PUBBLICO - INTERVENTI A SOSTEGNO DELLE FAMIGLIE DEI MINORI AUTISTICI TRA IL DODICESIMO E IL DICIASSETTESIMO ANNO DI ET\u00c0. - Campodimele<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/campodimele\/2026\/04\/21\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO PUBBLICO - INTERVENTI A SOSTEGNO DELLE FAMIGLIE DEI MINORI AUTISTICI TRA IL DODICESIMO E IL DICIASSETTESIMO ANNO DI ET\u00c0. - Campodimele\" \/>\n<meta property=\"og:description\" content=\"Aperti i termini per l&#8217;accesso agli interventi a sostegno delle famiglie dei minori autistici tra il dodicesimo e il diciassettesimo anno di et\u00e0.&nbsp; Descrizione&nbsp; Il\u00a0Distretto Socio Sanitario LT4\u00a0ha pubblicato l&#8217;avviso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/campodimele\/2026\/04\/21\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\/\" \/>\n<meta property=\"og:site_name\" content=\"Campodimele\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-21T09:58:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-21T10:00:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2026\/04\/1893560588img_8671-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"689\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"campodimele\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"campodimele\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2026\\\/04\\\/21\\\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2026\\\/04\\\/21\\\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\\\/\"},\"author\":{\"name\":\"campodimele\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#\\\/schema\\\/person\\\/707b1b5905116ac44a5a52a8f829f0da\"},\"headline\":\"AVVISO PUBBLICO &#8211; INTERVENTI A SOSTEGNO DELLE FAMIGLIE DEI MINORI AUTISTICI TRA IL DODICESIMO E IL DICIASSETTESIMO ANNO DI ET\u00c0.\",\"datePublished\":\"2026-04-21T09:58:44+00:00\",\"dateModified\":\"2026-04-21T10:00:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2026\\\/04\\\/21\\\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\\\/\"},\"wordCount\":237,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2026\\\/04\\\/21\\\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2026\\\/04\\\/1893560588img_8671-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2026\\\/04\\\/21\\\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2026\\\/04\\\/21\\\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\\\/\",\"name\":\"AVVISO PUBBLICO - INTERVENTI A SOSTEGNO DELLE FAMIGLIE DEI MINORI AUTISTICI TRA IL DODICESIMO E IL DICIASSETTESIMO ANNO DI ET\u00c0. - Campodimele\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2026\\\/04\\\/21\\\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2026\\\/04\\\/21\\\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2026\\\/04\\\/1893560588img_8671-1.jpg\",\"datePublished\":\"2026-04-21T09:58:44+00:00\",\"dateModified\":\"2026-04-21T10:00:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#\\\/schema\\\/person\\\/707b1b5905116ac44a5a52a8f829f0da\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2026\\\/04\\\/21\\\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2026\\\/04\\\/21\\\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2026\\\/04\\\/21\\\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2026\\\/04\\\/1893560588img_8671-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2026\\\/04\\\/1893560588img_8671-1.jpg\",\"width\":1080,\"height\":689},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/2026\\\/04\\\/21\\\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO PUBBLICO &#8211; INTERVENTI A SOSTEGNO DELLE FAMIGLIE DEI MINORI AUTISTICI TRA IL DODICESIMO E IL DICIASSETTESIMO ANNO DI ET\u00c0.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/\",\"name\":\"Campodimele\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#\\\/schema\\\/person\\\/707b1b5905116ac44a5a52a8f829f0da\",\"name\":\"campodimele\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g\",\"caption\":\"campodimele\"},\"sameAs\":[\"http:\\\/\\\/www.comune.campodimele.lt.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/author\\\/campodimele\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO PUBBLICO - INTERVENTI A SOSTEGNO DELLE FAMIGLIE DEI MINORI AUTISTICI TRA IL DODICESIMO E IL DICIASSETTESIMO ANNO DI ET\u00c0. - Campodimele","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/campodimele\/2026\/04\/21\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO PUBBLICO - INTERVENTI A SOSTEGNO DELLE FAMIGLIE DEI MINORI AUTISTICI TRA IL DODICESIMO E IL DICIASSETTESIMO ANNO DI ET\u00c0. - Campodimele","og_description":"Aperti i termini per l&#8217;accesso agli interventi a sostegno delle famiglie dei minori autistici tra il dodicesimo e il diciassettesimo anno di et\u00e0.&nbsp; Descrizione&nbsp; Il\u00a0Distretto Socio Sanitario LT4\u00a0ha pubblicato l&#8217;avviso [&hellip;]","og_url":"https:\/\/comunicacity.net\/campodimele\/2026\/04\/21\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\/","og_site_name":"Campodimele","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-04-21T09:58:44+00:00","article_modified_time":"2026-04-21T10:00:55+00:00","og_image":[{"width":1080,"height":689,"url":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2026\/04\/1893560588img_8671-1.jpg","type":"image\/jpeg"}],"author":"campodimele","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"campodimele","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/campodimele\/2026\/04\/21\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/campodimele\/2026\/04\/21\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\/"},"author":{"name":"campodimele","@id":"https:\/\/comunicacity.net\/campodimele\/#\/schema\/person\/707b1b5905116ac44a5a52a8f829f0da"},"headline":"AVVISO PUBBLICO &#8211; INTERVENTI A SOSTEGNO DELLE FAMIGLIE DEI MINORI AUTISTICI TRA IL DODICESIMO E IL DICIASSETTESIMO ANNO DI ET\u00c0.","datePublished":"2026-04-21T09:58:44+00:00","dateModified":"2026-04-21T10:00:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/campodimele\/2026\/04\/21\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\/"},"wordCount":237,"image":{"@id":"https:\/\/comunicacity.net\/campodimele\/2026\/04\/21\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2026\/04\/1893560588img_8671-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/campodimele\/2026\/04\/21\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\/","url":"https:\/\/comunicacity.net\/campodimele\/2026\/04\/21\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\/","name":"AVVISO PUBBLICO - INTERVENTI A SOSTEGNO DELLE FAMIGLIE DEI MINORI AUTISTICI TRA IL DODICESIMO E IL DICIASSETTESIMO ANNO DI ET\u00c0. - Campodimele","isPartOf":{"@id":"https:\/\/comunicacity.net\/campodimele\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/campodimele\/2026\/04\/21\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/campodimele\/2026\/04\/21\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2026\/04\/1893560588img_8671-1.jpg","datePublished":"2026-04-21T09:58:44+00:00","dateModified":"2026-04-21T10:00:55+00:00","author":{"@id":"https:\/\/comunicacity.net\/campodimele\/#\/schema\/person\/707b1b5905116ac44a5a52a8f829f0da"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/campodimele\/2026\/04\/21\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/campodimele\/2026\/04\/21\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/campodimele\/2026\/04\/21\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\/#primaryimage","url":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2026\/04\/1893560588img_8671-1.jpg","contentUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2026\/04\/1893560588img_8671-1.jpg","width":1080,"height":689},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/campodimele\/2026\/04\/21\/avviso-pubblico-interventi-a-sostegno-delle-famiglie-dei-minori-autistici-tra-il-dodicesimo-e-il-diciassettesimo-anno-di-eta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/campodimele\/"},{"@type":"ListItem","position":2,"name":"AVVISO PUBBLICO &#8211; INTERVENTI A SOSTEGNO DELLE FAMIGLIE DEI MINORI AUTISTICI TRA IL DODICESIMO E IL DICIASSETTESIMO ANNO DI ET\u00c0."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/campodimele\/#website","url":"https:\/\/comunicacity.net\/campodimele\/","name":"Campodimele","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/campodimele\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/campodimele\/#\/schema\/person\/707b1b5905116ac44a5a52a8f829f0da","name":"campodimele","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9fcca03445f192b35763d0f79f388f29c39208f271ff091495c26b0c1ff1b825?s=96&d=mm&r=g","caption":"campodimele"},"sameAs":["http:\/\/www.comune.campodimele.lt.it"],"url":"https:\/\/comunicacity.net\/campodimele\/author\/campodimele\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00003116"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts\/16170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/users\/242"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/comments?post=16170"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts\/16170\/revisions"}],"predecessor-version":[{"id":16180,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/posts\/16170\/revisions\/16180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/media\/16181"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/media?parent=16170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/categories?post=16170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/tags?post=16170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}