{"id":15,"date":"2017-08-11T14:20:27","date_gmt":"2017-08-11T12:20:27","guid":{"rendered":"https:\/\/comunicacity.net\/campodimele\/?post_type=turismo&#038;p=15"},"modified":"2017-08-11T14:29:43","modified_gmt":"2017-08-11T12:29:43","slug":"il-turismo-ambientale-e-naturalistico","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-ambientale-e-naturalistico\/","title":{"rendered":"Il Turismo ambientale e naturalistico"},"content":{"rendered":"<p>Arte e storia ma anche paesaggi meravigliosi e verde incontaminato fanno di Campodimele un luogo adatto anche agli amanti dello sport e della natura.<\/p>\n<p class=\"text_verdana_10px_regolare_giustificato_marginato_black\">La rocca su cui sorge \u00e8 letteralmente circondata da prati verdi e alberi di olivo, non a caso \u00e8 stato considerato uno dei \u201cBorghi pi\u00f9 belli d&#8217;Italia\u201d ma anche e soprattutto il pi\u00f9 longevo, grazie alle sue caratteristiche naturali, gastronomiche e climatiche. Nel borgo ha sede il Parco Naturale dei Monti Aurunci che ha realizzato per gli amanti del trekking e delle passeggiate nella natura sentieri su panorami di straordinario di pregio.<\/p>\n<p class=\"text_verdana_10px_regolare_giustificato_marginato_black\">Il Parco degli Aurunci e le faggete, sono infatti mete predilette per lunghe passeggiate di quei turisti in cerca di frescura e di quiete. Si pu\u00f2 poi sempre scendere gi\u00f9 al vecchio Mulino del &#8220;malo tempo&#8221; e starsene nel verde del giardino, usufruendo delle strutture pic nic con bracieri in pietra e tavoli in legno costruiti proprio per ospitare cittadini e turisti che salgono dal mare per trovare qui un po&#8217; di frescura.<\/p>\n<p class=\"text_verdana_10px_regolare_giustificato_marginato_black\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-18\" src=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2017\/08\/IMG714202.jpg\" alt=\"\" width=\"351\" height=\"276\" srcset=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2017\/08\/IMG714202.jpg 351w, https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2017\/08\/IMG714202-300x236.jpg 300w\" sizes=\"auto, (max-width: 351px) 100vw, 351px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arte e storia ma anche paesaggi meravigliosi e verde incontaminato fanno di Campodimele un luogo adatto anche agli amanti dello sport e della natura. La rocca su cui sorge \u00e8 [&hellip;]<\/p>\n","protected":false},"featured_media":17,"parent":0,"menu_order":30,"template":"","meta":[],"plugin_turismo":[],"class_list":["post-15","turismo","type-turismo","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Turismo ambientale e naturalistico - Campodimele<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-ambientale-e-naturalistico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Turismo ambientale e naturalistico - Campodimele\" \/>\n<meta property=\"og:description\" content=\"Arte e storia ma anche paesaggi meravigliosi e verde incontaminato fanno di Campodimele un luogo adatto anche agli amanti dello sport e della natura. La rocca su cui sorge \u00e8 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-ambientale-e-naturalistico\/\" \/>\n<meta property=\"og:site_name\" content=\"Campodimele\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2017-08-11T12:29:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2017\/08\/IMG434686.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"399\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/turismo\\\/il-turismo-ambientale-e-naturalistico\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/turismo\\\/il-turismo-ambientale-e-naturalistico\\\/\",\"name\":\"Il Turismo ambientale e naturalistico - Campodimele\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/turismo\\\/il-turismo-ambientale-e-naturalistico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/turismo\\\/il-turismo-ambientale-e-naturalistico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2017\\\/08\\\/IMG434686.jpg\",\"datePublished\":\"2017-08-11T12:20:27+00:00\",\"dateModified\":\"2017-08-11T12:29:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/turismo\\\/il-turismo-ambientale-e-naturalistico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/turismo\\\/il-turismo-ambientale-e-naturalistico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/turismo\\\/il-turismo-ambientale-e-naturalistico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2017\\\/08\\\/IMG434686.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2017\\\/08\\\/IMG434686.jpg\",\"width\":399,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/turismo\\\/il-turismo-ambientale-e-naturalistico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Turismo ambientale e naturalistico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/\",\"name\":\"Campodimele\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Turismo ambientale e naturalistico - Campodimele","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-ambientale-e-naturalistico\/","og_locale":"it_IT","og_type":"article","og_title":"Il Turismo ambientale e naturalistico - Campodimele","og_description":"Arte e storia ma anche paesaggi meravigliosi e verde incontaminato fanno di Campodimele un luogo adatto anche agli amanti dello sport e della natura. La rocca su cui sorge \u00e8 [&hellip;]","og_url":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-ambientale-e-naturalistico\/","og_site_name":"Campodimele","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2017-08-11T12:29:43+00:00","og_image":[{"width":399,"height":300,"url":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2017\/08\/IMG434686.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-ambientale-e-naturalistico\/","url":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-ambientale-e-naturalistico\/","name":"Il Turismo ambientale e naturalistico - Campodimele","isPartOf":{"@id":"https:\/\/comunicacity.net\/campodimele\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-ambientale-e-naturalistico\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-ambientale-e-naturalistico\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2017\/08\/IMG434686.jpg","datePublished":"2017-08-11T12:20:27+00:00","dateModified":"2017-08-11T12:29:43+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-ambientale-e-naturalistico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-ambientale-e-naturalistico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-ambientale-e-naturalistico\/#primaryimage","url":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2017\/08\/IMG434686.jpg","contentUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2017\/08\/IMG434686.jpg","width":399,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-ambientale-e-naturalistico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/campodimele\/"},{"@type":"ListItem","position":2,"name":"Il Turismo ambientale e naturalistico"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/campodimele\/#website","url":"https:\/\/comunicacity.net\/campodimele\/","name":"Campodimele","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/campodimele\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/turismo\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/types\/turismo"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/media\/17"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/media?parent=15"}],"wp:term":[{"taxonomy":"plugin_turismo","embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/plugin_turismo?post=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}