{"id":19,"date":"2017-08-11T14:21:50","date_gmt":"2017-08-11T12:21:50","guid":{"rendered":"https:\/\/comunicacity.net\/campodimele\/?post_type=turismo&#038;p=19"},"modified":"2017-08-11T14:29:26","modified_gmt":"2017-08-11T12:29:26","slug":"il-turismo-enogastronomico","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-enogastronomico\/","title":{"rendered":"Il Turismo enogastronomico"},"content":{"rendered":"<p class=\"text_verdana_10px_regolare_giustificato_marginato_black\">Campodimele \u00e8 anche luogo adatto per gli amanti dei buoni sapori e della natura grazie alle sue eccellenze enogastronomiche. Le sue campagne forniscono per gli amanti della tavola i frutti genuini della terra che sono alla base di pasti genuini da gustare nella quiete della valle. La famosa zuppa di cicerchie \u00e8 d&#8217;obbligo! \u00a0Non si pu\u00f2 andarsene senza averla assaggiata e senza aver comprato una piccola confezione da portare a casa o agli amici. La coltivazione della leguminosa di Campodimele per esempio vanta antiche tradizioni ed \u00e8 riconosciuta D.O.P.<\/p>\n<p class=\"text_verdana_10px_regolare_giustificato_marginato_black\">Per gli amanti della buona cucina non solo la zuppa di cicerchie ma anche la &#8220;laina&#8221;, pasta fatta in casa con sola farina e acqua, senza aggiunta di uova e condita con le cicerchie cotte con sugo di pomodoro, cipolla, aglio, brodo, e servita con ricotta essiccata di capra o le &#8220;ciammotte&#8221; che sono delle chiocciole molto gustose, che a Campodimele vengono cucinate con la menta e altre erbe aromatiche.<\/p>\n<p class=\"text_verdana_10px_regolare_giustificato_marginato_black\" style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-20\" src=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2017\/08\/IMG642821.jpg\" alt=\"\" width=\"444\" height=\"333\" srcset=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2017\/08\/IMG642821.jpg 444w, https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2017\/08\/IMG642821-300x225.jpg 300w\" sizes=\"auto, (max-width: 444px) 100vw, 444px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Campodimele \u00e8 anche luogo adatto per gli amanti dei buoni sapori e della natura grazie alle sue eccellenze enogastronomiche. Le sue campagne forniscono per gli amanti della tavola i frutti [&hellip;]<\/p>\n","protected":false},"featured_media":21,"parent":0,"menu_order":50,"template":"","meta":[],"plugin_turismo":[],"class_list":["post-19","turismo","type-turismo","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Turismo enogastronomico - Campodimele<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-enogastronomico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Turismo enogastronomico - Campodimele\" \/>\n<meta property=\"og:description\" content=\"Campodimele \u00e8 anche luogo adatto per gli amanti dei buoni sapori e della natura grazie alle sue eccellenze enogastronomiche. Le sue campagne forniscono per gli amanti della tavola i frutti [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-enogastronomico\/\" \/>\n<meta property=\"og:site_name\" content=\"Campodimele\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2017-08-11T12:29:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2017\/08\/IMG56948.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/turismo\\\/il-turismo-enogastronomico\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/turismo\\\/il-turismo-enogastronomico\\\/\",\"name\":\"Il Turismo enogastronomico - Campodimele\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/turismo\\\/il-turismo-enogastronomico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/turismo\\\/il-turismo-enogastronomico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2017\\\/08\\\/IMG56948.jpg\",\"datePublished\":\"2017-08-11T12:21:50+00:00\",\"dateModified\":\"2017-08-11T12:29:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/turismo\\\/il-turismo-enogastronomico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/turismo\\\/il-turismo-enogastronomico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/turismo\\\/il-turismo-enogastronomico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2017\\\/08\\\/IMG56948.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/wp-content\\\/uploads\\\/sites\\\/102\\\/2017\\\/08\\\/IMG56948.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/turismo\\\/il-turismo-enogastronomico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Turismo enogastronomico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/\",\"name\":\"Campodimele\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/campodimele\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Turismo enogastronomico - Campodimele","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-enogastronomico\/","og_locale":"it_IT","og_type":"article","og_title":"Il Turismo enogastronomico - Campodimele","og_description":"Campodimele \u00e8 anche luogo adatto per gli amanti dei buoni sapori e della natura grazie alle sue eccellenze enogastronomiche. Le sue campagne forniscono per gli amanti della tavola i frutti [&hellip;]","og_url":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-enogastronomico\/","og_site_name":"Campodimele","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2017-08-11T12:29:26+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2017\/08\/IMG56948.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-enogastronomico\/","url":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-enogastronomico\/","name":"Il Turismo enogastronomico - Campodimele","isPartOf":{"@id":"https:\/\/comunicacity.net\/campodimele\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-enogastronomico\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-enogastronomico\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2017\/08\/IMG56948.jpg","datePublished":"2017-08-11T12:21:50+00:00","dateModified":"2017-08-11T12:29:26+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-enogastronomico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-enogastronomico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-enogastronomico\/#primaryimage","url":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2017\/08\/IMG56948.jpg","contentUrl":"https:\/\/comunicacity.net\/campodimele\/wp-content\/uploads\/sites\/102\/2017\/08\/IMG56948.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/campodimele\/turismo\/il-turismo-enogastronomico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/campodimele\/"},{"@type":"ListItem","position":2,"name":"Il Turismo enogastronomico"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/campodimele\/#website","url":"https:\/\/comunicacity.net\/campodimele\/","name":"Campodimele","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/campodimele\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/turismo\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/types\/turismo"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/media\/21"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/media?parent=19"}],"wp:term":[{"taxonomy":"plugin_turismo","embeddable":true,"href":"https:\/\/comunicacity.net\/campodimele\/wp-json\/wp\/v2\/plugin_turismo?post=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}