{"id":1054,"date":"2019-05-02T08:59:44","date_gmt":"2019-05-02T06:59:44","guid":{"rendered":"https:\/\/comunicacity.net\/cancello-ed-arnone\/?p=1054"},"modified":"2023-02-02T15:41:36","modified_gmt":"2023-02-02T14:41:36","slug":"martedi-21-maggio-il-corso-convegno-autismo-e-aba","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/05\/02\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\/","title":{"rendered":"Marted\u00ec 21 Maggio il Corso-Convegno \u201cAutismo e ABA\u201d"},"content":{"rendered":"<p class=\"p3\"><span class=\"s2\">L\u2019Amministrazione Comunale di concerto con il dott. Elpidio Cecere, psicologo e formatore esperto dei disturbi del neuro sviluppo, la disabilit\u00e0, l\u2019inclusione dei minori non accompagnati, organizza il corso-convegno \u201cAutismo e ABA\u201d che si terr\u00e0 Marted\u00ec 21 Maggio 2019, dalle ore 17:30 alle ore 19:00, presso l\u2019Aula Magna dell\u2019Istituto Comprensivo \u201cUgo Foscolo\u201d di Via Settembrini.<\/span><\/p>\n<p class=\"p3\"><span class=\"s2\">Chiunque fosse interessato a partecipare, pu\u00f2 richiedere il modulo di iscrizione presso l\u2019Ufficio Servizi Sociali del Comune nei giorni Marted\u00ec &#8211; Gioved\u00ec &#8211; Venerd\u00ec. <\/span><\/p>\n<p class=\"p3\"><span class=\"s2\">Il modulo di iscrizione, debitamente compilato e corredato dal documento di riconoscimento, dovr\u00e0 essere consegnato all\u2019Ufficio Protocollo dell\u2019Ente oppure trasmesso a mezzo pec all\u2019indirizzo protocollo.cancelloarnone@asmepec.it entro e non oltre le ore 14:00 del giorno 10 Maggio 2019.<\/span><\/p>\n<p class=\"p3\"><span class=\"s2\">Il corso-convegno \u00e8 gratuito e al termine di esso sar\u00e0 rilasciato un attestato di partecipazione.<\/span><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Amministrazione Comunale di concerto con il dott. Elpidio Cecere, psicologo e formatore esperto dei disturbi del neuro sviluppo, la disabilit\u00e0, l\u2019inclusione dei minori non accompagnati, organizza il corso-convegno \u201cAutismo e [&hellip;]<\/p>\n","protected":false},"author":398,"featured_media":1055,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marted\u00ec 21 Maggio il Corso-Convegno \u201cAutismo e ABA\u201d - Cancello ed Arnone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/05\/02\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marted\u00ec 21 Maggio il Corso-Convegno \u201cAutismo e ABA\u201d - Cancello ed Arnone\" \/>\n<meta property=\"og:description\" content=\"L\u2019Amministrazione Comunale di concerto con il dott. Elpidio Cecere, psicologo e formatore esperto dei disturbi del neuro sviluppo, la disabilit\u00e0, l\u2019inclusione dei minori non accompagnati, organizza il corso-convegno \u201cAutismo e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/05\/02\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\/\" \/>\n<meta property=\"og:site_name\" content=\"Cancello ed Arnone\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-02T06:59:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-02T14:41:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/05\/F8DCF9E3-2046-45BC-9471-ABCEBBDD94B7.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin_E\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin_E\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/05\\\/02\\\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/05\\\/02\\\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\\\/\"},\"author\":{\"name\":\"Admin_E\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#\\\/schema\\\/person\\\/eaea9f1aebcbd61eb9878e6232bd2a03\"},\"headline\":\"Marted\u00ec 21 Maggio il Corso-Convegno \u201cAutismo e ABA\u201d\",\"datePublished\":\"2019-05-02T06:59:44+00:00\",\"dateModified\":\"2023-02-02T14:41:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/05\\\/02\\\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\\\/\"},\"wordCount\":140,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/05\\\/02\\\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2019\\\/05\\\/F8DCF9E3-2046-45BC-9471-ABCEBBDD94B7.jpeg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/05\\\/02\\\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/05\\\/02\\\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\\\/\",\"name\":\"Marted\u00ec 21 Maggio il Corso-Convegno \u201cAutismo e ABA\u201d - Cancello ed Arnone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/05\\\/02\\\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/05\\\/02\\\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2019\\\/05\\\/F8DCF9E3-2046-45BC-9471-ABCEBBDD94B7.jpeg\",\"datePublished\":\"2019-05-02T06:59:44+00:00\",\"dateModified\":\"2023-02-02T14:41:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#\\\/schema\\\/person\\\/eaea9f1aebcbd61eb9878e6232bd2a03\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/05\\\/02\\\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/05\\\/02\\\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/05\\\/02\\\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2019\\\/05\\\/F8DCF9E3-2046-45BC-9471-ABCEBBDD94B7.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2019\\\/05\\\/F8DCF9E3-2046-45BC-9471-ABCEBBDD94B7.jpeg\",\"width\":960,\"height\":676},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/05\\\/02\\\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marted\u00ec 21 Maggio il Corso-Convegno \u201cAutismo e ABA\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/\",\"name\":\"Cancello ed Arnone\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#\\\/schema\\\/person\\\/eaea9f1aebcbd61eb9878e6232bd2a03\",\"name\":\"Admin_E\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g\",\"caption\":\"Admin_E\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/author\\\/oollppcancelloarnone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marted\u00ec 21 Maggio il Corso-Convegno \u201cAutismo e ABA\u201d - Cancello ed Arnone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/05\/02\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\/","og_locale":"it_IT","og_type":"article","og_title":"Marted\u00ec 21 Maggio il Corso-Convegno \u201cAutismo e ABA\u201d - Cancello ed Arnone","og_description":"L\u2019Amministrazione Comunale di concerto con il dott. Elpidio Cecere, psicologo e formatore esperto dei disturbi del neuro sviluppo, la disabilit\u00e0, l\u2019inclusione dei minori non accompagnati, organizza il corso-convegno \u201cAutismo e [&hellip;]","og_url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/05\/02\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\/","og_site_name":"Cancello ed Arnone","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-05-02T06:59:44+00:00","article_modified_time":"2023-02-02T14:41:36+00:00","og_image":[{"width":960,"height":676,"url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/05\/F8DCF9E3-2046-45BC-9471-ABCEBBDD94B7.jpeg","type":"image\/jpeg"}],"author":"Admin_E","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Admin_E","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/05\/02\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/05\/02\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\/"},"author":{"name":"Admin_E","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#\/schema\/person\/eaea9f1aebcbd61eb9878e6232bd2a03"},"headline":"Marted\u00ec 21 Maggio il Corso-Convegno \u201cAutismo e ABA\u201d","datePublished":"2019-05-02T06:59:44+00:00","dateModified":"2023-02-02T14:41:36+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/05\/02\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\/"},"wordCount":140,"image":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/05\/02\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/05\/F8DCF9E3-2046-45BC-9471-ABCEBBDD94B7.jpeg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/05\/02\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\/","url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/05\/02\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\/","name":"Marted\u00ec 21 Maggio il Corso-Convegno \u201cAutismo e ABA\u201d - Cancello ed Arnone","isPartOf":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/05\/02\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/05\/02\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/05\/F8DCF9E3-2046-45BC-9471-ABCEBBDD94B7.jpeg","datePublished":"2019-05-02T06:59:44+00:00","dateModified":"2023-02-02T14:41:36+00:00","author":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#\/schema\/person\/eaea9f1aebcbd61eb9878e6232bd2a03"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/05\/02\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/05\/02\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/05\/02\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\/#primaryimage","url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/05\/F8DCF9E3-2046-45BC-9471-ABCEBBDD94B7.jpeg","contentUrl":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/05\/F8DCF9E3-2046-45BC-9471-ABCEBBDD94B7.jpeg","width":960,"height":676},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/05\/02\/martedi-21-maggio-il-corso-convegno-autismo-e-aba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/cancello-ed-arnone\/"},{"@type":"ListItem","position":2,"name":"Marted\u00ec 21 Maggio il Corso-Convegno \u201cAutismo e ABA\u201d"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#website","url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/","name":"Cancello ed Arnone","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/cancello-ed-arnone\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#\/schema\/person\/eaea9f1aebcbd61eb9878e6232bd2a03","name":"Admin_E","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g","caption":"Admin_E"},"url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/author\/oollppcancelloarnone\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts\/1054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/users\/398"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/comments?post=1054"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts\/1054\/revisions"}],"predecessor-version":[{"id":1056,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts\/1054\/revisions\/1056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/media\/1055"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/media?parent=1054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/categories?post=1054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/tags?post=1054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}