{"id":1118,"date":"2019-07-13T11:04:45","date_gmt":"2019-07-13T09:04:45","guid":{"rendered":"https:\/\/comunicacity.net\/cancello-ed-arnone\/?p=1118"},"modified":"2023-02-02T15:41:30","modified_gmt":"2023-02-02T14:41:30","slug":"grande-entusiasmo-per-la-pedalata-ecologica","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/07\/13\/grande-entusiasmo-per-la-pedalata-ecologica\/","title":{"rendered":"Grande entusiasmo per la pedalata ecologica."},"content":{"rendered":"<p>Grande entusiasmo per la pedalata ecologica. La manifestazione ha visto la partecipazione di \u201cciclisti\u201d di tutte le et\u00e0, per la maggior parte bambini. Il gruppo dei partecipanti, con in testa l\u2019assessore all\u2019ambiente Gaetano Ambrosca, ha attraversato, scortato dal servizio dei Vigili Urbani e del Gruppo Comunale di Protezione Civile, varie strade del paese.<br \/>\nAlla fine del percorso, i partecipanti hanno trovato ad accoglierli in Villa Comunale il \u201cTeknoBus\u201d, un bus di linea completamente ristrutturato, dotato di tecnologie di produzione energetica atte a rispettare l\u2019ambiente. Una \u201clezione\u201d di educazione ambientale sul corretto svolgimento della raccolta differenziata. Un modo creativo per coinvolgere direttamente i pi\u00f9 giovani e per sensibilizzare le famiglie, per esporre alla cittadinanza l\u2019importanza del riciclo e di come i materiali possono godere di una nuova vita grazie all\u2019impegno di tutti. Al termine della visita, tutti i bambini hanno ricevuto un simpatico gadget.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1119\" src=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/3F48578A-BBAD-4C90-8DCA-13F9645D0D2E-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/3F48578A-BBAD-4C90-8DCA-13F9645D0D2E-300x225.jpeg 300w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/3F48578A-BBAD-4C90-8DCA-13F9645D0D2E-768x576.jpeg 768w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/3F48578A-BBAD-4C90-8DCA-13F9645D0D2E-1024x768.jpeg 1024w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/3F48578A-BBAD-4C90-8DCA-13F9645D0D2E-680x510.jpeg 680w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1120\" src=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/9A285767-B820-4A04-A372-62708D19B486-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/9A285767-B820-4A04-A372-62708D19B486-300x225.jpeg 300w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/9A285767-B820-4A04-A372-62708D19B486-768x576.jpeg 768w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/9A285767-B820-4A04-A372-62708D19B486-1024x768.jpeg 1024w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/9A285767-B820-4A04-A372-62708D19B486-680x510.jpeg 680w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1121\" src=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/D7E50AA4-4DAC-467D-A75D-3E26B4747079-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/D7E50AA4-4DAC-467D-A75D-3E26B4747079-300x225.jpeg 300w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/D7E50AA4-4DAC-467D-A75D-3E26B4747079-768x577.jpeg 768w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/D7E50AA4-4DAC-467D-A75D-3E26B4747079-1024x769.jpeg 1024w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/D7E50AA4-4DAC-467D-A75D-3E26B4747079-680x511.jpeg 680w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1123\" src=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/827D0D05-D820-4A82-8B7A-9062EF46F677-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/827D0D05-D820-4A82-8B7A-9062EF46F677-300x225.jpeg 300w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/827D0D05-D820-4A82-8B7A-9062EF46F677-768x577.jpeg 768w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/827D0D05-D820-4A82-8B7A-9062EF46F677-1024x769.jpeg 1024w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/827D0D05-D820-4A82-8B7A-9062EF46F677-680x511.jpeg 680w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1124\" src=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/4D9E6128-6EB7-493E-AF2C-86174D53845E-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/4D9E6128-6EB7-493E-AF2C-86174D53845E-300x225.jpeg 300w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/4D9E6128-6EB7-493E-AF2C-86174D53845E-768x577.jpeg 768w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/4D9E6128-6EB7-493E-AF2C-86174D53845E-1024x769.jpeg 1024w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/4D9E6128-6EB7-493E-AF2C-86174D53845E-680x511.jpeg 680w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1125\" src=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/9E64F841-9B36-4AD9-8425-F0C04B00EE41-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/9E64F841-9B36-4AD9-8425-F0C04B00EE41-300x225.jpeg 300w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/9E64F841-9B36-4AD9-8425-F0C04B00EE41-768x576.jpeg 768w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/9E64F841-9B36-4AD9-8425-F0C04B00EE41.jpeg 1024w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/9E64F841-9B36-4AD9-8425-F0C04B00EE41-680x510.jpeg 680w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1126 aligncenter\" src=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/E1B77DDE-41F9-4EDB-8D2B-ECC41B8F8EAD-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/E1B77DDE-41F9-4EDB-8D2B-ECC41B8F8EAD-225x300.jpeg 225w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/E1B77DDE-41F9-4EDB-8D2B-ECC41B8F8EAD-680x907.jpeg 680w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/E1B77DDE-41F9-4EDB-8D2B-ECC41B8F8EAD.jpeg 718w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1127\" src=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/95B32731-92BE-4FB8-A800-62D7EAD7E504-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/95B32731-92BE-4FB8-A800-62D7EAD7E504-300x225.jpeg 300w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/95B32731-92BE-4FB8-A800-62D7EAD7E504-768x576.jpeg 768w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/95B32731-92BE-4FB8-A800-62D7EAD7E504-1024x768.jpeg 1024w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/95B32731-92BE-4FB8-A800-62D7EAD7E504-680x510.jpeg 680w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1128 aligncenter\" src=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/79E0C51C-D4A2-4FDF-8973-65BACD3DAA47-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/79E0C51C-D4A2-4FDF-8973-65BACD3DAA47-225x300.jpeg 225w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/79E0C51C-D4A2-4FDF-8973-65BACD3DAA47.jpeg 768w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/79E0C51C-D4A2-4FDF-8973-65BACD3DAA47-680x907.jpeg 680w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1129\" src=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/05D6DA18-D3F0-4B1B-8ECD-37CBD40D97B2-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/05D6DA18-D3F0-4B1B-8ECD-37CBD40D97B2-300x225.jpeg 300w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/05D6DA18-D3F0-4B1B-8ECD-37CBD40D97B2-768x576.jpeg 768w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/05D6DA18-D3F0-4B1B-8ECD-37CBD40D97B2.jpeg 1024w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/05D6DA18-D3F0-4B1B-8ECD-37CBD40D97B2-680x510.jpeg 680w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1130 aligncenter\" src=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/AAF1FDEC-4E61-48C8-8F6C-B2A7D4E0AC10-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/AAF1FDEC-4E61-48C8-8F6C-B2A7D4E0AC10-225x300.jpeg 225w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/AAF1FDEC-4E61-48C8-8F6C-B2A7D4E0AC10.jpeg 768w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/AAF1FDEC-4E61-48C8-8F6C-B2A7D4E0AC10-680x907.jpeg 680w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grande entusiasmo per la pedalata ecologica. La manifestazione ha visto la partecipazione di \u201cciclisti\u201d di tutte le et\u00e0, per la maggior parte bambini. Il gruppo dei partecipanti, con in testa [&hellip;]<\/p>\n","protected":false},"author":398,"featured_media":1126,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grande entusiasmo per la pedalata ecologica. - Cancello ed Arnone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/07\/13\/grande-entusiasmo-per-la-pedalata-ecologica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grande entusiasmo per la pedalata ecologica. - Cancello ed Arnone\" \/>\n<meta property=\"og:description\" content=\"Grande entusiasmo per la pedalata ecologica. La manifestazione ha visto la partecipazione di \u201cciclisti\u201d di tutte le et\u00e0, per la maggior parte bambini. Il gruppo dei partecipanti, con in testa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/07\/13\/grande-entusiasmo-per-la-pedalata-ecologica\/\" \/>\n<meta property=\"og:site_name\" content=\"Cancello ed Arnone\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-13T09:04:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-02T14:41:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/E1B77DDE-41F9-4EDB-8D2B-ECC41B8F8EAD.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"718\" \/>\n\t<meta property=\"og:image:height\" content=\"958\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin_E\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin_E\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/07\\\/13\\\/grande-entusiasmo-per-la-pedalata-ecologica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/07\\\/13\\\/grande-entusiasmo-per-la-pedalata-ecologica\\\/\"},\"author\":{\"name\":\"Admin_E\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#\\\/schema\\\/person\\\/eaea9f1aebcbd61eb9878e6232bd2a03\"},\"headline\":\"Grande entusiasmo per la pedalata ecologica.\",\"datePublished\":\"2019-07-13T09:04:45+00:00\",\"dateModified\":\"2023-02-02T14:41:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/07\\\/13\\\/grande-entusiasmo-per-la-pedalata-ecologica\\\/\"},\"wordCount\":154,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/07\\\/13\\\/grande-entusiasmo-per-la-pedalata-ecologica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2019\\\/07\\\/E1B77DDE-41F9-4EDB-8D2B-ECC41B8F8EAD.jpeg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/07\\\/13\\\/grande-entusiasmo-per-la-pedalata-ecologica\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/07\\\/13\\\/grande-entusiasmo-per-la-pedalata-ecologica\\\/\",\"name\":\"Grande entusiasmo per la pedalata ecologica. - Cancello ed Arnone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/07\\\/13\\\/grande-entusiasmo-per-la-pedalata-ecologica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/07\\\/13\\\/grande-entusiasmo-per-la-pedalata-ecologica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2019\\\/07\\\/E1B77DDE-41F9-4EDB-8D2B-ECC41B8F8EAD.jpeg\",\"datePublished\":\"2019-07-13T09:04:45+00:00\",\"dateModified\":\"2023-02-02T14:41:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#\\\/schema\\\/person\\\/eaea9f1aebcbd61eb9878e6232bd2a03\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/07\\\/13\\\/grande-entusiasmo-per-la-pedalata-ecologica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/07\\\/13\\\/grande-entusiasmo-per-la-pedalata-ecologica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/07\\\/13\\\/grande-entusiasmo-per-la-pedalata-ecologica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2019\\\/07\\\/E1B77DDE-41F9-4EDB-8D2B-ECC41B8F8EAD.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2019\\\/07\\\/E1B77DDE-41F9-4EDB-8D2B-ECC41B8F8EAD.jpeg\",\"width\":718,\"height\":958},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2019\\\/07\\\/13\\\/grande-entusiasmo-per-la-pedalata-ecologica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grande entusiasmo per la pedalata ecologica.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/\",\"name\":\"Cancello ed Arnone\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#\\\/schema\\\/person\\\/eaea9f1aebcbd61eb9878e6232bd2a03\",\"name\":\"Admin_E\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g\",\"caption\":\"Admin_E\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/author\\\/oollppcancelloarnone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grande entusiasmo per la pedalata ecologica. - Cancello ed Arnone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/07\/13\/grande-entusiasmo-per-la-pedalata-ecologica\/","og_locale":"it_IT","og_type":"article","og_title":"Grande entusiasmo per la pedalata ecologica. - Cancello ed Arnone","og_description":"Grande entusiasmo per la pedalata ecologica. La manifestazione ha visto la partecipazione di \u201cciclisti\u201d di tutte le et\u00e0, per la maggior parte bambini. Il gruppo dei partecipanti, con in testa [&hellip;]","og_url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/07\/13\/grande-entusiasmo-per-la-pedalata-ecologica\/","og_site_name":"Cancello ed Arnone","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-07-13T09:04:45+00:00","article_modified_time":"2023-02-02T14:41:30+00:00","og_image":[{"width":718,"height":958,"url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/E1B77DDE-41F9-4EDB-8D2B-ECC41B8F8EAD.jpeg","type":"image\/jpeg"}],"author":"Admin_E","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Admin_E","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/07\/13\/grande-entusiasmo-per-la-pedalata-ecologica\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/07\/13\/grande-entusiasmo-per-la-pedalata-ecologica\/"},"author":{"name":"Admin_E","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#\/schema\/person\/eaea9f1aebcbd61eb9878e6232bd2a03"},"headline":"Grande entusiasmo per la pedalata ecologica.","datePublished":"2019-07-13T09:04:45+00:00","dateModified":"2023-02-02T14:41:30+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/07\/13\/grande-entusiasmo-per-la-pedalata-ecologica\/"},"wordCount":154,"image":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/07\/13\/grande-entusiasmo-per-la-pedalata-ecologica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/E1B77DDE-41F9-4EDB-8D2B-ECC41B8F8EAD.jpeg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/07\/13\/grande-entusiasmo-per-la-pedalata-ecologica\/","url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/07\/13\/grande-entusiasmo-per-la-pedalata-ecologica\/","name":"Grande entusiasmo per la pedalata ecologica. - Cancello ed Arnone","isPartOf":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/07\/13\/grande-entusiasmo-per-la-pedalata-ecologica\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/07\/13\/grande-entusiasmo-per-la-pedalata-ecologica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/E1B77DDE-41F9-4EDB-8D2B-ECC41B8F8EAD.jpeg","datePublished":"2019-07-13T09:04:45+00:00","dateModified":"2023-02-02T14:41:30+00:00","author":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#\/schema\/person\/eaea9f1aebcbd61eb9878e6232bd2a03"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/07\/13\/grande-entusiasmo-per-la-pedalata-ecologica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/07\/13\/grande-entusiasmo-per-la-pedalata-ecologica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/07\/13\/grande-entusiasmo-per-la-pedalata-ecologica\/#primaryimage","url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/E1B77DDE-41F9-4EDB-8D2B-ECC41B8F8EAD.jpeg","contentUrl":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2019\/07\/E1B77DDE-41F9-4EDB-8D2B-ECC41B8F8EAD.jpeg","width":718,"height":958},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2019\/07\/13\/grande-entusiasmo-per-la-pedalata-ecologica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/cancello-ed-arnone\/"},{"@type":"ListItem","position":2,"name":"Grande entusiasmo per la pedalata ecologica."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#website","url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/","name":"Cancello ed Arnone","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/cancello-ed-arnone\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#\/schema\/person\/eaea9f1aebcbd61eb9878e6232bd2a03","name":"Admin_E","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g","caption":"Admin_E"},"url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/author\/oollppcancelloarnone\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts\/1118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/users\/398"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/comments?post=1118"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts\/1118\/revisions"}],"predecessor-version":[{"id":1131,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts\/1118\/revisions\/1131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/media\/1126"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/media?parent=1118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/categories?post=1118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/tags?post=1118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}