{"id":2053,"date":"2024-01-23T18:01:20","date_gmt":"2024-01-23T17:01:20","guid":{"rendered":"https:\/\/comunicacity.net\/cancello-ed-arnone\/?p=2053"},"modified":"2024-01-23T18:01:20","modified_gmt":"2024-01-23T17:01:20","slug":"cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2024\/01\/23\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\/","title":{"rendered":"CERIMONIA INAUGURALE DELLO &#8220;STALLO TEMPORANEO E AREA PET TERAPY&#8221; DOMANI 24 GENNAIO 2024"},"content":{"rendered":"<p>Nel 2017 l\u2019Agenzia Nazionale dei Beni Confiscati ha trasferito al patrimonio indisponibile del Comune di Cancello ed Arnone due lotti ubicati in Cancello ed Arnone in via Tronara.<\/p>\n<p>Ad oggi, a seguito dell\u2019intervento del Comune, una superficie di 330 mq \u00e8 stata suddivisa in 3 aree:<\/p>\n<p>una adibita allo stallo temporaneo dei cani randagi, un\u2019area di sgambamento e un\u2019area per le attivit\u00e0 connesse.<br \/>\nIl Sindaco Avv. Raffaele Ambrosca invita la cittadinanza a partecipare all\u2019inaugurazione che si terr\u00e0 Domani 24 Gennaio alle ore 10:30.\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-2055\" src=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2024\/01\/IMG_8722.jpg\" alt=\"\" width=\"640\" height=\"640\" srcset=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2024\/01\/IMG_8722.jpg 960w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2024\/01\/IMG_8722-300x300.jpg 300w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2024\/01\/IMG_8722-150x150.jpg 150w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2024\/01\/IMG_8722-768x768.jpg 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Nel 2017 l\u2019Agenzia Nazionale dei Beni Confiscati ha trasferito al patrimonio indisponibile del Comune di Cancello ed Arnone due lotti ubicati in Cancello ed Arnone in via Tronara. Ad oggi, [&hellip;]<\/p>\n","protected":false},"author":398,"featured_media":2054,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CERIMONIA INAUGURALE DELLO &quot;STALLO TEMPORANEO E AREA PET TERAPY&quot; DOMANI 24 GENNAIO 2024 - Cancello ed Arnone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/2024\/01\/23\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CERIMONIA INAUGURALE DELLO &quot;STALLO TEMPORANEO E AREA PET TERAPY&quot; DOMANI 24 GENNAIO 2024 - Cancello ed Arnone\" \/>\n<meta property=\"og:description\" content=\"Nel 2017 l\u2019Agenzia Nazionale dei Beni Confiscati ha trasferito al patrimonio indisponibile del Comune di Cancello ed Arnone due lotti ubicati in Cancello ed Arnone in via Tronara. Ad oggi, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/2024\/01\/23\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Cancello ed Arnone\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-23T17:01:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2024\/01\/IMG_8721.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin_E\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin_E\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2024\\\/01\\\/23\\\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2024\\\/01\\\/23\\\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\\\/\"},\"author\":{\"name\":\"Admin_E\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#\\\/schema\\\/person\\\/eaea9f1aebcbd61eb9878e6232bd2a03\"},\"headline\":\"CERIMONIA INAUGURALE DELLO &#8220;STALLO TEMPORANEO E AREA PET TERAPY&#8221; DOMANI 24 GENNAIO 2024\",\"datePublished\":\"2024-01-23T17:01:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2024\\\/01\\\/23\\\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\\\/\"},\"wordCount\":93,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2024\\\/01\\\/23\\\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2024\\\/01\\\/IMG_8721.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2024\\\/01\\\/23\\\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2024\\\/01\\\/23\\\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\\\/\",\"name\":\"CERIMONIA INAUGURALE DELLO \\\"STALLO TEMPORANEO E AREA PET TERAPY\\\" DOMANI 24 GENNAIO 2024 - Cancello ed Arnone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2024\\\/01\\\/23\\\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2024\\\/01\\\/23\\\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2024\\\/01\\\/IMG_8721.jpg\",\"datePublished\":\"2024-01-23T17:01:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#\\\/schema\\\/person\\\/eaea9f1aebcbd61eb9878e6232bd2a03\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2024\\\/01\\\/23\\\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2024\\\/01\\\/23\\\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2024\\\/01\\\/23\\\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2024\\\/01\\\/IMG_8721.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2024\\\/01\\\/IMG_8721.jpg\",\"width\":960,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2024\\\/01\\\/23\\\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CERIMONIA INAUGURALE DELLO &#8220;STALLO TEMPORANEO E AREA PET TERAPY&#8221; DOMANI 24 GENNAIO 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/\",\"name\":\"Cancello ed Arnone\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#\\\/schema\\\/person\\\/eaea9f1aebcbd61eb9878e6232bd2a03\",\"name\":\"Admin_E\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g\",\"caption\":\"Admin_E\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/author\\\/oollppcancelloarnone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CERIMONIA INAUGURALE DELLO \"STALLO TEMPORANEO E AREA PET TERAPY\" DOMANI 24 GENNAIO 2024 - Cancello ed Arnone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2024\/01\/23\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\/","og_locale":"it_IT","og_type":"article","og_title":"CERIMONIA INAUGURALE DELLO \"STALLO TEMPORANEO E AREA PET TERAPY\" DOMANI 24 GENNAIO 2024 - Cancello ed Arnone","og_description":"Nel 2017 l\u2019Agenzia Nazionale dei Beni Confiscati ha trasferito al patrimonio indisponibile del Comune di Cancello ed Arnone due lotti ubicati in Cancello ed Arnone in via Tronara. Ad oggi, [&hellip;]","og_url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2024\/01\/23\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\/","og_site_name":"Cancello ed Arnone","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-01-23T17:01:20+00:00","og_image":[{"width":960,"height":960,"url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2024\/01\/IMG_8721.jpg","type":"image\/jpeg"}],"author":"Admin_E","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Admin_E"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2024\/01\/23\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2024\/01\/23\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\/"},"author":{"name":"Admin_E","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#\/schema\/person\/eaea9f1aebcbd61eb9878e6232bd2a03"},"headline":"CERIMONIA INAUGURALE DELLO &#8220;STALLO TEMPORANEO E AREA PET TERAPY&#8221; DOMANI 24 GENNAIO 2024","datePublished":"2024-01-23T17:01:20+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2024\/01\/23\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\/"},"wordCount":93,"image":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2024\/01\/23\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2024\/01\/IMG_8721.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2024\/01\/23\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\/","url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2024\/01\/23\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\/","name":"CERIMONIA INAUGURALE DELLO \"STALLO TEMPORANEO E AREA PET TERAPY\" DOMANI 24 GENNAIO 2024 - Cancello ed Arnone","isPartOf":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2024\/01\/23\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2024\/01\/23\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2024\/01\/IMG_8721.jpg","datePublished":"2024-01-23T17:01:20+00:00","author":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#\/schema\/person\/eaea9f1aebcbd61eb9878e6232bd2a03"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2024\/01\/23\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/cancello-ed-arnone\/2024\/01\/23\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2024\/01\/23\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\/#primaryimage","url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2024\/01\/IMG_8721.jpg","contentUrl":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2024\/01\/IMG_8721.jpg","width":960,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2024\/01\/23\/cerimonia-inaugurale-dello-stallo-temporaneo-e-area-pet-terapy-domani-24-gennaio-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/cancello-ed-arnone\/"},{"@type":"ListItem","position":2,"name":"CERIMONIA INAUGURALE DELLO &#8220;STALLO TEMPORANEO E AREA PET TERAPY&#8221; DOMANI 24 GENNAIO 2024"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#website","url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/","name":"Cancello ed Arnone","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/cancello-ed-arnone\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#\/schema\/person\/eaea9f1aebcbd61eb9878e6232bd2a03","name":"Admin_E","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g","caption":"Admin_E"},"url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/author\/oollppcancelloarnone\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"18"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts\/2053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/users\/398"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/comments?post=2053"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts\/2053\/revisions"}],"predecessor-version":[{"id":2056,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts\/2053\/revisions\/2056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/media\/2054"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/media?parent=2053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/categories?post=2053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/tags?post=2053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}