{"id":468,"date":"2018-09-10T15:42:02","date_gmt":"2018-09-10T13:42:02","guid":{"rendered":"https:\/\/comunicacity.net\/cancello-ed-arnone\/?p=468"},"modified":"2023-02-02T15:44:41","modified_gmt":"2023-02-02T14:44:41","slug":"il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/10\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\/","title":{"rendered":"Il Sindaco Raffaele Ambrosca ha partecipato alla cerimonia di avvicendamento tra il Colonnello Pilota Pasquale Di Palma ed il Colonnello Pilota Nicola Lucivero."},"content":{"rendered":"<p>Questa mattina il sindaco Raffaele Ambrosca ha partecipato alla cerimonia di avvicendamento tra il Colonnello Pilota Pasquale Di Palma ed il Colonnello Pilota Nicola Lucivero che ha avuto luogo presso il 9\u00b0 Stormo &#8220;Francesco Baracca&#8221; dell&#8217;Aeronautica Militare Italiana di Grazzanise.<\/p>\n<p>Il Colonnello di Palma lascia il Comando del 9\u00b0 Stormo, dopo due anni di intenso lavoro, al Colonnello Lucivero, proveniente dal Supreme Headquarters of Allied Powers in Europe (SHAPE), Belgio.<\/p>\n<p>L&#8217;evento \u00e8 stato presieduto dal Comandante del Comando delle Forze di Supporto e Speciali (Cfss), generale di divisione aerea &#8220;Gianpaolo Miniscalco&#8221;, ex comandante del 9\u00b0 Stormo, e ha visto la partecipazione di autorit\u00e0 civile, militare e religiose locali, oltre naturalmente allo schieramento del personale militare e civile dello Stormo.<\/p>\n<p>L&#8217;importanza dell&#8217;evento si inquadra nella strategia di un proficuo e sinergico rapporto con la base militare, la cui pista, per almeno la met\u00e0 della sua lunghezza, poggia sul territorio di Cancello ed Arnone.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questa mattina il sindaco Raffaele Ambrosca ha partecipato alla cerimonia di avvicendamento tra il Colonnello Pilota Pasquale Di Palma ed il Colonnello Pilota Nicola Lucivero che ha avuto luogo presso [&hellip;]<\/p>\n","protected":false},"author":398,"featured_media":367,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-468","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Sindaco Raffaele Ambrosca ha partecipato alla cerimonia di avvicendamento tra il Colonnello Pilota Pasquale Di Palma ed il Colonnello Pilota Nicola Lucivero. - Cancello ed Arnone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/10\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Sindaco Raffaele Ambrosca ha partecipato alla cerimonia di avvicendamento tra il Colonnello Pilota Pasquale Di Palma ed il Colonnello Pilota Nicola Lucivero. - Cancello ed Arnone\" \/>\n<meta property=\"og:description\" content=\"Questa mattina il sindaco Raffaele Ambrosca ha partecipato alla cerimonia di avvicendamento tra il Colonnello Pilota Pasquale Di Palma ed il Colonnello Pilota Nicola Lucivero che ha avuto luogo presso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/10\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\/\" \/>\n<meta property=\"og:site_name\" content=\"Cancello ed Arnone\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-10T13:42:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-02T14:44:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2016\/07\/Ambrosca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin_E\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin_E\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/10\\\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/10\\\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\\\/\"},\"author\":{\"name\":\"Admin_E\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#\\\/schema\\\/person\\\/eaea9f1aebcbd61eb9878e6232bd2a03\"},\"headline\":\"Il Sindaco Raffaele Ambrosca ha partecipato alla cerimonia di avvicendamento tra il Colonnello Pilota Pasquale Di Palma ed il Colonnello Pilota Nicola Lucivero.\",\"datePublished\":\"2018-09-10T13:42:02+00:00\",\"dateModified\":\"2023-02-02T14:44:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/10\\\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\\\/\"},\"wordCount\":171,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/10\\\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2016\\\/07\\\/Ambrosca.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/10\\\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/10\\\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\\\/\",\"name\":\"Il Sindaco Raffaele Ambrosca ha partecipato alla cerimonia di avvicendamento tra il Colonnello Pilota Pasquale Di Palma ed il Colonnello Pilota Nicola Lucivero. - Cancello ed Arnone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/10\\\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/10\\\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2016\\\/07\\\/Ambrosca.jpg\",\"datePublished\":\"2018-09-10T13:42:02+00:00\",\"dateModified\":\"2023-02-02T14:44:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#\\\/schema\\\/person\\\/eaea9f1aebcbd61eb9878e6232bd2a03\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/10\\\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/10\\\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/10\\\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2016\\\/07\\\/Ambrosca.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2016\\\/07\\\/Ambrosca.jpg\",\"width\":400,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/10\\\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Sindaco Raffaele Ambrosca ha partecipato alla cerimonia di avvicendamento tra il Colonnello Pilota Pasquale Di Palma ed il Colonnello Pilota Nicola Lucivero.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/\",\"name\":\"Cancello ed Arnone\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#\\\/schema\\\/person\\\/eaea9f1aebcbd61eb9878e6232bd2a03\",\"name\":\"Admin_E\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g\",\"caption\":\"Admin_E\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/author\\\/oollppcancelloarnone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Sindaco Raffaele Ambrosca ha partecipato alla cerimonia di avvicendamento tra il Colonnello Pilota Pasquale Di Palma ed il Colonnello Pilota Nicola Lucivero. - Cancello ed Arnone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/10\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\/","og_locale":"it_IT","og_type":"article","og_title":"Il Sindaco Raffaele Ambrosca ha partecipato alla cerimonia di avvicendamento tra il Colonnello Pilota Pasquale Di Palma ed il Colonnello Pilota Nicola Lucivero. - Cancello ed Arnone","og_description":"Questa mattina il sindaco Raffaele Ambrosca ha partecipato alla cerimonia di avvicendamento tra il Colonnello Pilota Pasquale Di Palma ed il Colonnello Pilota Nicola Lucivero che ha avuto luogo presso [&hellip;]","og_url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/10\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\/","og_site_name":"Cancello ed Arnone","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-09-10T13:42:02+00:00","article_modified_time":"2023-02-02T14:44:41+00:00","og_image":[{"width":400,"height":450,"url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2016\/07\/Ambrosca.jpg","type":"image\/jpeg"}],"author":"Admin_E","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Admin_E","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/10\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/10\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\/"},"author":{"name":"Admin_E","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#\/schema\/person\/eaea9f1aebcbd61eb9878e6232bd2a03"},"headline":"Il Sindaco Raffaele Ambrosca ha partecipato alla cerimonia di avvicendamento tra il Colonnello Pilota Pasquale Di Palma ed il Colonnello Pilota Nicola Lucivero.","datePublished":"2018-09-10T13:42:02+00:00","dateModified":"2023-02-02T14:44:41+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/10\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\/"},"wordCount":171,"image":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/10\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2016\/07\/Ambrosca.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/10\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\/","url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/10\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\/","name":"Il Sindaco Raffaele Ambrosca ha partecipato alla cerimonia di avvicendamento tra il Colonnello Pilota Pasquale Di Palma ed il Colonnello Pilota Nicola Lucivero. - Cancello ed Arnone","isPartOf":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/10\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/10\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2016\/07\/Ambrosca.jpg","datePublished":"2018-09-10T13:42:02+00:00","dateModified":"2023-02-02T14:44:41+00:00","author":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#\/schema\/person\/eaea9f1aebcbd61eb9878e6232bd2a03"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/10\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/10\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/10\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\/#primaryimage","url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2016\/07\/Ambrosca.jpg","contentUrl":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2016\/07\/Ambrosca.jpg","width":400,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/10\/il-sindaco-raffaele-ambrosca-ha-partecipato-alla-cerimonia-di-avvicendamento-tra-il-colonnello-pilota-pasquale-di-palma-ed-il-colonnello-pilota-nicola-lucivero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/cancello-ed-arnone\/"},{"@type":"ListItem","position":2,"name":"Il Sindaco Raffaele Ambrosca ha partecipato alla cerimonia di avvicendamento tra il Colonnello Pilota Pasquale Di Palma ed il Colonnello Pilota Nicola Lucivero."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#website","url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/","name":"Cancello ed Arnone","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/cancello-ed-arnone\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#\/schema\/person\/eaea9f1aebcbd61eb9878e6232bd2a03","name":"Admin_E","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g","caption":"Admin_E"},"url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/author\/oollppcancelloarnone\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts\/468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/users\/398"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/comments?post=468"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts\/468\/revisions"}],"predecessor-version":[{"id":469,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts\/468\/revisions\/469"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/media\/367"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/media?parent=468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/categories?post=468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/tags?post=468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}